{"id":1463850,"date":"2025-06-23T06:03:52","date_gmt":"2025-06-23T13:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/"},"modified":"2025-06-23T06:03:52","modified_gmt":"2025-06-23T13:03:52","slug":"eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","title":{"rendered":"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;"},"content":{"rendered":"<p>Eyal Sela, embajador de Israel en Argentina, se refiri\u00f3 al recrudecimiento del conflicto b\u00e9lico en Medio Oriente, tras el ataque de Estados Unidos a objetivos militares de Ir\u00e1n.<\/p>\n<p>En CNN Primera Ma\u00f1ana, asegur\u00f3 que <strong>\u201cIsrael act\u00faa en defensa propia frente a una amenaza que considera existencial\u201d<\/strong>.<\/p>\n<p>Destac\u00f3 que \u201cdesde hace 11 d\u00edas Israel inici\u00f3 esta operaci\u00f3n contra Ir\u00e1n para quitar la opci\u00f3n de borrarnos del mapa v\u00eda nuclear o misiles bal\u00edsticos\u201d.<\/p>\n<p>El diplom\u00e1tico remarc\u00f3 que, por los ataques dirigidos contra centros clave del programa nuclear, <strong>\u201cIr\u00e1n sufri\u00f3 bastante da\u00f1o de los ataques, primero de Israel y despu\u00e9s de Estados Unidos, con ataques a los tres sitios donde pueden enriquecer el uranio\u201d<\/strong>.<\/p>\n<p>No obstante, asegur\u00f3 que \u201c<strong>la amenaza persiste. Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel<\/strong>.<br \/>Atacan ciudades, hospitales y mezquitas\u201d.<\/p>\n<p>Y afirm\u00f3 que, frente a esta situaci\u00f3n, <strong>su pa\u00eds \u201cmantiene su ofensiva\u201d y se va a \u201cseguir buscando los misiles que est\u00e1n a punto de lanzar contra Israel\u201d<\/strong>.<\/p>\n<p>Eyal Sela, adem\u00e1s, alert\u00f3 sobre la influencia de Teher\u00e1n a nivel global al asegurar que <strong>\u201cIr\u00e1n est\u00e1 detr\u00e1s de atentados no solo en Argentina, sino en distintas partes del mundo. Est\u00e1 en contacto con Hezbollah\u201d<\/strong>.<\/p>\n<p>Aunque aclar\u00f3 que <strong>\u201cno tenemos una amenaza concreta en Argentina pero hay que estar alerta, seguimos trabajando\u201d<\/strong>.<\/p>\n<p>En relaci\u00f3n al d\u00eda a d\u00eda en territorio israel\u00ed, el embajador describi\u00f3 un escenario a\u00fan restringido por cuestiones de seguridad y afirm\u00f3 que \u201ctodav\u00eda no hay colegios, solo hay supermercados y cosas de necesidad. No pueden estar m\u00e1s de 30 personas en el mismo lugar\u201d.<\/p>\n<p>Sin embargo, asegur\u00f3 que la poblaci\u00f3n cuenta con recursos de protecci\u00f3n como los <strong>\u201csistema de alerta que ayuda a la gente a buscar refugios\u201d<\/strong>, y a\u00f1adi\u00f3 que lo que \u201cimporta es que la gente tenga seguridad\u201d.<\/p>\n<p>Y remarc\u00f3 que a pesar del conflicto, el pa\u00eds comienza a reactivar su conectividad a\u00e9rea ya que \u201cde a poco se est\u00e1 abriendo el cielo. Hay vuelos que entran y salen a trav\u00e9s de terceros pa\u00edses\u201d.<\/p>\n<p>Respecto al futuro del conflicto, Eyal Sela se\u00f1al\u00f3 que el desenlace depende del gobierno iran\u00ed<\/p>\n<p>Y concluy\u00f3 que <strong>\u201cdepende de Ir\u00e1n si quiere seguir dialogando y buscar una soluci\u00f3n\u201d<\/strong> y profundiz\u00f3 que <strong>\u201cIr\u00e1n est\u00e1 m\u00e1s d\u00e9bil. Las capacidades est\u00e1n bajando pero todav\u00eda tienen posibilidades de hacer ataques\u201d<\/strong>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eyal Sela, embajador de Israel en Argentina, se refiri\u00f3 al recrudecimiento del conflicto b\u00e9lico en Medio Oriente, tras el ataque de Estados Unidos a objetivos militares de Ir\u00e1n. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cIsrael act\u00faa en defensa propia frente a una amenaza que considera existencial\u201d. Destac\u00f3 que \u201cdesde hace 11 d\u00edas Israel inici\u00f3 esta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1463850","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eyal Sela: &quot;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eyal Sela: &quot;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Eyal Sela, embajador de Israel en Argentina, se refiri\u00f3 al recrudecimiento del conflicto b\u00e9lico en Medio Oriente, tras el ataque de Estados Unidos a objetivos militares de Ir\u00e1n. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cIsrael act\u00faa en defensa propia frente a una amenaza que considera existencial\u201d. Destac\u00f3 que \u201cdesde hace 11 d\u00edas Israel inici\u00f3 esta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T13:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;\",\"datePublished\":\"2025-06-23T13:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\"},\"wordCount\":449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\",\"name\":\"Eyal Sela: \\\"Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-06-23T13:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eyal Sela: \"Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","og_locale":"es_ES","og_type":"article","og_title":"Eyal Sela: \"Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel\" - Noticias","og_description":"Eyal Sela, embajador de Israel en Argentina, se refiri\u00f3 al recrudecimiento del conflicto b\u00e9lico en Medio Oriente, tras el ataque de Estados Unidos a objetivos militares de Ir\u00e1n. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cIsrael act\u00faa en defensa propia frente a una amenaza que considera existencial\u201d. Destac\u00f3 que \u201cdesde hace 11 d\u00edas Israel inici\u00f3 esta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","og_site_name":"Noticias","article_published_time":"2025-06-23T13:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/"},"author":{"name":"","@id":""},"headline":"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;","datePublished":"2025-06-23T13:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/"},"wordCount":449,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","url":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","name":"Eyal Sela: \"Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-06-23T13:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Eyal Sela: &#171;Ir\u00e1n sigue lanzando misiles a la poblaci\u00f3n civil en Israel&#187;","url":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/23\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-06-23T13:03:52Z","datePublished":"2025-06-23T13:03:52Z","dateModified":"2025-06-23T13:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Eyal Sela: &#171;Ir\\u00e1n sigue lanzando misiles a la poblaci\\u00f3n civil en Israel&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/23\\\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/23\\\/eyal-sela-iran-sigue-lanzando-misiles-a-la-poblacion-civil-en-israel\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-06-23T13:03:52Z\",\"datePublished\":\"2025-06-23T13:03:52Z\",\"dateModified\":\"2025-06-23T13:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463593,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/16\/eyal-sela-iran-tiene-como-fin-desaparecer-a-israel\/","url_meta":{"origin":1463850,"position":0},"title":"Eyal Sela: &#171;Ir\u00e1n tiene como fin desaparecer a Israel&#187;","author":"","date":"junio 16, 2025","format":false,"excerpt":"Eyal Sela, embajador de Israel en Argentina, habl\u00f3 este lunes en CNN Radio con Nacho Gir\u00f3n sobre el conflicto con Ir\u00e1n y aclar\u00f3 que \u201csiempre dijeron que su objetivo es borrar a Israel del mapa\u201d.\u201cTodas las noches nos levantamos al menos dos o tres veces y buscamos el refugio dentro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472570,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/26\/aliados-trump-golfo-presionan-guerra-iran-trax\/","url_meta":{"origin":1463850,"position":1},"title":"Los aliados de Trump en el Golfo presionan para que se aborden sus preocupaciones antes de que termine la guerra con Ir\u00e1n","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Antes de la guerra con Ir\u00e1n, los aliados \u00e1rabes del Golfo del presidente Donald Trump presionaron en\u00e9rgicamente en contra del conflicto militar, temiendo los ataques que Teher\u00e1n ahora est\u00e1 lanzando contra ellos.A medida que la guerra se prolonga, temen que una salida r\u00e1pida pueda dejarlos en peor situaci\u00f3n que antes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463508,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/12\/israel-lanza-ataques-preventivos-iran-trax\/","url_meta":{"origin":1463850,"position":2},"title":"Israel lanza &#171;ataques preventivos&#187; contra Ir\u00e1n","author":"","date":"junio 12, 2025","format":false,"excerpt":"Israel lanz\u00f3 lo que denomin\u00f3 \u201cataques preventivos\u201d contra Ir\u00e1n y se declar\u00f3 estado de emergencia en Israel, seg\u00fan el ministro de Defensa del pa\u00eds, Israel Katz.\u201cTras el ataque preventivo del Estado de Israel contra Ir\u00e1n, se espera un ataque con misiles y drones contra el Estado de Israel y su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463603,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/16\/mapas-ataques-aereos-israelies-represalia-iran-trax\/","url_meta":{"origin":1463850,"position":3},"title":"Los ataques a\u00e9reos israel\u00edes sobre Ir\u00e1n y la represalia, en mapas","author":"","date":"junio 16, 2025","format":false,"excerpt":"El ataque sin precedentes de Israel contra la sede del Ministerio de Defensa de Ir\u00e1n en Teher\u00e1n, junto con otros lugares vinculados al programa nuclear iran\u00ed, ha desencadenado un intercambio de misiles entre ambos pa\u00edses que ya lleva varios d\u00edas. Las tensiones no han hecho m\u00e1s que aumentar y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459021,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/21\/eyal-sela-embajador-israeli-en-argentina-sigue-siendo-prioridad-la-recuperacion-de-los-rehenes-y-la-erradicacion-de-hamas\/","url_meta":{"origin":1463850,"position":4},"title":"Eyal Sela, embajador israel\u00ed en Argentina: &#171;Sigue siendo prioridad la recuperaci\u00f3n de los rehenes y la erradicaci\u00f3n de Hamas&#187;","author":"","date":"febrero 21, 2025","format":false,"excerpt":"Eyal Sela, embajador de Israel en Argentina, se refiri\u00f3 a la continuidad del acuerdo entre su pa\u00eds y el grupo terrorista Hamas y sobre el reclamo por el cuerpo de Shiri Bibas, que deb\u00eda ser entregado esta semana.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cayer fue uno de los d\u00edas m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472543,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/25\/promesa-netanyahu-ataques-guerra-iran-trax\/","url_meta":{"origin":1463850,"position":5},"title":"La promesa de Netanyahu tras los ataques en Ir\u00e1n en 2025 result\u00f3 vac\u00eda, pero los israel\u00edes siguen apoyando la guerra actual","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Si creemos en la palabra del primer ministro de Israel, Benjamin Netanyahu, los primeros ataques de la guerra contra Ir\u00e1n no deber\u00edan haber sido necesarios.Tras la guerra de 12 d\u00edas con Ir\u00e1n en junio de 2025, Netanyahu declar\u00f3 una victoria inequ\u00edvoca. Israel hab\u00eda \u201celiminado dos amenazas existenciales\u201d, al destruir los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1463850"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463850\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1463850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1463850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1463850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}