{"id":1471760,"date":"2026-02-28T19:04:01","date_gmt":"2026-03-01T03:04:01","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/"},"modified":"2026-02-28T19:04:01","modified_gmt":"2026-03-01T03:04:01","slug":"quien-fue-ayatola-jamenei-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","title":{"rendered":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?"},"content":{"rendered":"<p>El ayatola Seyyed Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n que gobern\u00f3 el pa\u00eds durante casi cuatro d\u00e9cadas, muri\u00f3 el s\u00e1bado 28 de febrero, <a href=\"https:\/\/cnnespanol.cnn.com\/mundo\/live-news\/israel-lanza-ataque-preventivo-iran-trax?post-id=cmm72u0vb00263j6ssn2zv530\">confirmaron m\u00faltiples medios estatales iran\u00edes. <\/a><\/p>\n<p>\u201cEl l\u00edder supremo de Ir\u00e1n ha alcanzado el martirio\u201d, inform\u00f3 el canal estatal IRIB la ma\u00f1ana del domingo.<\/p>\n<p>Anteriormente, el presidente de Estados Unidos, Donald Trump, y dos fuentes israel\u00edes, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/28\/mundo\/iran-ayatola-ali-jamenei-muere-dice-trump-trax\">aseguraron que Jamenei falleci\u00f3 en los ataques.<\/a><\/p>\n<p>Aqu\u00ed un vistazo a sus datos m\u00e1s relevantes.<\/p>\n<p>Fecha de nacimiento: 17 de julio de 1939<\/p>\n<p>Fecha de fallecimiento: 28 de febrero de 2026<\/p>\n<ul>\n<li><strong>Lugar      de nacimiento: <\/strong>Mashhad, Ir\u00e1n<\/li>\n<li><strong>Nombre de nacimiento: <\/strong>Seyyed Al\u00ed Jamenei<\/li>\n<li><strong>Padre:<\/strong> ayatola Sayyid Jawad Husaini      Jamenei<\/li>\n<li><strong>Madre:      <\/strong>Nombre no disponible p\u00fablicamente<\/li>\n<li><strong>Matrimonio:      <\/strong>Casado en 1964<\/li>\n<li><strong>Hijos:<\/strong> Mostafa, Mojtaba, Massoud,      Maysam, Hoda y Boshra<\/li>\n<li><strong>Educaci\u00f3n:      <\/strong>Estudi\u00f3 con el futuro ayatola Jomeini en el seminario isl\u00e1mico de Qom,      Ir\u00e1n.<\/li>\n<li><strong>Religi\u00f3n:<\/strong>      isl\u00e1mica, musulmana chi\u00edta<\/li>\n<\/ul>\n<p>Jamenei tambi\u00e9n era conocido como el l\u00edder supremo.<\/p>\n<p><strong>1962 \u2013<\/strong> Junto con Jomeini, comienza su participaci\u00f3n en las protestas, oponi\u00e9ndose a las pol\u00edticas del Sha de Ir\u00e1n, Mohammad Reza Pahlavi.<\/p>\n<p><strong>1977 &#8211;<\/strong> Junto con otros cl\u00e9rigos, forma la Asociaci\u00f3n de Cl\u00e9rigos Combatientes, que se convierte en el Partido de la Rep\u00fablica Isl\u00e1mica.<\/p>\n<p><strong>1980-1987 &#8211;<\/strong> Secretario general y miembro del mando central del Partido de la Rep\u00fablica Isl\u00e1mica.<\/p>\n<p><strong>Junio <\/strong><strong>\u200b\u200bde 1981-<\/strong> Resulta herido al explotar una bomba colocada en una grabadora durante una conferencia de prensa.<\/p>\n<p><strong>13 de octubre de 1981-3 de agosto de 1989-<\/strong> Presidente de Ir\u00e1n.<\/p>\n<p><strong>Marzo de 1985-<\/strong> Sobrevive cuando una bomba suicida detona cerca.<\/p>\n<p><strong>4 de junio de 1989 hasta la actualidad-<\/strong> Es elegido provisionalmente l\u00edder supremo de la Rep\u00fablica Isl\u00e1mica de Ir\u00e1n tras la muerte de Jomeini.<\/p>\n<p><strong>28 de julio de 1989-<\/strong> Un refer\u00e9ndum oficializa su elecci\u00f3n y un grupo de l\u00edderes religiosos confirma m\u00e1s tarde su elecci\u00f3n como l\u00edder supremo.<\/p>\n<p><strong>Mayo de 2011-<\/strong> Jamenei se ve envuelto en una lucha por el poder p\u00fablico con el presidente iran\u00ed Mahmoud Ahmadinejad.<\/p>\n<p><strong>Febrero de 2012-<\/strong> emite una declaraci\u00f3n de que Ir\u00e1n respaldar\u00e1 a cualquier naci\u00f3n o grupo que luche contra Israel.<\/p>\n<p><strong>Marzo de 2012-<\/strong> Reacciona a las tensiones relacionadas con el programa nuclear de Ir\u00e1n y acoge con agrado el comentario del presidente estadounidense, Barack Obama, de que \u201clo mejor para Estados Unidos, Israel y el mundo\u201d es resolver pac\u00edficamente la crisis nuclear de Ir\u00e1n.<\/p>\n<p><strong>Marzo de 2012-<\/strong> Los aliados de Jamenei obtienen alrededor del 75 % de los esca\u00f1os en las elecciones parlamentarias contra el movimiento de oposici\u00f3n rival de Ahmadinejad.<\/p>\n<p><strong>21 de marzo de 2013 &#8211;<\/strong> Jamenei, en un discurso televisado, amenaza a Tel Aviv y Haifa afirmando que \u201ca veces los funcionarios del r\u00e9gimen sionista (Israel) amenazan con lanzar una invasi\u00f3n militar, pero ellos mismos saben que si cometen el m\u00e1s m\u00ednimo error, los musulmanes La Rep\u00fablica arrasar\u00e1 Tel Aviv y Haifa\u201d.<\/p>\n<p><strong>Enero de 2015-<\/strong> Jamenei publica una carta abierta en su sitio web, dirigida a los j\u00f3venes occidentales, pidi\u00e9ndoles que no juzguen al Islam bas\u00e1ndose en los ataques terroristas de Charlie Hebdo.<\/p>\n<p><strong>21 de octubre de 2015-<\/strong> Jamenei aprueba condicionalmente el acuerdo nuclear firmado entre su pa\u00eds y seis potencias mundiales en julio.<\/p>\n<p><strong>7 de febrero de 2017-<\/strong> Seg\u00fan su sitio web, Jamenei dice en una reuni\u00f3n de comandantes de la fuerza a\u00e9rea de Ir\u00e1n en Teher\u00e1n: \u201cSin embargo, agradecemos a este nuevo hombre en la Casa Blanca, ya que hizo en gran medida el trabajo que hab\u00edamos estado tratando de hacer en las \u00faltimas d\u00e9cadas para divulgar el verdadero rostro de Estados Unidos. Hab\u00edamos estado trabajando para mostrar al mundo la profundidad de la corrupci\u00f3n en el Gobierno estadounidense y en las filas y filas de la \u00e9lite gobernante. [El presidente de EE.UU. Donald] Trump lo hizo pocos d\u00edas despu\u00e9s de llegar a la Casa Blanca\u201d.<\/p>\n<p><strong>9 de enero de 2018-<\/strong> Hablando en el aniversario de la revoluci\u00f3n iran\u00ed que comenz\u00f3 en 1978, Jamenei dice que los iran\u00edes tienen derecho a protestar. Pero tambi\u00e9n culpa a Estados Unidos e Israel por los disturbios civiles m\u00e1s recientes.<\/p>\n<p><strong>13 de agosto de 2018-<\/strong> En un discurso publicado en su sitio web, Jamenei dice que \u201cno habr\u00e1 guerra ni negociaremos con Estados Unidos\u201d, luego de la primera ola de sanciones reimpuestas por el Gobierno de Trump a Ir\u00e1n despu\u00e9s de que Estados Unidos anunciara su retirada. del acuerdo nuclear con Ir\u00e1n en mayo. Jamenei parece contradecir al presidente iran\u00ed, Hassan Rouhani, quien anteriormente hab\u00eda dicho que Ir\u00e1n estaba dispuesto a mantener conversaciones con Estados Unidos para resolver el asunto, algo que el asesor de seguridad nacional de Trump, John Bolton, descart\u00f3 como posible \u201cpropaganda\u201d.<\/p>\n<p><strong>24 de junio de 2019-<\/strong> Trump anuncia nuevas sanciones contra Ir\u00e1n, en parte como represalia tras el derribo de un dron estadounidense, y las medidas punitivas apuntan a Jamenei, funcionarios militares y el principal diplom\u00e1tico de Ir\u00e1n.<\/p>\n<p><strong>5 de enero de 2020-<\/strong> Tras la muerte del general Qasem Soleimani en un ataque con aviones no tripulados estadounidenses en Bagdad, el asesor militar de Jamenei, Hassan Dehghan, dice que la \u201crespuesta de su pa\u00eds seguramente ser\u00e1 militar y contra sitios militares\u201d.<\/p>\n<p><strong>17 de enero de 2020- <\/strong>Por primera vez en ocho a\u00f1os, Jamenei dirige las oraciones del viernes en Teher\u00e1n y llama a los funcionarios estadounidenses \u201cpayasos estadounidenses\u201d en su desafiante serm\u00f3n.<\/p>\n<p><strong>28 de noviembre de 2020-<\/strong> un d\u00eda despu\u00e9s del aparente asesinato del principal cient\u00edfico nuclear de Ir\u00e1n, Mohsen Fakhrizadeh, Jamenei jura venganza por su asesinato. Ir\u00e1n culp\u00f3 a Israel por el ataque y dijo que la operaci\u00f3n ten\u00eda el sello de la agencia de inteligencia exterior de Israel, el Mossad.<\/p>\n<p><strong>8 de enero de 2021-<\/strong> Jamenei proh\u00edbe la importaci\u00f3n de vacunas covid-19 desde Estados Unidos y Gran Breta\u00f1a a Ir\u00e1n. En una aparici\u00f3n en la televisi\u00f3n estatal, califica las vacunas como poco confiables.<\/p>\n<p><strong>19 de junio de 2021-<\/strong> El aliado cercano de Jamenei, Ebrahim Raisi, gana las elecciones presidenciales. La elecci\u00f3n del jefe del poder judicial de l\u00ednea dura, que tiene un historial brutal en materia de derechos humanos, genera especulaciones de que lo est\u00e1n preparando para suceder alg\u00fan d\u00eda a Jamenei. La participaci\u00f3n electoral general es del 48,8 %, la m\u00e1s baja desde el establecimiento de la Rep\u00fablica Isl\u00e1mica en 1979.<\/p>\n<p><strong>25 de junio de 2021-<\/strong> La televisi\u00f3n estatal de Ir\u00e1n informa que Jamenei recibi\u00f3 su primera dosis de la vacuna covid-19 desarrollada en Ir\u00e1n, conocida como vacuna CovIran Barekat. Su uso fue aprobado a mediados de junio, seg\u00fan las autoridades iran\u00edes.<\/p>\n<p><strong>1 de marzo de 2022-<\/strong> En un discurso televisado, Jamenei acusa a Estados Unidos de causar el conflicto en Ucrania, comparando al Gobierno de EE.UU. con un \u201cr\u00e9gimen tipo mafia\u201d.<\/p>\n<p><strong>9 de febrero de 2024 &#8211; <\/strong>Meta confirma a CNN que las cuentas de Facebook e Instagram de Jamenei fueron eliminadas por \u201cviolar repetidamente nuestra pol\u00edtica de Organizaciones e Individuos Peligrosos\u201d. Aunque Meta no especific\u00f3 el motivo, la pol\u00edtica no permite que organizaciones o individuos que proclamen una misi\u00f3n violenta o participen en actos violentos tengan presencia en Meta.<\/p>\n<p><strong>6 de julio de 2025 &#8211;<\/strong> Jamenei asisti\u00f3 a una reuni\u00f3n religiosa en la que es fue primera aparici\u00f3n p\u00fablica en varias semanas. Jamenei no hab\u00eda sido visto en p\u00fablico desde que su pa\u00eds se vio envuelto en un conflicto el 13 de junio, cuando Israel atac\u00f3 unilateralmente sitios militares y nucleares iran\u00edes. Posteriormente, Estados Unidos se uni\u00f3 y bombarde\u00f3 tres sitios nucleares clave de Ir\u00e1n antes de que el presidente Donald Trump declarara un alto el fuego. Jamenei pas\u00f3 supuestamente los 12 d\u00edas del conflicto escondido en un b\u00fanker, con poco acceso a comunicaciones externas. Durante el conflicto, tanto pol\u00edticos israel\u00edes como Trump discutieron abiertamente la posibilidad de derrocar al Gobierno de Jamenei y destituirlo por la fuerza.<\/p>\n<p><strong>17 de enero de 2026 &#8211; <\/strong>Jamenei reconoci\u00f3 que miles de iran\u00edes murieron durante m\u00e1s de dos semanas de disturbios en el pa\u00eds, muertes que atribuy\u00f3 al presidente de Estados Unidos, Donald Trump, quien seg\u00fan \u00e9l \u201calent\u00f3 abiertamente\u201d a los manifestantes prometi\u00e9ndoles \u201capoyo militar\u201d estadounidense. Jamenei no mencion\u00f3 las brutales t\u00e1cticas de las fuerzas de seguridad de Ir\u00e1n para sofocar las protestas.<\/p>\n<p><strong>28 de febrero de 2026 &#8211; <\/strong>Muere tras una serie de ataques conjuntos de Estados Unidos e Israel contra Ir\u00e1n, que ten\u00edan como objetivo a la m\u00e1xima dirigencia iran\u00ed, incluido Jamenei.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ayatola Seyyed Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n que gobern\u00f3 el pa\u00eds durante casi cuatro d\u00e9cadas, muri\u00f3 el s\u00e1bado 28 de febrero, confirmaron m\u00faltiples medios estatales iran\u00edes. \u201cEl l\u00edder supremo de Ir\u00e1n ha alcanzado el martirio\u201d, inform\u00f3 el canal estatal IRIB la ma\u00f1ana del domingo. Anteriormente, el presidente de Estados Unidos, Donald Trump, y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471760","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ayatola Seyyed Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n que gobern\u00f3 el pa\u00eds durante casi cuatro d\u00e9cadas, muri\u00f3 el s\u00e1bado 28 de febrero, confirmaron m\u00faltiples medios estatales iran\u00edes. \u201cEl l\u00edder supremo de Ir\u00e1n ha alcanzado el martirio\u201d, inform\u00f3 el canal estatal IRIB la ma\u00f1ana del domingo. Anteriormente, el presidente de Estados Unidos, Donald Trump, y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-01T03:04:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?\",\"datePublished\":\"2026-03-01T03:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\"},\"wordCount\":1486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\",\"name\":\"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-01T03:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias","og_description":"El ayatola Seyyed Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n que gobern\u00f3 el pa\u00eds durante casi cuatro d\u00e9cadas, muri\u00f3 el s\u00e1bado 28 de febrero, confirmaron m\u00faltiples medios estatales iran\u00edes. \u201cEl l\u00edder supremo de Ir\u00e1n ha alcanzado el martirio\u201d, inform\u00f3 el canal estatal IRIB la ma\u00f1ana del domingo. Anteriormente, el presidente de Estados Unidos, Donald Trump, y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-01T03:04:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?","datePublished":"2026-03-01T03:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/"},"wordCount":1486,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","name":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-01T03:04:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n fue el ayatola Al\u00ed Jamenei, el l\u00edder supremo de Ir\u00e1n?","url":"http:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/quien-fue-ayatola-jamenei-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-01T03:04:01Z","datePublished":"2026-03-01T03:04:01Z","dateModified":"2026-03-01T03:04:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n fue el ayatola Al\\u00ed Jamenei, el l\\u00edder supremo de Ir\\u00e1n?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/02\\\/28\\\/quien-fue-ayatola-jamenei-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/02\\\/28\\\/quien-fue-ayatola-jamenei-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-01T03:04:01Z\",\"datePublished\":\"2026-03-01T03:04:01Z\",\"dateModified\":\"2026-03-01T03:04:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463601,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/16\/ali-jamenei-quien-es-ayatola-lider-supremo-iran-trax\/","url_meta":{"origin":1471760,"position":0},"title":"\u00bfQui\u00e9n es el ayatola Ali Jamenei, el l\u00edder supremo de Ir\u00e1n?","author":"","date":"junio 16, 2025","format":false,"excerpt":"He aqu\u00ed un vistazo al l\u00edder supremo de Ir\u00e1n, el ayatol\u00e1 Seyyed Ali Jamenei.Datos personalesFecha de nacimiento: 17 de julio de 1939Lugar de nacimiento: Mashhad, Ir\u00e1nNombre de nacimiento: Seyyed Ali JameneiPadre: ayatola Sayyid Jawad Husaini JameneiMadre: Nombre no disponible p\u00fablicamenteMatrimonio: Casado en 1964Hijos: Mostafa, Mojtaba, Massoud, Maysam, Hoda y BoshraEducaci\u00f3n:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463576,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/15\/trump-plan-israel-matar-ayatola-jamenei-iran-trax\/","url_meta":{"origin":1471760,"position":1},"title":"Trump rechaz\u00f3 un plan de Israel para matar al l\u00edder de Ir\u00e1n, el ayatol\u00e1 Al\u00ed Jamenei, seg\u00fan un funcionario de EE.UU.","author":"","date":"junio 15, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, rechaz\u00f3 un plan de Israel para matar al l\u00edder supremo de Ir\u00e1n, el ayatol\u00e1 Al\u00ed Jamenei, seg\u00fan declar\u00f3 este domingo a CNN un funcionario estadounidense.En medio de las continuas oleadas de ataques rec\u00edprocos entre Israel e Ir\u00e1n, el presidente Donald Trump ha dejado claro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471759,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/iran-ayatola-ali-jamenei-muere-dice-trump-trax\/","url_meta":{"origin":1471760,"position":2},"title":"Muere el ayatola Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n, dicen Trump y fuentes de Israel","author":"","date":"febrero 28, 2026","format":false,"excerpt":"El ayatola Al\u00ed Jamenei, l\u00edder supremo de Ir\u00e1n que gobern\u00f3 el pa\u00eds durante casi cuatro d\u00e9cadas, muri\u00f3, seg\u00fan el presidente de EE.UU., Donald Trump, y dos fuentes israel\u00edes.Israel no ha compartido pruebas de la muerte de Jamenei, y un portavoz del Ministerio de Asuntos Exteriores iran\u00ed insisti\u00f3 anteriormente en que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472053,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/10\/trump-declaraciones-sobre-mojtaba-jamenei-iran-trax\/","url_meta":{"origin":1471760,"position":3},"title":"Trump dice que no cree que Mojtaba Jamenei, nuevo l\u00edder supremo de Ir\u00e1n, &#171;pueda vivir en paz&#187;","author":"","date":"marzo 10, 2026","format":false,"excerpt":"El presidente Donald Trump afirm\u00f3 que no cree que Mojtaba Jamenei, a quien Ir\u00e1n design\u00f3 como l\u00edder supremo para suceder a su padre, el difunto ayatol\u00e1 Al\u00ed Jamenei, pueda \u201cvivir en paz\u201d.\u201cNo creo que pueda vivir en paz\u201d, declar\u00f3 Trump en una entrevista con Fox News sobre Jamenei.No qued\u00f3 claro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471766,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/01\/exclusivo-trump-cruzo-linea-roja-muerte-ayatola-jamenei-iran-trax\/","url_meta":{"origin":1471760,"position":4},"title":"Exclusivo: Trump cruz\u00f3 una &#171;l\u00ednea roja muy peligrosa&#187; al matar al l\u00edder supremo, dice funcionario iran\u00ed a CNN","author":"","date":"marzo 1, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, ha cruzado \u201cuna l\u00ednea roja muy peligrosa\u201d al matar al l\u00edder supremo de Ir\u00e1n, Al\u00ed Jamenei, dijo a CNN en una entrevista exclusiva el viceministro de Relaciones Exteriores iran\u00ed, Saeed Khatibzadeh, el domingo.Khatibzadeh dijo que muchos seguidores chiitas en todo el mundo reaccionar\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470188,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/17\/ali-jamenei-trump-iran-trax\/","url_meta":{"origin":1471760,"position":5},"title":"El l\u00edder supremo de Ir\u00e1n califica a Trump de &#171;criminal&#187; y afirma que EE.UU. debe rendir cuentas, seg\u00fan medios estatales","author":"","date":"enero 17, 2026","format":false,"excerpt":"El l\u00edder supremo de Ir\u00e1n, el ayatol\u00e1 Ali Jamenei, calific\u00f3 este s\u00e1bado a Donald Trump de \u201ccriminal\u201d por el apoyo del presidente de Estados Unidos a las recientes protestas antigubernamentales en el pa\u00eds, seg\u00fan la agencia de noticias estatal Tasnim.Jamenei insinu\u00f3 que Trump era responsable por las \u201cv\u00edctimas\u201d y los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471760"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471760\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}