{"id":1471785,"date":"2026-03-02T05:03:49","date_gmt":"2026-03-02T13:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/"},"modified":"2026-03-02T05:03:49","modified_gmt":"2026-03-02T13:03:49","slug":"zendaya-tom-holland-boda-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","title":{"rendered":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach"},"content":{"rendered":"<p>Los actores Zendaya y Tom Holland se casaron en una ceremonia secreta, seg\u00fan el estilista de Zendaya, Law Roach.<\/p>\n<p>El domingo, en la alfombra roja de los premios Actores 2026 en Los \u00c1ngeles, Roach declar\u00f3 al medio Access Hollywood que \u201cla boda ya se celebr\u00f3\u201d.<\/p>\n<p>\u201cSe la perdieron\u201d, dijo Roach, quien lleva m\u00e1s de una d\u00e9cada trabajando con Zendaya.<\/p>\n<p>Zendaya y Holland, ambos de 29 a\u00f1os, se conocieron en 2017 durante el rodaje de \u201cSpider-Man: Homecoming\u201d, y su qu\u00edmica durante la gira de prensa de la pel\u00edcula dio pie a especulaciones sobre una posible relaci\u00f3n.<\/p>\n<p>Sin embargo, no fue hasta julio de 2021 que esta se confirm\u00f3, cuando la pareja fue fotografiada bes\u00e1ndose en el coche de Holland.<\/p>\n<p>Desde entonces, \u201cTomdaya\u201d han mantenido su relaci\u00f3n con discreci\u00f3n, compartiendo solo ocasionalmente fotos en entrevistas o redes sociales.<\/p>\n<p>Y lo han logrado a pesar de haberse convertido en dos de las mayores estrellas de Hollywood: Zendaya ha aparecido recientemente en pel\u00edculas taquilleras como \u201cDune: Parte Dos\u201d (2024) y \u201cChallengers\u201d (2024), mientras que Holland interpreta a Peter Parker en la franquicia de Marvel \u201cSpider-Man\u201d.<\/p>\n<p>La aparici\u00f3n de un anillo de diamantes en el dedo de Zendaya en los Globos de Oro en enero de 2025 desat\u00f3 especulaciones sobre la posible propuesta de matrimonio de Holland, lo que posteriormente confirm\u00f3 en una entrevista en septiembre de ese a\u00f1o.<\/p>\n<p>En febrero de este a\u00f1o, surgieron rumores de que la pareja se hab\u00eda casado en secreto, despu\u00e9s de que Zendaya fuera vista con un anillo de oro en lugar del anillo de diamantes.<\/p>\n<p>Ahora parece que Roach ha revelado la verdad, aunque ni Zendaya ni Holland han hecho comentarios al respecto.<\/p>\n<p>CNN contact\u00f3 a representantes de Zendaya y Holland para solicitarles comentarios.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los actores Zendaya y Tom Holland se casaron en una ceremonia secreta, seg\u00fan el estilista de Zendaya, Law Roach. El domingo, en la alfombra roja de los premios Actores 2026 en Los \u00c1ngeles, Roach declar\u00f3 al medio Access Hollywood que \u201cla boda ya se celebr\u00f3\u201d. \u201cSe la perdieron\u201d, dijo Roach, quien lleva m\u00e1s de una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471785","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los actores Zendaya y Tom Holland se casaron en una ceremonia secreta, seg\u00fan el estilista de Zendaya, Law Roach. El domingo, en la alfombra roja de los premios Actores 2026 en Los \u00c1ngeles, Roach declar\u00f3 al medio Access Hollywood que \u201cla boda ya se celebr\u00f3\u201d. \u201cSe la perdieron\u201d, dijo Roach, quien lleva m\u00e1s de una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-02T13:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach\",\"datePublished\":\"2026-03-02T13:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\",\"name\":\"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-02T13:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias","og_description":"Los actores Zendaya y Tom Holland se casaron en una ceremonia secreta, seg\u00fan el estilista de Zendaya, Law Roach. El domingo, en la alfombra roja de los premios Actores 2026 en Los \u00c1ngeles, Roach declar\u00f3 al medio Access Hollywood que \u201cla boda ya se celebr\u00f3\u201d. \u201cSe la perdieron\u201d, dijo Roach, quien lleva m\u00e1s de una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-02T13:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/"},"author":{"name":"","@id":""},"headline":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach","datePublished":"2026-03-02T13:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","name":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-02T13:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach","url":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/zendaya-tom-holland-boda-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-02T13:03:49Z","datePublished":"2026-03-02T13:03:49Z","dateModified":"2026-03-02T13:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Zendaya y Tom Holland se casaron en secreto, afirma el estilista Law Roach\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/zendaya-tom-holland-boda-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/zendaya-tom-holland-boda-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-02T13:03:49Z\",\"datePublished\":\"2026-03-02T13:03:49Z\",\"dateModified\":\"2026-03-02T13:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472291,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/17\/zendaya-especulaciones-boda-tom-holland-orix\/","url_meta":{"origin":1471785,"position":0},"title":"\u00bfSe casaron? Zendaya habla de las especulaciones sobre su relaci\u00f3n con Tom Holland","author":"","date":"marzo 17, 2026","format":false,"excerpt":"Zendaya se refiri\u00f3 a los rumores sobre una supuesta boda con Tom Holland que han surgido en los \u00faltimos d\u00edas.La actriz fue invitada la noche del 16 de marzo al programa \u201cJimmy Kimmel Live!\u201d. Durante su charla con Jimmy Kimmel, habl\u00f3 de distintos temas, como su m\u00e1s reciente pel\u00edcula, \u201cThe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457258,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/06\/zendaya-glamour-viejo-hollywood-anillo-diamantes-trax\/","url_meta":{"origin":1471785,"position":1},"title":"Zendaya canaliza el glamour del viejo Hollywood mientras los fan\u00e1ticos especulan sobre un enorme anillo de diamantes","author":"","date":"enero 6, 2025","format":false,"excerpt":"Zendaya fue una imagen del viejo glamour de Hollywood en los Premios Globo de Oro este domingo por la noche, al llegar con un elegante vestido de Louis Vuitton con una cola plisada que se extend\u00eda detr\u00e1s de ella mientras caminaba por la alfombra roja del Beverly Hilton de Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471809,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/5-cosas-3-de-marzo-orix\/","url_meta":{"origin":1471785,"position":2},"title":"Las 5 cosas que debes saber este 3 de marzo","author":"","date":"marzo 3, 2026","format":false,"excerpt":"La guerra en Medio Oriente expone los l\u00edmites del poder del Kremlin. Primarias en EE.UU. \u00bfQu\u00e9 hay detr\u00e1s de los cambios en el gabinete de Delcy Rodr\u00edguez? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455242,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/18\/spider-man-4-tom-holland-zendaya-borrador-guion-trax\/","url_meta":{"origin":1471785,"position":3},"title":"Tom Holland y Zendaya leyeron un borrador del guion de &#8216;Spider-Man 4&#8217; y creen que ser\u00e1 \u201cdigna del respeto de los fans\u201d","author":"","date":"octubre 18, 2024","format":false,"excerpt":"(CNN) --\u00a0La estrella de la franquicia \"Spider-Man\" parece emocionada con la \u00faltima secuela, incluso si tiene algunas notas.Tom Holland, quien interpreta a Peter Parker\/Spider-Man, habl\u00f3 sobre eso en el \"Rich Roll Podcast\". El actor comparti\u00f3 que \u00e9l y su novia en la vida real, Zendaya, quien interpreta a Michelle \"MJ\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465895,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/27\/spider-man-brand-new-day-personajes-actores-estreno-trax\/","url_meta":{"origin":1471785,"position":4},"title":"Todos los personajes de Marvel confirmados para &#171;Spider-Man: Brand New Day&#187;","author":"","date":"agosto 27, 2025","format":false,"excerpt":"Tras la trilog\u00eda de pel\u00edculas de Spider-Man protagonizada por Tom Holland que finaliz\u00f3 con \u201cSpider-Man: No Way Home\u201d en 2021, todo indica que la pr\u00f3xima cinta del superh\u00e9roe ar\u00e1cnido de Marvel ser\u00e1 como un relanzamiento, con nuevos personajes y el inicio de una nueva saga.La pr\u00f3xima pel\u00edcula se titula \u201cSpider-Man:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456938,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/12\/24\/pelicula-christopher-nolan-adaptacion-odisea-homero-trax\/","url_meta":{"origin":1471785,"position":5},"title":"La pr\u00f3xima pel\u00edcula de Christopher Nolan ser\u00e1 una adaptaci\u00f3n repleta de celebridades de &#8216;La Odisea&#8217; de Homero","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"El director ganador del Oscar Christopher Nolan llevar\u00e1 al p\u00fablico a la m\u00edtica Grecia con su m\u00e1s reciente proyecto.Universal Pictures anunci\u00f3 esta semana que Nolan dirigir\u00e1 una adaptaci\u00f3n cinematogr\u00e1fica de \u201cLa Odisea\u201d, un antiguo poema que se cree fue escrito por Homero entre 750 y 650 a. C. y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471785"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471785\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}