{"id":1471787,"date":"2026-03-02T06:03:55","date_gmt":"2026-03-02T14:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/"},"modified":"2026-03-02T06:03:55","modified_gmt":"2026-03-02T14:03:55","slug":"guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","title":{"rendered":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial"},"content":{"rendered":"<p>Los tel\u00e9fonos comenzaron a vibrar sin descanso en Guadalajara el domingo 22 de febrero. En grupos de WhatsApp y chats familiares se mezclaban datos confirmados, rumores y miedo, acompa\u00f1ados de advertencias: \u201cNo salgan\u201d, \u201cHay bloqueos\u201d, \u201cEst\u00e1n quemando coches\u201d. Fotos de veh\u00edculos ardiendo y avisos sobre carreteras cerradas se propagaban con rapidez. Nadie sab\u00eda con certeza qu\u00e9 estaba ocurriendo, pero todos intu\u00edan que era grave.<\/p>\n<p>Horas m\u00e1s tarde, la Secretar\u00eda de la Defensa de M\u00e9xico <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/22\/mexico\/violencia-jalisco-bloqueo-vias-enfrentamientos-orix\">confirm\u00f3 la muerte <\/a>de Nemesio Oseguera Cervantes, alias \u201cEl Mencho\u201d, el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/22\/mexico\/quien-era-el-mencho-expolicia-liderar-cjng-violentos-mexico-orix\">poderoso l\u00edder del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG)<\/a>. Seg\u00fan las autoridades, el capo muri\u00f3 mientras era trasladado en helic\u00f3ptero tras un operativo militar realizado en Tapalpa, Jalisco, un pueblo ubicado a unos 120 km al suroeste de Guadalajara, en una zona monta\u00f1osa que hab\u00eda servido al capo m\u00e1s buscado del pa\u00eds de refugio y escondite por su dif\u00edcil acceso.<\/p>\n<p>Ha pasado m\u00e1s de una semana desde entonces, el tr\u00e1fico volvi\u00f3 a la normalidad, las oficinas reabrieron y los estudiantes regresaron a clases. La ciudad mexicana que en unos meses ser\u00e1 sede del Mundial recuper\u00f3, en apariencia, su ritmo habitual. Sin embargo, el miedo que se instal\u00f3 tras la ca\u00edda del Mencho no se ha disipado.<\/p>\n<p>Para muchos, la violencia del domingo, que caus\u00f3 estragos en 20 estados del pa\u00eds, no fue solo una reacci\u00f3n inmediata al operativo militar que termin\u00f3 con la muerte del l\u00edder del violento cartel\u2014y que, seg\u00fan las autoridades, dej\u00f3 25 militares fallecidos\u2014, sino <a href=\"https:\/\/www.cnn.com\/2026\/02\/23\/americas\/jalisco-cjng-sinaloa-mexico-cartels-war-intl-latam\">una advertencia<\/a> de lo que podr\u00eda venir: reacomodos internos, disputas por el control y una nueva ola de violencia.<\/p>\n<p>Jos\u00e9 Luis Tapia, un propietario de un Airbnb en Guadalajara, cuenta a CNN que el domingo del operativo la primera persona que le avis\u00f3 que algo hab\u00eda ocurrido era una de sus hu\u00e9spedes, una turista alemana, que le dijo que hab\u00eda visto algunos reportes de violencia. \u201cPens\u00e9 que hab\u00eda bloqueos, pero afuera de la ciudad\u201d, se\u00f1ala.<\/p>\n<p>\u201cBloqueos\u201d es la palabra que muchos mexicanos (y visitantes en M\u00e9xico) usan para referirse al cierre de avenidas por parte de hombres armados que se identifican como miembros del crimen organizado. A veces implica el incendio de veh\u00edculos. \u201cFamilias que les quitan el coche y salen corriendo, porque si no lo hacen, los matan\u201d, explica Tapia.<\/p>\n<p>Lo que Tapia percibi\u00f3 como algo lejano en realidad era parte de un estallido de violencia a gran escala: las autoridades <a href=\"https:\/\/cnnespanol.cnn.com\/mexico\/live-news\/ultima-hora-nemesio-mencho-oseguera-orix?post-id=cmm09nv1q000t356t93wxry5q\">registraron al menos 65 bloqueos <\/a>en todo Jalisco, uno de los principales bastiones <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/24\/mexico\/mexico-carteles-principales-donde-operan-orix\">donde opera el CJNG<\/a>, durante la jornada de caos que se desat\u00f3 despu\u00e9s de que los integrantes del cartel reaccionaran a la muerte de su l\u00edder.<\/p>\n<p>Comercios como las tiendas Oxxo, una cadena de tiendas de conveniencia que se encuentran en todo el pa\u00eds, fueron blanco de ataque de los operadores del CJNG que salieron a las calles. Afuera de una de ellas, Tapia vio c\u00f3mo una persona peg\u00f3 un letrero improvisado en el que ofrec\u00eda comida para quien lo necesitara. Soluciones de emergencia para una situaci\u00f3n in\u00e9dita.<\/p>\n<p>Tapia lleg\u00f3 a Guadalajara en 2018 proveniente de la Ciudad de M\u00e9xico. \u201cEn marzo cumplo ocho a\u00f1os aqu\u00ed y en la Ciudad de M\u00e9xico no recuerdo haber vivido tanto miedo\u201d, afirm\u00f3. Durante a\u00f1os, cuando reci\u00e9n se hab\u00eda mudado, dice que las referencias al narco eran constantes. \u201cMuchas personas tienen una historia, a m\u00ed me contaban, \u2018mira, aqu\u00ed viv\u00eda Caro Quintero\u2019, o alguien m\u00e1s cuyo vecino era Miguel \u00c1ngel F\u00e9lix Gallardo, an\u00e9cdotas que pueden sonar incre\u00edbles, pero son reales\u201d.<\/p>\n<p>Para \u00e9l, la jornada de ese domingo marc\u00f3 un antes y un despu\u00e9s. Tapia dice que aun cuando en Guadalajara la violencia se ha vuelto en algo cotidiano, los sucesos del domingo pasado superan lo que la sociedad tapat\u00eda ha vivido en estos a\u00f1os. \u201cTodos sent\u00edamos que en un momento esto iba a explotar\u201d, cuenta. \u201cY explot\u00f3\u201d.<\/p>\n<p>Entre quienes viven hoy en Guadalajara hay algunos que llegaron huyendo de lugares donde la violencia no les dej\u00f3 otra opci\u00f3n. B. G., una comerciante que pidi\u00f3 el anonimato por razones de seguridad, se mud\u00f3 a Guadalajara de Reynosa, una ciudad fronteriza en Tamaulipas, en el norte de M\u00e9xico, en busca de un refugio para su familia.<\/p>\n<p>\u201cLa situaci\u00f3n comenz\u00f3 en 2008-2009\u201d, recuerda, pero decidi\u00f3 irse cuando se enter\u00f3 de que uno de los amigos de su hijo en la guarder\u00eda era el hijo de un presunto miembro de la delincuencia organizada. \u201cReynosa es muy peque\u00f1o, ah\u00ed todos se conocen a todos\u201d, explica.<\/p>\n<p>Lleg\u00f3 a Guadalajara en 2019. Ella, su esposo y su hijo <a href=\"https:\/\/www.acnur.org\/mx\/desplazamiento-interno#:~:text=Desplazamiento%20Interno%20en%20M%C3%A9xico,de%20120%25%20respecto%20a%202023.\">son tres de los cerca de 210.000 desplazados por la violencia interna en M\u00e9xico entre 2015 y 2020<\/a>, seg\u00fan datos reunidos por la Oficina del Alto Comisionado de las Naciones Unidas para los Refugiados (ACNUR, en ingl\u00e9s).<\/p>\n<p>\u00bfPor qu\u00e9 Guadalajara? \u201cMe enamor\u00e9 de la ciudad desde el primer momento\u201d, recuerda. La comparaci\u00f3n con la ciudad donde creci\u00f3 es inevitable. Ah\u00ed, cuenta B.G., la sensaci\u00f3n de desamparo es demasiado grande.<\/p>\n<p>\u201cEn Reynosa, la rutina antes de salir es revisar las p\u00e1ginas de Facebook donde avisan de las balaceras\u201d, dice. \u201cAs\u00ed como revisar el clima, antes de salir ya uno sabe por qu\u00e9 avenida no se debe pasar\u201d.<\/p>\n<p>B.G. no minimiza lo que pas\u00f3 en Guadalajara el domingo. \u201cLo que hicimos fue encerrarnos y encender una vela\u201d, se\u00f1ala. \u201cYo soy una persona espiritual\u201d. Aunque el miedo los oblig\u00f3 a B.G. y a su familia a quedarse en casa, encontr\u00f3 gestos de solidaridad entre sus vecinos el d\u00eda de los bloqueos y tambi\u00e9n despu\u00e9s de eso.<\/p>\n<p>\u201cMucha gente se organiz\u00f3 para avisar si ten\u00eda un espacio extra en su casa para guardar un coche o comida de m\u00e1s\u201d, recuerda. Dice que esos peque\u00f1os actos de solidaridad le dan esperanza por el futuro.<\/p>\n<p>En toda la conversaci\u00f3n su tono es abierto y alegre. La \u00fanica vez que se le quiebra la voz es cuando habla de su hijo. \u201cYo vine ac\u00e1 para ofrecerle lo mejor, \u00e9l sabe que tiene unos pap\u00e1s que lo apoyar\u00e1n en todo, y yo estoy dispuesta a hacer lo que sea por defenderlo. Por eso vinimos aqu\u00ed\u201d.<\/p>\n<p>El estallido de violencia que vivi\u00f3 M\u00e9xico ese domingo <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/24\/mexico\/dramatica-expansion-carteles-cjng-violencia-trax\">mostr\u00f3 el alcance<\/a> que tiene el CJNG en el pa\u00eds: barricadas de autos en llamas y bloqueos carreteros afectaron 20 de los 32 estados que componen el pa\u00eds. El aeropuerto de Guadalajara detuvo sus operaciones y decenas de vuelos fueron cancelados.<\/p>\n<p>Adem\u00e1s, la violencia no se limit\u00f3 a zonas rurales, lleg\u00f3 a destinos tur\u00edsticos como Puerto Vallarta o Canc\u00fan y afect\u00f3 a ciudades como Guadalajara, que ser\u00e1 sede de varios partidos del Mundial de f\u00fatbol este verano.<\/p>\n<p>\u201cLo m\u00e1s impactante es que todos estos lugares, donde se quemaron autos y autobuses y se bloquearon carreteras, funcionan como una radiograf\u00eda que evidencia la presencia del Cartel Jalisco Nueva Generaci\u00f3n\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/24\/mexico\/dramatica-expansion-carteles-cjng-violencia-trax\">dijo a CNN<\/a> Catalina P\u00e9rez Correa, profesora mexicana de derecho especializada en crimen organizado.<\/p>\n<p>La violencia, seg\u00fan P\u00e9rez Correa, dej\u00f3 claro que estas redes criminales ya no operan solo en unas pocas regiones: est\u00e1n en todo el pa\u00eds.<\/p>\n<p>Las autoridades insisten en que la situaci\u00f3n est\u00e1 bajo control en las zonas que m\u00e1s caos vieron el d\u00eda en que cay\u00f3 el Mencho. La presidenta de M\u00e9xico, Claudia Sheinbaum, quien ha adoptado una postura m\u00e1s dura frente al narcotr\u00e1fico, bajo la presi\u00f3n del Gobierno de Donald Trump, asegur\u00f3 que<a href=\"https:\/\/www.cnn.com\/world\/live-news\/mexico-el-mencho-killed-travel-chaos-02-23-26-intl-hnk?post-id=cmlz93wxs00083d5ugba2qojr\"> \u201cla paz, la seguridad y la normalidad se mantienen\u201d<\/a> en el pa\u00eds. Mientras que el secretario de Seguridad, Omar Garc\u00eda Harfuch,<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/23\/mexico\/mundial-guadalajara-violencia-mencho-cjng-orix\"> dijo que el centro de mando<\/a> estar\u00eda atento \u201ccualquier tipo de reacci\u00f3n que haya o de reestructuraci\u00f3n dentro del cartel\u201d y trabajar\u00eda para reforzar la zona.<\/p>\n<p>La selecci\u00f3n de M\u00e9xico jugar\u00e1 en Guadalajara uno de sus partidos y la ciudad tambi\u00e9n recibir\u00e1 a las selecciones de Corea del Sur, Colombia, Uruguay, Espa\u00f1a y a otros dos equipos que a\u00fan no se definen en el repechaje. Por ello, autoridades estatales esperan la llegada de cerca de 3 millones de turistas durante esas semanas.<\/p>\n<p>La violencia, inevitablemente, gener\u00f3 dudas sobre si Guadalajara estaba lista para continuar como sede del certamen, cuestionamientos que ya exist\u00edan desde que M\u00e9xico fue designado coanfitri\u00f3n.<\/p>\n<p>De vuelta en la capital de Jalisco, Tapia coincide en que lo ocurrido ese domingo en la ciudad donde vive expuso la cruda realidad de la violencia que golpea a M\u00e9xico.<\/p>\n<p>\u201cYa se pas\u00f3 una barrera, y deja expuesta una realidad que muchos no quer\u00edamos ver. Esto ya es intolerable. Se invierte m\u00e1s en cosas cosm\u00e9ticas que en cosas de fondo. \u00bfC\u00f3mo es posible que tengamos gobernantes m\u00e1s preocupados por el Mundial que por sus gobernados?\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los tel\u00e9fonos comenzaron a vibrar sin descanso en Guadalajara el domingo 22 de febrero. En grupos de WhatsApp y chats familiares se mezclaban datos confirmados, rumores y miedo, acompa\u00f1ados de advertencias: \u201cNo salgan\u201d, \u201cHay bloqueos\u201d, \u201cEst\u00e1n quemando coches\u201d. Fotos de veh\u00edculos ardiendo y avisos sobre carreteras cerradas se propagaban con rapidez. Nadie sab\u00eda con certeza [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471787","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los tel\u00e9fonos comenzaron a vibrar sin descanso en Guadalajara el domingo 22 de febrero. En grupos de WhatsApp y chats familiares se mezclaban datos confirmados, rumores y miedo, acompa\u00f1ados de advertencias: \u201cNo salgan\u201d, \u201cHay bloqueos\u201d, \u201cEst\u00e1n quemando coches\u201d. Fotos de veh\u00edculos ardiendo y avisos sobre carreteras cerradas se propagaban con rapidez. Nadie sab\u00eda con certeza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-02T14:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial\",\"datePublished\":\"2026-03-02T14:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\"},\"wordCount\":1560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\",\"name\":\"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-02T14:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias","og_description":"Los tel\u00e9fonos comenzaron a vibrar sin descanso en Guadalajara el domingo 22 de febrero. En grupos de WhatsApp y chats familiares se mezclaban datos confirmados, rumores y miedo, acompa\u00f1ados de advertencias: \u201cNo salgan\u201d, \u201cHay bloqueos\u201d, \u201cEst\u00e1n quemando coches\u201d. Fotos de veh\u00edculos ardiendo y avisos sobre carreteras cerradas se propagaban con rapidez. Nadie sab\u00eda con certeza [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-02T14:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/"},"author":{"name":"","@id":""},"headline":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial","datePublished":"2026-03-02T14:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/"},"wordCount":1560,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","name":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-02T14:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Entre el miedo y la incertidumbre: as\u00ed se vive en Guadalajara tras la ca\u00edda del Mencho y a la espera del Mundial","url":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-02T14:03:55Z","datePublished":"2026-03-02T14:03:55Z","dateModified":"2026-03-02T14:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Entre el miedo y la incertidumbre: as\\u00ed se vive en Guadalajara tras la ca\\u00edda del Mencho y a la espera del Mundial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/guadalajara-miedo-incertidumbre-violencia-mencho-narcotrafico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-02T14:03:55Z\",\"datePublished\":\"2026-03-02T14:03:55Z\",\"dateModified\":\"2026-03-02T14:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471555,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/23\/que-pasa-mexico-operativo-muerte-mencho-oseguera-cjng-orix\/","url_meta":{"origin":1471787,"position":0},"title":"\u00bfQu\u00e9 est\u00e1 pasando en M\u00e9xico? As\u00ed fue el operativo en el que muri\u00f3 el Mencho y la ola de violencia que le sigui\u00f3","author":"","date":"febrero 23, 2026","format":false,"excerpt":"En 48 horas, la larga misi\u00f3n de dar con el paradero de Nemesio \u201cEl Mencho\u201d Oseguera, l\u00edder y cofundador del Cartel Jalisco Nueva Generaci\u00f3n, pas\u00f3 de una ansiada pista concreta a realizar el operativo que este domingo result\u00f3 en la muerte del temido l\u00edder narco en el oeste de M\u00e9xico.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471648,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/25\/detencion-hacha-operador-cjng-tlaxcala-mencho-orix\/","url_meta":{"origin":1471787,"position":1},"title":"M\u00e9xico captura a &#171;El Hacha&#187;, supuesto operador clave del CJNG en Tlaxcala, d\u00edas despu\u00e9s de la muerte del Mencho","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Las autoridades mexicanas detuvieron este mi\u00e9rcoles a Isaac Moreno Romero, alias \u201cEl Hacha\u201d, se\u00f1alado como l\u00edder de una c\u00e9lula del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG) con presencia en el estado de Tlaxcala, en el centro de M\u00e9xico, y vinculado con secuestros, extorsiones, homicidios y tr\u00e1fico ilegal de combustibles, confirm\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471565,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/23\/mundial-guadalajara-violencia-mencho-cjng-orix\/","url_meta":{"origin":1471787,"position":2},"title":"Faltan cuatro meses para el Mundial y Guadalajara es sede: \u00bfpuede la lucha por el futuro del CJNG acosarla con su violencia?","author":"","date":"febrero 23, 2026","format":false,"excerpt":"La muerte de Nemesio \u201cel Mencho\u201d Oseguera, l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n (CJNG), desat\u00f3 inmediatos temores de una nueva ola de violencia en M\u00e9xico, que podr\u00eda extenderse m\u00e1s all\u00e1 de los bloqueos e incendios registrados el domingo. Los antecedentes de otros episodios de luchas internas de sucesi\u00f3n y entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473543,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/04\/27\/detencion-jardinero-cjng-mencho-orix\/","url_meta":{"origin":1471787,"position":3},"title":"M\u00e9xico detiene a alias &#171;El Jardinero&#187;, posible sucesor del &#171;Mencho&#187; en el Cartel Jalisco Nueva Generaci\u00f3n","author":"","date":"abril 27, 2026","format":false,"excerpt":"Fuerzas especiales de la Secretar\u00eda de Marina de M\u00e9xico detuvieron en el estado de Nayarit a Audias Flores Silva, alias \u201cEl Jardinero\u201d, identificado como uno de los presuntos l\u00edderes del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG), dos meses despu\u00e9s de la ca\u00edda de Nemesio Rub\u00e9n Oseguera Cervantes, alias \u201cEl Mencho\u201d, considerado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473607,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/04\/28\/quien-es-jardinero-sucesor-mencho-operativo-orix\/","url_meta":{"origin":1471787,"position":4},"title":"\u00bfQui\u00e9n es el Jardinero, se\u00f1alado como posible sucesor del Mencho, y c\u00f3mo fue el operativo para detenerlo?","author":"","date":"abril 28, 2026","format":false,"excerpt":"En un operativo encabezado por la Secretar\u00eda de Marina (Semar), las fuerzas federales mexicanas detuvieron a uno de los presuntos l\u00edderes del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG) y posible sucesor de Nemesio \u201cMencho\u201d Oseguera Cervantes, l\u00edder del CJNG que muri\u00f3 tras una operaci\u00f3n federal en febrero.Se trata de Audias Flores\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473479,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/04\/24\/mundial-guadalajara-sedes-personas-inseguridad-orix\/","url_meta":{"origin":1471787,"position":5},"title":"Faltan menos de dos meses para el Mundial y en Guadalajara, una de las sedes, 9 de cada 10 personas se sienten inseguras","author":"","date":"abril 24, 2026","format":false,"excerpt":"A poco menos de dos meses de que se realice el Mundial de F\u00fatbol 2026 de la FIFA \u2014el evento deportivo m\u00e1s importante a nivel internacional y que este a\u00f1o se llevar\u00e1 a cabo en M\u00e9xico, Estados Unidos y Canad\u00e1\u2014, una de las sedes mexicanas del torneo atraviesa una situaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471787"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471787\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}