{"id":1471800,"date":"2026-03-02T17:03:41","date_gmt":"2026-03-03T01:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/"},"modified":"2026-03-02T17:03:41","modified_gmt":"2026-03-03T01:03:41","slug":"eclipse-total-lunar-marzo-luna-de-sangre-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","title":{"rendered":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?"},"content":{"rendered":"<p>El 3 de marzo de 2026, los observadores del cielo de gran parte del mundo ser\u00e1n testigos de un espectacular evento celestial: un eclipse lunar total, a menudo llamado luna de sangre. Durante este fen\u00f3meno la Luna atravesar\u00e1 completamente la sombra de la Tierra, ti\u00f1\u00e9ndose de un llamativo color rojo cobrizo durante casi una hora.<\/p>\n<p><a href=\"https:\/\/svs.gsfc.nasa.gov\/5604\">Seg\u00fan la NASA<\/a>, casi 2.500 millones de personas viven dentro de la zona de visibilidad total para este eclipse. Para quienes est\u00e9n en partes de Asia, el Pac\u00edfico, Australia o Am\u00e9rica, este evento del 3 de marzo promete un espect\u00e1culo memorable tanto para madrugadores como para trasnochadores.<\/p>\n<p>La fase total del eclipse, conocida como totalidad, durar\u00e1 aproximadamente 58 minutos, de 11:04 a 12:02 UTC (6:04 a 7:02 a.m., hora de Miami). El eclipse m\u00e1s grande, cuando la Luna se encuentra en su punto m\u00e1s profundo dentro de la sombra de la Tierra, ocurrir\u00e1 a las 11:33 UTC. El evento completo, incluyendo las fases penumbral y parcial, durar\u00e1 aproximadamente 5 horas y 39 minutos.<\/p>\n<p>Este eclipse lunar total ser\u00e1 completamente visible desde:<\/p>\n<ul>\n<li>Oeste de Norteam\u00e9rica (desde      Columbia Brit\u00e1nica hacia el sur, pasando por California y Baja California)<\/li>\n<li>Oc\u00e9ano Pac\u00edfico y sus islas      (incluyendo Hawai, Guam, Fiji y la Polinesia Francesa)<\/li>\n<li>Asia Oriental (China, Jap\u00f3n,      las Coreas, Taiw\u00e1n y Filipinas)<\/li>\n<li>Australia y Nueva Zelandia      (ambos pa\u00edses en su totalidad)<\/li>\n<li>Centroam\u00e9rica y el este de      Norteam\u00e9rica ver\u00e1n la totalidad, pero la Luna se pondr\u00e1 durante o justo      despu\u00e9s del final del eclipse.<\/li>\n<li>Asia Central y gran parte de      Sudam\u00e9rica solo presenciar\u00e1n las fases penumbrales o parciales.<\/li>\n<li>El eclipse no ser\u00e1 visible      desde Europa ni \u00c1frica.<\/li>\n<\/ul>\n<p>Un eclipse lunar total ocurre cuando el Sol, la Tierra y la Luna se alinean perfectamente, haciendo que la Luna atraviese la sombra umbral de la Tierra. Durante la totalidad, la luz solar se filtra a trav\u00e9s de la atm\u00f3sfera terrestre, dispersando la luz azul y permitiendo que solo los tonos rojos y anaranjados alcancen la superficie lunar, creando el espectacular efecto de luna de sangre.<\/p>\n<p><a href=\"https:\/\/www.timeanddate.com\/eclipse\/lunar\/2026-march-3\">Time and Date<\/a> ofrece una transmisi\u00f3n en vivo exclusiva con animaciones en tiempo real, mapas y comentarios de expertos.<\/p>\n<p>El <a href=\"https:\/\/griffithobservatory.org\/event\/total-lunar-eclipse-broadcast-march-3-2026\/\">Observatorio Griffith<\/a> tendr\u00e1 una transmisi\u00f3n en l\u00ednea en vivo desde Los \u00c1ngeles, de 00:37 a.m. a 6:25 a.,m., hora est\u00e1ndar del Pac\u00edfico, es decir de 3:37 a.m a 9:35 a.m., hora de Miami, el 3 de marzo.<\/p>\n<p>El astrof\u00edsico Gianluca Masi organizar\u00e1 una transmisi\u00f3n global con im\u00e1genes en vivo desde varios lugares internacionales a partir de las 3:30 a.m. , hora de Miami.<\/p>\n<p><a href=\"https:\/\/www.space.com\/news\/live\/total-lunar-eclipse-blood-moon-march-2026-live-updates\">Space.com<\/a> ofrece una p\u00e1gina de \u201cActualizaciones en vivo\u201d, que generalmente integra las principales fuentes astron\u00f3micas para facilitar su visualizaci\u00f3n.<\/p>\n<p><a href=\"https:\/\/svs.gsfc.nasa.gov\/5605\">NASA SVS<\/a> proporciona animaciones telesc\u00f3picas detalladas y es una fuente confiable de cobertura oficial de la agencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 3 de marzo de 2026, los observadores del cielo de gran parte del mundo ser\u00e1n testigos de un espectacular evento celestial: un eclipse lunar total, a menudo llamado luna de sangre. Durante este fen\u00f3meno la Luna atravesar\u00e1 completamente la sombra de la Tierra, ti\u00f1\u00e9ndose de un llamativo color rojo cobrizo durante casi una hora. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471800","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El 3 de marzo de 2026, los observadores del cielo de gran parte del mundo ser\u00e1n testigos de un espectacular evento celestial: un eclipse lunar total, a menudo llamado luna de sangre. Durante este fen\u00f3meno la Luna atravesar\u00e1 completamente la sombra de la Tierra, ti\u00f1\u00e9ndose de un llamativo color rojo cobrizo durante casi una hora. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T01:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?\",\"datePublished\":\"2026-03-03T01:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\",\"name\":\"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-03T01:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias","og_description":"El 3 de marzo de 2026, los observadores del cielo de gran parte del mundo ser\u00e1n testigos de un espectacular evento celestial: un eclipse lunar total, a menudo llamado luna de sangre. Durante este fen\u00f3meno la Luna atravesar\u00e1 completamente la sombra de la Tierra, ti\u00f1\u00e9ndose de un llamativo color rojo cobrizo durante casi una hora. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-03T01:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/"},"author":{"name":"","@id":""},"headline":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?","datePublished":"2026-03-03T01:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","name":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-03T01:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?","url":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/02\/eclipse-total-lunar-marzo-luna-de-sangre-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-03T01:03:41Z","datePublished":"2026-03-03T01:03:41Z","dateModified":"2026-03-03T01:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Eclipse total lunar de marzo: \\u00bfcu\\u00e1ndo y d\\u00f3nde podr\\u00e1 verse la luna de sangre?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/eclipse-total-lunar-marzo-luna-de-sangre-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/02\\\/eclipse-total-lunar-marzo-luna-de-sangre-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-03T01:03:41Z\",\"datePublished\":\"2026-03-03T01:03:41Z\",\"dateModified\":\"2026-03-03T01:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471594,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/24\/eclipse-total-luna-sangre-marzo-cuando-donde-orix\/","url_meta":{"origin":1471800,"position":0},"title":"Eclipse total lunar de marzo: \u00bfcu\u00e1ndo y d\u00f3nde podr\u00e1 verse la luna de sangre?","author":"","date":"febrero 24, 2026","format":false,"excerpt":"El 3 de marzo de 2026, los observadores del cielo de gran parte del mundo ser\u00e1n testigos de un espectacular evento celestial: un eclipse lunar total, a menudo llamado luna de sangre. Durante este fen\u00f3meno la Luna atravesar\u00e1 completamente la sombra de la Tierra, ti\u00f1\u00e9ndose de un llamativo color rojo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459864,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/13\/eclipse-lunar-total-cuando-hora-como-ver-orix\/","url_meta":{"origin":1471800,"position":1},"title":"Eclipse lunar total del 14 de marzo: cu\u00e1ndo, a qu\u00e9 hora y c\u00f3mo ver desde todo el mundo","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Desde la noche del 13 de marzo hasta temprano en la ma\u00f1ana del 14 de marzo de 2025, la Luna se te\u00f1ir\u00e1 de rojo en un espectacular eclipse lunar total que ser\u00e1 visible desde varias partes del mundo.Este fen\u00f3meno astron\u00f3mico, que se produce cuando la Tierra se interpone entre el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459918,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/14\/marzo-2025-luna-de-sangre-trax\/","url_meta":{"origin":1471800,"position":2},"title":"FOTOS | La &#171;luna de sangre&#187; de marzo ilumina el cielo","author":"","date":"marzo 14, 2025","format":false,"excerpt":"La Luna brill\u00f3 con un espectacular color rojo entre el jueves por la noche y el viernes por la ma\u00f1ana, al pasar a la sombra de la Tierra durante un eclipse lunar total.Un eclipse lunar se produce cuando la Tierra se encuentra entre el Sol y la Luna, y los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447322,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/25\/como-ver-eclipse-lunar-luna-gusano-trax\/","url_meta":{"origin":1471800,"position":3},"title":"As\u00ed puedes ver el pr\u00f3ximo eclipse lunar de la luna de gusano","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) -- Una brillante luna de gusano iluminar\u00e1 el cielo este lunes con una actuaci\u00f3n celestial reservada para quienes se aventuren en las primeras horas de la ma\u00f1ana: un eclipse lunar penumbral.La luna llena de marzo, conocida como la luna de gusano por el Almanaque de los Agricultores debido a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459877,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/13\/eclipse-lunar-que-es-datos-orix\/","url_meta":{"origin":1471800,"position":4},"title":"Qu\u00e9 es un eclipse lunar, qu\u00e9 tipos hay, cu\u00e1ndo son los pr\u00f3ximos eclipses y otros datos que debes saber","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Este 14 de marzo hay un eclipse lunar, que tendr\u00e1 visibilidad en las Am\u00e9ricas, Europa y parte de Asia. \u00bfQu\u00e9 es este fen\u00f3meno, qu\u00e9 lo causa y con qu\u00e9 frecuencia? Aqu\u00ed las respuestas a esas y otras preguntas.Primero lo primero.La Luna orbita la Tierra una vez cada 29 d\u00edas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466207,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/06\/luna-llena-maiz-punto-maximo-eclipse-lunar-total-trax\/","url_meta":{"origin":1471800,"position":5},"title":"La luna llena de ma\u00edz alcanzar\u00e1 su punto m\u00e1ximo este fin de semana, acompa\u00f1ada de un eclipse lunar total. Esto vendr\u00e1","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Muchos observadores del cielo alrededor del mundo tendr\u00e1n la oportunidad de ver un deslumbrante espect\u00e1culo celeste este fin de semana: un eclipse lunar total que podr\u00eda hacer que la luna adquiera un tono rojizo intenso.El eclipse lunar ser\u00e1 visible el domingo para quienes se encuentren en Europa, \u00c1frica, Asia y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471800"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471800\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}