{"id":1471816,"date":"2026-03-03T08:03:38","date_gmt":"2026-03-03T16:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/"},"modified":"2026-03-03T08:03:38","modified_gmt":"2026-03-03T16:03:38","slug":"mamdani-trump-inmigracion-activistas-propalestinos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","title":{"rendered":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos"},"content":{"rendered":"<p>Durante una reuni\u00f3n no anunciada con <a href=\"https:\/\/www.cnn.com\/2026\/02\/26\/politics\/trump-mamdani-meet-washington-white-house\">el presidente Donald Trump<\/a> la semana pasada, el alcalde de la ciudad de Nueva York, Zohran Mamdani, mencion\u00f3 a cuatro manifestantes propalestinos perseguidos por las autoridades federales de inmigraci\u00f3n: <a href=\"https:\/\/www.cnn.com\/2025\/03\/11\/us\/mahmoud-khalil-columbia-ice-green-card-hnk\">Mahmoud Khalil<\/a>, <a href=\"https:\/\/www.cnn.com\/2025\/03\/31\/us\/what-we-know-college-activists-immigration-hnk\">Yunseo Chung<\/a>, <a href=\"https:\/\/www.cnn.com\/2025\/04\/30\/us\/vermont-judge-orders-release-of-mohsen-mahdawi\">Mohsen Mahdawi<\/a> y <a href=\"https:\/\/www.cnn.com\/2025\/05\/07\/us\/palestinian-woman-arrest-ice-nypd\">Leqaa Kordia<\/a>.<\/p>\n<p>\u201cPed\u00ed que se desestimaran estos casos\u201d, dijo Mamdani el viernes durante la ceremonia de inauguraci\u00f3n en el Centro del Patrimonio de Weeksville. \u201cY el presidente dijo que lo investigar\u00eda\u201d.<\/p>\n<p>El alcalde dijo que tambi\u00e9n habl\u00f3 sobre <a href=\"https:\/\/www.cnn.com\/2026\/02\/27\/us\/ellie-aghayeva-columbia-student-ice-detention-wwk-hnk\">Ellie Aghayeva<\/a>, estudiante de pregrado en Columbia que fue detenida por agentes federales, durante su reuni\u00f3n con el presidente el jueves. Se\u00f1al\u00f3 que Trump le inform\u00f3 que ser\u00eda liberada y que Aghayeva qued\u00f3 en libertad m\u00e1s tarde ese mismo d\u00eda.<\/p>\n<p>Los otros cuatro forman parte de un grupo de no ciudadanos propalestinos que fueron blanco de las autoridades federales de inmigraci\u00f3n el a\u00f1o pasado, despu\u00e9s de que protestas contra la operaci\u00f3n militar de Israel, que <a href=\"https:\/\/www.cnn.com\/2025\/10\/19\/middleeast\/gaza-ceasefire-palestnians-ruins-reconstruction-latam-intl\">devast\u00f3 gran parte de Gaza<\/a> se extendieran por Estados Unidos. Trump hab\u00eda prometido tomar medidas contra los no ciudadanos que protestaran contra Israel, a quienes describi\u00f3 como \u201csimpatizantes de Hamas\u201d. La ola de arrestos provoc\u00f3 indignaci\u00f3n y preocupaci\u00f3n entre defensores de derechos civiles, quienes argumentan que los detenidos fueron blanco de medidas por expresiones protegidas por la Constituci\u00f3n.<\/p>\n<p>Solo una de las cuatro \u2014Leqaa Kordia, una mujer palestina de 33 a\u00f1os que hab\u00eda vivido en Paterson, Nueva Jersey, durante casi una d\u00e9cada\u2014 permanece bajo custodia, seg\u00fan sus abogados. Los otros tres enfrentan sus casos de inmigraci\u00f3n desde sus hogares.<\/p>\n<p>El gobierno \u201cse centr\u00f3 en personas que se hab\u00edan expresado de diversas maneras y en diversos grados a favor de los derechos humanos palestinos\u201d, declar\u00f3 a CNN Brett Max Kaufman, abogado principal de la ACLU que representa a Khalil y Mahdawi. \u201cTom\u00f3 estas medidas contra ellos, para detenerlos y expulsarlos del pa\u00eds, como represalia por ese discurso\u201d.<\/p>\n<p>Un funcionario de la Casa Blanca afirm\u00f3 que no hab\u00eda novedades que ofrecer. CNN se puso en contacto con el Departamento de Seguridad Nacional para obtener comentarios sobre cada uno de los casos.<\/p>\n<p>Los continuos procedimientos de inmigraci\u00f3n contra los cuatro manifestantes ocurren despu\u00e9s de que <a href=\"https:\/\/www.cnn.com\/2025\/09\/30\/politics\/first-amendment-judge-young-donald-trump-deportation-pro-palestinian-protesters\">un juez federal<\/a> criticara a Trump y su administraci\u00f3n por atacar la libertad de expresi\u00f3n \u201cbajo el manto de una definici\u00f3n inconstitucionalmente amplia de antisemitismo\u201d utilizada en los esfuerzos para deportar a estudiantes propalestinos.<\/p>\n<p>Esto es lo que sabemos sobre los cuatro y la situaci\u00f3n de sus casos:<\/p>\n<p>Mahmoud Khalil, un joven de 31 a\u00f1os con tarjeta de residencia permanente que cursaba una maestr\u00eda en la Universidad de Columbia, fue el primer manifestante estudiantil pro-palestino arrestado por las autoridades federales de inmigraci\u00f3n. Khalil, ciudadano argelino nacido en un campo de refugiados palestinos en Siria, hab\u00eda actuado como portavoz del <a href=\"https:\/\/www.cnn.com\/2024\/04\/19\/us\/palestinian-protest-columbia-what-we-know\/index.html\">campamento pro-palestino de Columbia.<\/a> Imitando a los manifestantes contra la guerra de Vietnam, los estudiantes instalaron el <a href=\"https:\/\/www.cnn.com\/2024\/04\/27\/business\/columbia-history-divestment-student-protests\/\">campamento<\/a> para exigir a Columbia que desinvirtiera en sus v\u00ednculos acad\u00e9micos con Israel y en sus inversiones en fabricantes de armas y empresas tecnol\u00f3gicas que hacen negocios con el gobierno israel\u00ed.<\/p>\n<p>En <a href=\"https:\/\/www.cnn.com\/2025\/03\/14\/us\/video\/mahmoud-khalil-arrest-video-digvid\">un video capturado<\/a> por su esposa, que ten\u00eda ocho meses de embarazo en ese momento, Khalil fue detenido por agentes federales vestidos de civil en su apartamento, propiedad de la universidad, el 8 de marzo de 2025.<\/p>\n<p>Los agentes <a href=\"https:\/\/www.cnn.com\/2025\/04\/24\/us\/mahmoud-khalil-arrest-news-update\">no ten\u00edan orden judicial,<\/a> pero afirmaron que actuaban bajo \u00f3rdenes del Departamento de Estado. Primero le informaron a Khalil que le <a href=\"https:\/\/www.cnn.com\/2025\/03\/10\/us\/mahmoud-khalil-columbia-university-israel-hnk\/index.html\">revocar\u00edan la visa de estudiante<\/a> . Cuando su esposa mostr\u00f3 a los agentes su tarjeta de residencia, le dijeron: \u201cEl Departamento de Estado tambi\u00e9n la hab\u00eda revocado\u201d. Fue trasladado r\u00e1pidamente a cientos de kil\u00f3metros de distancia, a Luisiana, donde permaneci\u00f3 detenido en el Centro de Procesamiento de ICE de Luisiana Central.<\/p>\n<p>Para justificar la orden de deportaci\u00f3n de Khalil, el Departamento de Estado cit\u00f3 una disposici\u00f3n poco utilizada de la <a href=\"https:\/\/www.cnn.com\/2025\/04\/10\/us\/mahmoud-khalil-evidence-deadline\/index.html\">Ley de Inmigraci\u00f3n y Nacionalidad<\/a> que permite la expulsi\u00f3n de no ciudadanos bas\u00e1ndose en creencias \u201cpor lo dem\u00e1s legales\u201d si el Secretario de Estado determina que su presencia o actividades representan una amenaza a los intereses de la pol\u00edtica exterior estadounidense.<\/p>\n<p>En el tribunal de inmigraci\u00f3n, el gobierno federal present\u00f3 un breve memorando firmado por el secretario de Estado, Marco Rubio, que dec\u00eda que permitir que Khalil permanezca en el pa\u00eds socavar\u00eda \u201cla pol\u00edtica estadounidense para combatir el antisemitismo en todo el mundo y en los Estados Unidos, adem\u00e1s de los esfuerzos para proteger a los estudiantes jud\u00edos del acoso y la violencia en los Estados Unidos\u201d.<\/p>\n<p>Khalil pas\u00f3 m\u00e1s de tres meses en detenci\u00f3n migratoria, perdi\u00e9ndose el nacimiento de su hijo. En mayo, un juez federal dictamin\u00f3 que la base de pol\u00edtica exterior para su detenci\u00f3n <a href=\"https:\/\/www.nyclu.org\/press-release\/court-finds-trump-admins-use-of-obscure-immigration-law-provision-to-detain-mahmoud-khalil-likely-unconstitutional\">era probablemente inconstitucional<\/a>. Fue <a href=\"https:\/\/www.cnn.com\/2025\/06\/20\/us\/mahmoud-khalil-ordered-released-by-judge\">liberado en junio de 2025<\/a> despu\u00e9s de que el mismo juez determinara que no representaba un riesgo de fuga ni un peligro para la seguridad p\u00fablica y citara \u201ccircunstancias extraordinarias\u201d en el caso, incluyendo un <a href=\"https:\/\/www.cnn.com\/2025\/06\/20\/us\/mahmoud-khalil-ordered-released-by-judge\">intento de castigarlo que violaba el debido proceso<\/a>.<\/p>\n<p>Pero a\u00fan podr\u00eda enfrentar la deportaci\u00f3n: en enero, un panel de apelaciones federal <a href=\"https:\/\/www.cnn.com\/2026\/01\/15\/us\/mahmoud-khalil-appeals-court-reversal\">revoc\u00f3 una decisi\u00f3n de un tribunal inferior<\/a> que lo hab\u00eda liberado de la detenci\u00f3n, determinando que el tribunal federal no tiene jurisdicci\u00f3n hasta que su caso de inmigraci\u00f3n llegue a su fin.<\/p>\n<p>Esa decisi\u00f3n no entrar\u00e1 en vigor \u201chasta que agotemos nuestras apelaciones en el Tercer Circuito\u201d, declar\u00f3 a CNN Kaufman, el abogado de la ACLU que representa a Khalil y Mahdawi. Kaufman a\u00f1adi\u00f3 que los abogados de Khalil planean presentar una solicitud de revisi\u00f3n ante el pleno del tribunal de apelaciones para finales de marzo.<\/p>\n<p>Khalil mantuvo que fue atacado por su libertad de expresi\u00f3n protegida por la Constituci\u00f3n.<\/p>\n<p>\u201cMi arresto fue una consecuencia directa de ejercer mi derecho a la libertad de expresi\u00f3n mientras defend\u00eda una Palestina libre y el fin del genocidio en Gaza\u201d, escribi\u00f3 en <a href=\"https:\/\/www.aclu.org\/news\/free-speech\/a-letter-from-palestinian-activist-mahmoud-khalil\">una carta de 2025 desde la detenci\u00f3n.<\/a><\/p>\n<p>En marzo de 2025, los funcionarios de inmigraci\u00f3n decidieron deportar a <a href=\"https:\/\/www.cnn.com\/2025\/03\/24\/us\/yunseo-chung-columbia-lawsuit-trump-ice\/index.html\">Yunseo Chung<\/a>, una estudiante de Columbia de 21 a\u00f1os procedente de Corea del Sur con estatus de residente permanente, despu\u00e9s de que ella y otros estudiantes fueran arrestados por la polic\u00eda local en una sentada en la universidad.<\/p>\n<p>Agentes federales de inmigraci\u00f3n fueron a buscarla a casa de sus padres y registraron su residencia universitaria en Columbia, seg\u00fan una demanda presentada ante un tribunal federal. Un funcionario federal de las fuerzas del orden inform\u00f3 a los abogados de Chung que se le revocar\u00eda la residencia permanente legal.<\/p>\n<p>En la demanda, los abogados de Chung describieron su intento de deportaci\u00f3n como \u201cun ataque sin precedentes e injustificable a la Primera Enmienda y otros derechos, que no soporta un escrutinio legal b\u00e1sico\u201d.<\/p>\n<p>Un juez impidi\u00f3 que los funcionarios de inmigraci\u00f3n detuvieran a Chung en <a href=\"https:\/\/www.cnn.com\/2025\/03\/24\/us\/yunseo-chung-columbia-lawsuit-trump-ice\/index.html\">una orden emitida en marzo,<\/a> argumentando que \u201cno hab\u00eda indicios de que ella fuera una amenaza extranjera\u201d.<\/p>\n<p>\u201cDespu\u00e9s del miedo constante que sent\u00ed en mi mente durante las \u00faltimas semanas, esta decisi\u00f3n me ha quitado un mill\u00f3n de libras de encima\u201d, <a href=\"https:\/\/www.cunyclear.org\/yunseo-chung\">escribi\u00f3 Chung en una declaraci\u00f3n<\/a> despu\u00e9s de la orden.<\/p>\n<p>El Departamento de Justicia dijo en una declaraci\u00f3n en ese momento que \u201cno se disculpa por sus esfuerzos para defender la agenda del presidente Trump en los tribunales y proteger a los jud\u00edos estadounidenses del vil antisemitismo\u201d.<\/p>\n<p>Mohsen Mahdawi, un estudiante palestino de 35 a\u00f1os con tarjeta verde que estudia en Columbia, fue <a href=\"https:\/\/www.cnn.com\/2025\/04\/14\/us\/mohsen-mahdawi-columbia-university-trump\">detenido en Vermont<\/a> despu\u00e9s de llegar a una cita de naturalizaci\u00f3n el 14 de abril del a\u00f1o pasado.<\/p>\n<p>Mahdawi naci\u00f3 y creci\u00f3 en la Ribera Occidental ocupada por Israel y lleg\u00f3 a Estados Unidos en 2014. Al igual que Khalil, hab\u00eda participado en activismo propalestino en el campus de Columbia, aunque se retir\u00f3 <a href=\"https:\/\/www.cnn.com\/2025\/04\/14\/us\/mohsen-mahdawi-columbia-university-trump\">de la organizaci\u00f3n<\/a> en marzo de 2024. Habl\u00f3 p\u00fablicamente sobre haber presenciado la muerte de amigos y seres queridos a manos del Ej\u00e9rcito israel\u00ed y dijo que un soldado israel\u00ed le dispar\u00f3 en la pierna cuando ten\u00eda 15 a\u00f1os, <a href=\"https:\/\/www.columbiaspectator.com\/news\/2025\/04\/17\/thoughtful-compassionate-intelligent-friends-of-mohsen-mahdawi-gs-25-speak-against-characterizations-of-him-by-the-federal-government\/\">seg\u00fan Columbia Spectator<\/a>.<\/p>\n<p>Durante la cita del 14 de abril, el estudiante <a href=\"https:\/\/www.cnn.com\/2025\/04\/30\/us\/vermont-judge-orders-release-of-mohsen-mahdawi\">aprob\u00f3 su examen de naturalizaci\u00f3n<\/a> y prest\u00f3 juramento para convertirse en ciudadano estadounidense, pero fue detenido por agentes de Investigaciones de Seguridad Nacional en el lugar, seg\u00fan sus abogados. Qued\u00f3 en libertad bajo fianza en mayo.<\/p>\n<p>Tras la liberaci\u00f3n de Mahdawi, el gobierno continu\u00f3 sus esfuerzos para deportarlo, utilizando la misma l\u00f3gica de pol\u00edtica exterior que en el caso de Khalil, <a href=\"https:\/\/apnews.com\/article\/mohsen-mahdawi-trump-columbia-deportation-8d0746636b3f4baed4704283e0cadae3\">seg\u00fan inform\u00f3 AP<\/a>. Mahdawi tambi\u00e9n tiene un caso en curso en <a href=\"https:\/\/www.documentcloud.org\/documents\/25896887-mahdawi-habeas-as-filed\/\">un tribunal federal de distrito,<\/a> alegando su detenci\u00f3n ilegal. Comenz\u00f3 una maestr\u00eda en la Escuela de Asuntos Internacionales y P\u00fablicos de Columbia el oto\u00f1o pasado, <a href=\"https:\/\/www.acluvt.org\/cases\/mahdawi\/\">seg\u00fan la ACLU<\/a>.<\/p>\n<p>A principios de este mes, un juez <a href=\"https:\/\/apnews.com\/article\/mohsen-mahdawi-trump-columbia-deportation-8d0746636b3f4baed4704283e0cadae3\">impidi\u00f3 que la administraci\u00f3n Trump<\/a> deportara a Mahdawi, citando un error de procedimiento por parte de los abogados del gobierno, inform\u00f3 AP.<\/p>\n<p>Pero el gobierno a\u00fan puede apelar esa decisi\u00f3n. Tricia McLaughlin, portavoz del Departamento de Seguridad Nacional, describi\u00f3 a Mahdawi como un l\u00edder de \u201cdisturbios proterroristas\u201d cuya visa deber\u00eda ser revocada.<\/p>\n<p>\u201cNing\u00fan juez activista, ni \u00e9ste ni ning\u00fan otro, nos va a impedir hacer eso\u201d, dijo en un comunicado, seg\u00fan AP.<\/p>\n<p>Kordia es la \u00fanica manifestante entre los cuatro mencionados por Mamdani que se encuentra detenida.<\/p>\n<p>Fue detenida menos de una semana despu\u00e9s de Khalil y trasladada en avi\u00f3n a un centro de detenci\u00f3n en Texas, seg\u00fan consta en documentos judiciales, donde lleva recluida casi un a\u00f1o. Sus abogados, en documentos judiciales, afirmaron que ha enfrentado graves problemas de salud durante su detenci\u00f3n, incluyendo <a href=\"https:\/\/muslimadvocates.org\/2026\/02\/leqaa-kordisa-condemns-horrific-hospitalization-detention\/\">una convulsi\u00f3n<\/a> en febrero, y que se le ha negado el derecho a seguir principios fundamentales de su fe, como comer halal y rezar cinco veces al d\u00eda.<\/p>\n<p>Sus abogados dicen que Kordia, quien creci\u00f3 en la Ribera Occidental ocupada, fue atacada debido a una protesta propalestina a la que asisti\u00f3 afuera de las puertas del campus de Columbia en abril de 2024. Fue arrestada por la polic\u00eda de Nueva York, pero r\u00e1pidamente liberada y los cargos en su contra fueron desestimados, seg\u00fan documentos judiciales.<\/p>\n<p>Kordia lleg\u00f3 a Estados Unidos primero con una visa de turista y luego cambi\u00f3 a una visa de estudiante. Estudiaba ingl\u00e9s mientras trabajaba como camarera y en una tienda de ropa, y ayudaba a cuidar a su madre y hermano, ciudadanos estadounidenses, seg\u00fan sus abogados. En 2022, tras la aprobaci\u00f3n de su solicitud de visa familiar para obtener la residencia permanente legal, se retir\u00f3 del programa de visas de estudiante, sin saber que ten\u00eda que esperar hasta que una visa estuviera disponible, seg\u00fan sus abogados.<\/p>\n<p>El Departamento de Seguridad Nacional (DHS) inform\u00f3 a CNN que Kordia fue arrestada por violaciones migratorias relacionadas con quedarse en el pa\u00eds m\u00e1s tiempo del permitido por su visa de estudiante vencida. Tambi\u00e9n mencionaron su participaci\u00f3n en protestas a favor de Hamas en la Universidad de Columbia y afirmaron que se la encontr\u00f3 brindando apoyo financiero a personas que viven en pa\u00edses hostiles a Estados Unidos.<\/p>\n<p>Sus abogados dicen que el \u201capoyo financiero\u201d se refiere a los pagos que Kordia hizo a miembros de su familia en la Ribera Occidental y Gaza para ayudarlos a pagar sus cuentas y reconstruir sus hogares y negocios despu\u00e9s de los ataques a\u00e9reos israel\u00edes.<\/p>\n<p>Un juez de inmigraci\u00f3n ha ordenado dos veces la libertad bajo fianza de Kordia. Sin embargo, en ambos casos, el DHS orden\u00f3 una suspensi\u00f3n autom\u00e1tica, manteni\u00e9ndola detenida. Actualmente se encuentra en medio de procesos legales en curso, tanto en el tribunal de inmigraci\u00f3n como en el tribunal federal, donde sus abogados argumentan que fue objeto de un ataque inconstitucional debido a su libertad de expresi\u00f3n y que sus derechos religiosos est\u00e1n siendo violados durante su detenci\u00f3n.<\/p>\n<p>El primo de Kordia, Hamzah Abushaban, acogi\u00f3 con satisfacci\u00f3n el apoyo de Mamdani.<\/p>\n<p>\u201cEl alcalde Mamdani tiene toda la raz\u00f3n al pedir al presidente Trump que libere a Leqaa Kordia, la querida hija de un ciudadano estadounidense\u201d, dijo en un comunicado.<\/p>\n<p>\u201cDurante casi un a\u00f1o, mi prima Leqaa ha estado encerrada en el centro de detenci\u00f3n de ICE, privada de preciosos cumplea\u00f1os, d\u00edas festivos y momentos irremplazables con su familia\u201d, continu\u00f3.<\/p>\n<p>Leqaa es una joven que pertenece a su hogar, segura, libre y rodeada de quienes la quieren. Se acab\u00f3 el tiempo de las demoras. Instamos al presidente Trump a que libere a Leqaa de inmediato y le permita recuperar su libertad, su dignidad y su vida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante una reuni\u00f3n no anunciada con el presidente Donald Trump la semana pasada, el alcalde de la ciudad de Nueva York, Zohran Mamdani, mencion\u00f3 a cuatro manifestantes propalestinos perseguidos por las autoridades federales de inmigraci\u00f3n: Mahmoud Khalil, Yunseo Chung, Mohsen Mahdawi y Leqaa Kordia. \u201cPed\u00ed que se desestimaran estos casos\u201d, dijo Mamdani el viernes durante [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471816","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Durante una reuni\u00f3n no anunciada con el presidente Donald Trump la semana pasada, el alcalde de la ciudad de Nueva York, Zohran Mamdani, mencion\u00f3 a cuatro manifestantes propalestinos perseguidos por las autoridades federales de inmigraci\u00f3n: Mahmoud Khalil, Yunseo Chung, Mohsen Mahdawi y Leqaa Kordia. \u201cPed\u00ed que se desestimaran estos casos\u201d, dijo Mamdani el viernes durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T16:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos\",\"datePublished\":\"2026-03-03T16:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\"},\"wordCount\":2218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\",\"name\":\"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-03T16:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias","og_description":"Durante una reuni\u00f3n no anunciada con el presidente Donald Trump la semana pasada, el alcalde de la ciudad de Nueva York, Zohran Mamdani, mencion\u00f3 a cuatro manifestantes propalestinos perseguidos por las autoridades federales de inmigraci\u00f3n: Mahmoud Khalil, Yunseo Chung, Mohsen Mahdawi y Leqaa Kordia. \u201cPed\u00ed que se desestimaran estos casos\u201d, dijo Mamdani el viernes durante [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-03T16:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/"},"author":{"name":"","@id":""},"headline":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos","datePublished":"2026-03-03T16:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/"},"wordCount":2218,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","name":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-03T16:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos","url":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-03T16:03:38Z","datePublished":"2026-03-03T16:03:38Z","dateModified":"2026-03-03T16:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mamdani asegura que le pidi\\u00f3 a Trump retirar los cargos de inmigraci\\u00f3n contra activistas propalestinos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/03\\\/mamdani-trump-inmigracion-activistas-propalestinos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/03\\\/mamdani-trump-inmigracion-activistas-propalestinos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-03T16:03:38Z\",\"datePublished\":\"2026-03-03T16:03:38Z\",\"dateModified\":\"2026-03-03T16:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468587,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/11\/21\/trump-reunion-mamdani-trax\/","url_meta":{"origin":1471816,"position":0},"title":"El alcalde electo de Nueva York, Zohran Mamdani, se re\u00fane con el presidente Donald Trump en la Casa Blanca","author":"","date":"noviembre 21, 2025","format":false,"excerpt":"El presidente Donald Trump se reuni\u00f3 con el alcalde electo de la ciudad de Nueva York, Zoran Mamdani, en la Casa Blanca.De pie en la Oficina Oval junto a Trump, el alcalde electo de la ciudad de Nueva York, Zohran Mamdani, dijo que tuvieron \u201cuna reuni\u00f3n productiva\u201d centrada en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468657,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/11\/24\/reunion-trump-mamdani-detalles-trax\/","url_meta":{"origin":1471816,"position":1},"title":"Dentro de la sala: lo que ocurri\u00f3 en la reuni\u00f3n entre Trump y Mamdani","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"Hablaron de bienes ra\u00edces, debatieron sobre un complejo c\u00f3digo de zonificaci\u00f3n y analizaron c\u00f3mo lograr que una gran empresa de servicios p\u00fablicos reduzca las tarifas de electricidad.Luego conversaron sobre lo que implica construir vivienda en la ciudad m\u00e1s grande de Estados Unidos y sobre c\u00f3mo la salud de los cinco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473304,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/04\/18\/mamdani-obama-reunion-nueva-york-trax\/","url_meta":{"origin":1471816,"position":2},"title":"Mamdani y Obama se reunir\u00e1n cara a cara en la ciudad de Nueva York","author":"","date":"abril 18, 2026","format":false,"excerpt":"El alcalde de la ciudad de Nueva York, Zohran Mamdani, se reunir\u00e1 con el expresidente Barack Obama este s\u00e1bado en un evento de cuidado infantil en la ciudad de Nueva York, dijo a CNN una fuente familiarizada con el asunto.Mamdani saludar\u00e1 a ni\u00f1os y padres en un centro de educaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464126,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/01\/trump-arrestaria-zohran-mamdani-si-desafia-ice-nueva-york-trax\/","url_meta":{"origin":1471816,"position":3},"title":"Donald Trump dice que &#171;tendr\u00eda que arrestar&#187; a Zohran Mamdani si desaf\u00eda a los agentes de inmigraci\u00f3n en Nueva York","author":"","date":"julio 1, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump dijo que \u201ctendr\u00e1 que arrestar\u201d Zohran Mamdani \u2014quien se alz\u00f3 con la victoria en las primarias dem\u00f3cratas para la alcald\u00eda de Nueva York este martes\u2014 si desaf\u00eda al Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE) en la ciudad de Nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468525,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/11\/19\/trump-reunion-alcalde-nueva-york-zohran-mamdani-trax\/","url_meta":{"origin":1471816,"position":4},"title":"Trump dice que se reunir\u00e1 con el alcalde electo de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 este mi\u00e9rcoles que planea recibir al alcalde electo de la ciudad de Nueva York, Zohran Mamdani, el viernes en la Oficina Oval, en la primera reuni\u00f3n cara a cara entre ambos desde que el joven pol\u00edtico gan\u00f3 los comicios a principios de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468617,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/11\/22\/neoyorquinos-elogian-zohran-mamdani-trump-optimistas-trax\/","url_meta":{"origin":1471816,"position":5},"title":"Los neoyorquinos elogian la estrategia de Zohran Mamdani con Trump y dicen que se mantienen cautelosamente optimistas","author":"","date":"noviembre 22, 2025","format":false,"excerpt":"Los neoyorquinos saben que no deben ser demasiado optimistas.Un d\u00eda despu\u00e9s de que Zohran Mamdani recibiera una c\u00e1lida y sorprendente recepci\u00f3n en la Casa Blanca por parte del presidente Donald Trump, quien en los \u00faltimos meses ha criticado al alcalde electo de la ciudad de Nueva York llam\u00e1ndolo \u201clun\u00e1tico\u201d y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471816"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471816\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}