{"id":1471817,"date":"2026-03-03T08:03:38","date_gmt":"2026-03-03T16:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/"},"modified":"2026-03-03T08:03:38","modified_gmt":"2026-03-03T16:03:38","slug":"quimicos-secretos-alimentos-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","title":{"rendered":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU."},"content":{"rendered":"<p>Una nueva investigaci\u00f3n revel\u00f3 que al menos 111 sustancias cuyo estatus de seguridad se desconoce han sido a\u00f1adidas a alimentos, bebidas y suplementos vendidos en Estados Unidos sin alertar a la Administraci\u00f3n de Alimentos y Medicamentos (FDA).<\/p>\n<p>\u201cLas empresas alimentarias est\u00e1n decidiendo por s\u00ed mismas a\u00f1adir en secreto ingredientes qu\u00edmicos no revisados \u200b\u200ba sus productos, en lugar de seguir las directrices federales vigentes para garantizar que los alimentos sean \u2018generalmente reconocidos como seguros\u2019 (GRAS, por sus siglas en ingl\u00e9s)\u201d, declar\u00f3 Melanie Benesh, vicepresidenta de asuntos gubernamentales del Grupo de Trabajo Ambiental, una organizaci\u00f3n de defensa de la salud y el medio ambiente que realiz\u00f3 la investigaci\u00f3n publicada el martes.<\/p>\n<p>Para cumplir con el est\u00e1ndar GRAS, las empresas deben demostrar la seguridad de cualquier nuevo ingrediente alimentario proporcionando evidencia cient\u00edfica ampliamente aceptada y p\u00fablica. Notificar a la FDA sobre estos datos de seguridad es habitual y garantiza el cumplimiento normativo. Adem\u00e1s es voluntario, lo que significa que los fabricantes pueden autodeterminar legalmente la seguridad de sus productos.<\/p>\n<p>\u201cLos fabricantes ahora explotan rutinariamente esta laguna legal de GRAS; cada vez se considera m\u00e1s \u2018generalmente reconocido como secreto\u2019 en lugar de \u2018generalmente reconocido como seguro\u2019\u201d, afirm\u00f3 Benesh.<\/p>\n<p>La investigaci\u00f3n del EWG encontr\u00f3 49 de las sustancias qu\u00edmicas a\u00f1adidas por la industria en aproximadamente 4.000 productos incluidos en la base de datos FoodData Central del Departamento de Agricultura de EE.UU., que proporciona acceso p\u00fablico a informaci\u00f3n sobre nutrientes e ingredientes.<\/p>\n<p>\u201cDado que el gobierno nunca ha revisado estas sustancias qu\u00edmicas, los consumidores no tienen forma de saber si son seguras o conllevan riesgos desconocidos para la salud\u201d, declar\u00f3 Benesh.<\/p>\n<p>Aunque la laguna legal GRAS es legal en Estados Unidos, es dif\u00edcil justificarla desde un punto de vista cient\u00edfico y \u00e9tico, afirm\u00f3 Mathilde Touvier, directora de investigaci\u00f3n del Instituto Nacional de Salud e Investigaci\u00f3n M\u00e9dica de Francia en Par\u00eds, quien estudia los efectos nocivos para la salud de los aditivos en los alimentos ultraprocesados.<\/p>\n<p>\u201cEs muy problem\u00e1tico que se permita a las empresas autodeterminar que sus propios ingredientes son \u2018GRAS\u2019 dado el evidente conflicto de intereses financieros\u201d, declar\u00f3 Touvier, quien no particip\u00f3 en la investigaci\u00f3n del EWG. \u201cLas decisiones sobre la seguridad de las sustancias qu\u00edmicas alimentarias deber\u00edan basarse en una evaluaci\u00f3n independiente de las autoridades de salud p\u00fablica\u201d.<\/p>\n<p>CNN contact\u00f3 a la Asociaci\u00f3n Estadounidense de Bebidas (ABA, por sus siglas en ingl\u00e9s) y a la Asociaci\u00f3n de Marcas de Consumo (CBA, por sus siglas en ingl\u00e9s), que representan a los fabricantes de alimentos y bebidas. La ABA no envi\u00f3 una respuesta antes de la publicaci\u00f3n.<\/p>\n<p>Sarah Gallo, vicepresidenta s\u00e9nior de la CBA, afirm\u00f3 que la organizaci\u00f3n formaba parte de una coalici\u00f3n, Americans for Ingredient Transparency, que aboga por una legislaci\u00f3n federal que establezca uniformidad nacional para la seguridad y divulgaci\u00f3n de los ingredientes.<\/p>\n<p>\u201cApoyamos que la reforma de GRAS forme parte de ese proyecto de ley\u201d, declar\u00f3 Gallo, y a\u00f1adi\u00f3 que Estados Unidos cuenta con uno de los sistemas alimentarios m\u00e1s seguros y regulados del mundo.<\/p>\n<p>De las 49 sustancias qu\u00edmicas encontradas en los alimentos, 22 eran extractos, seg\u00fan la investigaci\u00f3n. Muchas parecen naturales e inofensivos: aloe vera, canela, cacao, aceite de semilla de ar\u00e1ndano, piel de uva, granos de caf\u00e9 verde, c\u00e1\u00f1amo, melisa y hongos, por nombrar solo algunos.<\/p>\n<p>\u201cAl tomar sustancias de la piel de uva, aloe vera y hongos, por ejemplo, se puede obtener un extracto concentrado o una mezcla de sustancias derivadas de ellas\u201d, afirm\u00f3 la bioqu\u00edmica Maricel Maffini, exprofesora adjunta de investigaci\u00f3n de la Facultad de Medicina de la Universidad de Tufts en Boston, coautora de la investigaci\u00f3n del EWG.<\/p>\n<p>\u201cDeber\u00eda ser posible analizar ese extracto o mezcla si se va a comercializar\u201d.<\/p>\n<p>Seg\u00fan el informe del EWG, se encontraron extractos de t\u00e9 verde nunca revisados \u200b\u200bpor la FDA en 901 productos de la base de datos, incluyendo granola y barritas energ\u00e9ticas, caramelos y chicles, helados, refrescos, t\u00e9s, aguas y mariscos.<\/p>\n<p>\u201cExiste una gran diferencia entre los antioxidantes del t\u00e9 verde que se preparan en casa y un extracto purificado de un antioxidante de t\u00e9 verde elaborado en un laboratorio\u201d, afirm\u00f3 Maffini, consultora independiente que ha publicado 11 art\u00edculos en revistas cient\u00edficas revisadas por pares y dos cap\u00edtulos de libros sobre el impacto de las sustancias qu\u00edmicas en el cuerpo humano.<\/p>\n<p>\u201cEso ya no es t\u00e9 verde. Es una sustancia completamente diferente, nueva, extra\u00edda sint\u00e9ticamente para aumentar su disponibilidad como antioxidante\u201d, explic\u00f3 Maffini. \u201cPuede parecer natural, pero no lo es, y el efecto que este nuevo extracto tendr\u00e1 en el cuerpo ser\u00e1 muy diferente\u201d.<\/p>\n<p>Por ejemplo, el t\u00e9 verde de hojas sueltas puede combatir la inflamaci\u00f3n cancer\u00edgena, reducir la presi\u00f3n arterial y el colesterol, mejorar la salud cerebral y prolongar la vida. Sin embargo, los extractos de t\u00e9 verde altamente concentrados han sido vinculados con la alteraci\u00f3n de los estr\u00f3genos y da\u00f1os al h\u00edgado. Existen al menos 100 casos confirmados de da\u00f1o hep\u00e1tico grave en personas que utilizan extractos concentrados de t\u00e9 verde que se venden para la p\u00e9rdida de peso y la recuperaci\u00f3n muscular.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n, se encontraron extractos de aloe vera que no fueron revisados por la FDA en m\u00e1s de 450 productos de FoodData Central, una base de datos de alimentos y nutrientes administrada por el Servicio de Investigaci\u00f3n Agr\u00edcola del USDA. Su uso parece ser mayor en jugos de frutas y verduras, bebidas de frutas y n\u00e9ctares.<\/p>\n<p>Como tratamiento com\u00fan para quemaduras, muchos consumidores perciben el aloe vera como natural y, por lo tanto, inocuo, seg\u00fan los expertos. Sin embargo, el extracto de aloe vera de hoja entera sin purificar puede causar c\u00e1ncer, y la FDA prohibi\u00f3 el uso de una forma de aloe vera en laxantes debido a la preocupaci\u00f3n por su relaci\u00f3n con el c\u00e1ncer en animales y la insuficiencia renal en humanos.<\/p>\n<p>\u201cMuchas personas creen que los productos etiquetados como \u2018naturales\u2019 siempre son seguros y beneficiosos. Esto no es necesariamente cierto. Las hierbas medicinales no tienen que pasar por las mismas pruebas que los medicamentos\u201d, afirma la Biblioteca Nacional de Medicina en su sitio web, y a\u00f1ade que algunas hierbas pueden ser muy da\u00f1inas. \u201cAlgunas hierbas pueden interactuar con medicamentos con o sin receta\u201d. El impacto en la salud de cualquier sustancia, natural o no, puede tener efectos significativamente diferentes seg\u00fan su forma, dosis e interacciones con otras afecciones, afirm\u00f3 Touvier.<\/p>\n<p>\u201cEl betacaroteno es seguro en niveles nutricionales presentes en frutas y verduras, pero la suplementaci\u00f3n en dosis altas aumenta el riesgo de c\u00e1ncer de pulm\u00f3n, especialmente en fumadores\u201d, explic\u00f3. \u201cDe igual manera, la fibra de los alimentos integrales es beneficiosa, mientras que ciertas fibras purificadas han mostrado efectos adversos sobre la inflamaci\u00f3n intestinal o la composici\u00f3n de la microbiota\u201d.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n, se encontraron extractos de hongos nunca reportados a la FDA en 428 productos, incluyendo caf\u00e9, jugos y n\u00e9ctares de frutas y verduras, sopas y leches.<\/p>\n<p>Si bien los hongos pueden ser fuentes de nutrientes, consumir la especie incorrecta puede ser mortal, mientras que otros pueden causar reacciones al\u00e9rgicas, problemas digestivos e interactuar negativamente con ciertos medicamentos, especialmente los anticoagulantes.<\/p>\n<p>En 2024, la FDA inst\u00f3 a los fabricantes a dejar de usar el hongo <em>Amanita muscaria<\/em> de cabeza roja debido a \u201cinformes de eventos adversos graves asociados con m\u00faltiples productos alimenticios\u201d. La agencia llam\u00f3 la atenci\u00f3n sobre <em>A. muscaria<\/em> por primera vez 12 a\u00f1os antes al incluir la especie en una lista de \u201cagentes t\u00f3xicos que causan envenenamiento tras la ingesti\u00f3n\u201d.<\/p>\n<p>Los consumidores se han visto perjudicados por la falta de supervisi\u00f3n de las sustancias GRAS en el pasado. Un sustituto de carne congelado a base de vegetales fue retirado voluntariamente del mercado en el verano de 2022 despu\u00e9s de que el fabricante recibiera 470 quejas por enfermedades gastrointestinales, hep\u00e1ticas, de las v\u00edas biliares y de la ves\u00edcula biliar.<\/p>\n<p>El creador de contenido Luke Wesley Pearson public\u00f3 en Instagram que se someti\u00f3 a una cirug\u00eda de ves\u00edcula biliar de emergencia despu\u00e9s de consumir el sustituto de carne dos veces. Otros dos consumidores declararon a CNN que tambi\u00e9n se sometieron a una cirug\u00eda de ves\u00edcula biliar despu\u00e9s de consumir el producto.<\/p>\n<p>El culpable parec\u00eda ser la harina de tara, elaborada a partir de las vainas de un \u00e1rbol espinoso llamado algarrobo peruano. Otro ingrediente derivado de este \u00e1rbol es la goma de tara, que se ha utilizado de forma segura durante a\u00f1os como espesante o estabilizador en alimentos. Sin embargo, la harina de tara se elabora de forma diferente a la goma de tara, y esta harina \u201cno se ha caracterizado adecuadamente ni se ha utilizado previamente como ingrediente alimentario para consumo humano en Estados Unidos\u201d, seg\u00fan la FDA.<\/p>\n<p>Tras la investigaci\u00f3n de la FDA sobre la harina de tara, la agencia tard\u00f3 dos a\u00f1os en retirar la sustancia de la lista GRAS.<\/p>\n<p>\u201cLa harina de tara se introduce en el suministro de alimentos, y solo porque hay un brote de lesi\u00f3n hep\u00e1tica la FDA considera si es segura\u201d, declar\u00f3 a CNN en 2024 el Dr. Pieter Cohen, profesor asociado de medicina en la Facultad de Medicina de Harvard en Boston.<\/p>\n<p>Cohen fue coautor de un art\u00edculo sobre los peligros del sistema GRAS publicado en <em>The New England Journal of Medicine<\/em> y no particip\u00f3 en la investigaci\u00f3n del EWG.<\/p>\n<p>\u201cPeor a\u00fan, la FDA tarda dos a\u00f1os en llegar a esa conclusi\u00f3n, mientras que en todo momento pone en riesgo a los consumidores\u201d, declar\u00f3 Cohen. \u201cEste incidente demuestra lo deficiente que es nuestro sistema de regulaci\u00f3n alimentaria. Es completamente retr\u00f3grado\u201d.<\/p>\n<p>Un informe de 2014 del Consejo de Defensa de los Recursos Naturales, un grupo de defensa del medio ambiente, utiliz\u00f3 las solicitudes de la Ley Federal de Libertad de Informaci\u00f3n para revisar c\u00f3mo las empresas se comunican con la FDA con respecto a los nuevos aditivos alimentarios.<\/p>\n<p>La investigaci\u00f3n revel\u00f3 que 56 empresas aparentemente se basaron en determinaciones de seguridad GRAS no divulgadas para 275 sustancias qu\u00edmicas. Sin embargo, cuando un fabricante present\u00f3 una solicitud GRAS a la FDA, la agencia actu\u00f3 con rigor, rechazando o haciendo que se retiraran una de cada cinco solicitudes.<\/p>\n<p>Un an\u00e1lisis realizado en 2022 por el Grupo de Trabajo Ambiental revel\u00f3 que casi el 99 % de las nuevas sustancias qu\u00edmicas utilizadas en alimentos o envases de alimentos desde el a\u00f1o 2000 recibieron autorizaci\u00f3n para su uso, no por parte de la FDA, sino por parte de la industria alimentaria y qu\u00edmica. Durante ese per\u00edodo, los fabricantes de alimentos solicitaron permiso a la FDA para introducir una nueva sustancia solo diez veces, seg\u00fan el an\u00e1lisis.<\/p>\n<p>La administraci\u00f3n Trump ha indicado que quiere corregir la laguna legal GRAS que permite a las empresas declarar autom\u00e1ticamente productos seguros sin supervisi\u00f3n federal.<\/p>\n<p>\u201cDurante demasiado tiempo, la laguna legal de GRAS ha permitido que ingredientes ingresen al suministro de alimentos sin una transparencia significativa ni la supervisi\u00f3n de la FDA. Bajo el liderazgo del secretario Kennedy, el HHS est\u00e1 tomando medidas para cerrar esas brechas y restaurar la confianza p\u00fablica\u201d, declar\u00f3 Andrew Nixon, subsecretario adjunto de relaciones con los medios del Departamento de Salud y Servicios Humanos de EE.UU., organismo que supervisa la FDA.<\/p>\n<p>\u201cDurante el \u00faltimo a\u00f1o hemos impulsado reformas para fortalecer la supervisi\u00f3n de la v\u00eda GRAS, incluyendo medidas para exigir una mayor notificaci\u00f3n, mejorar la revisi\u00f3n interinstitucional y aumentar la transparencia en torno a la seguridad de los ingredientes alimentarios mediante la elaboraci\u00f3n de normas propuestas\u201d, declar\u00f3 Nixon en un correo electr\u00f3nico.<\/p>\n<p>Hist\u00f3ricamente, los cambios en la FDA han sido lentos. Un ejemplo de ello es el BHA o butilhidroxianisol, un conservante antioxidante sint\u00e9tico utilizado en cosm\u00e9ticos, envases de alimentos y miles de alimentos como helados, dulces, refrigerios, productos c\u00e1rnicos y cereales para el desayuno.<\/p>\n<p>Bas\u00e1ndose en investigaciones con animales, la Agencia Internacional para la Investigaci\u00f3n del C\u00e1ncer clasific\u00f3 el BHA como posible carcin\u00f3geno humano del Grupo 2B, y la Uni\u00f3n Europea lo clasifica como un posible disruptor hormonal.<\/p>\n<p>Un m\u00e9dico solicit\u00f3 a la FDA la prohibici\u00f3n del BHA en 1990, pero no se tom\u00f3 ninguna medida hasta que la FDA anunci\u00f3 que reevaluar\u00eda la seguridad de la sustancia qu\u00edmica en febrero.<\/p>\n<p>Solucionar la laguna legal de la norma GRAS sustancia por sustancia ser\u00e1 un proceso lento, por lo que, a menos que el HHS promulgue una reforma radical, muchos de los llamados ingredientes GRAS en alimentos cuya seguridad nunca se ha comprobado seguir\u00e1n presentes en los alimentos que consumen los estadounidenses, afirm\u00f3 Cohen.<\/p>\n<p>\u201cEn definitiva, la administraci\u00f3n b\u00e1sicamente est\u00e1 pidiendo educadamente a la industria que se adhiera a la intenci\u00f3n de la ley, lo cual no difiere de la situaci\u00f3n actual\u201d, declar\u00f3. \u201cNo he visto nada revolucionario en cuanto a la mejora de la seguridad de nuestro suministro de alimentos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva investigaci\u00f3n revel\u00f3 que al menos 111 sustancias cuyo estatus de seguridad se desconoce han sido a\u00f1adidas a alimentos, bebidas y suplementos vendidos en Estados Unidos sin alertar a la Administraci\u00f3n de Alimentos y Medicamentos (FDA). \u201cLas empresas alimentarias est\u00e1n decidiendo por s\u00ed mismas a\u00f1adir en secreto ingredientes qu\u00edmicos no revisados \u200b\u200ba sus productos, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1471817","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &quot;en secreto&quot; de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &quot;en secreto&quot; de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una nueva investigaci\u00f3n revel\u00f3 que al menos 111 sustancias cuyo estatus de seguridad se desconoce han sido a\u00f1adidas a alimentos, bebidas y suplementos vendidos en Estados Unidos sin alertar a la Administraci\u00f3n de Alimentos y Medicamentos (FDA). \u201cLas empresas alimentarias est\u00e1n decidiendo por s\u00ed mismas a\u00f1adir en secreto ingredientes qu\u00edmicos no revisados \u200b\u200ba sus productos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T16:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.\",\"datePublished\":\"2026-03-03T16:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\"},\"wordCount\":2269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\",\"name\":\"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos \\\"en secreto\\\" de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-03T16:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos \"en secreto\" de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos \"en secreto\" de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias","og_description":"Una nueva investigaci\u00f3n revel\u00f3 que al menos 111 sustancias cuyo estatus de seguridad se desconoce han sido a\u00f1adidas a alimentos, bebidas y suplementos vendidos en Estados Unidos sin alertar a la Administraci\u00f3n de Alimentos y Medicamentos (FDA). \u201cLas empresas alimentarias est\u00e1n decidiendo por s\u00ed mismas a\u00f1adir en secreto ingredientes qu\u00edmicos no revisados \u200b\u200ba sus productos, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-03T16:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.","datePublished":"2026-03-03T16:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/"},"wordCount":2269,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","name":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos \"en secreto\" de riesgos desconocidos en miles de alimentos en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-03T16:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.","url":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-03T16:03:38Z","datePublished":"2026-03-03T16:03:38Z","dateModified":"2026-03-03T16:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Investigaci\\u00f3n descubre qu\\u00edmicos a\\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/03\\\/quimicos-secretos-alimentos-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2026\\\/03\\\/03\\\/quimicos-secretos-alimentos-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-03T16:03:38Z\",\"datePublished\":\"2026-03-03T16:03:38Z\",\"dateModified\":\"2026-03-03T16:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471664,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/25\/mayoria-estadounidenses-gobierno-quimicos-toxicos-trax\/","url_meta":{"origin":1471817,"position":0},"title":"La mayor\u00eda de los estadounidenses creen que el Gobierno no los protege de los productos qu\u00edmicos t\u00f3xicos","author":"","date":"febrero 25, 2026","format":false,"excerpt":"M\u00e1s del 70 % de los adultos estadounidenses est\u00e1n muy o algo preocupados por la exposici\u00f3n a sustancias qu\u00edmicas t\u00f3xicas en sus alimentos y agua potable, seg\u00fan una nueva encuesta de Pew Charitable Trusts.La preocupaci\u00f3n p\u00fablica es tan intensa que 5 de cada 6 adultos en Estados Unidos manifestaron que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465112,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/04\/alimentos-ultraprocesados-perdida-peso-trax\/","url_meta":{"origin":1471817,"position":1},"title":"Comer alimentos m\u00ednimamente procesados duplica p\u00e9rdida de peso incluso con  ultraprocesados que son saludables, dice estudio","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Las personas en el Reino Unido perdieron el doble de peso comiendo comidas t\u00edpicamente hechas en casa que cuando com\u00edan alimentos ultraprocesados comprados en tiendas considerados saludables, seg\u00fan ha descubierto la investigaci\u00f3n m\u00e1s reciente.\u201cEste nuevo estudio muestra que incluso cuando una dieta ultraprocesada cumple con las pautas nutricionales, las personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452300,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","url_meta":{"origin":1471817,"position":2},"title":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas.El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459818,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","url_meta":{"origin":1471817,"position":3},"title":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464734,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/21\/clima-extremo-sube-precios-alimentos-trax\/","url_meta":{"origin":1471817,"position":4},"title":"El clima extremo causado por el cambio clim\u00e1tico eleva los precios de los alimentos en todo el mundo, seg\u00fan un estudio","author":"","date":"julio 21, 2025","format":false,"excerpt":"Un nuevo estudio ha descubierto que el clima extremo causado por el cambio clim\u00e1tico est\u00e1 elevando los precios de los alimentos b\u00e1sicos en todo el mundo y plantea riesgos m\u00e1s amplios para la sociedad.El precio de una amplia gama de productos, desde las patatas en Reino Unido hasta el caf\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469897,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/08\/conservantes-alimentos-cancer-diabetes-trax\/","url_meta":{"origin":1471817,"position":5},"title":"Los conservantes de alimentos podr\u00edan est\u00e1n vinculados al c\u00e1ncer y la diabetes tipo 2, seg\u00fan estudios","author":"","date":"enero 8, 2026","format":false,"excerpt":"Los conservantes comunes utilizados para mantener los alimentos seguros y prolongar su vida \u00fatil podr\u00edan estar relacionados con un mayor riesgo de varios tipos de c\u00e1ncer y diabetes tipo 2, seg\u00fan dos nuevos estudios realizados en Francia.\u201cEstos son hallazgos muy importantes sobre los conservantes que no solo se utilizan ampliamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1471817"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1471817\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1471817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1471817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1471817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}