{"id":1442566,"date":"2023-12-24T00:33:39","date_gmt":"2023-12-24T08:33:39","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1442566"},"modified":"2023-12-24T00:33:39","modified_gmt":"2023-12-24T08:33:39","slug":"mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","title":{"rendered":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo"},"content":{"rendered":"<p>(CNN) &#8212; Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda, con el mundo llam\u00e1ndole, se aleja de ti y empieza a correr.<\/p>\n<p>No hay temor como el de un padre que busca a su hijo perdido. Te dices a ti mismo que todo ir\u00e1 bien, pero tu mente va a los peores lugares.<\/p>\n<p>Ahora que este a\u00f1o llega a su fin, a\u00fan recuerdo el miedo que sent\u00ed una luminosa ma\u00f1ana de s\u00e1bado de finales de septiembre, en una carrera de cinco kil\u00f3metros en Clarkston, Georgia, mientras esperaba a mi hijo de 11 a\u00f1os en la l\u00ednea de meta.<\/p>\n<p>Sab\u00eda que pod\u00eda correr 5 km en unos 30 minutos. Cuando no lo vi en la marca de 35 minutos, empec\u00e9 a preguntarme qu\u00e9 hab\u00eda salido mal. Y cuando se acercaban los 40 minutos y segu\u00eda sin aparecer, sal\u00ed a buscarlo.<\/p>\n<p>\u00bfSe hab\u00eda perdido? \u00bfHabl\u00f3 con un desconocido? \u00bfLo hab\u00eda atropellado un coche? Cruc\u00e9 las v\u00edas del tren y mir\u00e9 a lo largo de una larga recta, esperando ver su cara, pregunt\u00e1ndome si deb\u00eda seguir corriendo hasta encontrarlo.<\/p>\n<p>&#171;No hay muro que detenga a un padre que quiere un futuro mejor para su hijo&#187;, Juan Gonz\u00e1lez<\/p>\n<p>Ya hab\u00eda sido una ma\u00f1ana inusual. Una hora antes, cuando lleg\u00e1bamos a la ciudad, mi hijo vio un insecto en el cap\u00f3 de mi coche. Era verde ne\u00f3n, no m\u00e1s grande que una u\u00f1a. Y era simp\u00e1tico. Esta cosita verde salt\u00f3 al dedo de mi hijo, camin\u00f3 por mi camiseta y luego volvi\u00f3 a la mano de mi hijo, donde permaneci\u00f3 mucho, mucho tiempo. Se qued\u00f3 tanto tiempo que al final le pusimos un nombre: Amiguito.<\/p>\n<p>El trayecto desde el auto hasta la mesa de inscripci\u00f3n fue de unos 400 metros. Amiguito se qued\u00f3 con mi hijo. Volvimos al coche para dejar algunas cosas. Amiguito sigui\u00f3 con mi hijo. Volvimos a cruzar las v\u00edas del tren y esperamos a que empezara la carrera. Amiguito nos acompa\u00f1\u00f3.<\/p>\n<p>M\u00e1s tarde me enter\u00e9 de que era un grillo arb\u00f3reo, probablemente un grillo arb\u00f3reo de la nieve, seg\u00fan Will Hudson, profesor de Entomolog\u00eda de la Universidad de Georgia, que vio una foto que le envi\u00e9.<\/p>\n<p>&#171;Si el grillo tuviera un poco de fr\u00edo, entonces sentarse en algo caliente como tu mano le caer\u00eda bastante bien&#187;, me dijo cuando le cont\u00e9 la historia.<\/p>\n<p>Thomas Lake con el grillo en la camiseta el d\u00eda que corri\u00f3 una carrera de 5 km con su hijo. Cr\u00e9dito: Thomas Lake<\/p>\n<p>Unos minutos antes de la carrera, Amiguito se cay\u00f3 o salt\u00f3 de la mano de mi hijo y aterriz\u00f3 en la acera. Quiz\u00e1 quer\u00eda ir libre. Pero no era un buen lugar para ello. El tr\u00e1fico peatonal era denso e impredecible. Amiguito estaba en peligro. As\u00ed que mi hijo se arrodill\u00f3 y le tendi\u00f3 la mano. Amiguito volvi\u00f3.<\/p>\n<p>La carrera estaba a punto de empezar y al peque\u00f1o insecto verde le esperaba una carrera salvaje. Mi hijo correr\u00eda r\u00e1pido, y la carrera ser\u00eda larga, y sus brazos se balancear\u00edan, y el amiguito rebotar\u00eda y ser\u00eda empujado y finalmente se soltar\u00eda. Me sent\u00ed obligado a tener una charla con mi hijo.<br \/>\n&#171;Perder\u00e1s a tu amiguito&#187;, le dije.<\/p>\n<p>Mi hijo asinti\u00f3, tratando el momento con la solemnidad adecuada.<\/p>\n<p>Amiguito se pos\u00f3 en silencio en su mu\u00f1eca.<\/p>\n<p>Empez\u00f3 la carrera y los perd\u00ed de vista.<\/p>\n<p>Corr\u00ed bastante bien, aunque no tan r\u00e1pido como en la universidad, y me emocion\u00e9 al llegar a la meta. Esa emoci\u00f3n dio paso a la ansiedad cuando mi hijo no apareci\u00f3.<\/p>\n<p>Mira c\u00f3mo padre e hijo ganaron la carrera de globos m\u00e1s antigua del mundo<\/p>\n<p>Hab\u00eda corrido 30:34 en otra carrera de 5 km a finales de primavera. Hoy no estaba ni cerca. Y m\u00e1s all\u00e1 del umbral de los 40 minutos, me entr\u00f3 el p\u00e1nico.<\/p>\n<p>No paraba de preguntar a la gente si le hab\u00edan visto. Nadie lo hab\u00eda visto. Al otro lado de la pista, en la larga recta, lo busqu\u00e9 a la distancia. No estaba.<\/p>\n<p>De vuelta a la sede de la carrera, me preguntaba c\u00f3mo emitir un bolet\u00edn con todos los puntos para describir a mi hijo. Y en mi confusi\u00f3n, ni siquiera lo vi cruzar la l\u00ednea de meta.<\/p>\n<p>Pero all\u00ed estaba, gracias a Dios, justo antes de la marca de 45 minutos.<\/p>\n<p>Y all\u00ed estaba el peque\u00f1o insecto, montado en el pliegue superior de su pulgar derecho como un capit\u00e1n muy peque\u00f1o en un barco muy alto.<\/p>\n<p>El profesor de Entomolog\u00eda me cont\u00f3 algo m\u00e1s sobre estos grillos arb\u00f3reos de la nieve. Como viven en \u00e1rboles y arbustos, est\u00e1n acostumbrados a sentir el viento.<\/p>\n<p>Son buenos aguantando.<\/p>\n<p>Mis predicciones hab\u00edan sido err\u00f3neas. Mi hijo no hab\u00eda corrido r\u00e1pido y no hab\u00eda perdido a Amiguito, y estos dos hechos parec\u00edan relacionados de alg\u00fan modo. Le ech\u00f3 la culpa a un resfriado del que se estaba recuperando. Yo sospechaba que era algo m\u00e1s que eso, pero no le pregunt\u00e9 demasiado al respecto.<\/p>\n<p>Un ni\u00f1o tiene sus razones, algunas de ellas desconocidas incluso para \u00e9l mismo. Hay m\u00e1s de una forma de ganar una carrera.<\/p>\n<p>Volvimos al coche sonriendo y encontramos unos arbustos en el estacionamiento que me parecieron un buen lugar para que mi hijo dejara a Amiguito. Su breve e intensa amistad hab\u00eda llegado a su fin.<\/p>\n<p>&#171;S\u00e9 libre&#187;, dijo mi hijo y le dio un suave empuj\u00f3n a Amiguito. Le cost\u00f3 un poco m\u00e1s, pero finalmente se solt\u00f3 de su dedo y baj\u00f3 en picado, con su cuerpo verde brillante fundi\u00e9ndose con los arbustos verde oscuro, una fr\u00e1gil criatura que se perd\u00eda de vista.<\/p>\n<p>Un d\u00eda, mi hijo tambi\u00e9n se marchar\u00e1 y emprender\u00e1 su propia aventura. Hace poco, mi hermano me envi\u00f3 una foto de nosotros juntos. Casi me rompe el coraz\u00f3n. Mi hijo, que entonces ten\u00eda 6 a\u00f1os, me cog\u00eda de la mano y me miraba con una expresi\u00f3n indescriptible de esperanza e inocencia. Parec\u00eda que intentaba decirme algo. Pero yo miraba al frente, a otra cosa. Cuando vi aquella foto, me entraron ganas de gritarme: \u00a1Gira la cabeza! \u00a1M\u00edralo! \u00a1No hay nada m\u00e1s importante en el mundo!<\/p>\n<p>Mi hijo sab\u00eda la verdad. A veces la vida te regala algo hermoso, un tesoro fr\u00e1gil y fugaz que se te pega a la mano. No hay necesidad de precipitarse. Tr\u00e1talo con delicadeza. Saborea cada momento. Af\u00e9rrate mientras puedas.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2023 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda, con el mundo llam\u00e1ndole, se [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1442566","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda, con el mundo llam\u00e1ndole, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-24T08:33:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo\",\"datePublished\":\"2023-12-24T08:33:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\"},\"wordCount\":1204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\",\"name\":\"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2023-12-24T08:33:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","og_locale":"es_ES","og_type":"article","og_title":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias","og_description":"(CNN) &#8212; Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda, con el mundo llam\u00e1ndole, se [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","og_site_name":"Noticias","article_published_time":"2023-12-24T08:33:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/"},"author":{"name":"","@id":""},"headline":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo","datePublished":"2023-12-24T08:33:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/"},"wordCount":1204,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","name":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2023-12-24T08:33:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo","url":"http:\/\/noticiasya.com\/el-centro\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2023-12-24T08:33:39Z","datePublished":"2023-12-24T08:33:39Z","dateModified":"2023-12-24T08:33:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\\u00f3 a la meta, sal\\u00ed a buscarlo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2023\\\/12\\\/24\\\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2023\\\/12\\\/24\\\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-12-24T08:33:39Z\",\"datePublished\":\"2023-12-24T08:33:39Z\",\"dateModified\":\"2023-12-24T08:33:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442525,"url":"https:\/\/noticiasya.com\/el-centro\/2023\/12\/23\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo\/","url_meta":{"origin":1442566,"position":0},"title":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN) -- Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442567,"url":"https:\/\/noticiasya.com\/el-centro\/2023\/12\/24\/mi-hijo-y-yo-corrimos-la-misma-carrera-de-5-km-cuando-no-llego-a-la-meta-sali-a-buscarlo-3\/","url_meta":{"origin":1442566,"position":1},"title":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) -- Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446749,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/03\/09\/carrera-hijo-perdido-grillo-trax\/","url_meta":{"origin":1442566,"position":2},"title":"Mi hijo y yo corrimos la misma carrera de 5 km. Cuando no lleg\u00f3 a la meta, sal\u00ed a buscarlo","author":"","date":"marzo 9, 2024","format":false,"excerpt":"(CNN) -- Un nuevo beb\u00e9 llega a casa, esta fr\u00e1gil criatura de repente bajo tu cuidado, y junto con la alegr\u00eda hay destellos de terror. Cada nuevo hito parece aumentar el riesgo de cat\u00e1strofe. Tu hijo se mantiene sentado y luego de pie. Da un primer paso vacilante. Un d\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465611,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/08\/18\/neymar-mensaje-hijo-derrota-santos-vasco-da-gama-orix\/","url_meta":{"origin":1442566,"position":3},"title":"Neymar comparti\u00f3 el tierno mensaje que su hijo le escribi\u00f3 tras la peor derrota de su carrera","author":"","date":"agosto 18, 2025","format":false,"excerpt":"La del domingo no fue una actuaci\u00f3n m\u00e1s para Neymar. El exdelantero del FC Barcelona y el PSG, que volvi\u00f3 al Santos de Brasil a finales de enero, sufri\u00f3 la peor derrota de su carrera: 0-6 frente al Vasco da Gama en su propio estadio, ante su gente, que acab\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472537,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/03\/25\/vamos-casa-hijo-madre-buscadora-ceci-flores-restos-hijo-desaparecido-2019-orix\/","url_meta":{"origin":1442566,"position":4},"title":"&#171;\u00a1Vamos a casa, hijo!&#187;: la madre buscadora Ceci Flores dice que encontr\u00f3 restos de su hijo desaparecido en 2019 en M\u00e9xico","author":"","date":"marzo 25, 2026","format":false,"excerpt":"\u201c\u00a1Vamos a casa, hijo\u201d. Fue con estas palabras que Ceci Flores, fundadora del Colectivo Madres Buscadoras de Sonora, anunci\u00f3 el martes el hallazgo de restos que, seg\u00fan afirma, corresponden a su hijo Marco Antonio Sauceda Rocha, quien fue v\u00edctima de desaparici\u00f3n forzada en 2019, cuando un grupo armado se lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459892,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/03\/13\/mujer-dejo-ee-uu-mudarse-espana-hijo-tragedia-familiar-trax\/","url_meta":{"origin":1442566,"position":5},"title":"&#171;Valencia nos ha ayudado a sanar&#187;: Esta mujer dej\u00f3 EE.UU. para mudarse a Espa\u00f1a con su hijo tras una tragedia familiar","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Al vivir lo que ella describe como una existencia de \u201ccuento de hadas\u201d con su esposo y su hijo en Chicago, Mar\u00eda Robertson-Justiniano sinti\u00f3 que su futuro ya estaba planeado.Pero todo cambi\u00f3 en 2018, cuando su marido Alex muri\u00f3 inesperadamente.\u201cFue un shock total\u201d, le dice Mar\u00eda a CNN Travel, describiendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1442566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1442566"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1442566\/revisions"}],"predecessor-version":[{"id":1442583,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1442566\/revisions\/1442583"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1442566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1442566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1442566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}