{"id":1466810,"date":"2025-09-25T07:03:51","date_gmt":"2025-09-25T14:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/"},"modified":"2025-09-25T07:03:51","modified_gmt":"2025-09-25T14:03:51","slug":"asistente-trump-deja-casa-blanca-alto-perfil-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","title":{"rendered":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato"},"content":{"rendered":"<p>Taylor Budowich, secretario general adjunto de Comunicaciones del presidente de EE.UU., Donald Trump, dejar\u00e1 el Gobierno a finales de este mes para ocupar un nuevo cargo, dijo a CNN una fuente familiarizada con el asunto.<\/p>\n<p>Su salida inminente lo convierte en el asistente de m\u00e1s alto perfil en dejar la Casa Blanca durante el segundo mandato de Trump, que ya llega a los ocho meses. No es inusual que los asistentes de la Casa Blanca roten despu\u00e9s de alrededor de un a\u00f1o. La relativa estabilidad del personal en este Gobierno contrasta con el primer mandato de Trump, caracterizado por una alta rotaci\u00f3n.<\/p>\n<p>Budowich, quien se neg\u00f3 a hacer comentarios el mi\u00e9rcoles, se desempe\u00f1\u00f3 como portavoz de Trump tras su salida de la Casa Blanca, en 2021, y luego dirigi\u00f3 el Comit\u00e9 independiente de campa\u00f1a af\u00edn MAGA Inc., antes de reincorporarse a la campa\u00f1a de 2024.<\/p>\n<p>Axios fue el primero en informar sobre su salida.<\/p>\n<p>Hasta ahora, el asistente de m\u00e1s alto perfil en salir hab\u00eda sido Mike Waltz. Pero aunque fue destituido como asesor de Seguridad Nacional en mayo, desde entonces fue confirmado como embajador de Trump en Naciones Unidas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Taylor Budowich, secretario general adjunto de Comunicaciones del presidente de EE.UU., Donald Trump, dejar\u00e1 el Gobierno a finales de este mes para ocupar un nuevo cargo, dijo a CNN una fuente familiarizada con el asunto. Su salida inminente lo convierte en el asistente de m\u00e1s alto perfil en dejar la Casa Blanca durante el segundo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466810","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias\" \/>\n<meta property=\"og:description\" content=\"Taylor Budowich, secretario general adjunto de Comunicaciones del presidente de EE.UU., Donald Trump, dejar\u00e1 el Gobierno a finales de este mes para ocupar un nuevo cargo, dijo a CNN una fuente familiarizada con el asunto. Su salida inminente lo convierte en el asistente de m\u00e1s alto perfil en dejar la Casa Blanca durante el segundo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T14:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato\",\"datePublished\":\"2025-09-25T14:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\"},\"wordCount\":235,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\",\"name\":\"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-25T14:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias","og_description":"Taylor Budowich, secretario general adjunto de Comunicaciones del presidente de EE.UU., Donald Trump, dejar\u00e1 el Gobierno a finales de este mes para ocupar un nuevo cargo, dijo a CNN una fuente familiarizada con el asunto. Su salida inminente lo convierte en el asistente de m\u00e1s alto perfil en dejar la Casa Blanca durante el segundo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-25T14:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/"},"author":{"name":"","@id":""},"headline":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato","datePublished":"2025-09-25T14:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/"},"wordCount":235,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","name":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-25T14:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un asistente de Trump deja la Casa Blanca en la salida de m\u00e1s alto perfil de su segundo mandato","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/25\/asistente-trump-deja-casa-blanca-alto-perfil-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-25T14:03:51Z","datePublished":"2025-09-25T14:03:51Z","dateModified":"2025-09-25T14:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un asistente de Trump deja la Casa Blanca en la salida de m\\u00e1s alto perfil de su segundo mandato\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/25\\\/asistente-trump-deja-casa-blanca-alto-perfil-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/25\\\/asistente-trump-deja-casa-blanca-alto-perfil-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-25T14:03:51Z\",\"datePublished\":\"2025-09-25T14:03:51Z\",\"dateModified\":\"2025-09-25T14:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455858,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/11\/15\/trump-elige-steven-cheung-director-comunicaciones-casa-blanca-trax\/","url_meta":{"origin":1466810,"position":0},"title":"Trump elige Steven Cheung, portavoz de su campa\u00f1a, como director de comunicaciones de la Casa Blanca","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN) -- El presidente electo Donald Trump nombr\u00f3 a Steven Cheung como director de comunicaciones de la Casa Blanca, promoviendo al portavoz de su campa\u00f1a a uno de los principales roles de comunicaciones en el Gobierno.Cheung ha sido nombrado asistente del presidente y director de comunicaciones. Durante el primer mandato\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457761,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/01\/22\/desaparece-version-espanol-sitio-casa-blanca-orix\/","url_meta":{"origin":1466810,"position":1},"title":"Desaparece la versi\u00f3n en espa\u00f1ol del sitio web de la Casa Blanca","author":"","date":"enero 22, 2025","format":false,"excerpt":"Repitiendo una medida tomada durante su primer mandato (2017-2021), Donald Trump cerr\u00f3 esta semana el sitio de la Casa Blanca en espa\u00f1ol y sus redes sociales en el mismo idioma.Al intentar ingresar en la p\u00e1gina web aparece el mensaje de \u201cP\u00e1gina no encontrada\u201d y un enlace que redirige al usuario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472856,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/04\/03\/gabinete-trump-nadie-salvo-despidos-bondi-noem-trax\/","url_meta":{"origin":1466810,"position":2},"title":"&#171;Esto es una recalibraci\u00f3n&#187;: el gabinete de Trump teme que nadie est\u00e9 a salvo tras los despidos de Bondi y Noem","author":"","date":"abril 3, 2026","format":false,"excerpt":"Cuando el presidente Donald Trump destituy\u00f3 a su secretaria de Justicia, Pam Bondi, envi\u00f3 un mensaje claro a los miembros restantes de su gabinete: la seguridad laboral de la que hab\u00edan disfrutado hasta ahora ya no est\u00e1 garantizada.Trump se ha mostrado cada vez m\u00e1s dispuesto a despedir a altos funcionarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467833,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/10\/29\/ataques-cia-maduro-poder-militar-trump-trax\/","url_meta":{"origin":1466810,"position":3},"title":"Ciberataques de la CIA contra Maduro no conformaron a Trump en su primer mandato. Ahora EE.UU. alardea de su poder militar","author":"","date":"octubre 29, 2025","format":false,"excerpt":"En el \u00faltimo a\u00f1o del primer mandato del presidente Donald Trump, la CIA llev\u00f3 a cabo un ciberataque clandestino contra el Gobierno venezolano, inhabilitando la red inform\u00e1tica utilizada por el servicio de inteligencia del l\u00edder Nicol\u00e1s Maduro.El ataque, descrito a CNN por cuatro fuentes familiarizadas con la operaci\u00f3n, fue un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469022,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","url_meta":{"origin":1466810,"position":4},"title":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"El comisionado de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s), Marty Makary, est\u00e1 bajo un renovado escrutinio por parte de los funcionarios de Trump.La agencia atraviesa un periodo de agitaci\u00f3n continua, incluida una serie de salidas de alto perfil que han generado preguntas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455249,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/10\/19\/lideres-militares-gobierno-trump-alertan-posibilidad-segundo-mandato-trax\/","url_meta":{"origin":1466810,"position":5},"title":"AN\u00c1LISIS | L\u00edderes militares que prestaron servicio bajo el Gobierno de Trump alertan sobre la posibilidad de que gane un segundo mandato","author":"","date":"octubre 19, 2024","format":false,"excerpt":"(CNN) -- La sugerencia del expresidente Donald Trump de que las fuerzas armadas estadounidenses deber\u00edan utilizarse para hacer frente \"al enemigo desde dentro\" el d\u00eda de las elecciones ha reavivado la preocupaci\u00f3n sobre lo que podr\u00eda pedirles a los militares si gana un segundo mandato como comandante en jefe.Y son\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466810"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466810\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}