{"id":1466862,"date":"2025-09-26T04:03:49","date_gmt":"2025-09-26T11:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/"},"modified":"2025-09-26T04:03:49","modified_gmt":"2025-09-26T11:03:49","slug":"tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","title":{"rendered":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo"},"content":{"rendered":"<p>La madrugada del 18 de marzo de 1976, Francisco Ten\u00f3rio Cerqueira J\u00fanior, un reconocido pianista brasile\u00f1o que se encontraba de gira en Buenos Aires, sali\u00f3 del hotel donde se hospedaba para comprar cigarrillos. Jam\u00e1s regres\u00f3 y no se supo m\u00e1s de \u00e9l. Hasta ahora.<\/p>\n<p>Tenorinho, como se lo conoc\u00eda familiarmente, ten\u00eda 35 a\u00f1os, una esposa y cuatro hijos, m\u00e1s un beb\u00e9 en camino. Se dedicaba a la m\u00fasica desde la adolescencia y su talento lo hab\u00eda tra\u00eddo hasta la capital argentina para una serie de conciertos en el Teatro Gran Rex, junto a grandes figuras del bossa nova como Vinicius de Moraes y Toquinho.<\/p>\n<p>Su desaparici\u00f3n caus\u00f3 gran desolaci\u00f3n entre familiares y amigos. El propio Vinicius fue uno de los impulsores de su b\u00fasqueda. Pero el contexto pol\u00edtico y social era extremadamente complejo: por esos d\u00edas se estaba gestando en Argentina el golpe de Estado c\u00edvico militar que, el 24 de marzo, derrocar\u00eda la presidencia de Mar\u00eda Estela Mart\u00ednez de Per\u00f3n e iniciar\u00eda el per\u00edodo m\u00e1s oscuro de la historia del pa\u00eds.<\/p>\n<p>Seg\u00fan se pudo reconstruir en base al expediente judicial, Tenorinho sali\u00f3 del hotel Normandie, ubicado a pocos metros de la Avenida Corrientes, en pleno centro porte\u00f1o, alrededor de las 3 de la madrugada. Dijo que iba a comprar cigarrillos y un medicamento, pero no regres\u00f3.<\/p>\n<p>Dos d\u00edas despu\u00e9s, el 20 de marzo, el cad\u00e1ver de un hombre aparec\u00eda en un terreno bald\u00edo en el Partido de Tigre, a unos 30 km del hotel donde hab\u00eda estado el m\u00fasico. Ten\u00eda impactos de bala, seg\u00fan consta en el informe policial que se incluye en el expediente. Se lo enterr\u00f3 sin ser identificado en el cementerio de Benav\u00eddez, en la provincia de Buenos Aires.<\/p>\n<p>En ese momento, los hechos no quedaron relacionados.<\/p>\n<p>La incertidumbre y la angustia de la familia eran totales. Y as\u00ed se mantuvieron por casi 50 a\u00f1os. Hasta que, a fines de agosto de este a\u00f1o, se conoci\u00f3 que el m\u00fasico hab\u00eda sido asesinado y enterrado como cad\u00e1ver no identificado en un cementerio bonaerense, apenas d\u00edas despu\u00e9s de su desaparici\u00f3n.<\/p>\n<p>Ten\u00f3rio figura en la<a href=\"https:\/\/basededatos.parquedelamemoria.org.ar\/registros\/3118\/\"> lista <\/a>Comisi\u00f3n Nacional sobre la Desaparici\u00f3n de Personas, una comisi\u00f3n creada en 1983 tras el fin de la dictadura c\u00edvico-militar de Argentina, para investigar las desapariciones y violaciones a los derechos humanos ocurridas entre 1976 y 1983. El pianista es considerado v\u00edctima del terrorismo de Estado, aunque, como con la mayor\u00eda de las v\u00edctimas, determinar las circunstancias exactas de su muerte es muy complejo debido a la clandestinidad que acompa\u00f1\u00f3 este per\u00edodo.<\/p>\n<p>\u201cEl hallazgo de Ten\u00f3rio J\u00fanior es un amargo recordatorio de la impunidad que persiste en muchos de estos aberrantes cr\u00edmenes, cuyo impacto reverbera durante d\u00e9cadas y generaciones\u201d, dijo Jan Jarab, representante de ONU Derechos Humanos para Am\u00e9rica del Sur, en un comentario publicado en la p\u00e1gina web del organismo. \u201cTen\u00f3rio J\u00fanior no era militante pol\u00edtico, ni activista. El abuso de poder que puso fin a su vida tambi\u00e9n provoc\u00f3 que miles de personas -militantes o no- fueran asesinadas, desaparecidas, exiliadas y perseguidas en el Cono Sur durante d\u00e9cadas, mediante m\u00e9todos que no conocieron de jurisdicci\u00f3n ni fronteras\u201d.<\/p>\n<p>La identificaci\u00f3n de Ten\u00f3rio fue realizada por el Equipo Argentino de Antropolog\u00eda Forense (EAAF) en base a un cotejo de huellas dactilares. El EAAF es un reconocido equipo interdisciplinario que ya ha ayudado a identificar a cientos de desparecidos de la \u00faltima dictadura argentina.<\/p>\n<p>Se trata de peritos de diversas \u00e1reas que aportan pruebas para las investigaciones que lleva la justicia en casos de lesa humanidad, mediante el an\u00e1lisis de restos humanos y otros elementos. Estos expertos permiten ayudar a reconstruir lo sucedido con las desapariciones forzadas por el terrorismo de Estado. Tambi\u00e9n cuentan entre sus hitos la identificaci\u00f3n en 1997 de los restos del Che Guevara. Actualmente participan en b\u00fasquedas e identificaciones en m\u00e1s de 40 pa\u00edses.<\/p>\n<p>El expediente del cad\u00e1ver enterrado en Benav\u00eddez fue recuperado por la Procuradur\u00eda de Cr\u00edmenes contra la Humanidad (PCCH), un organismo que lleva a\u00f1os revisando causas tramitadas por la justicia penal bonaerense entre 1975 y 1983 por el hallazgo de personas muertas cuya identidad era desconocida. El objetivo de esta b\u00fasqueda es determinar si se trata de v\u00edctimas del terrorismo de Estado que siguen en condici\u00f3n de desaparecidas.<\/p>\n<p>\u201cPor la fecha, por las caracter\u00edsticas, es que nosotros solicitamos cotejar las huellas digitales que est\u00e1n en ese expediente de aquel cad\u00e1ver hallado en esa \u00e9poca (pocos d\u00edas despu\u00e9s de la desaparici\u00f3n del m\u00fasico) con las huellas digitales de Ten\u00f3rio\u201d, explic\u00f3 a CNN Mariana Segura, directora para Sudam\u00e9rica del EAAF.<\/p>\n<p>Si bien el golpe de Estado ocurri\u00f3 d\u00edas despu\u00e9s de la desaparici\u00f3n de Ten\u00f3rio J\u00fanior, \u201cya desde 1975 ten\u00edamos personas que se encontraban en calidad de desaparecidas\u201d, explica Segura. \u201cY ese tipo de denuncias fueron ingresadas en las investigaciones (de cr\u00edmenes de lesa humanidad) porque, m\u00e1s all\u00e1 de no corresponder al per\u00edodo exacto, por el modus operandi y por la forma en que fueron desaparecidas esas personas antes, correspond\u00edan tambi\u00e9n a desapariciones forzadas\u201d.<\/p>\n<p>El cotejo del EAAF dio positivo. El pasado 26 de agosto, la C\u00e1mara Federal porte\u00f1a firm\u00f3 la resoluci\u00f3n que acredita que aquel cuerpo enterrado en Benav\u00eddez era el del pianista Ten\u00f3rio J\u00fanior y remiti\u00f3 la informaci\u00f3n al juez Sebasti\u00e1n Casanello, cuyo juzgado tramita una investigaci\u00f3n sobre lo que se conoci\u00f3 como el Plan C\u00f3ndor, una coordinaci\u00f3n secreta de inteligencia y contrainsurgencia entre las dictaduras de Argentina, Bolivia, Brasil, Chile, Paraguay y Uruguay, que ya estaba estaba en funcionamiento al momento de la desaparici\u00f3n de Ten\u00f3rio.<\/p>\n<p>Sin embargo, los restos del m\u00fasico no han sido recuperados. \u201cEn nuestro pa\u00eds y en el resto de Latinoam\u00e9rica, cuando hay una inhumaci\u00f3n como NN (persona no identificada) y no hay una orden espec\u00edfica de una autoridad para preservar la sepultura hasta conocer su identidad (algo que claramente no ocurre en una dictadura), entonces los restos pasaban a un osario com\u00fan entre los cuatro y cinco a\u00f1os, dependiendo de la jur\u00eddica\u201d, explica Segura.<\/p>\n<p>Eso pas\u00f3 con el cuerpo de Ten\u00f3rio. En 1982, la sepultura fue reocupada y sus restos pasaron a un osario com\u00fan.<\/p>\n<p>\u201cEntonces, no es un escenario sencillo de recuperaci\u00f3n. No es un camino que hemos cerrado completamente, pero somos muy cautos de no generar falsas esperanzas, sobre todo a los familiares, respecto de una recuperaci\u00f3n de restos\u201d, aclara la especialista.<\/p>\n<p>A pesar del paso de los a\u00f1os, y aunque, como se\u00f1ala Segura, no siempre pueden recuperarse los restos de las personas, todav\u00eda se siguen logrando identificaciones, como en el caso de Ten\u00f3rio. Esto ocurre gracias al trabajo de investigadores como los miembros de la PCCH y el EAAF, y otros organismos judiciales y civiles que constantemente revisan expedientes, informaci\u00f3n y diferentes elementos. Desde el EAAF invitan a las familias de personas desaparecidas a que se acerquen a ellos. Todo elemento puede ayudar a acelerar identificaciones y poder lograr respuestas.<\/p>\n<p>La familia de Ten\u00f3rio J\u00fanior recibi\u00f3 la noticia del hallazgo a trav\u00e9s de la Comisi\u00f3n Especial de Muertos y Desaparecidos Pol\u00edticos (CEMDP) de Brasil, a cargo del fiscal Iv\u00e1n Marx.<\/p>\n<p>\u201c50 a\u00f1os despu\u00e9s, que sea posible darle a la familia una respuesta es algo que emociona. Pero tambi\u00e9n una gran responsabilidad\u201d, le dijo el fiscal Marx a CNN en una entrevista v\u00eda zoom. \u201cHay que medir las palabras, hay que sentir el momento para decirlo de una forma no tan r\u00e1pida y que se comprenda el procedimiento y tenga el tiempo tambi\u00e9n para procesar el duelo\u201d.<\/p>\n<p>Marx cont\u00f3 que la familia se sorprendi\u00f3, no esperaban una respuesta tan definitiva luego de tantos a\u00f1os de incertidumbre.<\/p>\n<p>En un comunicado difundido en redes sociales, los hijos del m\u00fasico dijeron que recibieron la noticia \u201ccon sorpresa\u201d y \u201ccon una mezcla de alivio y tristeza\u201d.<\/p>\n<p>Alivio de saber lo que pas\u00f3 con su padre. \u201cTristeza por la confirmaci\u00f3n de que Ten\u00f3rio fue v\u00edctima de la violencia y enterrado como un desconocido, lejos de la familia, de los amigos, de los compa\u00f1eros de m\u00fasica\u201d. CNN intent\u00f3 contactar a los familiares, pero por el momento prefirieron no hablar, m\u00e1s all\u00e1 del comunicado.<\/p>\n<p>En el escrito, lamentaron haber sido privados de crecer con \u00e9l y que su madre se viera obligada a \u201ccriar sola a cuatro ni\u00f1os de 8, 7, 5 y 4 a\u00f1os\u201d, adem\u00e1s del beb\u00e9 que estaba en camino, al que no lleg\u00f3 a conocer, como tampoco a sus ocho nietos.<\/p>\n<p>En el comunicado, los hijos del m\u00fasico dejan asentadas las preguntas que a\u00fan no tienen respuesta: \u00bfQui\u00e9n mat\u00f3 a Ten\u00f3rio? \u00bfPor qu\u00e9?<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madrugada del 18 de marzo de 1976, Francisco Ten\u00f3rio Cerqueira J\u00fanior, un reconocido pianista brasile\u00f1o que se encontraba de gira en Buenos Aires, sali\u00f3 del hotel donde se hospedaba para comprar cigarrillos. Jam\u00e1s regres\u00f3 y no se supo m\u00e1s de \u00e9l. Hasta ahora. Tenorinho, como se lo conoc\u00eda familiarmente, ten\u00eda 35 a\u00f1os, una esposa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466862","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La madrugada del 18 de marzo de 1976, Francisco Ten\u00f3rio Cerqueira J\u00fanior, un reconocido pianista brasile\u00f1o que se encontraba de gira en Buenos Aires, sali\u00f3 del hotel donde se hospedaba para comprar cigarrillos. Jam\u00e1s regres\u00f3 y no se supo m\u00e1s de \u00e9l. Hasta ahora. Tenorinho, como se lo conoc\u00eda familiarmente, ten\u00eda 35 a\u00f1os, una esposa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T11:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo\",\"datePublished\":\"2025-09-26T11:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\"},\"wordCount\":1573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\",\"name\":\"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-26T11:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias","og_description":"La madrugada del 18 de marzo de 1976, Francisco Ten\u00f3rio Cerqueira J\u00fanior, un reconocido pianista brasile\u00f1o que se encontraba de gira en Buenos Aires, sali\u00f3 del hotel donde se hospedaba para comprar cigarrillos. Jam\u00e1s regres\u00f3 y no se supo m\u00e1s de \u00e9l. Hasta ahora. Tenorinho, como se lo conoc\u00eda familiarmente, ten\u00eda 35 a\u00f1os, una esposa [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-26T11:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/"},"author":{"name":"","@id":""},"headline":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo","datePublished":"2025-09-26T11:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/"},"wordCount":1573,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","name":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-26T11:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un pianista brasile\u00f1o desapareci\u00f3 en Argentina d\u00edas antes del golpe militar. Casi 50 a\u00f1os despu\u00e9s, lograron identificarlo","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/26\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-26T11:03:49Z","datePublished":"2025-09-26T11:03:49Z","dateModified":"2025-09-26T11:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un pianista brasile\\u00f1o desapareci\\u00f3 en Argentina d\\u00edas antes del golpe militar. Casi 50 a\\u00f1os despu\\u00e9s, lograron identificarlo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/26\\\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/26\\\/tenorio-junior-pianista-brasil-desaparecido-dictadura-argentina-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-26T11:03:49Z\",\"datePublished\":\"2025-09-26T11:03:49Z\",\"dateModified\":\"2025-09-26T11:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467793,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","url_meta":{"origin":1466862,"position":0},"title":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga.En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471364,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/02\/17\/vinicius-prestianni-benfica-real-madrid-presunto-racismo-orix\/","url_meta":{"origin":1466862,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 entre Prestianni y Vin\u00edcius en el Benfica vs. Real Madrid y por qu\u00e9 se habla de racismo en la Champions?","author":"","date":"febrero 17, 2026","format":false,"excerpt":"El Real Madrid venci\u00f3 al Benfica como visitante por 1 a 0 y dio un gran paso en su b\u00fasqueda de clasificar a los octavos de final de la Champions League, pero los titulares tras el partido hablan m\u00e1s del incidente que oblig\u00f3 al \u00e1rbitro a suspender el juego durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455422,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/10\/29\/mensaje-vinicius-jr-balon-de-oro-lo-hare-10-veces-mas-necesario-no-estan-preparados-orix\/","url_meta":{"origin":1466862,"position":2},"title":"El mensaje de Vin\u00edcius Jr. tras el Bal\u00f3n de Oro 2024: &#171;Lo har\u00e9 10 veces m\u00e1s si es necesario. No est\u00e1n preparados&#187;","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 Espa\u00f1a tuvo una noche redonda en el mundo del f\u00fatbol este lunes, cuando sus jugadores Rodri y Aitana Bonmat\u00ed ganaron el Bal\u00f3n de Oro 2024, lo cual les reconoce como los mejores jugadores del mundo.Ahora puedes seguirnos en\u00a0WhatsApp ChannelTras el anuncio de los ganadores, uno de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452493,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/09\/06\/vinicius-jr-declaraciones-racismo-malestar-espana-orix\/","url_meta":{"origin":1466862,"position":3},"title":"Ola de malestar en Espa\u00f1a por las declaraciones de Vinicius Jr. a CNN sobre el racismo en el pa\u00eds","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Hablar de racismo no le resulta f\u00e1cil, sobre todo porque lo ha vivido en su propia piel. Sin embargo, siempre que le preguntan al respecto, Vinicius Jr., jugador brasile\u00f1o del Real Madrid, encuentra las palabras con las que abordar el asunto. Incluso lo ha hecho entre l\u00e1grimas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451818,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/08\/13\/real-madrid-ofrecio-vinicius-jr-mil-millones-dolares-arabia-saudita-trax\/","url_meta":{"origin":1466862,"position":4},"title":"Vin\u00edcius Jr. habr\u00eda recibido una oferta por m\u00e1s de mil millones de d\u00f3lares para jugar en Arabia Saudita, seg\u00fan reportes","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN) --\u00a0 Seg\u00fan varios reportes, incluidos los de Reuters y ESPN, a la estrella del Real Madrid Vin\u00edcius Jr. le ofrecieron un lucrativo contrato por m\u00e1s de mil millones de d\u00f3lares para jugar en Arabia Saudita.Reuters, citando fuentes an\u00f3nimas, inform\u00f3 que Vin\u00edcius fue contactado por funcionarios saud\u00edes que le ofrecieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452198,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/08\/27\/vinicius-jr-real-madrid-balon-de-oro-kylian-mbappe-trax\/","url_meta":{"origin":1466862,"position":5},"title":"Favorito al Bal\u00f3n de Oro, Vin\u00edcius Jr., en exclusiva mundial: &#171;Quiero hacer historia con el Real Madrid&#187;","author":"","date":"agosto 27, 2024","format":false,"excerpt":"(CNN) -- La superestrella del Real Madrid Vin\u00edcius Jr. tiene la vista puesta en alcanzar logros a\u00fan m\u00e1s altos esta temporada, ya que el brasile\u00f1o dijo a CNN en la primera parte de una entrevista en exclusiva a nivel mundial que Los Blancos podr\u00edan ganar un triplete hist\u00f3rico esta temporada,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466862"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466862\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}