{"id":1466902,"date":"2025-09-27T10:03:45","date_gmt":"2025-09-27T17:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/"},"modified":"2025-09-27T10:03:45","modified_gmt":"2025-09-27T17:03:45","slug":"atletico-de-madrid-golea-real-madrid-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","title":{"rendered":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada"},"content":{"rendered":"<p>El Atl\u00e9tico de Madrid recuper\u00f3 la mejor de sus im\u00e1genes para golear 5-2 al Real Madrid en el derbi del Metropolitano, fulminando la racha de siete triunfos en la temporada de Xabi Alonso, con un doblete de Juli\u00e1n \u00c1lvarez m\u00e1s los goles de Robin Le Normand, Alexander Sorloth y Antoine Griezmann.<\/p>\n<p>El Barcelona tiene en su mano convertirse en el nuevo l\u00edder de LaLiga EA Sports, en su encuentro en Montjuic ante la Real Sociedad, tras la primera derrota del Real Madrid. El equipo de Xabi Alonso levant\u00f3 en el primer acto un tanto inicial de Le Normand, con pleno de efectividad en dos tiros a puerta de Kylian Mbapp\u00e9 y Arda G\u00fcler, antes de ser igualado en el a\u00f1adido con un testarazo de Sorloth.<\/p>\n<p>La segunda parte la domin\u00f3 el Atl\u00e9tico de Madrid, que aprovech\u00f3 un penal de G\u00fcler para adelantarse en el marcador a los 51 minutos con el lanzamiento de Juli\u00e1n \u00c1lvarez, que cerr\u00f3 su doblete con un gran gol de falta en el 63 para desatar la fiesta en la afici\u00f3n rojiblanca, euf\u00f3rica con el broche a la goleada en el a\u00f1adido marcado por Griezmann.<\/p>\n<p>El equipo rojiblanco recorta a 6 puntos la distancia con el Real Madrid en la clasificaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Atl\u00e9tico de Madrid recuper\u00f3 la mejor de sus im\u00e1genes para golear 5-2 al Real Madrid en el derbi del Metropolitano, fulminando la racha de siete triunfos en la temporada de Xabi Alonso, con un doblete de Juli\u00e1n \u00c1lvarez m\u00e1s los goles de Robin Le Normand, Alexander Sorloth y Antoine Griezmann. El Barcelona tiene en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466902","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Atl\u00e9tico de Madrid recuper\u00f3 la mejor de sus im\u00e1genes para golear 5-2 al Real Madrid en el derbi del Metropolitano, fulminando la racha de siete triunfos en la temporada de Xabi Alonso, con un doblete de Juli\u00e1n \u00c1lvarez m\u00e1s los goles de Robin Le Normand, Alexander Sorloth y Antoine Griezmann. El Barcelona tiene en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-27T17:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada\",\"datePublished\":\"2025-09-27T17:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\"},\"wordCount\":247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\",\"name\":\"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-27T17:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","og_locale":"es_ES","og_type":"article","og_title":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias","og_description":"El Atl\u00e9tico de Madrid recuper\u00f3 la mejor de sus im\u00e1genes para golear 5-2 al Real Madrid en el derbi del Metropolitano, fulminando la racha de siete triunfos en la temporada de Xabi Alonso, con un doblete de Juli\u00e1n \u00c1lvarez m\u00e1s los goles de Robin Le Normand, Alexander Sorloth y Antoine Griezmann. El Barcelona tiene en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","og_site_name":"Noticias","article_published_time":"2025-09-27T17:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/"},"author":{"name":"","@id":""},"headline":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada","datePublished":"2025-09-27T17:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/"},"wordCount":247,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","url":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","name":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-27T17:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Atl\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/27\/atletico-de-madrid-golea-real-madrid-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-27T17:03:45Z","datePublished":"2025-09-27T17:03:45Z","dateModified":"2025-09-27T17:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Atl\\u00e9tico de Madrid corta la racha triunfal del Real Madrid con una goleada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/27\\\/atletico-de-madrid-golea-real-madrid-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/27\\\/atletico-de-madrid-golea-real-madrid-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-27T17:03:45Z\",\"datePublished\":\"2025-09-27T17:03:45Z\",\"dateModified\":\"2025-09-27T17:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1453268,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/10\/01\/robin-le-normand-atletico-madrid-traumatismo-craneoencefalico-real-madrid-trax\/","url_meta":{"origin":1466902,"position":0},"title":"Diagnostican a Robin Le Normand del Atl\u00e9tico de Madrid de traumatismo craneoencef\u00e1lico tras incidente en partido contra el Real Madrid","author":"","date":"octubre 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Dos d\u00edas despu\u00e9s del partido de LaLiga entre el Atl\u00e9tico de Madrid y su rival local, el Real Madrid, el Atl\u00e9tico anunci\u00f3 que el defensa Robin Le Normand sufri\u00f3 un \"traumatismo craneoencef\u00e1lico\" al chocar con el mediocampista del Madrid Aur\u00e9lien Tchouam\u00e9ni al final del partido del domingo (1-1).A escasos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466872,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/26\/atletico-madrid-real-madrid-clasico-laliga-orix\/","url_meta":{"origin":1466902,"position":1},"title":"Atl\u00e9tico de Madrid vs. Real Madrid, por LaLiga: previa, horarios, posibles formaciones y c\u00f3mo ver por TV e internet","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"La capital de Espa\u00f1a se paraliza este s\u00e1bado con el cl\u00e1sico entre el Atl\u00e9tico de Madrid y el Real Madrid, v\u00e1lido por la s\u00e9ptima fecha de LaLiga. Ser\u00e1 un duelo entre equipos que pasan por momentos opuestos: la confianza de un \u201cMerengue\u201d que arrasa en el comienzo de la temporada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466530,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/16\/real-madrid-gana-marsella-champions-league-orix\/","url_meta":{"origin":1466902,"position":2},"title":"Real Madrid gan\u00f3 con algo de sufrimiento en la Champions League con dos penales de Mbapp\u00e9","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"No mereci\u00f3 sufrir tanto. Esa es la primera conclusi\u00f3n que deja el debut del Real Madrid en la Liga de Campeones 2025\/2026. El Merengue puso primera en el torneo recibiendo en el Bernab\u00e9u al Olympique Marsella de Francia, un rival que no hab\u00eda empezado bien la temporada, y lo derrot\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470011,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/01\/12\/real-madrid-despide-xabi-alonso-orix\/","url_meta":{"origin":1466902,"position":3},"title":"El Real Madrid se despide de Xabi Alonso","author":"","date":"enero 12, 2026","format":false,"excerpt":"La relaci\u00f3n entre el Real Madrid y Xabi Alonso no aguanto m\u00e1s. Despu\u00e9s del fracaso en la Supercopa de Espa\u00f1a, en la que su eterno rival el Barcelona se coron\u00f3 campe\u00f3n, el club blanco anunci\u00f3 la salida del director t\u00e9cnico por mutuo acuerdo.\u201cEl Real Madrid C. F. comunica que, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467793,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/10\/27\/vinicius-jr-enojo-xabi-alonso-real-madrid-barcelona-orix\/","url_meta":{"origin":1466902,"position":4},"title":"Los pormenores del enojo de Vin\u00edcius Jr. con Xabi Alonso en la victoria del Real Madrid sobre el Barcelona","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El cl\u00e1sico entre el Real Madrid y el FC Barcelona tuvo tres grandes protagonistas. El primero fue el club merengue, que se sacudi\u00f3 una racha de cuatro derrotas seguidas en cl\u00e1sicos contra el cuadro cul\u00e9 y se afianz\u00f3 en el liderato de LaLiga.En segundo lugar, Kylian Mbapp\u00e9, quien ratific\u00f3 su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470085,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/01\/14\/real-madrid-albacete-octavos-copa-del-rey-arbeloa-efe\/","url_meta":{"origin":1466902,"position":5},"title":"El debut de Arbeloa en el Real Madrid es un batacazo: eliminados de la Copa del Rey por un equipo de segunda divisi\u00f3n","author":"","date":"enero 14, 2026","format":false,"excerpt":"Lejos de arreglar cualquier problema del Real Madrid con Xabi Alonso, el estreno de \u00c1lvaro Arbeloa dej\u00f3 el peor sabor de boca posible con derrota y eliminaci\u00f3n de la Copa del Rey ante un Albacete que firm\u00f3 el primer triunfo de su historia frente al club blanco, encontrando el premio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466902"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466902\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}