{"id":1466965,"date":"2025-09-29T23:03:47","date_gmt":"2025-09-30T06:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/"},"modified":"2025-09-29T23:03:47","modified_gmt":"2025-09-30T06:03:47","slug":"huracan-tierra-cierre-gobierno-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","title":{"rendered":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?"},"content":{"rendered":"<p><a href=\"https:\/\/www.cnn.com\/2025\/09\/29\/weather\/hurricane-forecast-imelda-humberto-track-climate-hnk\">Los dos enormes sistemas tropicales<\/a> que se arremolinan frente a la costa sudeste son un duro recordatorio de que el potencial <a href=\"https:\/\/www.cnn.com\/2025\/09\/29\/politics\/government-shutdown-senate-trump\">cierre del Gobierno<\/a> se avecina en medio de la temporada de huracanes del Atl\u00e1ntico.<\/p>\n<p>Los meteor\u00f3logos de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) y los especialistas en respuesta a desastres de la Agencia Federal para el Manejo de Emergencias (FEMA por sus siglas en ingl\u00e9s) planean seguir trabajando durante el cierre, como ha sido el caso en cierres anteriores, pero una falla en la financiaci\u00f3n del Gobierno a\u00fan es probable que interrumpa los esfuerzos de preparaci\u00f3n y respuesta ante tormentas y huracanes y otros desastres, dijeron expertos a CNN.<\/p>\n<p>Tanto la NOAA como la FEMA est\u00e1n entrando en el cierre en estados debilitados, tras haber despedido a personal experimentado desde el inicio de la administraci\u00f3n Trump.<\/p>\n<p>En el Servicio Meteorol\u00f3gico Nacional, que forma parte de la NOAA, los gerentes est\u00e1n trabajando para cubrir la falta de personal contratando nuevos pronosticadores y trasladando a algunos meteor\u00f3logos a oficinas con escasez de personal.<\/p>\n<p>Sin embargo, el proceso de contrataci\u00f3n est\u00e1 resultando lent\u00edsimo, con las primeras ofertas de trabajo para varias docenas de t\u00e9cnicos electr\u00f3nicos, meteor\u00f3logos e hidr\u00f3logos reci\u00e9n salidos o a punto de salir, seg\u00fan el puesto.<\/p>\n<p>Una vez contratados, la formaci\u00f3n del nuevo personal llevar\u00e1 meses, y tampoco habr\u00e1 suficientes para compensar a toda la gente experimentada que la agencia perdi\u00f3.<\/p>\n<p>Un cierre probablemente ralentizar\u00eda a\u00fan m\u00e1s la contrataci\u00f3n.<\/p>\n<p>La agencia de pron\u00f3stico meteorol\u00f3gico tiene menos de 4.000 empleados por primera vez en d\u00e9cadas, habiendo perdido m\u00e1s de 560 personas por despidos, incentivos de jubilaci\u00f3n anticipada y otros programas de la administraci\u00f3n Trump destinados a reducir el tama\u00f1o del gobierno federal.<\/p>\n<p>Esto ha dejado a algunas oficinas locales de pron\u00f3stico del NWS sin suficiente personal para realizar lanzamientos de globos meteorol\u00f3gicos dos veces al d\u00eda y operar 24 horas al d\u00eda, 7 d\u00edas a la semana.<\/p>\n<p>Pero la agencia tiene suficiente personal para predecir con precisi\u00f3n tormentas tropicales y huracanes, dijo un funcionario de la NOAA que habl\u00f3 con CNN bajo condici\u00f3n de anonimato por temor a represalias.<\/p>\n<p>En el caso de la tormenta tropical Imelda, el funcionario dijo que la agencia est\u00e1 desplegando personal en las oficinas de pron\u00f3stico costeras en la trayectoria de la tormenta para ayudarlas a manejar la mayor carga de trabajo.<\/p>\n<p>Por lo general, durante los cierres gubernamentales, la mayor\u00eda de los pronosticadores y t\u00e9cnicos del NWS est\u00e1n exentos de ser suspendidos, o puestos en licencia sin goce de sueldo, y se espera que ese sea el caso si este ocurre, afirm\u00f3 el funcionario.<\/p>\n<p>Las tripulaciones que vuelan y mantienen los aviones de investigaci\u00f3n cazadores de huracanes de la agencia normalmente tambi\u00e9n est\u00e1n exentas, dijeron, por lo que los vuelos que tienen como objetivo mejorar la precisi\u00f3n del pron\u00f3stico tambi\u00e9n continuar\u00edan.<\/p>\n<p>Sin embargo, aunque la NOAA ha presentado su plan de cierre a la Oficina de Administraci\u00f3n y Presupuesto de la Casa Blanca, a\u00fan no ha escuchado qu\u00e9 partes de la agencia podr\u00e1n continuar operando.<\/p>\n<p>Otro funcionario de la NOAA, que habl\u00f3 bajo condici\u00f3n de anonimato porque no estaba autorizado a hablar con los medios, dijo a CNN que esto parec\u00eda ser una planificaci\u00f3n inusualmente tard\u00eda para un cierre que parece inminente.<\/p>\n<p>\u201cEs inusual que no tengamos ninguna orientaci\u00f3n en este momento, creo que es justo decir que es notable\u201d, dijeron.<\/p>\n<p>La portavoz de la NOAA, Kim Doster, solo dijo que los \u201cproductos y servicios\u201d de la agencia continuar\u00edan durante el cierre, pero no ofreci\u00f3 m\u00e1s detalles debido a la falta de detalles de la OMB.<\/p>\n<p>El personal que trabaje durante el cierre no recibir\u00e1 su salario, lo que har\u00e1 que un cierre a largo plazo sea a\u00fan m\u00e1s doloroso.<\/p>\n<p>Muchos empleados que operan los sat\u00e9lites de la NOAA tambi\u00e9n estar\u00edan exentos de la suspensi\u00f3n temporal de empleo, dijo el segundo funcionario de la NOAA. \u201cSomos una agencia de informaci\u00f3n, es fundamental que la informaci\u00f3n fluya\u201d.<\/p>\n<p>Dijeron que con toda probabilidad los pron\u00f3sticos de tormentas no sufrir\u00edan durante un cierre, pero no pod\u00edan decir lo mismo sobre los esfuerzos de respuesta a las tormentas, dadas las p\u00e9rdidas de personal de FEMA y los cambios en el liderazgo.<\/p>\n<p>\u201cSomos nosotros quienes les avisamos que viene, FEMA es quien los ayuda a sobrevivir\u201d, dijo el funcionario. \u201cCreo que el verdadero problema ser\u00e1 la respuesta\u201d.<\/p>\n<p>En FEMA, los funcionarios esperan con ansias ver c\u00f3mo la administraci\u00f3n gestionar\u00e1 tareas clave, como el despliegue de equipos en zonas de desastre, si se produce un cierre gubernamental. Con la moral ya desplomada, la plantilla menguante y el futuro de la agencia incierto, un cierre podr\u00eda llevar a FEMA peligrosamente al l\u00edmite.<\/p>\n<p>La mayor\u00eda del personal de FEMA recibe sus salarios a trav\u00e9s del Fondo de Ayuda para Desastres, lo que los protege de un cierre, y los l\u00edderes pueden reincorporar a los trabajadores suspendidos para la respuesta ante desastres.<\/p>\n<p>Sin embargo, la columna vertebral de la agencia \u2014sus equipos administrativos y de apoyo en la sede y las oficinas regionales\u2014 podr\u00eda verse obligada a trabajar sin sueldo hasta que finalice el impasse.<\/p>\n<p>Si la Casa Blanca limita la definici\u00f3n de \u201cpersonal esencial\u201d, la agencia podr\u00eda perder a\u00fan m\u00e1s trabajadores durante un cierre, adem\u00e1s de las fuertes p\u00e9rdidas por despidos y adquisiciones de este a\u00f1o, que ya le han costado a FEMA alrededor de un tercio de su personal de tiempo completo seg\u00fan algunas estimaciones, incluidos muchos l\u00edderes veteranos.<\/p>\n<p>Deanne Criswell, quien dirigi\u00f3 FEMA bajo la presidencia de Biden y prepar\u00f3 a la agencia para varias situaciones de cierre inminente, dijo que un cierre probablemente dejar\u00eda a muchas menos personas en roles de liderazgo y apoyo para guiar a los equipos de respuesta ante desastres.<\/p>\n<p>Este es s\u00f3lo un obst\u00e1culo m\u00e1s para una agencia que ya est\u00e1 bajo escrutinio adicional por parte de la Secretaria de Seguridad Nacional, Kristi Noem, quien ahora debe aprobar cada subvenci\u00f3n y contrato de m\u00e1s de US$ 100.000.<\/p>\n<p>\u201cEsto afectar\u00e1 la capacidad de FEMA para contar con los recursos necesarios para realizar su trabajo\u201d, dijo Criswell. \u201cY cada uno de estos eventos posteriores, como un cierre gubernamental, simplemente llevar\u00e1 a m\u00e1s personas a ese punto cr\u00edtico\u201d.<\/p>\n<p>Si se necesita personal en persona pero no se le paga, el estr\u00e9s financiero podr\u00eda golpear r\u00e1pidamente, ya que las personas acumulan gastos de manutenci\u00f3n sin un cheque de pago.<\/p>\n<p>\u201cEl personal que sigue trabajando estar\u00e1 menos preparado por no recibir su salario\u201d, declar\u00f3 a CNN un veterano funcionario de FEMA que trabaja en respuesta a desastres. \u201cBas\u00e1ndome en todos los intentos de esta Administraci\u00f3n por politizar la ayuda y frustrar al personal de carrera, preveo que un cierre ser\u00e1 innecesariamente dif\u00edcil. Simplemente no est\u00e1 claro c\u00f3mo\u201d.<\/p>\n<p>FEMA depende de la ayuda de otras agencias federales para responder a los desastres, por lo que las licencias prolongadas en otras partes podr\u00edan <strong><\/strong>arruinar toda la operaci\u00f3n, incluso si FEMA permanece pr\u00e1cticamente intacta.<\/p>\n<p>Dentro de FEMA, probablemente solo continuar\u00edan las labores relacionadas con desastres. Todo lo financiado por el presupuesto operativo general de la agencia, incluidos los programas clave de resiliencia y mitigaci\u00f3n, se paralizar\u00eda, afirm\u00f3 Criswell.<\/p>\n<p>El seguro contra inundaciones del Gobierno, conocido como el Programa Nacional de Seguros contra Inundaciones (NFIP, por sus siglas en ingl\u00e9s), tambi\u00e9n vence el 30 de septiembre. Despu\u00e9s de esta fecha, FEMA no emitir\u00e1 nuevas p\u00f3lizas, pero seguir\u00e1 ofreciendo pagos para reclamaciones v\u00e1lidas con fondos disponibles.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los dos enormes sistemas tropicales que se arremolinan frente a la costa sudeste son un duro recordatorio de que el potencial cierre del Gobierno se avecina en medio de la temporada de huracanes del Atl\u00e1ntico. Los meteor\u00f3logos de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) y los especialistas en respuesta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466965","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los dos enormes sistemas tropicales que se arremolinan frente a la costa sudeste son un duro recordatorio de que el potencial cierre del Gobierno se avecina en medio de la temporada de huracanes del Atl\u00e1ntico. Los meteor\u00f3logos de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) y los especialistas en respuesta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T06:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?\",\"datePublished\":\"2025-09-30T06:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\"},\"wordCount\":1371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\",\"name\":\"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-30T06:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias","og_description":"Los dos enormes sistemas tropicales que se arremolinan frente a la costa sudeste son un duro recordatorio de que el potencial cierre del Gobierno se avecina en medio de la temporada de huracanes del Atl\u00e1ntico. Los meteor\u00f3logos de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) y los especialistas en respuesta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-30T06:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?","datePublished":"2025-09-30T06:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/"},"wordCount":1371,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","name":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-30T06:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-30T06:03:47Z","datePublished":"2025-09-30T06:03:47Z","dateModified":"2025-09-30T06:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 sucede si un hurac\\u00e1n toca tierra mientras el Gobierno de EE.UU. est\\u00e1 cerrado?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/29\\\/huracan-tierra-cierre-gobierno-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/29\\\/huracan-tierra-cierre-gobierno-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-30T06:03:47Z\",\"datePublished\":\"2025-09-30T06:03:47Z\",\"dateModified\":\"2025-09-30T06:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463440,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/06\/11\/trump-eliminar-fema-temporada-huracanes-trax\/","url_meta":{"origin":1466965,"position":0},"title":"Trump dice que planea eliminar gradualmente FEMA despu\u00e9s de la temporada de huracanes de 2025","author":"","date":"junio 11, 2025","format":false,"excerpt":"El presidente Donald Trump dijo este martes que planea eliminar gradualmente la Agencia Federal para el Manejo de Emergencias (FEMA, por sus siglas en ingl\u00e9s) despu\u00e9s de la temporada de huracanes de este a\u00f1o, ofreciendo el cronograma m\u00e1s claro hasta el momento de los planes a largo plazo de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463067,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/06\/01\/temporada-huracanes-2025-agencias-meteorologicas-trax\/","url_meta":{"origin":1466965,"position":1},"title":"La temporada de huracanes 2025 llega en medio del desmantelamiento de agencias meteorol\u00f3gicas: \u00bfcu\u00e1ntas tormentas habr\u00e1?","author":"","date":"junio 1, 2025","format":false,"excerpt":"El comienzo de otra temporada de huracanes, que promete estar por encima de la media, encuentra a las agencias meteorol\u00f3gicas y de respuesta a desastres de Estados Unidos m\u00e1s desbordadas que nunca, lo que podr\u00eda dejar a decenas de millones de estadounidenses en una situaci\u00f3n m\u00e1s vulnerable ante estas enormes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462683,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/05\/22\/pronostico-huracanes-2025-cuantos-trax\/","url_meta":{"origin":1466965,"position":2},"title":"La temporada de huracanes 2025 llega en medio del desmantelamiento de agencias meteorol\u00f3gicas: \u00bfcu\u00e1ntas tormentas habr\u00e1?","author":"","date":"mayo 22, 2025","format":false,"excerpt":"El comienzo de otra temporada de huracanes, que promete estar por encima de la media, encuentra a las agencias meteorol\u00f3gicas y de respuesta a desastres de Estados Unidos m\u00e1s desbordadas que nunca, lo que podr\u00eda dejar a decenas de millones de estadounidenses en una situaci\u00f3n m\u00e1s vulnerable ante estas enormes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467905,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/10\/31\/cazadores-huracanes-sin-cobrar-cierre-gobierno-trax\/","url_meta":{"origin":1466965,"position":3},"title":"Melissa fue uno de los ciclones m\u00e1s fuertes registrados. Los cazadores de huracanes de la NOAA volaron hacia \u00e9l sin cobrar","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Azotados por vientos violentos y fuertes turbulencias, los cazadores de huracanes de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) han pasado la \u00faltima semana sumergi\u00e9ndose en el ojo de Melissa, un cicl\u00f3n de ferocidad hist\u00f3rica, para recopilar datos vitales. Lo han hecho sin descanso, las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464378,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/07\/09\/burocracia-respuesta-fema-inundaciones-texas-trax\/","url_meta":{"origin":1466965,"position":4},"title":"La burocracia ralentiz\u00f3 la respuesta de FEMA a las inundaciones en Texas","author":"","date":"julio 9, 2025","format":false,"excerpt":"Mientras enormes inundaciones arrasaban el centro de Texas a finales de la semana pasada, funcionarios de la Agencia Federal para el Manejo de Emergencias (FEMA, por sus siglas en ingl\u00e9s) actuaron de inmediato, prepar\u00e1ndose para desplegar equipos cr\u00edticos de b\u00fasqueda y rescate y recursos vitales, como lo han hecho en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465057,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/08\/02\/fema-liberar-fondos-seguridad-informe-cnn-trax\/","url_meta":{"origin":1466965,"position":5},"title":"FEMA planea liberar casi US$ 1.000 millones en fondos de seguridad tras informe de CNN sobre propuesta de recorte","author":"","date":"agosto 2, 2025","format":false,"excerpt":"La Agencia Federal para el Manejo de Emergencias (FEMA, por sus siglas en ingl\u00e9s) est\u00e1 poniendo a disposici\u00f3n de comunidades de todo el pa\u00eds casi US$ 1.000 millones en fondos para preparaci\u00f3n ante desastres y seguridad nacional, solo una semana despu\u00e9s de que CNN informara sobre el plan propuesto por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466965"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466965\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}