{"id":1466971,"date":"2025-09-30T03:03:49","date_gmt":"2025-09-30T10:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/"},"modified":"2025-09-30T03:03:49","modified_gmt":"2025-09-30T10:03:49","slug":"congreso-cierre-de-gobierno-probabilidades-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","title":{"rendered":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras"},"content":{"rendered":"<p>A menos de 24 horas de un posible <a href=\"https:\/\/www.cnn.com\/2025\/09\/26\/politics\/government-shutdown-september-2025-explained\">cierre del Gobierno<\/a>, los republicanos del Senado dar\u00e1n a los dem\u00f3cratas una \u00faltima oportunidad para apoyar su plan para mantener las luces encendidas a partir de la medianoche. Pero dentro del Capitolio, pocos creen que los dem\u00f3cratas est\u00e9n dispuestos a ceder.<\/p>\n<p>El amargo estancamiento entre republicanos y dem\u00f3cratas en las \u00faltimas semanas (centrado en gran medida en torno a miles de millones de d\u00f3lares en subsidios mejorados de la Ley de Atenci\u00f3n M\u00e9dica Asequible) ahora parece probable que resulte en el primer lapso de financiaci\u00f3n gubernamental de la segunda administraci\u00f3n del presidente Donald Trump.<\/p>\n<p>Cualquier esperanza de un acuerdo de \u00faltima hora se desvaneci\u00f3 este lunes por la tarde, despu\u00e9s de que una reuni\u00f3n crucial en el Despacho Oval con <a href=\"https:\/\/www.cnn.com\/politics\/president-donald-trump-47\">el presidente Donald Trump<\/a> y los principales l\u00edderes del Congreso no produjera ning\u00fan avance en las negociaciones de financiaci\u00f3n.<\/p>\n<p>Ahora, antes de la medianoche, el Senado tiene previsto votar al menos una vez m\u00e1s sobre <a href=\"https:\/\/www.cnn.com\/2025\/09\/19\/politics\/government-funding-bill-shutdown-house-senate\" rel=\"noopener noreferrer\" target=\"_blank\">un plan de financiaci\u00f3n republicano<\/a> que los dem\u00f3cratas ya han rechazado.<\/p>\n<p>La medida del l\u00edder de la mayor\u00eda del Senado, John Thune, busca maximizar la presi\u00f3n sobre su hom\u00f3logo, el l\u00edder de la minor\u00eda del Senado, Chuck Schumer, quien hasta ahora ha bloqueado un plan para un proyecto de ley de financiaci\u00f3n sin cambios, sin compromisos para extender los subsidios del Obamacare.<\/p>\n<p>Schumer, por su parte, afirm\u00f3 que el resultado depende de Trump y sus l\u00edderes republicanos.<\/p>\n<p>\u201cAhora est\u00e1 en manos del presidente. Puede evitar un cierre si logra que el l\u00edder republicano acepte lo que queremos\u201d, declar\u00f3 Schumer este lunes por la noche, horas despu\u00e9s de que los cuatro principales l\u00edderes del Congreso se reunieran con Trump para <a href=\"https:\/\/www.cnn.com\/2025\/09\/29\/politics\/democrats-trump-meeting-health-care-shutdown\">una reuni\u00f3n de \u00faltimo momento<\/a> en la Casa Blanca.<\/p>\n<p>Pero los republicanos han acusado a Schumer de mantener como reh\u00e9n el financiamiento del Gobierno en pos de sus demandas e insisten en que cualquier negociaci\u00f3n sobre esos cr\u00e9ditos fiscales no deber\u00eda estar vinculada a mantener abierto el aparato gubernamental.<\/p>\n<p>Incluso uno de los mayores defensores del Partido Republicano en el Senado a favor de extender esos cr\u00e9ditos, el senador Josh Hawley de Missouri, dijo que no cree que los dem\u00f3cratas deban obligar al Gobierno a un cierre por este tema.<\/p>\n<p>\u201cNo entiendo qu\u00e9 tiene que ver el cierre del Gobierno con eso\u201d, dijo Hawley. \u201cMi mensaje para ellos es: \u2018Oigan, trabajar\u00e9 con ustedes en todo eso. Creo que hay muchos puntos en com\u00fan, pero dejemos de lado la financiaci\u00f3n del Gobierno\u2019\u201d.<\/p>\n<p>Thune y su conferencia republicana llevan mucho tiempo creyendo que Schumer ceder\u00e1, sobre todo porque la propia oficina de presupuesto de la Casa Blanca ha <a href=\"https:\/\/www.cnn.com\/2025\/09\/26\/politics\/government-shutdown-trump-firing-memo-democrats\">amenazado con despidos masivos<\/a> si el Congreso permite un cierre y cede parte de su autoridad presupuestaria al poder ejecutivo.<\/p>\n<p>Y si se produce un cierre, la sensaci\u00f3n predominante entre los republicanos del Congreso es que los votantes culpar\u00e1n a los dem\u00f3cratas por sus exigencias, no al Partido Republicano que propone un acuerdo de financiaci\u00f3n sin condiciones.<\/p>\n<p>\u201cSi quieren tener ese debate, es un debate que hay que tener. No se puede usar la financiaci\u00f3n del Gobierno como reh\u00e9n para ello\u201d, dijo el senador republicano Eric Schmitt de Missouri.<\/p>\n<p>\u201cChuck Schumer le teme a su propia sombra y no quiere que se le perciba como colaborador del presidente Trump\u201d, dijo Schmitt. \u201cEs una pena, porque creo que el pueblo estadounidense va a sufrir por ello\u201d.<\/p>\n<p>Cuando se le pregunt\u00f3 si hay margen para negociar los subsidios del Obamacare antes de la medianoche del martes, el senador republicano John Kennedy dijo: \u201cNo, a menos que Chuck deje de fumar marihuana\u201d.<\/p>\n<p>\u201cPodemos negociar los subsidios del Obamacare y su reforma, pero no podemos hacerlo ma\u00f1ana a medianoche\u201d, a\u00f1adi\u00f3 Kennedy. \u201cEso es lo que exigi\u00f3 el senador Schumer, y es una propuesta muy poco seria. Chuck quiere un cierre del Gobierno\u201d.<\/p>\n<p>Los dem\u00f3cratas han dejado claro durante semanas que quieren una concesi\u00f3n de Trump en materia de salud a cambio de ayudar a mantener el Gobierno en funcionamiento.<\/p>\n<p>En los \u00faltimos d\u00edas, Schumer y Jeffries han argumentado que cualquier acuerdo sobre salud, como esos subsidios, debe promulgarse. Creen que es la \u00fanica manera de garantizar que el presidente cumpla su palabra.<\/p>\n<p>\u201cTenemos que lidiar con el colapso de la atenci\u00f3n m\u00e9dica. Nos estamos desmoronando, y no podemos dejar a los habitantes de Vermont y a los estadounidenses abandonados a su suerte\u201d, dijo el senador dem\u00f3crata Peter Welch. \u201cNecesitamos que el presidente reconozca que debe acatar las autorizaciones de gasto del Congreso\u201d.<\/p>\n<p>Welch expres\u00f3 su escepticismo sobre que ambas partes lleguen a un acuerdo antes de la medianoche de ma\u00f1ana.<\/p>\n<p>\u201cCreo que las probabilidades est\u00e1n en contra en este momento, y lo digo con mucho pesar\u201d, dijo Welch sobre la posibilidad de llegar a un acuerdo, y agreg\u00f3: \u201cMi esperanza es que mantengamos las luces encendidas, y si se apagan, quiero que se vuelvan a encender lo antes posible\u201d.<\/p>\n<p>El senador John Fetterman, el \u00fanico dem\u00f3crata que vot\u00f3 a favor del plan de financiaci\u00f3n del Partido Republicano durante una votaci\u00f3n fallida la semana pasada, dijo que est\u00e1 preocupado por los millones de personas cuyas vidas podr\u00edan verse afectadas por un cierre gubernamental.<\/p>\n<p>\u201cCorren el riesgo de sumir a nuestra naci\u00f3n en el caos. Millones y millones de vidas se ver\u00e1n trastocadas\u201d, dijo. \u201c\u00bfQu\u00e9 mensaje transmite esto a nuestro pa\u00eds, a nuestros aliados y a nuestros enemigos?\u201d<\/p>\n<p>Los l\u00edderes republicanos en el Senado est\u00e1n decidiendo un plan: seguir votando sobre una extensi\u00f3n de financiaci\u00f3n de siete semanas hasta que los dem\u00f3cratas finalmente capitulen.<\/p>\n<p>La creencia entre los principales republicanos es que los dem\u00f3cratas comenzar\u00e1n a ceder despu\u00e9s de escuchar las protestas p\u00fablicas por la p\u00e9rdida de servicios gubernamentales cr\u00edticos y cuando los empleados federales sean suspendidos o incluso despedidos.<\/p>\n<p>El proyecto de ley republicano, aprobado en la C\u00e1mara de Representantes a principios de este mes en gran medida siguiendo las l\u00edneas del partido, extender\u00eda la financiaci\u00f3n del Gobierno hasta finales de noviembre y no incluye disposiciones pol\u00edticas superfluas.<\/p>\n<p>Sin embargo, junto con el vencimiento de los subsidios del Obamacare, los dem\u00f3cratas han exigido que se reviertan los recortes a Medicaid promulgados bajo la \u201cGran y Hermosa Ley\u201d de Trump, y que se limite su capacidad para recortar el gasto federal sin el consentimiento del Capitolio.<\/p>\n<p>Thune y el presidente de la C\u00e1mara de Representantes, Mike Johnson, al salir de la reuni\u00f3n a puertas cerradas del lunes por la tarde con Trump, dijeron que creen que la posici\u00f3n dem\u00f3crata es insostenible y que planean presionar a los dem\u00f3cratas con votaciones repetidas sobre la medida provisional.<\/p>\n<p>\u201cS\u00ed\u201d, dijo a CNN el l\u00edder de la mayor\u00eda del Senado, John Barrasso, cuando se le pregunt\u00f3 si seguir\u00edan programando votaciones sobre el plan republicano. Barrasso afirm\u00f3 que mantendr\u00edan este enfoque \u201chasta que el Gobierno vuelva a funcionar tras el fin del cierre de Schumer\u201d.<\/p>\n<p>Al salir de la reuni\u00f3n de los l\u00edderes republicanos del Senado el lunes por la noche, el senador Markwayne Mullin coincidi\u00f3 con la t\u00e1ctica. \u201cLo volveremos a poner en el pleno\u201d si el paquete no avanza el martes.<\/p>\n<p>\u201cNo hay otra opci\u00f3n\u201d, dijo Mullin.<\/p>\n<p>El senador Kevin Cramer, republicano de Dakota del Norte, predijo que incluso si hay un cierre del Gobierno, los dem\u00f3cratas no podr\u00e1n resistir por mucho tiempo.<\/p>\n<p>\u201cCreo que mi sensaci\u00f3n es que, si hay un cierre, ser\u00e1 breve, porque no creo que 47 senadores dem\u00f3cratas quieran arriesgarse en algo que, quiero decir, seamos sinceros, financiar el Gobierno para los dem\u00f3cratas es como caerse de un tronco\u201d, dijo.<\/p>\n<p>\u201cEs lo que hacen. Es lo que les apasiona. As\u00ed que no veo, ni siquiera a Chuck Schumer, mantenerse firme por mucho tiempo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A menos de 24 horas de un posible cierre del Gobierno, los republicanos del Senado dar\u00e1n a los dem\u00f3cratas una \u00faltima oportunidad para apoyar su plan para mantener las luces encendidas a partir de la medianoche. Pero dentro del Capitolio, pocos creen que los dem\u00f3cratas est\u00e9n dispuestos a ceder. El amargo estancamiento entre republicanos y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466971","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias\" \/>\n<meta property=\"og:description\" content=\"A menos de 24 horas de un posible cierre del Gobierno, los republicanos del Senado dar\u00e1n a los dem\u00f3cratas una \u00faltima oportunidad para apoyar su plan para mantener las luces encendidas a partir de la medianoche. Pero dentro del Capitolio, pocos creen que los dem\u00f3cratas est\u00e9n dispuestos a ceder. El amargo estancamiento entre republicanos y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T10:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras\",\"datePublished\":\"2025-09-30T10:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\"},\"wordCount\":1398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\",\"name\":\"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-30T10:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias","og_description":"A menos de 24 horas de un posible cierre del Gobierno, los republicanos del Senado dar\u00e1n a los dem\u00f3cratas una \u00faltima oportunidad para apoyar su plan para mantener las luces encendidas a partir de la medianoche. Pero dentro del Capitolio, pocos creen que los dem\u00f3cratas est\u00e9n dispuestos a ceder. El amargo estancamiento entre republicanos y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-30T10:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/"},"author":{"name":"","@id":""},"headline":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras","datePublished":"2025-09-30T10:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/"},"wordCount":1398,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","name":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-30T10:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"http:\/\/noticiasya.com\/monterey-salinas\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Congreso de EE.UU. tiene un d\u00eda m\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/congreso-cierre-de-gobierno-probabilidades-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-30T10:03:49Z","datePublished":"2025-09-30T10:03:49Z","dateModified":"2025-09-30T10:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Congreso de EE.UU. tiene un d\\u00eda m\\u00e1s para evitar un cierre del Gobierno. Las probabilidades no son alentadoras\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/30\\\/congreso-cierre-de-gobierno-probabilidades-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/30\\\/congreso-cierre-de-gobierno-probabilidades-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-30T10:03:49Z\",\"datePublished\":\"2025-09-30T10:03:49Z\",\"dateModified\":\"2025-09-30T10:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466948,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/29\/amenaza-cierre-gobierno-capitolio-atrinchera-trax\/","url_meta":{"origin":1466971,"position":0},"title":"&#171;Prep\u00e1rense&#187;: la amenaza de cierre del Gobierno se profundiza mientras el Capitolio se atrinchera","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"El presidente Donald Trump y los republicanos en el Congreso creen que hay solo una manera de evitar un cierre a la medianoche del martes: que el l\u00edder dem\u00f3crata del Senado, Chuck Schumer, cambie de opini\u00f3n.Los l\u00edderes republicanos a\u00fan necesitan votos cruciales de Schumer y su partido para que cualquier\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467928,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/11\/01\/analisis-trump-arruinar-estrategia-republicanos-cierre-gobierno-trax\/","url_meta":{"origin":1466971,"position":1},"title":"Trump acaba de arruinar la estrategia de los l\u00edderes republicanos sobre el cierre del Gobierno de EE.UU.","author":"","date":"noviembre 1, 2025","format":false,"excerpt":"Tras casi un mes de cierre del Gobierno, el presidente Donald Trump, que se hab\u00eda mantenido notablemente callado, finalmente intervino con una propuesta para ponerle fin.Los l\u00edderes republicanos del Congreso probablemente desear\u00edan que no lo hubiera hecho.Trump inst\u00f3 este jueves a los republicanos a poner fin al cierre del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468141,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/11\/08\/democratas-bloquean-proyecto-republicano-cierre-gobierno-trax\/","url_meta":{"origin":1466971,"position":2},"title":"Dem\u00f3cratas del Senado bloquean proyecto republicano para pagar a trabajadores federales y se agrava el cierre del Gobierno","author":"","date":"noviembre 8, 2025","format":false,"excerpt":"El Senado de EE.UU. no logr\u00f3 aprobar un proyecto de ley este viernes para pagar a los trabajadores federales forzados a trabajar sin sueldo durante el cierre del Gobierno, ya que los dem\u00f3cratas se negaron a ceder ante los intentos republicanos de financiar cualquier parte del aparato gubernamental sin importantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470578,"url":"https:\/\/noticiasya.com\/el-centro\/2026\/01\/28\/democratas-reforma-ice-cierre-gobierno-trax\/","url_meta":{"origin":1466971,"position":3},"title":"Dem\u00f3cratas exigen una reforma profunda a ICE, mientras aumenta el riesgo de cierre del Gobierno","author":"","date":"enero 28, 2026","format":false,"excerpt":"Los dem\u00f3cratas en el Congreso se oponen a cualquier acuerdo de financiamiento con el presidente Donald Trump esta semana que no incluya cambios significativos en la aplicaci\u00f3n de las leyes migratorias federales, lo que incrementa notablemente las probabilidades de un cierre del Gobierno al final de la semana.En el Capitolio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467937,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/11\/01\/cierre-gobierno-efectos-trax\/","url_meta":{"origin":1466971,"position":4},"title":"&#171;El problema es que todos quieren ganar&#187;: el Congreso est\u00e1 en un punto muerto, mientras los efectos del cierre aumentan","author":"","date":"noviembre 1, 2025","format":false,"excerpt":"El cierre del Gobierno est\u00e1 a punto de convertirse en el m\u00e1s largo de la historia de EE.UU., y los legisladores a\u00fan no saben cu\u00e1nto m\u00e1s durar\u00e1.En Washington, los senadores se fueron de la ciudad el fin de semana, estancados y m\u00e1s frustrados que nunca, mientras que por primera vez\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467628,"url":"https:\/\/noticiasya.com\/el-centro\/2025\/10\/22\/republicanos-involucrar-trump-negociaciones-cierre-gobierno-rechazo-lideres-trax\/","url_meta":{"origin":1466971,"position":5},"title":"Algunos republicanos dicen que Trump debe involucrarse en negociaciones del cierre del Gobierno. Sus l\u00edderes rechazan la idea","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Los l\u00edderes republicanos se han mantenido firmes en una posici\u00f3n sencilla en su enfrentamiento con los dem\u00f3cratas sobre el financiamiento del Gobierno: no habr\u00e1 negociaciones hasta que termine el cierre gubernamental.Pero a medida que el impasse se prolonga, algunos republicanos de base est\u00e1n empezando a preguntarse si es hora de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466971"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466971\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}