{"id":1466972,"date":"2025-09-30T03:03:49","date_gmt":"2025-09-30T10:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/"},"modified":"2025-09-30T03:03:49","modified_gmt":"2025-09-30T10:03:49","slug":"eeuu-presencia-permanente-drones-corea-sur-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","title":{"rendered":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur"},"content":{"rendered":"<p>La Fuerza A\u00e9rea de Estados Unidos est\u00e1 instalando una presencia permanente de drones en la pen\u00ednsula de Corea, reviviendo un escuadr\u00f3n de la Segunda Guerra Mundial para reforzar la seguridad en medio de crecientes tensiones militares en la regi\u00f3n.<\/p>\n<p>El 431.\u00ba Escuadr\u00f3n de Reconocimiento Expedicionario se activ\u00f3 el lunes en la Base A\u00e9rea de Kunsan, en la costa oeste de Corea del Sur, al sur de la capital, Se\u00fal. Desde la instalaci\u00f3n, volar\u00e1 drones MQ-9 Reaper.<\/p>\n<p>Se trata de otra medida para fortalecer la capacidad a\u00e9rea de las fuerzas estadounidenses en la pen\u00ednsula, tras el reposicionamiento de cazas F-16 m\u00e1s cerca de Corea del Norte en los \u00faltimos meses. Esto tambi\u00e9n ocurre pocas semanas despu\u00e9s de que el l\u00edder norcoreano, Kim Jong-un, <a href=\"https:\/\/www.cnn.com\/2025\/09\/04\/china\/china-xi-kim-meeting-military-parade-intl-hnk\">se presentara hombro con hombro<\/a> con el l\u00edder chino, Xi Jinping, en un multitudinario <a href=\"https:\/\/www.cnn.com\/2025\/09\/03\/china\/china-military-parade-authoritarian-leaders-intl-hnk\">desfile militar<\/a> en Beijing.<\/p>\n<p>Los Reapers son aviones turboh\u00e9lice monomotor no tripulados que pueden realizar una variedad de misiones de combate y otras misiones, seg\u00fan una hoja informativa de la Fuerza A\u00e9rea.<\/p>\n<p>Con un alcance extendido de m\u00e1s de 2.575 kil\u00f3metros (1.600 millas) y la capacidad de permanecer en el aire indefinidamente con reabastecimiento de combustible a\u00e9reo, los Reapers proporcionar\u00e1n un impulso sustancial a las fuerzas estadounidenses en la regi\u00f3n.<\/p>\n<p>El alcance de los Reapers no solo cubre Corea del Norte (la zona desmilitarizada (DMZ) entre Corea del Norte y Corea del Sur est\u00e1 a unos 240 km al norte de Kunsan), sino tambi\u00e9n el Mar de China Oriental y Taiw\u00e1n, a unos 1.285 km de distancia.<\/p>\n<p>\u201cLas operaciones del MQ-9 apoyar\u00e1n las prioridades de inteligencia, vigilancia y reconocimiento entre Estados Unidos y Corea en todo el teatro de operaciones del Indopac\u00edfico\u201d, declar\u00f3 la Fuerza A\u00e9rea. La regi\u00f3n militar se extiende desde las aguas de la costa oeste de Estados Unidos hasta la frontera occidental de la India, y desde la Ant\u00e1rtida hasta el Polo Norte.<\/p>\n<p>\u201cEl despliegue del MQ-9 aporta una poderosa capacidad a la regi\u00f3n\u201d, dijo el teniente coronel Douglas Slater, quien comandar\u00e1 el escuadr\u00f3n, en un comunicado.<\/p>\n<p>\u201cEstamos aqu\u00ed para apoyar la misi\u00f3n, profundizar la cooperaci\u00f3n y demostrar nuestro compromiso compartido de mantener la seguridad y la estabilidad en todo el Indo-Pac\u00edfico\u201d, dijo Slater.<\/p>\n<p>Para misiones de combate, los MQ-9 pueden transportar una variedad de armas, desde misiles Hellfire hasta bombas guiadas por l\u00e1ser.<\/p>\n<p>El estacionamiento permanente de los Reapers en Kunsan muestra el compromiso de Washington con Corea del Sur y sus otros aliados y socios del Pac\u00edfico en un momento en que algunos han expresado dudas al respecto, mientras la administraci\u00f3n Trump analiza los desaf\u00edos de seguridad m\u00e1s cerca de casa.<\/p>\n<p>No se anunci\u00f3 cu\u00e1ntos Reapers estar\u00edan estacionados en Kunsan, pero una hoja informativa de la Fuerza A\u00e9rea muestra 50 en el inventario del Comando de Operaciones Especiales de EE. UU. a partir de enero.<\/p>\n<p>La designaci\u00f3n de la unidad de drones como el escuadr\u00f3n 431 revive un nombre que se remonta a la Segunda Guerra Mundial, cuando se activ\u00f3 en 1943 como el Escuadr\u00f3n de Cazas 431 en Australia, volando cazas de largo alcance P-38 Lightning como escoltas para los bombarderos estadounidenses en el teatro del Pac\u00edfico.<\/p>\n<p>El 431.\u00ba estuvo activo por \u00faltima vez como escuadr\u00f3n de pruebas para aviones F-111 en California y cerr\u00f3 en 1992.<\/p>\n<p>La activaci\u00f3n del escuadr\u00f3n en Corea del Sur es el segundo gran movimiento del a\u00f1o de la Fuerza A\u00e9rea en la pen\u00ednsula.<\/p>\n<p>En julio, el servicio comenz\u00f3 a trasladar aviones de combate F-16 desde Kunsan, a poco m\u00e1s de 80 millas al norte, a la base a\u00e9rea de Osan, para formar lo que llama un \u201csuperescuadr\u00f3n\u201d m\u00e1s cerca de Corea del Norte.<\/p>\n<p>Un total de 31 F-16 y 1.000 efectivos ser\u00e1n trasladados de Kunsan a Osan en octubre, dijo la Fuerza A\u00e9rea en un comunicado en julio.<\/p>\n<p>Se espera que la transferencia temporal dure hasta octubre del pr\u00f3ximo a\u00f1o para ver si puede \u201cmaximizar las capacidades y aumentar la efectividad del combate en la Pen\u00ednsula de Corea\u201d, seg\u00fan un comunicado de la Fuerza A\u00e9rea.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fuerza A\u00e9rea de Estados Unidos est\u00e1 instalando una presencia permanente de drones en la pen\u00ednsula de Corea, reviviendo un escuadr\u00f3n de la Segunda Guerra Mundial para reforzar la seguridad en medio de crecientes tensiones militares en la regi\u00f3n. El 431.\u00ba Escuadr\u00f3n de Reconocimiento Expedicionario se activ\u00f3 el lunes en la Base A\u00e9rea de Kunsan, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466972","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Fuerza A\u00e9rea de Estados Unidos est\u00e1 instalando una presencia permanente de drones en la pen\u00ednsula de Corea, reviviendo un escuadr\u00f3n de la Segunda Guerra Mundial para reforzar la seguridad en medio de crecientes tensiones militares en la regi\u00f3n. El 431.\u00ba Escuadr\u00f3n de Reconocimiento Expedicionario se activ\u00f3 el lunes en la Base A\u00e9rea de Kunsan, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T10:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur\",\"datePublished\":\"2025-09-30T10:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\"},\"wordCount\":749,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\",\"name\":\"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-30T10:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias","og_description":"La Fuerza A\u00e9rea de Estados Unidos est\u00e1 instalando una presencia permanente de drones en la pen\u00ednsula de Corea, reviviendo un escuadr\u00f3n de la Segunda Guerra Mundial para reforzar la seguridad en medio de crecientes tensiones militares en la regi\u00f3n. El 431.\u00ba Escuadr\u00f3n de Reconocimiento Expedicionario se activ\u00f3 el lunes en la Base A\u00e9rea de Kunsan, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-30T10:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur","datePublished":"2025-09-30T10:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/"},"wordCount":749,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","name":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-30T10:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur","url":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-centro\/2025\/09\/30\/eeuu-presencia-permanente-drones-corea-sur-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-30T10:03:49Z","datePublished":"2025-09-30T10:03:49Z","dateModified":"2025-09-30T10:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. recrea unidad de la Segunda Guerra Mundial para establecer una presencia permanente de drones en Corea del Sur\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/30\\\/eeuu-presencia-permanente-drones-corea-sur-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-centro\\\/2025\\\/09\\\/30\\\/eeuu-presencia-permanente-drones-corea-sur-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-30T10:03:49Z\",\"datePublished\":\"2025-09-30T10:03:49Z\",\"dateModified\":\"2025-09-30T10:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444691,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/31\/un-caza-f-16-estadounidense-se-estrella-frente-a-corea-del-sur-es-la-tercera-perdida-de-un-avion-con-base-en-corea-en-un-ano\/","url_meta":{"origin":1466972,"position":0},"title":"Un caza F-16 estadounidense se estrella frente a Corea del Sur; es la tercera p\u00e9rdida de un avi\u00f3n con base en Corea en un a\u00f1o","author":"","date":"enero 31, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- Un avi\u00f3n de combate F-16 de la Fuerza A\u00e9rea de Estados Unidos se estrell\u00f3 despu\u00e9s de sufrir una emergencia en vuelo frente a la costa de Corea del Sur este mi\u00e9rcoles; es el tercer accidente de uno de los aviones de guerra del ej\u00e9rcito\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450649,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/06\/24\/portaaviones-eeuu-corea-sur-pacto-rusia-corea-norte-temores-regionales-trax\/","url_meta":{"origin":1466972,"position":1},"title":"Un portaaviones de Estados Unidos llega a Corea del Sur mientras el pacto de defensa entre Rusia y Corea del Norte agrava los temores regionales","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN) -- Un portaaviones de la Armada de Estados Unidos lleg\u00f3 a Corea del Sur para hacer una demostraci\u00f3n de fuerza mientras Washington, Se\u00fal y Tokio publicaban este lunes una declaraci\u00f3n conjunta condenando la profundizaci\u00f3n de los lazos militares entre Corea del Norte y Rusia.El USS Theodore Roosevelt, de propulsi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455045,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/10\/11\/corea-del-norte-acusa-a-corea-del-sur-volar-drones-trax\/","url_meta":{"origin":1466972,"position":2},"title":"Corea del Norte acusa a Corea del Sur de volar drones sobre Pyongyang","author":"","date":"octubre 11, 2024","format":false,"excerpt":"(CNN) --\u00a0Corea del Norte acus\u00f3 a Corea del Sur de volar drones llenos de propaganda sobre Pyongyang y amenaz\u00f3 con \"represalias\", inform\u00f3 el viernes la prensa estatal.El Estado Mayor Conjunto de Corea del Sur no confirm\u00f3 ni neg\u00f3 las acusaciones, pero inst\u00f3 a Corea del Norte a \"no actuar precipitadamente\"\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455109,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/10\/15\/corea-del-norte-explosion-caminos-sur-trax\/","url_meta":{"origin":1466972,"position":3},"title":"Corea del Norte vuela carreteras cerca de la frontera con el Sur tras advertir de que cortar\u00eda completamente los lazos","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN) -- Corea del Norte vol\u00f3 este martes partes de dos importantes carreteras conectadas con el sur de la pen\u00ednsula, seg\u00fan informaron las autoridades surcoreanas, despu\u00e9s de que Pyongyang advirtiera de que tomar\u00eda medidas para aislar completamente su territorio del Sur.Partes de las l\u00edneas Gyeongui, en la costa oeste, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443838,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/kim-jong-un-promete-desmantelar-el-arco-de-unificacion-de-su-padre-en-corea-del-norte-y-declara-a-corea-del-sur-su-enemigo-principal\/","url_meta":{"origin":1466972,"position":4},"title":"Kim Jong Un promete desmantelar el arco de unificaci\u00f3n de su padre en Corea del Norte y declara a Corea del Sur su &#171;enemigo principal&#187;","author":"","date":"enero 16, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- El l\u00edder norcoreano Kim Jong Un prometi\u00f3 este lunes retirar un enorme monumento a la posible reunificaci\u00f3n de la Pen\u00ednsula de Corea que su padre construy\u00f3 en Pyongyang, calific\u00e1ndolo de \u201cmonstruo a la vista\u201d.La llamada de Kim durante un discurso en una reuni\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443840,"url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/16\/kim-jong-un-promete-desmantelar-el-arco-de-unificacion-de-su-padre-en-corea-del-norte-y-declara-a-corea-del-sur-su-enemigo-principal-2\/","url_meta":{"origin":1466972,"position":5},"title":"Kim Jong Un promete desmantelar el arco de unificaci\u00f3n de su padre en Corea del Norte y declara a Corea del Sur su &#171;enemigo principal&#187;","author":"","date":"enero 16, 2024","format":false,"excerpt":"Se\u00fal, Corea del Sur (CNN) -- El l\u00edder norcoreano Kim Jong Un prometi\u00f3 este lunes retirar un enorme monumento a la posible reunificaci\u00f3n de la Pen\u00ednsula de Corea que su padre construy\u00f3 en Pyongyang, calific\u00e1ndolo de \u201cmonstruo a la vista\u201d.La llamada de Kim durante un discurso en una reuni\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-centro\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/comments?post=1466972"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/posts\/1466972\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/media?parent=1466972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/categories?post=1466972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-centro\/wp-json\/wp\/v2\/tags?post=1466972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}