{"id":1444300,"date":"2024-01-23T04:33:53","date_gmt":"2024-01-23T12:33:53","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444300"},"modified":"2024-01-23T04:33:53","modified_gmt":"2024-01-23T12:33:53","slug":"relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","title":{"rendered":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La relatora especial de la Organizaci\u00f3n de las Naciones Unidas (ONU) para la Independencia de los Magistrados y Abogados, Margaret Satterthwaite, expres\u00f3 \u201cpreocupaci\u00f3n\u201d por el actual retraso en la elecci\u00f3n de nuevos integrantes del Poder Judicial de Bolivia.<\/p>\n<p>En un comunicado de prensa publicado este lunes en el portal de la oficina del Alto Comisionado de las Naciones Unidas para los Derechos Humanos, Satterthwaite llam\u00f3 a la construcci\u00f3n de los acuerdos pol\u00edticos necesarios en Bolivia para que la Asamblea Legislativa Plurinacional avance en el proceso de elecci\u00f3n de nuevos consejeros y magistrados. La Asamblea debe definir candidatos que luego son sometidos a voto popular.<\/p>\n<p>\u201cLa conducci\u00f3n de elecciones judiciales es uno de los elementos clave para asegurar la independencia e imparcialidad de la justicia en Bolivia\u201d, dijo la relatora.<\/p>\n<p>\u201cCon esto en mente, insisto en la importancia de que haya un proceso transparente, participativo e integral para preseleccionar a los candidatos en la Asamblea Legislativa Plurinacional y avanzar en la realizaci\u00f3n de elecciones\u201d, agreg\u00f3.<\/p>\n<p>CNN contact\u00f3 a la Asamblea Legislativa de Bolivia para conocer su posici\u00f3n sobre los dichos de la relatora y est\u00e1 a la espera de respuesta.<\/p>\n<p>La declaraci\u00f3n de Satterthwaite llega una semana despu\u00e9s de que Carlos Mesa, expresidente de Bolivia, le enviara una carta para pedirle un pronunciamiento sobre la situaci\u00f3n del Poder Judicial en su pa\u00eds. Mesa mand\u00f3 la misiva argumentando que, seg\u00fan dijo, es indebido que los actuales consejeros y magistrados extiendan el periodo de sus mandatos.<\/p>\n<p>Cabe recordar que, en una sentencia publicada en diciembre de 2023, los consejeros y magistrados se\u00f1alaron que deb\u00edan aprobar esa extensi\u00f3n para que el Poder Judicial no se quedara sin integrantes ante el retraso en la elecci\u00f3n de nuevos miembros.<\/p>\n<p>Satterthwaite, quien dijo estar en contacto con el Gobierno de Bolivia en este asunto, concluy\u00f3 diciendo que le preocupa \u201cque esta falta de acuerdos pol\u00edticos amenace con minar la independencia del Poder Judicial del pa\u00eds y que los periodos de los funcionarios actuales se hayan extendido indefinidamente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La relatora especial de la Organizaci\u00f3n de las Naciones Unidas (ONU) para la Independencia de los Magistrados y Abogados, Margaret Satterthwaite, expres\u00f3 \u201cpreocupaci\u00f3n\u201d por el actual retraso en la elecci\u00f3n de nuevos integrantes del Poder Judicial de Bolivia. En un comunicado de prensa publicado este lunes en el portal de la oficina [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444300","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La relatora especial de la Organizaci\u00f3n de las Naciones Unidas (ONU) para la Independencia de los Magistrados y Abogados, Margaret Satterthwaite, expres\u00f3 \u201cpreocupaci\u00f3n\u201d por el actual retraso en la elecci\u00f3n de nuevos integrantes del Poder Judicial de Bolivia. En un comunicado de prensa publicado este lunes en el portal de la oficina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T12:33:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia\",\"datePublished\":\"2024-01-23T12:33:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\"},\"wordCount\":388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\",\"name\":\"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-23T12:33:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","og_locale":"es_ES","og_type":"article","og_title":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La relatora especial de la Organizaci\u00f3n de las Naciones Unidas (ONU) para la Independencia de los Magistrados y Abogados, Margaret Satterthwaite, expres\u00f3 \u201cpreocupaci\u00f3n\u201d por el actual retraso en la elecci\u00f3n de nuevos integrantes del Poder Judicial de Bolivia. En un comunicado de prensa publicado este lunes en el portal de la oficina [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","og_site_name":"Noticias","article_published_time":"2024-01-23T12:33:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/"},"author":{"name":"","@id":""},"headline":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia","datePublished":"2024-01-23T12:33:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/"},"wordCount":388,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","name":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-23T12:33:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Relatora de la ONU expresa \u201cpreocupaci\u00f3n\u201d por el retraso en la elecci\u00f3n de integrantes del Poder Judicial de Bolivia","url":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-23T12:33:53Z","datePublished":"2024-01-23T12:33:53Z","dateModified":"2024-01-23T12:33:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Relatora de la ONU expresa \\u201cpreocupaci\\u00f3n\\u201d por el retraso en la elecci\\u00f3n de integrantes del Poder Judicial de Bolivia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/relatora-de-la-onu-expresa-preocupacion-por-el-retraso-en-la-eleccion-de-integrantes-del-poder-judicial-de-bolivia\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-23T12:33:53Z\",\"datePublished\":\"2024-01-23T12:33:53Z\",\"dateModified\":\"2024-01-23T12:33:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450997,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/07\/09\/tribunal-electoral-bolivia-suspender-primarias-elecciones-judiciales-orix\/","url_meta":{"origin":1444300,"position":0},"title":"El Tribunal Electoral de Bolivia propondr\u00e1 a los partidos suspender sus primarias para que no se empalmen con las elecciones judiciales","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Tribunal Supremo Electoral de Bolivia (TSE) plantear\u00e1 a los partidos pol\u00edticos que suspendan sus elecciones primarias para definir candidatos con el fin de que no se empalmen con las elecciones judiciales pendientes en el pa\u00eds, inform\u00f3 este martes el presidente del organismo, \u00d3scar Hassenteufel.El funcionario dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463095,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/02\/elecciones-judiciales-mexico-otros-paises-orix\/","url_meta":{"origin":1444300,"position":1},"title":"M\u00e1s all\u00e1 de M\u00e9xico, estos son los pa\u00edses que eligen a algunos de sus jueces por voto popular","author":"","date":"junio 2, 2025","format":false,"excerpt":"Este domingo 1 de junio los ciudadanos de M\u00e9xico eligieron por primera vez mediante el voto a jueces, ministros de la Suprema Corte y magistrados de todo el pa\u00eds.En la jornada electoral se vot\u00f3 para la designaci\u00f3n de 881 cargos a nivel nacional. Se trata de 9 ministros de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472799,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/02\/onu-eleccion-secretario-general-latinoamericano-orix\/","url_meta":{"origin":1444300,"position":2},"title":"La ONU es cada vez m\u00e1s cuestionada. \u00bfPuede salvarla un latinoamericano?","author":"","date":"abril 2, 2026","format":false,"excerpt":"Aumento de la militarizaci\u00f3n, resoluci\u00f3n bilateral de conflictos, liderazgos cada vez m\u00e1s poderosos y ret\u00f3ricas incendiarias son apenas una pincelada de una actualidad cada vez m\u00e1s normalizada. Para las Naciones Unidas, el organismo que en el Art\u00edculo 1 de su carta establece el prop\u00f3sito \u201cmantener la paz y la seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462889,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/28\/que-vota-elige-elecciones-judiciales-2025-orix\/","url_meta":{"origin":1444300,"position":3},"title":"\u00bfQu\u00e9 se vota y elige en las elecciones judiciales de M\u00e9xico 2025?","author":"","date":"mayo 28, 2025","format":false,"excerpt":"El Poder Judicial de M\u00e9xico se renovar\u00e1 y por primera vez en la historia ser\u00e1n los ciudadanos quienes elijan, por medio del voto, a jueces, ministros de la Suprema Corte y magistrados de todo el pa\u00eds.El Instituto Nacional Electoral (INE) ser\u00e1 el encargado de la organizaci\u00f3n de la elecci\u00f3n que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453017,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/09\/24\/boric-onu-crisis-venezuela-triunfo-oposicion-orix\/","url_meta":{"origin":1444300,"position":4},"title":"Boric reitera ante la ONU llamado para salida pol\u00edtica a la crisis en Venezuela que \u201creconozca el triunfo de la oposici\u00f3n\u201d","author":"","date":"septiembre 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de Chile, Gabriel Boric, dijo este martes que su pa\u00eds sigue con atenci\u00f3n \u201cla cr\u00edtica situaci\u00f3n\u201d que vive Venezuela y reiter\u00f3 su llamado a una salida pol\u00edtica de la crisis, que \u201creconozca el triunfo de la oposici\u00f3n\u201d.Durante su intervenci\u00f3n en la 79\u00b0 Asamblea General de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473358,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/21\/onu-cuestionada-latinoamericano-secretaria-general-orix\/","url_meta":{"origin":1444300,"position":5},"title":"La ONU es cada vez m\u00e1s cuestionada. \u00bfPuede salvarla un latinoamericano?","author":"","date":"abril 21, 2026","format":false,"excerpt":"Aumento de la militarizaci\u00f3n, resoluci\u00f3n bilateral de conflictos, liderazgos cada vez m\u00e1s poderosos y ret\u00f3ricas incendiarias son apenas una pincelada de una actualidad cada vez m\u00e1s normalizada. Para las Naciones Unidas, el organismo que en el Art\u00edculo 1 de su carta establece el prop\u00f3sito de \u201cmantener la paz y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1444300"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444300\/revisions"}],"predecessor-version":[{"id":1444316,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444300\/revisions\/1444316"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1444300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1444300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1444300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}