{"id":1444302,"date":"2024-01-23T05:33:37","date_gmt":"2024-01-23T13:33:37","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444302"},"modified":"2024-01-23T05:33:37","modified_gmt":"2024-01-23T13:33:37","slug":"seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","title":{"rendered":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado"},"content":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; Seis incendios forestales afectaron distintos puntos de Bogot\u00e1 este lunes y, de ellos, uno ocurrido en la zona de los Cerros Orientales a\u00fan no est\u00e1 controlado por los bomberos y los cuerpos de seguridad, inform\u00f3 el alcalde de la capital colombiana, Carlos Gal\u00e1n.<\/p>\n<p>El funcionario dijo en una rueda de prensa que las labores manuales para sofocar el fuego y el monitoreo con drones t\u00e9rmicos continuar\u00e1n durante la noche, que este martes se retomar\u00e1n los trabajos con el apoyo de helic\u00f3pteros a partir de las 6:00 a.m. (hora local), y que a\u00fan se desconocen las causas que originaron el siniestro.<\/p>\n<p>Los cuerpos de emergencia \u201cest\u00e1n revisando y revisando elementos que nos permitan despu\u00e9s determinar el origen\u201d, se\u00f1al\u00f3 Gal\u00e1n. Agreg\u00f3 que los c\u00e1lculos sobre las hect\u00e1reas afectadas a\u00fan son preliminares.<\/p>\n<p>En la atenci\u00f3n de los incendios intervinieron los Bomberos, Polic\u00eda de Bogot\u00e1, Defensa Civil, el Ej\u00e9rcito y la Fuerza Aeroespacial de Colombia y la Cruz Roja, entre otras instituciones.<\/p>\n<p>De acuerdo con el alcalde, Bogot\u00e1 vive una \u00e9poca dif\u00edcil por fen\u00f3menos como la \u201cinversi\u00f3n t\u00e9rmica\u201d, que complican el combate de incendios y afectan la calidad del aire. Por estos motivos, el funcionario pidi\u00f3 reforzar las medidas de prevenci\u00f3n de siniestros.<\/p>\n<p>En su cuenta de X, la alcald\u00eda llam\u00f3 a los ciudadanos a evitar conductas como arrojar colillas de cigarrillo o f\u00f3sforos en zonas boscosas, as\u00ed como a no quemar basura, encender fogatas o usar l\u00edquidos inflamables en \u00e1reas verdes.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; Seis incendios forestales afectaron distintos puntos de Bogot\u00e1 este lunes y, de ellos, uno ocurrido en la zona de los Cerros Orientales a\u00fan no est\u00e1 controlado por los bomberos y los cuerpos de seguridad, inform\u00f3 el alcalde de la capital colombiana, Carlos Gal\u00e1n. El funcionario dijo en una rueda de prensa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444302","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN en Espa\u00f1ol) &#8212; Seis incendios forestales afectaron distintos puntos de Bogot\u00e1 este lunes y, de ellos, uno ocurrido en la zona de los Cerros Orientales a\u00fan no est\u00e1 controlado por los bomberos y los cuerpos de seguridad, inform\u00f3 el alcalde de la capital colombiana, Carlos Gal\u00e1n. El funcionario dijo en una rueda de prensa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T13:33:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado\",\"datePublished\":\"2024-01-23T13:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\",\"name\":\"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-23T13:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","og_locale":"es_ES","og_type":"article","og_title":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias","og_description":"(CNN en Espa\u00f1ol) &#8212; Seis incendios forestales afectaron distintos puntos de Bogot\u00e1 este lunes y, de ellos, uno ocurrido en la zona de los Cerros Orientales a\u00fan no est\u00e1 controlado por los bomberos y los cuerpos de seguridad, inform\u00f3 el alcalde de la capital colombiana, Carlos Gal\u00e1n. El funcionario dijo en una rueda de prensa [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","og_site_name":"Noticias","article_published_time":"2024-01-23T13:33:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/"},"author":{"name":"","@id":""},"headline":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado","datePublished":"2024-01-23T13:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","name":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-23T13:33:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Seis incendios forestales afectaron a Bogot\u00e1 este lunes y uno de ellos a\u00fan no est\u00e1 controlado","url":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-23T13:33:37Z","datePublished":"2024-01-23T13:33:37Z","dateModified":"2024-01-23T13:33:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Seis incendios forestales afectaron a Bogot\\u00e1 este lunes y uno de ellos a\\u00fan no est\\u00e1 controlado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/seis-incendios-forestales-afectaron-a-bogota-este-lunes-y-uno-de-ellos-aun-no-esta-controlado\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-23T13:33:37Z\",\"datePublished\":\"2024-01-23T13:33:37Z\",\"dateModified\":\"2024-01-23T13:33:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460324,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/24\/corea-sur-incendios-forestales-mortales-miles-personas-trax\/","url_meta":{"origin":1444302,"position":0},"title":"Corea del Sur combate incendios forestales mortales en el sureste mientras evac\u00faan a miles de personas","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Corea del Sur est\u00e1 luchando por contener una serie de incendios forestales en el sureste del pa\u00eds despu\u00e9s de que m\u00e1s de dos docenas de focos que estallaron durante el fin de semana provocaron al menos cuatro muertos y obligaron a evacuar a miles de personas.Hasta el domingo por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453116,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/09\/26\/detienen-segundo-hombre-involucrado-incendios-quito-orix\/","url_meta":{"origin":1444302,"position":1},"title":"Detienen a un segundo hombre presuntamente involucrado en los incendios en Quito","author":"","date":"septiembre 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Polic\u00eda Nacional de Ecuador detuvo este jueves a un segundo hombre presuntamente involucrado en los incendios que esta semana afectan a Quito e hicieron que la Alcald\u00eda declarara emergencia en la capital, de acuerdo con un comunicado.Se trata, seg\u00fan las autoridades, de una persona de nacionalidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1405084,"url":"https:\/\/noticiasya.com\/el-paso\/2022\/06\/10\/bomberos-de-tijuana-toman-curso-para-sofocar-incendios-forestales\/","url_meta":{"origin":1444302,"position":2},"title":"Bomberos de Tijuana toman curso para sofocar incendios forestales","author":"agomez","date":"junio 10, 2022","format":"video","excerpt":"El personal de bomberos busca mejorar la capacidad de respuesta en incendios forestales que amenazan y llegan muchas veces a zonas habitadas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452520,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/09\/07\/bolivia-emergencia-nacional-incendios-forestales-orix\/","url_meta":{"origin":1444302,"position":3},"title":"Bolivia declara emergencia nacional por incendios forestales","author":"agomez","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol)-- Bolivia declar\u00f3 este s\u00e1bado emergencia nacional debido a los incendios forestales que afectan al pa\u00eds, informaron autoridades del Ejecutivo del presidente Luis Arce en una conferencia de prensa.Alan Lisperguer, ministro de Medio Ambiente y Agua, dijo en conferencia de prensa que hay 72 puntos de fuego activo. La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449482,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/05\/15\/incendios-forestales-canada-catastrofe-2016-la-bestia-trax\/","url_meta":{"origin":1444302,"position":4},"title":"Incendios forestales dif\u00edciles de manejar arrasan Canad\u00e1 y amenazan a una comunidad marcada por una cat\u00e1strofe pasada","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de 100 incendios forestales que azotan Canad\u00e1 est\u00e1n contaminando el aire con humo y obligando a miles de personas a evacuar mientras las llamas invaden comunidades, incluida una ciudad a la que a\u00fan atormenta un catastr\u00f3fico incendio de 2016 apodado \u201cLa Bestia\u201d.Las carreteras que salen de Fort\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457853,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/24\/trump-incendios-mala-gestion-california-trax\/","url_meta":{"origin":1444302,"position":5},"title":"Trump dice que la mala gesti\u00f3n en los bosques y el agua en California es culpable de los incendios forestales. \u00bfEs cierto?","author":"","date":"enero 24, 2025","format":false,"excerpt":"A principios de este mes, cuando m\u00e1s de 96 kil\u00f3metros cuadrados de Los \u00c1ngeles ardieron violentamente, el entonces presidente electo de Estados Unidos, Donald Trump, culp\u00f3 a un pez.Trump insinu\u00f3 falsamente en una publicaci\u00f3n de Truth Social que Los \u00c1ngeles carec\u00eda de agua para apagar los incendios porque el gobernador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1444302"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444302\/revisions"}],"predecessor-version":[{"id":1444318,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444302\/revisions\/1444318"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1444302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1444302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1444302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}