{"id":1444331,"date":"2024-01-23T20:33:30","date_gmt":"2024-01-24T04:33:30","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444331"},"modified":"2024-01-23T20:33:30","modified_gmt":"2024-01-24T04:33:30","slug":"lo-que-esta-en-juego-con-las-elecciones-en-el-salvador","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","title":{"rendered":"Lo que est\u00e1 en juego con las elecciones en El Salvador"},"content":{"rendered":"<p>(CNN) &#8212; El pr\u00f3ximo 4 de febrero poco m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.<\/p>\n<p>Nayib Bukele, actual presidente -con permiso de la Asamblea Legislativa para la campa\u00f1a electoral- busca un segundo mandato de cinco a\u00f1os. De ganar, como lo indican encuestas como la de Cid Gallup o la del Instituto de Opini\u00f3n P\u00fablica, de la Universidad Centroamericana, se convertir\u00e1 en el primero en repetir el cargo en la historia reciente de El Salvador, a pesar de que algunos sectores acad\u00e9micos y de juristas consideran que la Constituci\u00f3n proh\u00edbe la reelecci\u00f3n inmediata.<\/p>\n<p>El vicepresidente, F\u00e9lix Ulloa -tambi\u00e9n con permiso de los diputados para la campa\u00f1a-, buscar\u00e1 junto a Bukele seguir al frente del Ejecutivo.<\/p>\n<p>En la contienda, seg\u00fan el Tribunal Supremo Electoral, hay otros cinco aspirantes para el periodo comprendido entre el 1 de junio de 2024 al 1 de junio de 2029. Para ganar en primera vuelta un candidato debe obtener el 50% + 1 de los votos v\u00e1lidos. Si ninguno obtiene ese porcentaje, el Tribunal Supremo Electoral deber\u00e1 organizar el balotaje con los dos candidatos m\u00e1s votados.<\/p>\n<p>Manuel Flores<\/p>\n<p>Aspira a ser presidente de El Salvador bajo la bandera del partido Frente Farabundo Mart\u00ed para la Liberaci\u00f3n Nacional (FMLN). Es bi\u00f3logo y fundador del partido de izquierda. Fue alcalde de Quezaltepeque de 2003 a 2012 y durante los 9 a\u00f1os siguientes fungi\u00f3 como diputado de la Asamblea Legislativa.<\/p>\n<p>Joel S\u00e1nchez<\/p>\n<p>Es el candidato presidencial por el partido Alianza Republicana Nacionalista, Arena. Emigr\u00f3 a los 19 a\u00f1os hacia Estados Unidos debido al clima de inestabilidad pol\u00edtica y la guerra civil de El Salvador. Es Licenciado en Administraci\u00f3n de Empresas, por la Keiser University, en Fort Lauderdale, Florida. No posee trayectoria pol\u00edtica.<\/p>\n<p>Jos\u00e9 Renderos<\/p>\n<p>Es un m\u00e9dico obstetra, quien compite con el partido Fuerza Solidaria. En 2018 fue candidato a alcalde de San Miguel por el partido Alianza Republicana Nacionalista (Arena).<\/p>\n<p>Luis Parada<\/p>\n<p>Aspirante del partido Nuestro Tiempo. Es abogado y especialista en litigios y arbitrajes internacionales. Obtuvo una licenciatura en Seguridad Nacional en la Academia Militar de West Point y un m\u00e1ster en Gobierno en la Universidad de Georgetown.<\/p>\n<p>Marina Murillo<\/p>\n<p>Es arquitecta y busca llegar a la silla presidencial bajo la bandera del partido Fraternidad Patri\u00f3tica Salvadore\u00f1a.<\/p>\n<p>Voto desde el exterior<\/p>\n<p>Seg\u00fan los registros del Tribunal Supremo Electoral 741.094 salvadore\u00f1os que viven en el exterior y cuyo documento de identidad contiene la direcci\u00f3n del pa\u00eds en el que residen empezaron a votar desde el cinco de enero hasta el 4 de febrero de forma remota por internet, a trav\u00e9s del sitio de votacion.tse.gob.sv, una modalidad que por primera vez se implementa.<\/p>\n<p>Hasta este lunes, seg\u00fan los registros del TSE, 114.724 personas hab\u00edan emitido el voto para presidente y vicepresidente.<\/p>\n<p>Mientras tanto, los salvadore\u00f1os en el exterior cuyo documento tenga la direcci\u00f3n donde viv\u00edan en El Salvador podr\u00e1n votar, de manera presencial, el 4 de febrero en los centros de votaci\u00f3n que ser\u00e1n instalados en diferentes pa\u00edses.<\/p>\n<p>Control de la Asamblea Legislativa<\/p>\n<p>Las votaciones del 4 de febrero tambi\u00e9n definir\u00e1n la conformaci\u00f3n de la Asamblea Legislativa, actualmente controlada por Nuevas Ideas, el partido del presidente Bukele.<\/p>\n<p>La Asamblea estar\u00e1 integrada, a partir del 1 de mayo, por 60 diputados. Actualmente son 84, pero una reforma aprobada en junio de 2023 redujo la cifra, a petici\u00f3n del presidente Bukele.<\/p>\n<p>Asamblea de El Salvador autoriza a medio mill\u00f3n de ciudadanos en el pa\u00eds a votar con documento vencido en las elecciones de 2024<\/p>\n<p>Esa reforma tambi\u00e9n incluy\u00f3 un cambio en el sistema de asignaci\u00f3n de los esca\u00f1os. De esa manera, se dividir\u00e1 el n\u00famero de votos emitidos en cada uno de los 14 departamentos entre el n\u00famero de diputados a elegir por departamento. De esa manera se obtendr\u00e1 cu\u00e1les candidatos ganaran una diputaci\u00f3n.<\/p>\n<p>Algunos analistas advierten que esa forma de asignar las diputaciones favorecer\u00e1 al partido oficialista, que tiene mayor\u00eda calificada.<\/p>\n<p>Esto les permiti\u00f3 el primer d\u00eda de sus funciones, el 1 de mayo de 2021, remover del cargo a los magistrados de la Sala de lo Constitucional de la Corte Suprema de Justicia y en esa misma sesi\u00f3n relevar de sus funciones al fiscal general.<\/p>\n<p>Los diputados oficialistas y de partidos aliados han aprobado las iniciativas solicitadas por el presidente, entre estas el r\u00e9gimen de excepci\u00f3n y sus 22 pr\u00f3rrogas. La \u00faltima, el pasado 10 de enero.<\/p>\n<p>La medida fue aprobada a petici\u00f3n del Ejecutivo como respuesta a un repunte de violencia que en un solo d\u00eda de marzo de 2022 dej\u00f3 62 homicidios. Desde esa fecha, hasta ahora, las autoridades reportan la detenci\u00f3n de m\u00e1s de 75.000 personas. El Gobierno atribuye al r\u00e9gimen la reducci\u00f3n de la violencia, pero agrupaciones que trabajan a favor de los derechos humanos y organismos internacionales como Amnist\u00eda Internacional sostienen que ha permitido capturas arbitrarias y tratos denigrantes al interior de las prisiones.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El pr\u00f3ximo 4 de febrero poco m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente -con permiso de la Asamblea Legislativa para la campa\u00f1a electoral- busca un segundo mandato de cinco a\u00f1os. De [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444331","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El pr\u00f3ximo 4 de febrero poco m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente -con permiso de la Asamblea Legislativa para la campa\u00f1a electoral- busca un segundo mandato de cinco a\u00f1os. De [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T04:33:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lo que est\u00e1 en juego con las elecciones en El Salvador\",\"datePublished\":\"2024-01-24T04:33:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\"},\"wordCount\":884,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\",\"name\":\"Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-24T04:33:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que est\u00e1 en juego con las elecciones en El Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias","og_description":"(CNN) &#8212; El pr\u00f3ximo 4 de febrero poco m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente -con permiso de la Asamblea Legislativa para la campa\u00f1a electoral- busca un segundo mandato de cinco a\u00f1os. De [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","og_site_name":"Noticias","article_published_time":"2024-01-24T04:33:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/"},"author":{"name":"","@id":""},"headline":"Lo que est\u00e1 en juego con las elecciones en El Salvador","datePublished":"2024-01-24T04:33:30+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/"},"wordCount":884,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","name":"Lo que est\u00e1 en juego con las elecciones en El Salvador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-24T04:33:30+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lo que est\u00e1 en juego con las elecciones en El Salvador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lo que est\u00e1 en juego con las elecciones en El Salvador","url":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-24T04:33:30Z","datePublished":"2024-01-24T04:33:30Z","dateModified":"2024-01-24T04:33:30Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lo que est\\u00e1 en juego con las elecciones en El Salvador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/23\\\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-24T04:33:30Z\",\"datePublished\":\"2024-01-24T04:33:30Z\",\"dateModified\":\"2024-01-24T04:33:30Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444470,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/cuando-son-las-elecciones-de-el-salvador-2024-y-que-se-votara\/","url_meta":{"origin":1444331,"position":0},"title":"\u00bfCu\u00e1ndo son las elecciones de El Salvador 2024 y que se votar\u00e1?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados para votar en las pr\u00f3ximas elecciones nacionales de febrero.Se van a votar m\u00faltiples cargos, pero el que m\u00e1s llama la atenci\u00f3n es el de presidente, ya que el actual mandatario Nayib Bukele busca un segundo mandato de cinco a\u00f1os.Si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444814,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/02\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta\/","url_meta":{"origin":1444331,"position":1},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444853,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","url_meta":{"origin":1444331,"position":2},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445004,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/06\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-3\/","url_meta":{"origin":1444331,"position":3},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445006,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/06\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-4\/","url_meta":{"origin":1444331,"position":4},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465185,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/06\/eeuu-rechaza-comparar-reeleccion-bukele-el-salvador-regimenes-dictatoriales-orix\/","url_meta":{"origin":1444331,"position":5},"title":"EE.UU. rechaza comparaci\u00f3n del Gobierno de Bukele con &#171;reg\u00edmenes dictatoriales&#187; tras aprobaci\u00f3n de reelecci\u00f3n indefinida","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos dijo que rechaza comparar el proceso legislativo en El Salvador que habilit\u00f3 la reelecci\u00f3n sin restricciones y despeja el camino a nuevos mandatos del presidente Nayib Bukele con \u201creg\u00edmenes dictatoriales ileg\u00edtimos\u201d.El posicionamiento de EE.UU. llega despu\u00e9s de que la Asamblea Legislativa de El Salvador aprobara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1444331"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444331\/revisions"}],"predecessor-version":[{"id":1444348,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444331\/revisions\/1444348"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1444331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1444331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1444331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}