{"id":1444460,"date":"2024-01-26T10:33:47","date_gmt":"2024-01-26T18:33:47","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444460"},"modified":"2024-01-26T10:33:47","modified_gmt":"2024-01-26T18:33:47","slug":"el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","title":{"rendered":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata"},"content":{"rendered":"<p>(CNN) &#8212; El rey Carlos III ingres\u00f3 el viernes por la ma\u00f1ana en un hospital londinense para someterse a un &#171;procedimiento correctivo&#187; del agrandamiento de la pr\u00f3stata, seg\u00fan anunci\u00f3 el palacio de Buckingham.<\/p>\n<p>Esta noticia est\u00e1 en desarrollo y se actualizar\u00e1 pr\u00f3ximamente.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El rey Carlos III ingres\u00f3 el viernes por la ma\u00f1ana en un hospital londinense para someterse a un &#171;procedimiento correctivo&#187; del agrandamiento de la pr\u00f3stata, seg\u00fan anunci\u00f3 el palacio de Buckingham. Esta noticia est\u00e1 en desarrollo y se actualizar\u00e1 pr\u00f3ximamente. The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444460","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El rey Carlos III ingres\u00f3 el viernes por la ma\u00f1ana en un hospital londinense para someterse a un &#171;procedimiento correctivo&#187; del agrandamiento de la pr\u00f3stata, seg\u00fan anunci\u00f3 el palacio de Buckingham. Esta noticia est\u00e1 en desarrollo y se actualizar\u00e1 pr\u00f3ximamente. The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T18:33:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata\",\"datePublished\":\"2024-01-26T18:33:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\",\"name\":\"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-26T18:33:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","og_locale":"es_ES","og_type":"article","og_title":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias","og_description":"(CNN) &#8212; El rey Carlos III ingres\u00f3 el viernes por la ma\u00f1ana en un hospital londinense para someterse a un &#171;procedimiento correctivo&#187; del agrandamiento de la pr\u00f3stata, seg\u00fan anunci\u00f3 el palacio de Buckingham. Esta noticia est\u00e1 en desarrollo y se actualizar\u00e1 pr\u00f3ximamente. The-CNN-Wire\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","og_site_name":"Noticias","article_published_time":"2024-01-26T18:33:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/"},"author":{"name":"","@id":""},"headline":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata","datePublished":"2024-01-26T18:33:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","name":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-26T18:33:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\u00f3n de pr\u00f3stata","url":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-26T18:33:47Z","datePublished":"2024-01-26T18:33:47Z","dateModified":"2024-01-26T18:33:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El rey Carlos III llega a un hospital de Londres para someterse a una operaci\\u00f3n de pr\\u00f3stata\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/26\\\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/26\\\/el-rey-carlos-iii-llega-a-un-hospital-de-londres-para-someterse-a-una-operacion-de-prostata\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-26T18:33:47Z\",\"datePublished\":\"2024-01-26T18:33:47Z\",\"dateModified\":\"2024-01-26T18:33:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444961,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/05\/el-rey-carlos-iii-se-encuentra-bien-tras-someterse-a-una-operacion-de-prostata\/","url_meta":{"origin":1444460,"position":0},"title":"El rey Carlos III &#171;se encuentra bien&#187; tras someterse a una operaci\u00f3n de pr\u00f3stata","author":"","date":"febrero 5, 2024","format":false,"excerpt":"(CNN) --\u00a0CNN pudo saber que el rey Carlos \"se encuentra bien\" despu\u00e9s del procedimiento programado al que se someti\u00f3 este viernes.El rey Carlos III ingres\u00f3 el viernes por la ma\u00f1ana en un hospital londinense para someterse a un \"procedimiento correctivo\" del agrandamiento de la pr\u00f3stata, seg\u00fan anunci\u00f3 el palacio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444980,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/06\/como-se-detecto-el-cancer-del-rey-carlos-y-que-se-sabe-de-su-diagnostico-esto-es-lo-que-sabemos\/","url_meta":{"origin":1444460,"position":1},"title":"\u00bfC\u00f3mo se detect\u00f3 el c\u00e1ncer del rey Carlos y qu\u00e9 se sabe de su diagn\u00f3stico? Esto es lo que sabemos","author":"","date":"febrero 6, 2024","format":false,"excerpt":"Londres (CNN) -- El rey Carlos III fue diagnosticado con c\u00e1ncer y comenz\u00f3 el tratamiento en Londres.El rey Carlos III tiene c\u00e1ncer y se retirar\u00e1 de sus deberes p\u00fablicosEl impactante diagn\u00f3stico se produce una semana despu\u00e9s de que el monarca brit\u00e1nico de 75 a\u00f1os de edad fue dado de alta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444463,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/26\/que-es-el-agrandamiento-de-la-prostata-diagnosticado-al-rey-carlos-iii-y-como-saber-si-lo-tienes\/","url_meta":{"origin":1444460,"position":2},"title":"\u00bfQu\u00e9 es el agrandamiento de la pr\u00f3stata, diagnosticado al rey Carlos III, y c\u00f3mo saber si lo tienes?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El rey Carlos III ya se encuentra en el hospital\u00a0para recibir tratamiento por agrandamiento de la pr\u00f3stata, inform\u00f3 este mi\u00e9rcoles el Palacio de Buckingham.Desde el palacio explicaron que el rey busc\u00f3 tratamiento \"as\u00ed como miles de hombres cada a\u00f1o\" y que su condici\u00f3n es \"benigna\".\u00a0 Adem\u00e1s, indicaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445969,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/rey-carlos-responde-mensajes-cancer-trax\/","url_meta":{"origin":1444460,"position":3},"title":"El rey Carlos responde a los mensajes que ha recibido tras su diagn\u00f3stico de c\u00e1ncer","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) -- Los numerosos mensajes de apoyo tras el diagn\u00f3stico de c\u00e1ncer \"me han hecho llorar la mayor parte del tiempo\", dijo el rey Carlos en un nuevo comunicado publicado por el Palacio de Buckingham el viernes.El rey ha recibido m\u00e1s de 7.000 cartas y tarjetas de todo el mundo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445821,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/21\/carlos-iii-regresa-trabajo-audiencia-rishi-sunak-trax\/","url_meta":{"origin":1444460,"position":4},"title":"El rey Carlos III de Reino Unido retoma funciones por primera vez desde que le diagnosticaron c\u00e1ncer","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- El rey Carlos III regres\u00f3 al trabajo por primera vez desde que revel\u00f3 su diagn\u00f3stico de c\u00e1ncer.El monarca fue grabado estrechando la mano del primer ministro brit\u00e1nico, Rishi Sunak, cuando lleg\u00f3 al Palacio de Buckingham el mi\u00e9rcoles por la tarde.Su reuni\u00f3n supone la reanudaci\u00f3n de sus encuentros semanales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445239,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/10\/el-rey-carlos-agradece-al-publico-en-su-primer-mensaje-desde-el-diagnostico-de-cancer\/","url_meta":{"origin":1444460,"position":5},"title":"El rey Carlos agradece al p\u00fablico en su primer mensaje desde el diagn\u00f3stico de c\u00e1ncer","author":"","date":"febrero 10, 2024","format":false,"excerpt":"(CNN) --\u00a0En sus primeros comentarios p\u00fablicos desde su diagn\u00f3stico de c\u00e1ncer, el rey Carlos III expres\u00f3 su gratitud al p\u00fablico por su apoyo, diciendo que le brindaba \u201cel mayor consuelo y aliento\u201d, de acuerdo con un comunicado.\u201cMe gustar\u00eda agradecer de todo coraz\u00f3n los numerosos mensajes de apoyo y buenos deseos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1444460"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444460\/revisions"}],"predecessor-version":[{"id":1444476,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444460\/revisions\/1444476"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1444460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1444460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1444460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}