{"id":1444542,"date":"2024-01-28T03:33:41","date_gmt":"2024-01-28T11:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444542"},"modified":"2024-01-28T03:33:41","modified_gmt":"2024-01-28T11:33:41","slug":"biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","title":{"rendered":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump"},"content":{"rendered":"<p>(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald Trump a la pol\u00edtica de inmigraci\u00f3n antes de las elecciones.<\/p>\n<p>Horas despu\u00e9s de que el presidente de la C\u00e1mara de Representantes, Mike Johnson, advirtiera el viernes que el acuerdo fronterizo emergente en el Senado est\u00e1 \u201cmuerto al llegar\u201d, Biden ofreci\u00f3 este mensaje a los republicanos de la C\u00e1mara: \u201cAsegurar la frontera a trav\u00e9s de estas negociaciones es una victoria para Estados Unidos. Para todos los que exigen un control fronterizo m\u00e1s estricto, esta es la manera de hacerlo. Si se toma en serio la crisis fronteriza, que se apruebe un proyecto de ley bipartidista y yo lo firmar\u00e9\u201d.<\/p>\n<p>Senadores republicanos se enfurecen porque Trump entorpece un delicado acuerdo sobre inmigraci\u00f3n<\/p>\n<p>Biden asumi\u00f3 el cargo prometiendo restablecer el asilo y gestionar la frontera de forma \u201chumana\u201d. Pero su Gobierno ha enfrentado las duras realidades y los desaf\u00edos en la frontera entre Estados Unidos y M\u00e9xico en medio de una migraci\u00f3n r\u00e9cord en todo el hemisferio occidental, lo que la convierte en una vulnerabilidad pol\u00edtica aprovechada por los republicanos.<\/p>\n<p>En las \u00faltimas semanas, Trump ha presionado a los republicanos para que se opongan a que el compromiso fronterizo se debata delicadamente en el Senado porque quiere hacer campa\u00f1a sobre el tema en noviembre.<\/p>\n<p>A lo largo de su Gobierno, Biden se ha apoyado en medidas m\u00e1s restrictivas para tratar de frenar el flujo migratorio, pero la declaraci\u00f3n del viernes revel\u00f3 una postura m\u00e1s dura mientras el presidente intenta controlar un tema que lo acosa, mientras corre el riesgo de ponerlo en desacuerdo con algunos aliados.<\/p>\n<p>\u201c(El compromiso) me dar\u00eda, como presidente, una nueva autoridad de emergencia para cerrar la frontera cuando se vea abrumada. Y si se me diera esa autoridad, la usar\u00eda el d\u00eda que firmara el proyecto de ley\u201d, dec\u00eda la declaraci\u00f3n de Biden.<\/p>\n<p>La adopci\u00f3n por parte de Biden de una autoridad que le permitir\u00eda cerrar la frontera en caso de un aumento de inmigrantes fue sorprendente para los funcionarios actuales y anteriores de la administraci\u00f3n, as\u00ed como para los defensores de los inmigrantes.<\/p>\n<p>Johnson atac\u00f3 el s\u00e1bado a Biden por su respaldo al posible acuerdo fronterizo, argumentando que el presidente puede tomar medidas ejecutivas sin que el Congreso tome medidas dr\u00e1sticas contra los cruces de migrantes.<\/p>\n<p>Y en su primera declaraci\u00f3n sobre el acuerdo del Senado, Johnson afirm\u00f3 que obligar\u00eda a Estados Unidos a rendirse ante la migraci\u00f3n ilegal. \u201cSeg\u00fan los informes, la propuesta pendiente del Senado permitir\u00eda expresamente hasta 150.000 cruces ilegales cada mes (1,8 millones por a\u00f1o) antes de que se pudiera utilizar cualquier nueva autoridad de &#8216;cierre&#8217;. En ese momento, Estados Unidos ya se habr\u00e1 rendido\u201d, dijo Johnson en el comunicado.<\/p>\n<p>Sin embargo, una fuente familiarizada con el acuerdo del Senado dijo que Johnson est\u00e1 dando una interpretaci\u00f3n falsa de la propuesta. La fuente dijo que una vez que los cruces fronterizos alcancen un nivel que requiera que el Departamento de Seguridad Nacional tome medidas de emergencia, las autoridades federales tendr\u00edan que restringir significativamente los cruces fronterizos ilegales hasta que Estados Unidos vea que menos de 2.000 inmigrantes se acercan a la frontera por d\u00eda durante un periodo de dos semanas.<\/p>\n<p>Seg\u00fan el paquete que pronto se publicar\u00e1, se otorgar\u00eda al Departamento de Seguridad Nacional nueva autoridad de emergencia para cerrar la frontera si el promedio diario de migrantes que cruzan ilegalmente llega a 4.000 en un lapso de una semana. A ciertos inmigrantes se les permitir\u00eda quedarse si demostraran que huyen de la tortura o la persecuci\u00f3n en sus pa\u00edses.<\/p>\n<p>Los detalles siguen sin estar claros. Pero la autoridad recuerda una restricci\u00f3n fronteriza de la era covid invocada por Trump en 2020 que permiti\u00f3 a las autoridades rechazar a los migrantes en la frontera. Result\u00f3 en m\u00e1s cruces fronterizos repetidos y a\u00fan ejerci\u00f3 presi\u00f3n sobre el sistema de inmigraci\u00f3n.<\/p>\n<p>Funcionarios actuales y anteriores de Seguridad Nacional han dado la alarma sobre el acuerdo, generando dudas sobre la eficacia de la autoridad para cerrar la frontera.<\/p>\n<p>Es imposible cerrar la frontera a los solicitantes de asilo debido a la ley actual, a pesar de los m\u00faltiples intentos de Trump de hacerlo mientras estuvo en el cargo.<\/p>\n<p>Un exfuncionario de Biden dijo que la declaraci\u00f3n de Biden del viernes \u201cten\u00eda sentido pol\u00edtico para dejar un marcador ahora que Johnson dijo que no\u201d.<\/p>\n<p>A los funcionarios les preocupa que la nueva autoridad de emergencia suponga los mismos dolores de cabeza que acompa\u00f1aron al T\u00edtulo 42, una restricci\u00f3n de la era covid.<\/p>\n<p>\u00bfAgrav\u00f3 la implementaci\u00f3n del T\u00edtulo 42 la crisis migratoria en la frontera?, un analista lo explica<\/p>\n<p>El T\u00edtulo 42, una autoridad de salud p\u00fablica invocada por Trump durante la pandemia, permiti\u00f3 a las autoridades devolver a los migrantes encontrados en la frontera entre Estados Unidos y M\u00e9xico a M\u00e9xico o a su pa\u00eds de origen.<\/p>\n<p>Seg\u00fan el paquete que pronto se publicar\u00e1, se otorgar\u00eda al Departamento de Seguridad Nacional nueva autoridad de emergencia para cerrar la frontera si el promedio diario de migrantes que cruzan ilegalmente llega a 4.000 en un lapso de una semana. A ciertos inmigrantes se les permitir\u00eda quedarse si demostraran que huyen de la tortura o la persecuci\u00f3n en sus pa\u00edses.<\/p>\n<p>Los detalles siguen sin estar claros. Pero la autoridad recuerda una restricci\u00f3n fronteriza de la era Covid invocada por Trump en 2020 que permiti\u00f3 a las autoridades rechazar a los migrantes en la frontera. Result\u00f3 en m\u00e1s cruces fronterizos repetidos y a\u00fan ejerci\u00f3 presi\u00f3n sobre el sistema de inmigraci\u00f3n.<\/p>\n<p>Funcionarios actuales y anteriores de Seguridad Nacional han dado la alarma sobre el acuerdo, generando dudas sobre la eficacia de la autoridad para cerrar la frontera.<\/p>\n<p>Es imposible cerrar la frontera a los solicitantes de asilo debido a la ley actual, a pesar de los m\u00faltiples intentos de Trump de hacerlo mientras estuvo en el cargo.<\/p>\n<p>Un exfuncionario de Biden dijo que la declaraci\u00f3n de Biden del viernes \u201cten\u00eda sentido pol\u00edtico para dejar un marcador ahora que Johnson dijo que no\u201d.<\/p>\n<p>A los funcionarios les preocupa que la nueva autoridad de emergencia suponga los mismos dolores de cabeza que acompa\u00f1aron al T\u00edtulo 42, una restricci\u00f3n de la era Covid.<\/p>\n<p>El T\u00edtulo 42, una autoridad de salud p\u00fablica invocada por Trump durante la pandemia, permiti\u00f3 a las autoridades devolver a los migrantes encontrados en la frontera entre Estados Unidos y M\u00e9xico a M\u00e9xico o a su pa\u00eds de origen.<\/p>\n<p>Pero las autoridades a\u00fan enfrentan un gran n\u00famero de cruces fronterizos y miles de personas se reunieron en el norte de M\u00e9xico esperando cruzar.<\/p>\n<p>Mientras el T\u00edtulo 42 estaba vigente, los funcionarios tambi\u00e9n lidiaron con un aumento en el n\u00famero de personas que cruzaban repetidamente porque hab\u00eda pocas consecuencias legales o aceptaci\u00f3n por parte de M\u00e9xico, donde miles de migrantes fueron rechazados.<\/p>\n<p>Los defensores de los inmigrantes r\u00e1pidamente criticaron a Biden por su declaraci\u00f3n, revelando la brecha cada vez m\u00e1s profunda entre el presidente y la comunidad de defensores.<\/p>\n<p>Durante semanas, los defensores de los inmigrantes y los progresistas se preocuparon por los par\u00e1metros de un acuerdo fronterizo que incluye medidas punitivas para los migrantes que cruzan la frontera entre Estados Unidos y M\u00e9xico, incluidos los que buscan asilo, y dieron la alarma por las concesiones de la Casa Blanca en las conversaciones en curso.<\/p>\n<p>Migrantes participan en una caravana hacia la frontera con Estados Unidos en el estado de Chiapas, M\u00e9xico, el 8 de enero de 2024. (Stringer\/AFP\/Getty Images)<\/p>\n<p>Robyn Barnard, directora principal de defensa de los refugiados de Human Rights First, calific\u00f3 la situaci\u00f3n de decepcionante.<\/p>\n<p>\u201cEste presidente est\u00e1 dejando al descubierto su cruel desprecio y su voluntad de jugar a la pol\u00edtica con las vidas de los inmigrantes negros y morenos, muchos de los cuales vienen a nuestra frontera sur para ejercer su derecho legal a buscar asilo\u201d, dijo Barnard.<\/p>\n<p>\u201cSi escuchara a cualquiera de los expertos en inmigraci\u00f3n de su administraci\u00f3n, sabr\u00eda que estas propuestas (cerrar la frontera, expulsar a los inmigrantes, dificultar el acceso a la protecci\u00f3n de asilo) no son &#8216;justas&#8217; y no &#8216;asegurar\u00e1n la frontera&#8217;. Sin embargo, causar\u00e1n caos y sufrimiento humano\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Kerri Talbot, directora ejecutiva de Immigration Hub, denunci\u00f3 la politizaci\u00f3n de la frontera.<\/p>\n<p>&#171;Espero que los l\u00edderes de ambos partidos puedan dar un paso atr\u00e1s y pensar en soluciones reales que conduzcan a una frontera controlada&#187;, dijo a CNN. \u201cCerrar la frontera nunca ha sido posible. Lo que es posible es una frontera segura y humana con buenos recursos si el Congreso aprobara los fondos necesarios\u201d.<\/p>\n<p>A principios de semana, el senador dem\u00f3crata Alex Padilla de California advirti\u00f3 sobre una reacci\u00f3n progresista contra el Gobierno de Biden por el posible acuerdo de inmigraci\u00f3n.<\/p>\n<p>\u201cEst\u00e1 la sustancia y est\u00e1 el proceso. La frustraci\u00f3n sobre el proceso es, francamente, la falta de transparencia. Han pasado meses y todav\u00eda no hay lenguaje, ning\u00fan texto flotando para poder revisar y decir: &#8216;Estoy de acuerdo con esto&#8217; o &#8216;No estoy de acuerdo con aquello&#8217;\u201d, le dijo Padilla a Manu Raju de CNN.<\/p>\n<p>\u201cVolviendo al manual de Trump, los grandes \u00e9xitos de Trump en materia de seguridad fronteriza no son la respuesta al problema\u201d.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald Trump a la pol\u00edtica de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444542","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald Trump a la pol\u00edtica de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-28T11:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump\",\"datePublished\":\"2024-01-28T11:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\"},\"wordCount\":1675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\",\"name\":\"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-01-28T11:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","og_locale":"es_ES","og_type":"article","og_title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias","og_description":"(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald Trump a la pol\u00edtica de [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","og_site_name":"Noticias","article_published_time":"2024-01-28T11:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/"},"author":{"name":"","@id":""},"headline":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","datePublished":"2024-01-28T11:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/"},"wordCount":1675,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","name":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-01-28T11:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","url":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-01-28T11:33:41Z","datePublished":"2024-01-28T11:33:41Z","dateModified":"2024-01-28T11:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/28\\\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/01\\\/28\\\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-01-28T11:33:41Z\",\"datePublished\":\"2024-01-28T11:33:41Z\",\"dateModified\":\"2024-01-28T11:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444544,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-2\/","url_meta":{"origin":1444542,"position":0},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444545,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-3\/","url_meta":{"origin":1444542,"position":1},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443082,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/03\/la-casa-blanca-se-enfoca-en-la-disminucion-de-los-cruces-fronterizos-mientras-el-presidente-de-la-camara-se-dirige-a-la-frontera-entre-texas-y-mexico\/","url_meta":{"origin":1444542,"position":2},"title":"La Casa Blanca se enfoca en la disminuci\u00f3n de los cruces fronterizos mientras el presidente de la C\u00e1mara se dirige a la frontera entre Texas y M\u00e9xico","author":"","date":"enero 3, 2024","format":false,"excerpt":"(CNN) -- Mientras el presidente de la C\u00e1mara de Representantes, Mike Johnson, se dirige a la frontera entre Estados Unidos y M\u00e9xico, los funcionarios de la administraci\u00f3n de Joe Biden destacaron una ca\u00edda importante en los cruces fronterizos esta semana inmediatamente despu\u00e9s de las conversaciones de alto nivel entre Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446497,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/04\/conclusiones-duelo-visitas-biden-trump-frontera-sur-campana-trax-2\/","url_meta":{"origin":1444542,"position":3},"title":"Cuatro conclusiones del duelo de visitas de Biden y Trump a la frontera en plena campa\u00f1a pol\u00edtica","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden y su oponente pol\u00edtico Donald Trump est\u00e1n de acuerdo: la situaci\u00f3n a lo largo de la frontera entre Estados Unidos y M\u00e9xico necesita cambiar. Pero sus extraordinarias visitas a Texas mostraron que los probables rivales en las elecciones generales de 2024 no podr\u00edan estar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446140,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/01\/conclusiones-duelo-visitas-biden-trump-frontera-sur-campana-trax\/","url_meta":{"origin":1444542,"position":4},"title":"Cuatro conclusiones del duelo de visitas de Biden y Trump a la frontera en plena campa\u00f1a pol\u00edtica","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden y su oponente pol\u00edtico Donald Trump est\u00e1n de acuerdo: la situaci\u00f3n a lo largo de la frontera entre Estados Unidos y M\u00e9xico necesita cambiar. Pero sus extraordinarias visitas a Texas mostraron que los probables rivales en las elecciones generales de 2024 no podr\u00edan estar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444601,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/29\/analisis-trump-aprovecha-la-muerte-de-militares-de-ee-uu-y-la-crisis-fronteriza-para-vender-su-mensaje-en-las-elecciones-generales\/","url_meta":{"origin":1444542,"position":5},"title":"AN\u00c1LISIS | Trump aprovecha la muerte de militares de EE.UU. y la crisis fronteriza para vender su mensaje en las elecciones generales","author":"","date":"enero 29, 2024","format":false,"excerpt":"(CNN) -- El argumento central de Donald Trump para las elecciones generales es que el presidente Joe Biden es d\u00e9bil e incapaz mientras los acontecimientos se descontrolan en casa y en el extranjero.Y \u00e9l se presenta como el hombre fuerte que Estados Unidos necesita para salvarlo.El expresidente pas\u00f3 la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1444542"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444542\/revisions"}],"predecessor-version":[{"id":1444558,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1444542\/revisions\/1444558"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1444542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1444542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1444542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}