{"id":1449540,"date":"2024-05-17T07:03:44","date_gmt":"2024-05-17T14:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/"},"modified":"2024-05-17T07:03:44","modified_gmt":"2024-05-17T14:03:44","slug":"vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","title":{"rendered":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La vicepresidenta de Ecuador, Ver\u00f3nica Abad, inform\u00f3 este jueves que recibi\u00f3 una carta del consulado de Estados Unidos en Guayaquil en la que le notificaron que cancelaron su visa para ingresar a ese pa\u00eds.<\/p>\n<p>Abad dijo a Ecuavisa \u2015afiliada de CNN\u2015 que no cuenta con detalles sobre la medida.<\/p>\n<p>\u201cEs real. Tengo una carta del consulado de Guayaquil sin indicar las razones. No es mi prioridad porque s\u00e9 el respeto. Entiendo que habr\u00e1 razones en las cuales yo puedo abogar y preguntar. No es mi inter\u00e9s en este momento en realidad porque he trabajado muchos a\u00f1os con el pueblo norteamericano a trav\u00e9s de la fundaci\u00f3n con la que form\u00e9, Ecuador empresario, recib\u00eda fondos de Estados Unidos\u201d, dijo.<\/p>\n<p>Adem\u00e1s, Abad \u2015que mantiene una abierta y p\u00fablica confrontaci\u00f3n con el presidente Daniel Noboa desde que ambos asumieron funciones en noviembre del a\u00f1o pasado\u2015, se\u00f1al\u00f3 que se est\u00e1n mezclando los conflictos que han rodeado sus funciones y asuntos del plano pol\u00edtico y familiar.<\/p>\n<p>La Canciller\u00eda de Ecuador pide a la vicepresidenta Abad que no hable de pol\u00edtica exterior en p\u00fablico sin autorizaci\u00f3n<\/p>\n<p>\u201cEl pueblo norteamericano sabe claramente con qui\u00e9n trabaja, y este sin duda alguna nuevamente es una \u2018mezcladilla\u2019\u201d, enfatiz\u00f3.<\/p>\n<p>CNN consult\u00f3 a la embajada de Estados Unidos sobre la cancelaci\u00f3n de la visa de Abad, que declin\u00f3 revelar detalles.<\/p>\n<p>\u201cLos registros de visados son reservados, seg\u00fan la legislaci\u00f3n estadounidense; por lo tanto, la Embajada y Consulado de Estados Unidos no comenta sobre casos individuales\u201d, precis\u00f3 una portavoz de la embajada.<\/p>\n<p>A inicios de diciembre, Noboa envi\u00f3 de forma indefinida a Abad a Israel como embajadora y representante de Ecuador para la paz en medio del conflicto de ese pa\u00eds con Hamas en Gaza. Abad viaj\u00f3 a Israel expresando su desacuerdo con la designaci\u00f3n y durante los \u00faltimos meses ha se\u00f1alado que el gobierno de Noboa la ha hostigado y que buscar\u00eda mecanismos para retirarla de su cargo.<\/p>\n<p>CNN solicit\u00f3 al Gobierno de Ecuador una reacci\u00f3n sobre la situaci\u00f3n de la vicepresidenta y est\u00e1 a la espera de comentarios.<\/p>\n<p>Durante la campa\u00f1a electoral, Noboa recorri\u00f3 varios lugares del pa\u00eds lejos de su compa\u00f1era de f\u00f3rmula, quien a su vez realiz\u00f3 declaraciones que pusieron en aprietos a Noboa y generaron cr\u00edticas. Abad cumpli\u00f3 una agenda por separado de Noboa, y no se les vio juntos tampoco el d\u00eda de la elecci\u00f3n (15 de octubre) ni durante las celebraciones tras el triunfo de la candidatura.<\/p>\n<p>Detenci\u00f3n de hijo de Abad<\/p>\n<p>El 21 de marzo, Francisco Sebasti\u00e1n Barreiro Abad, hijo de la vicepresidenta de Ecuador, fue detenido por las autoridades ecuatorianas y acusado de tr\u00e1fico de influencias, inform\u00f3 la Fiscal\u00eda.<\/p>\n<p>Arrestan a uno de los hijos de la vicepresidenta de Ecuador<\/p>\n<p>Barreiro Abad fue detenido en el marco de varios allanamientos que la Fiscal\u00eda de Ecuador realiz\u00f3 en Quito y Cuenca como parte de la investigaci\u00f3n del caso Nene, en el que las autoridades indagan una presunta red de tr\u00e1fico de influencias desde la Vicepresidencia del pa\u00eds. La defensa de Barreiro Abad ha rechazado las acusaciones y ha insistido en la inocencia del se\u00f1alado.<\/p>\n<p>El hijo de Abad permaneci\u00f3 en prisi\u00f3n preventiva desde ese momento y fue enviado a la c\u00e1rcel de m\u00e1xima seguridad de La Roca en Guayaquil, algo que fue considerado como una desproporci\u00f3n por algunos juristas y tambi\u00e9n por la vicepresidenta.<\/p>\n<p>La semana pasada, tras resolverse una apelaci\u00f3n y el pago de una fianza, el hijo de Abad sali\u00f3 de prisi\u00f3n; deber\u00e1 presentarse semanalmente ante la Fiscal\u00eda y mantendr\u00e1 prohibici\u00f3n de salida del pa\u00eds mientras avanza el caso.<\/p>\n<p>La vicepresidenta Abad ha insistido en que su hijo es un perseguido y que no existen pruebas relevantes en su contra.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La vicepresidenta de Ecuador, Ver\u00f3nica Abad, inform\u00f3 este jueves que recibi\u00f3 una carta del consulado de Estados Unidos en Guayaquil en la que le notificaron que cancelaron su visa para ingresar a ese pa\u00eds. Abad dijo a Ecuavisa \u2015afiliada de CNN\u2015 que no cuenta con detalles sobre la medida. \u201cEs real. Tengo una [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449540","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0La vicepresidenta de Ecuador, Ver\u00f3nica Abad, inform\u00f3 este jueves que recibi\u00f3 una carta del consulado de Estados Unidos en Guayaquil en la que le notificaron que cancelaron su visa para ingresar a ese pa\u00eds. Abad dijo a Ecuavisa \u2015afiliada de CNN\u2015 que no cuenta con detalles sobre la medida. \u201cEs real. Tengo una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T14:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa\",\"datePublished\":\"2024-05-17T14:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\",\"name\":\"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-17T14:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0La vicepresidenta de Ecuador, Ver\u00f3nica Abad, inform\u00f3 este jueves que recibi\u00f3 una carta del consulado de Estados Unidos en Guayaquil en la que le notificaron que cancelaron su visa para ingresar a ese pa\u00eds. Abad dijo a Ecuavisa \u2015afiliada de CNN\u2015 que no cuenta con detalles sobre la medida. \u201cEs real. Tengo una [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-17T14:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/"},"author":{"name":"","@id":""},"headline":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa","datePublished":"2024-05-17T14:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","name":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-17T14:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\u00f3 la visa","url":"http:\/\/noticiasya.com\/el-paso\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/05\/17\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-17T14:03:44Z","datePublished":"2024-05-17T14:03:44Z","dateModified":"2024-05-17T14:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La vicepresidenta de Ecuador asegura que Estados Unidos le cancel\\u00f3 la visa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/05\\\/17\\\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/05\\\/17\\\/vicepresidenta-ecuador-estados-unidos-cancelo-visa-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-17T14:03:44Z\",\"datePublished\":\"2024-05-17T14:03:44Z\",\"dateModified\":\"2024-05-17T14:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450191,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/10\/fiscalia-ecuador-vicepresidenta-procesada-presunto-trafico-de-influencias-orix\/","url_meta":{"origin":1449540,"position":0},"title":"La Fiscal\u00eda de Ecuador anuncia que la vicepresidenta ser\u00e1 procesada por presunto tr\u00e1fico de influencias","author":"","date":"junio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda General de Ecuador se\u00f1al\u00f3 este lunes que reuni\u00f3 suficientes elementos que determinan la supuesta participaci\u00f3n de la vicepresidenta de la Rep\u00fablica, Ver\u00f3nica Abad, en el delito de tr\u00e1fico de influencias, en el mismo caso en el que es procesado su hijo, Francisco Sebasti\u00e1n Barreiro Abad,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457000,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/26\/noboa-intentado-destitucion-veronica-abad-vicepresidenta-ecuador-orix\/","url_meta":{"origin":1449540,"position":1},"title":"Noboa &#171;ha intentado todos los d\u00edas provocar mi destituci\u00f3n&#187;, dice la vicepresidenta de Ecuador a CNN","author":"","date":"diciembre 26, 2024","format":false,"excerpt":"La vicepresidenta de Ecuador, Ver\u00f3nica Abad, consider\u00f3 este jueves que \u201cse hizo justicia\u201d luego de que una jueza fren\u00f3 la suspensi\u00f3n del cargo que el Ministerio del Trabajo hab\u00eda dictado en su contra, argumentando una supuesta ausencia injustificada de sus funciones, y asegur\u00f3 que este proceso administrativo es un ejemplo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455984,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/20\/veronica-abad-vicepresidenta-ecuador-regresa-a-quito-orix\/","url_meta":{"origin":1449540,"position":2},"title":"&#171;Casi encadenada y encerrada&#187;: Ver\u00f3nica Abad, vicepresidenta de Ecuador, regresa a Quito","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La vicepresidenta de Ecuador, Ver\u00f3nica Abad, lleg\u00f3 a Quito este mi\u00e9rcoles despu\u00e9s de haber viajado en diciembre en calidad de representante diplom\u00e1tica del pa\u00eds, y en declaraciones a los medios en el aeropuerto denunci\u00f3 que ha sido dejada indefensa y se le ha prohibido hablar.Abad vivi\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456898,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/23\/ecuador-suspension-restituye-vicepresidenta-veronica-abad-orix\/","url_meta":{"origin":1449540,"position":3},"title":"Jueza de Ecuador deja sin efecto suspensi\u00f3n de 150 d\u00edas y restituye a vicepresidenta Ver\u00f3nica Abad en sus funciones","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Una jueza constitucional dej\u00f3 sin efecto este lunes la resoluci\u00f3n administrativa que suspend\u00eda por 150 d\u00edas a la vicepresidenta de Ecuador, Ver\u00f3nica Abad, en un fallo que dispuso adem\u00e1s una disculpa p\u00fablica.La jueza Nubia Vera acogi\u00f3 una acci\u00f3n planteada por la vicepresidencia para levantar una sanci\u00f3n administrativa dictada por el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455706,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/09\/gobierno-de-ecuador-suspende-vicepresidenta-veronica-abad-orix\/","url_meta":{"origin":1449540,"position":4},"title":"Gobierno de Ecuador suspende a vicepresidenta Ver\u00f3nica Abad por 150 d\u00edas en medio de una ola de cr\u00edticas","author":"","date":"noviembre 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Ministerio de Trabajo de Ecuador dio a conocer este s\u00e1bado una resoluci\u00f3n administrativa que suspende por 150 d\u00edas sin remuneraci\u00f3n a la vicepresidenta de la Rep\u00fablica, Ver\u00f3nica Abad, argumentando que ha cometido un \u201cabandono injustificado del trabajo por tres o m\u00e1s d\u00edas laborales consecutivos\u201d. Abad se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455810,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/13\/vicepresidenta-ecuador-asamblea-rechazar-suspension-cargo-orix\/","url_meta":{"origin":1449540,"position":5},"title":"La vicepresidenta de Ecuador pide a la Asamblea Nacional rechazar la decisi\u00f3n del Gobierno de suspenderla del cargo","author":"","date":"noviembre 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La vicepresidenta de Ecuador, Ver\u00f3nica Abad, pidi\u00f3 este mi\u00e9rcoles a la Asamblea Nacional de su pa\u00eds pronunciarse en contra de la resoluci\u00f3n del Ministerio de Trabajo que la suspendi\u00f3 del cargo por 150 d\u00edas con el argumento de que se ausent\u00f3 de sus funciones injustificadamente.Durante una comparecencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1449540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1449540"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1449540\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1449540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1449540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1449540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}