{"id":1450718,"date":"2024-06-26T12:03:47","date_gmt":"2024-06-26T19:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/"},"modified":"2024-06-26T12:03:47","modified_gmt":"2024-06-26T19:03:47","slug":"empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","title":{"rendered":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este mi\u00e9rcoles comenz\u00f3 en Argentina el juicio oral por el intento de homicidio contra la expresidenta Cristian Fern\u00e1ndez de Kirchner. Hace casi dos a\u00f1os, el jueves 1 de septiembre de 2022, un hombre se acerc\u00f3 a la entonces vicepresidenta mientras saludaba a sus simpatizantes en la puerta su domicilio, en el barrio de Recoleta de la Ciudad de Buenos Aires, le apunt\u00f3 con un arma a 15 cent\u00edmetros de su cara y apret\u00f3 el gatillo. La bala no sali\u00f3.<br \/>\nEl hombre fue detenido esa noche y luego identificado por la Polic\u00eda Federal como Fernando Sabag Montiel. Naci\u00f3 el 13 de enero de 1987 en el estado de Sao Paulo, Brasil, y reside en Argentina desde 1993, seg\u00fan informaron fuentes de la Direcci\u00f3n de Migraciones del pa\u00eds. Sabag Montiel ten\u00eda permiso para portar armas, seg\u00fan inform\u00f3 la Agencia Nacional de Materiales Controlados (Anmac). Hab\u00eda sido detenido previamente en 2021 por &#171;uso de arma impropia&#187;, por portar un cuchicho de gran tama\u00f1o, informaron en aquel momento a CNN fuentes policiales.<\/p>\n<p>&#171;La quise matar, b\u00e1sicamente, por la situaci\u00f3n del pa\u00eds. El arma estaba cargada, tir\u00e9 el gatillo y el tiro no sali\u00f3. Ten\u00eda 5 balas el arma&#187;, dijo Sabag Montiel en una entrevista que le brind\u00f3 al periodista Ariel Zak del canal de noticias C5N en junio de 2023, hablando desde la c\u00e1rcel donde cumple prisi\u00f3n preventiva.<\/p>\n<p>D\u00edas despu\u00e9s, Fern\u00e1ndez de Kirchner asegur\u00f3 que en ese momento no tom\u00f3 conciencia del intento de asesinato. En los videos del hecho se ve a la entonces vicepresidenta agach\u00e1ndose y a sus guardias de seguridad conteni\u00e9ndola, en medio de una multitud que apunta inmediatamente contra el atacante.<\/p>\n<p>Cristina Kirchner durante un discurso el 27 de abril de 2023, en la ciudad de La Plata, Argentina. (Cr\u00e9dito: Ignacio Amiconi\/Getty Images)<\/p>\n<p>Conforme avanz\u00f3 la investigaci\u00f3n, fue detenida tambi\u00e9n Brenda Uliarte, de 23 a\u00f1os, novia de Fernando Sabag Montiel, quien se declar\u00f3 inocente. En la misma entrevista que brind\u00f3 desde la c\u00e1rcel, el primer acusado se refiri\u00f3 a la detenci\u00f3n de su compa\u00f1era: &#171;Yo lo hice por motus propio. Est\u00e1n inventando una historia. Yo actu\u00e9 solo. Con respecto al atentado, tengo las pruebas de que Brenda Uliarte no tuvo nada que ver&#187;.<\/p>\n<p>El fallido atentado se produjo tras varios d\u00edas de manifestaciones en apoyo a la exvicepresidenta, despu\u00e9s de que el fiscal Diego Luciani pidiera 12 a\u00f1os de prisi\u00f3n en su contra y su inhabilitaci\u00f3n para ejercer cargos p\u00fablicos. A Cristina Kirchner se la acusaba de haber encabezado una asociaci\u00f3n il\u00edcita para defraudar al Estado cuando era presidenta, a partir de una supuesta redirecci\u00f3n de contratos millonarios de obras viales en la provincia argentina de Santa Cruz, conocida judicial y medi\u00e1ticamente como &#171;Causa Vialidad&#187;.<\/p>\n<p>Por esta causa, a Fern\u00e1ndez de Kirchner la declararon culpable de administraci\u00f3n fraudulenta y perjuicio a la administraci\u00f3n p\u00fablica el 6 de diciembre de 2022, con una condena a seis a\u00f1os de prisi\u00f3n. Sin embargo, como la sentencia a\u00fan no est\u00e1 firme, la exvicepresidenta sigue en libertad.<\/p>\n<p>Tras la detenci\u00f3n de Sabag Montiel, la agencia estatal de noticias T\u00e9lam inform\u00f3 con base en fuentes oficiales que, en un primer momento, el tel\u00e9fono m\u00f3vil que usaba el acusado fue reiniciado cuando los peritos intentaban extraer pruebas del mismo. Esto entorpeci\u00f3 los primeros pasos en la investigaci\u00f3n a cargo de Mar\u00eda Eugenia Capuchetti, ya que se tard\u00f3 m\u00e1s de un mes en poder obtener la informaci\u00f3n del celular. CNN a\u00fan no ha podido confirmar de manera independiente lo sucedido con el tel\u00e9fono m\u00f3vil de Sabag Montiel.<\/p>\n<p>El 12 de junio de 2023 la causa fue elevada a juicio oral con tres acusados: Fernando Sabag Montiel y Brenda Uliarte se\u00f1alados de ser &#171;coautores de tentativa de homicidio doblemente calificado por alevos\u00eda y el concurso premeditado de dos o m\u00e1s personas, agravado por el uso de armas de fuego&#187;, tal como reza la acusaci\u00f3n formal, y Nicol\u00e1s Carrizo, un tercer detenido, se\u00f1alado como part\u00edcipe secundario.<\/p>\n<p>Por su parte, la exvicepresidenta exigi\u00f3 que se investigue la supuesta autor\u00eda intelectual que motoriz\u00f3 este fallido atentado. Un abogado de Fern\u00e1ndez de Kirchner, Jos\u00e9 Manuel Ubeira, dijo a Radio Continental: &#171;Claramente tenemos un juicio contra la persona que tuvo la responsabilidad que se vio en televisi\u00f3n, o sea, el atacante, y las personas que lo rodeaban; pero todav\u00eda tenemos en una nebulosa qu\u00e9 es lo que lo motiv\u00f3 y qui\u00e9n lo financi\u00f3&#187;.<\/p>\n<p>Tal como declar\u00f3 en una entrevista con el medio argentino El Destape el otro abogado de Cristina Fern\u00e1ndez de Kirchner, Marcos Aldaz\u00e1bal, &#171;la exvicepresidenta tiene que declarar como testigo&#187;. Por otro lado, el letrado tambi\u00e9n destac\u00f3 que ser\u00e1 un juicio que durar\u00e1 \u201centre medio a\u00f1o y un a\u00f1o, aproximadamente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Este mi\u00e9rcoles comenz\u00f3 en Argentina el juicio oral por el intento de homicidio contra la expresidenta Cristian Fern\u00e1ndez de Kirchner. Hace casi dos a\u00f1os, el jueves 1 de septiembre de 2022, un hombre se acerc\u00f3 a la entonces vicepresidenta mientras saludaba a sus simpatizantes en la puerta su domicilio, en el barrio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450718","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Este mi\u00e9rcoles comenz\u00f3 en Argentina el juicio oral por el intento de homicidio contra la expresidenta Cristian Fern\u00e1ndez de Kirchner. Hace casi dos a\u00f1os, el jueves 1 de septiembre de 2022, un hombre se acerc\u00f3 a la entonces vicepresidenta mientras saludaba a sus simpatizantes en la puerta su domicilio, en el barrio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T19:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3\",\"datePublished\":\"2024-06-26T19:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\"},\"wordCount\":869,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\",\"name\":\"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-26T19:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Este mi\u00e9rcoles comenz\u00f3 en Argentina el juicio oral por el intento de homicidio contra la expresidenta Cristian Fern\u00e1ndez de Kirchner. Hace casi dos a\u00f1os, el jueves 1 de septiembre de 2022, un hombre se acerc\u00f3 a la entonces vicepresidenta mientras saludaba a sus simpatizantes en la puerta su domicilio, en el barrio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-26T19:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/"},"author":{"name":"","@id":""},"headline":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3","datePublished":"2024-06-26T19:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/"},"wordCount":869,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","name":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-26T19:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Empieza el juicio oral por el intento de asesinato de Cristina Fern\u00e1ndez de Kirchner: esto fue lo que pas\u00f3","url":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/26\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-26T19:03:47Z","datePublished":"2024-06-26T19:03:47Z","dateModified":"2024-06-26T19:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Empieza el juicio oral por el intento de asesinato de Cristina Fern\\u00e1ndez de Kirchner: esto fue lo que pas\\u00f3\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/26\\\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/26\\\/empieza-juicio-oral-intento-asesinato-cristina-fernandez-de-kirchner-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-26T19:03:47Z\",\"datePublished\":\"2024-06-26T19:03:47Z\",\"dateModified\":\"2024-06-26T19:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467213,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/08\/condena-intento-asesinato-cristina-fernandez-kirchner-orix\/","url_meta":{"origin":1450718,"position":0},"title":"Condenan a quienes intentaron asesinar a Cristina Fern\u00e1ndez de Kirchner en Argentina","author":"","date":"octubre 8, 2025","format":false,"excerpt":"Un juzgado argentino conden\u00f3 este mi\u00e9rcoles a los autores del intento de asesinato de la expresidenta Cristina Fern\u00e1ndez, ocurrido en septiembre de 2022, tras m\u00e1s de un a\u00f1o de juicio.El fallo del Tribunal Oral Federal N\u00b0 6 fij\u00f3 una pena de 10 a\u00f1os a Fernando Sabag Montiel, de 37 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456326,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/06\/cristina-kirchner-juicio-memorandum-iran-orix\/","url_meta":{"origin":1450718,"position":1},"title":"La Corte Suprema confirm\u00f3 que Cristina Kirchner ir\u00e1 a juicio oral por la causa del memor\u00e1ndum con Ir\u00e1n","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"Cristina Fern\u00e1ndez de Kirchner deber\u00e1 afrontar un nuevo juicio oral en su contra. Este jueves, la Corte Suprema de Justicia argentina rechaz\u00f3 el pedio de la defensa y confirm\u00f3 que la expresidenta ir\u00e1 a juicio por el memor\u00e1ndum con Ir\u00e1n.El texto del \u201cMemor\u00e1ndum de Entendimiento\u201d, firmado en 2013 durante su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463412,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/10\/quien-es-cristina-fernandez-kirchner-orix\/","url_meta":{"origin":1450718,"position":2},"title":"\u00bfQui\u00e9n es Cristina Fern\u00e1ndez de Kirchner y cu\u00e1l ha sido su relevancia en la pol\u00edtica de Argentina?","author":"","date":"junio 10, 2025","format":false,"excerpt":"Desde su triunfo en las elecciones presidenciales de 2007, Cristina Fern\u00e1ndez de Kirchner se consolid\u00f3 como una de las figuras m\u00e1s relevantes de la pol\u00edtica en Argentina de los \u00faltimos a\u00f1os, con seguidores y cr\u00edticos por igual y una enorme influencia en la vida del pa\u00eds.Fern\u00e1ndez de Kirchner, quien ya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463665,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/17\/prision-domiciliaria-expresidenta-argentina-cristina-kirchner-orix\/","url_meta":{"origin":1450718,"position":3},"title":"Otorgan prisi\u00f3n domiciliaria a la expresidenta de Argentina Cristina Fern\u00e1ndez de Kirchner","author":"","date":"junio 17, 2025","format":false,"excerpt":"La Justicia de Argentina concedi\u00f3 este martes prisi\u00f3n domiciliaria a la expresidenta Cristina Fern\u00e1ndez de Kirchner, a quien la semana pasada la Corte Suprema confirm\u00f3 una condena de seis a\u00f1os de c\u00e1rcel por la llamada causa Vialidad, en la que se le atribuyen actos de corrupci\u00f3n en la adjudicaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456103,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/26\/que-es-ficha-limpia-proyecto-terminar-carrera-politica-cristina-kirchner-orix\/","url_meta":{"origin":1450718,"position":4},"title":"\u00bfQu\u00e9 es la Ficha Limpia? El proyecto que podr\u00eda terminar con la carrera pol\u00edtica de Cristina Kirchner","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2014 En Argentina, este jueves, el Congreso de la Naci\u00f3n debatir\u00e1 un proyecto que podr\u00eda marcar un antes y un despu\u00e9s en la pol\u00edtica local: la Ley Ficha Limpia. La iniciativa busca impedir que personas con condenas judiciales confirmadas en segunda instancia accedan a cargos p\u00fablicos, ya sea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445365,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/13\/la-relacion-del-papa-francisco-con-los-presidentes-de-argentina\/","url_meta":{"origin":1450718,"position":5},"title":"La relaci\u00f3n del papa Francisco con los presidentes de Argentina","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El papa Francisco recibi\u00f3 este lunes al nuevo presidente de Argentina, Javier Milei. Es la ocasi\u00f3n n\u00famero 12 en que el pont\u00edfice recibe a mandatarios de su pa\u00eds natal, al que no ha regresado desde que fue nombrado papa en marzo de 2013. \u00bfC\u00f3mo fue la relaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1450718"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450718\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1450718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1450718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1450718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}