{"id":1450736,"date":"2024-06-27T03:03:52","date_gmt":"2024-06-27T10:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/"},"modified":"2024-06-27T03:03:52","modified_gmt":"2024-06-27T10:03:52","slug":"tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","title":{"rendered":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU"},"content":{"rendered":"<p>(CNN) &#8212; Los bancos internacionales est\u00e1n desempe\u00f1ando un papel importante en la capacidad de la junta militar de Myanmar para llevar a cabo su asalto sistem\u00e1tico y mortal contra su pueblo, seg\u00fan ha revelado un nuevo informe respaldado por Naciones Unidas.<\/p>\n<p>Los bancos tailandeses se han convertido en la principal fuente a trav\u00e9s de la cual el ej\u00e9rcito de Myanmar est\u00e1 comprando armas y suministros militares \u2013incluso piezas para helic\u00f3pteros de combate\u2013 utilizados para apoyar su guerra civil de tres a\u00f1os que ha devastado el pa\u00eds y matado a m\u00e1s de 5.000 civiles, dijo el relator especial de la ONU sobre derechos humanos Tom Andrews en un nuevo informe este mi\u00e9rcoles.<\/p>\n<p>Desde que tomaron el poder en un golpe de Estado en febrero de 2021, los militares han librado una guerra cada vez m\u00e1s intensa contra grupos armados \u00e9tnicos y fuerzas de resistencia popular en todo Myanmar. En los \u00faltimos meses ha sufrido importantes p\u00e9rdidas de territorio y soldados.<\/p>\n<p>Mientras hace frente a la oposici\u00f3n generalizada de la poblaci\u00f3n y a una crisis econ\u00f3mica que ha disparado los niveles de pobreza, la junta increment\u00f3 los ataques a\u00e9reos y los ataques contra civiles e infraestructuras civiles, y desplaz\u00f3 a m\u00e1s de 3 millones de personas.<\/p>\n<p>Quemas y decapitaciones: la junta militar de Myanmar intensifica las t\u00e1cticas de terror contra su pueblo<\/p>\n<p>La brutal campa\u00f1a de violencia del Ej\u00e9rcito llev\u00f3 a los pa\u00edses occidentales a imponer amplias sanciones a los l\u00edderes militares, sus familiares y simpatizantes, las empresas estatales, los bancos y los proveedores de combustible para aviones.<\/p>\n<p>&#171;La junta, o Consejo de Administraci\u00f3n del Estado (CAE), cuenta con dos recursos principales procedentes del extranjero: armas y dinero&#187;, afirma Andrews en el informe.<\/p>\n<p>El informe, titulado \u201cC\u00f3mo bancos y gobiernos facilitan la Junta Militar en Myanmar\u201d, revel\u00f3 que 16 bancos de siete pa\u00edses han procesado transacciones vinculadas a las adquisiciones del Ej\u00e9rcito en el \u00faltimo a\u00f1o.<\/p>\n<p>Las armas, tecnolog\u00edas de doble uso, equipos de fabricaci\u00f3n y materias primas aseguradas por la junta desde el extranjero alcanzaron los US$ 253 millones entre abril de 2023 y marzo de 2024, seg\u00fan el informe.<\/p>\n<p>Junta de Myanmar aplica ley de servicio militar obligatorio<\/p>\n<p>&#171;Al confiar en instituciones financieras que est\u00e1n dispuestas a hacer negocios con los bancos estatales de Myanmar bajo su control, la junta tiene f\u00e1cil acceso a los servicios financieros que necesita para llevar a cabo violaciones sistem\u00e1ticas de los derechos humanos, incluidos ataques a\u00e9reos contra civiles&#187;, dijo Andrews.<\/p>\n<p>Sin embargo, el volumen de armas y suministros militares adquiridos por la junta a trav\u00e9s de bancos extranjeros ha disminuido en un tercio desde 2023, y las exportaciones desde Singapur se han reducido dr\u00e1sticamente, seg\u00fan el informe.<\/p>\n<p>&#171;La buena noticia es que la junta est\u00e1 cada vez m\u00e1s aislada&#187;, dijo Andrews. &#171;La mala noticia es que la junta est\u00e1 eludiendo las sanciones y otras medidas aprovechando las lagunas en los reg\u00edmenes de sanciones, cambiando las instituciones financieras y aprovechando el fracaso de los Estados miembros para coordinar y hacer cumplir plenamente las acciones.&#187;<\/p>\n<p>Soldados del Ej\u00e9rcito de Liberaci\u00f3n Nacional Karen (KNLA) patrullan en un veh\u00edculo, junto a una zona destruida por un ataque a\u00e9reo militar de Myanmar en Myawaddy, una ciudad fronteriza entre Tailandia y Myanmar, el 15 de abril de 2024. (Cr\u00e9dito: Athit Perawongmetha\/Reuters)<\/p>\n<p>La conexi\u00f3n tailandesa<\/p>\n<p>Las entidades con sede en Singapur eran la tercera fuente de armas y material militar de Myanmar. Pero tras una investigaci\u00f3n gubernamental, el flujo de material armament\u00edstico a Myanmar procedente de empresas registradas en Singapur se redujo en casi un 90% en comparaci\u00f3n con el a\u00f1o anterior.<\/p>\n<p>En 2022, los bancos con sede en Singapur facilitaron m\u00e1s del 70% de las compras de la junta que pasaron por el sistema bancario. En 2023, esta cifra se hab\u00eda reducido a menos del 20%, seg\u00fan el informe.<\/p>\n<p>En busca de otras instituciones financieras, la Junta encontr\u00f3 a la vecina Tailandia.<\/p>\n<p>Entre 2022 y 2023, las exportaciones de armas y materiales relacionados de entidades con sede en Tailandia se duplicaron con creces, pasando de US$ 60 millones a casi US$ 130 millones el a\u00f1o pasado.<\/p>\n<p>Myanmar supera a Afganist\u00e1n y se convierte en el principal productor de opio del mundo, dice la ONU<\/p>\n<p>&#171;Muchas compras de SAC (junta) realizadas anteriormente a entidades con sede en Singapur, incluidas las piezas para los helic\u00f3pteros Mi-17 y Mi-35 utilizadas para llevar a cabo ataques a\u00e9reos contra objetivos civiles, ahora se obtienen de Tailandia&#187;, dijo el informe&#187;.<\/p>\n<p>El Siam Commercial Bank es uno de los bancos tailandeses que desempe\u00f1aron un &#171;papel crucial&#187; en este cambio, seg\u00fan el informe. En 2022, el banco facilit\u00f3 poco m\u00e1s de US$ 5 millones en transacciones relacionadas con los militares, en 2023 esa cifra se dispar\u00f3 a m\u00e1s de US$ 100 millones, seg\u00fan el informe.<\/p>\n<p>CNN se ha puesto en contacto con el Siam Commercial Bank para pedirle comentarios sobre el informe, pero no ha recibido respuesta.<\/p>\n<p>Un portavoz del Ministerio de Asuntos Exteriores de Tailandia dijo a CNN: &#171;Vimos el informe y lo estamos estudiando&#187;.<\/p>\n<p>&#171;Se han nombrado muchos pa\u00edses y ciertamente son pa\u00edses por los que pasar\u00eda la mayor\u00eda de las transacciones financieras de la regi\u00f3n&#187;, dijo el portavoz en un comunicado.<\/p>\n<p>Junta militar de Myanmar restringe la ayuda humanitaria tras el paso del cicl\u00f3n Mocha<\/p>\n<p>&#171;Nuestras instituciones bancarias y financieras siguen los protocolos bancarios como cualquier gran centro financiero. As\u00ed que tendremos que establecer primero los hechos antes de considerar cualquier otro paso&#187;.<\/p>\n<p>Andrews afirm\u00f3 que es &#171;fundamental&#187; que &#171;las instituciones financieras se tomen en serio sus obligaciones en materia de derechos humanos y no faciliten las transacciones mortales de la Junta.&#187;<\/p>\n<p>Adem\u00e1s, sancionar a las redes que suministran combustible de aviaci\u00f3n a la junta y al &#171;banco de confianza&#187; de los militares, Myanma Economic Bank, &#171;podr\u00eda desempe\u00f1ar un papel decisivo para ayudar a cambiar la situaci\u00f3n en Myanmar y salvar un n\u00famero incalculable de vidas&#187;, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los bancos internacionales est\u00e1n desempe\u00f1ando un papel importante en la capacidad de la junta militar de Myanmar para llevar a cabo su asalto sistem\u00e1tico y mortal contra su pueblo, seg\u00fan ha revelado un nuevo informe respaldado por Naciones Unidas. Los bancos tailandeses se han convertido en la principal fuente a trav\u00e9s de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450736","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los bancos internacionales est\u00e1n desempe\u00f1ando un papel importante en la capacidad de la junta militar de Myanmar para llevar a cabo su asalto sistem\u00e1tico y mortal contra su pueblo, seg\u00fan ha revelado un nuevo informe respaldado por Naciones Unidas. Los bancos tailandeses se han convertido en la principal fuente a trav\u00e9s de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T10:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU\",\"datePublished\":\"2024-06-27T10:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\"},\"wordCount\":1064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\",\"name\":\"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-27T10:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias","og_description":"(CNN) &#8212; Los bancos internacionales est\u00e1n desempe\u00f1ando un papel importante en la capacidad de la junta militar de Myanmar para llevar a cabo su asalto sistem\u00e1tico y mortal contra su pueblo, seg\u00fan ha revelado un nuevo informe respaldado por Naciones Unidas. Los bancos tailandeses se han convertido en la principal fuente a trav\u00e9s de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-27T10:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/"},"author":{"name":"","@id":""},"headline":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU","datePublished":"2024-06-27T10:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/"},"wordCount":1064,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","name":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-27T10:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\u00fan un experto de la ONU","url":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-27T10:03:52Z","datePublished":"2024-06-27T10:03:52Z","dateModified":"2024-06-27T10:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tailandia es ahora el destino bancario preferido de la junta de Myanmar mientras aumentan los ataques militares, seg\\u00fan un experto de la ONU\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/27\\\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/27\\\/tailandia-destino-bancario-junta-myanmar-ataques-militares-onu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-27T10:03:52Z\",\"datePublished\":\"2024-06-27T10:03:52Z\",\"dateModified\":\"2024-06-27T10:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465568,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/16\/junta-militar-myanmar-elecciones-onu-atrocidades-trax\/","url_meta":{"origin":1450736,"position":0},"title":"Esta junta militar cambi\u00f3 de imagen para celebrar elecciones. Pero la ONU encontr\u00f3 pruebas de atrocidades cada vez m\u00e1s graves","author":"","date":"agosto 16, 2025","format":false,"excerpt":"A medida que aumenta la evidencia de atrocidades cada vez m\u00e1s intensas, incluyendo la tortura de ni\u00f1os, que se est\u00e1n cometiendo en Myanmar, los generales de las fuerzas armadas del pa\u00eds est\u00e1n rebrandeando su r\u00e9gimen de junta y planeando elecciones manipuladas en una naci\u00f3n de la que solo controlan partes.Han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450719,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/26\/mexico-tercer-productor-opiaceos-metanfetaminas-onu-orix\/","url_meta":{"origin":1450736,"position":1},"title":"M\u00e9xico es el tercer mayor productor de opi\u00e1ceos y metanfetaminas, seg\u00fan informe de la ONU","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 M\u00e9xico es el tercer mayor productor de opi\u00e1ceos y metanfetaminas, de acuerdo con un informe difundido este mi\u00e9rcoles por la Organizaci\u00f3n de las Naciones Unidas contra la Droga y el Delito.El Informe Mundial sobre Drogas 2023 indica que el pa\u00eds es superado en este rubro por Afganist\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460735,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/02\/myanmar-terremotos-sobrevivientes-edificios-derrumbes-trax\/","url_meta":{"origin":1450736,"position":2},"title":"Los edificios en Myanmar siguen derrumb\u00e1ndose d\u00edas despu\u00e9s del mortal terremoto","author":"","date":"abril 2, 2025","format":false,"excerpt":"Cinco d\u00edas despu\u00e9s del potente terremoto que azot\u00f3 el pa\u00eds, los edificios en Myanmar siguen derrumb\u00e1ndose, creando condiciones peligrosas para los rescatistas que intentan sacar a los supervivientes de entre los escombros.M\u00e1s de 2.700 personas murieron en el terremoto de magnitud 7,7, y miles m\u00e1s resultaron heridas, seg\u00fan la junta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466991,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/09\/30\/estafadores-kokang-condenados-muerte-myanmar-china-trax\/","url_meta":{"origin":1450736,"position":3},"title":"Condenan a muerte en China a estafadores que dirig\u00edan un imperio criminal multimillonario","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Un tribunal en China conden\u00f3 a muerte a 11 personas por su papel en un imperio criminal multimillonario dirigido por una familia y levantado a partir de operaciones de estafa y apuestas en l\u00ednea en una remota regi\u00f3n fronteriza de Myanmar, as\u00ed como por la muerte de trabajadores que intentaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470603,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/29\/china-ejecuta-banda-criminal-myanmar-trax\/","url_meta":{"origin":1450736,"position":4},"title":"China ejecuta a 11 miembros de una banda que dirig\u00eda un imperio criminal de miles de millones de d\u00f3lares en Myanmar","author":"","date":"enero 29, 2026","format":false,"excerpt":"China ejecut\u00f3 a 11 miembros de la notoria banda criminal de la familia Ming, que operaba centros de estafa al estilo mafioso en Myanmar y mataba a trabajadores que intentaban escapar, informaron este jueves medios estatales chinos.La familia Ming era una de las llamadas \u201ccuatro familias\u201d del norte de Myanmar,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460760,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/02\/fuerzas-armadas-myanmar-alto-fuego-temporal-ayudar-terremoto-trax\/","url_meta":{"origin":1450736,"position":5},"title":"Fuerzas armadas de Myanmar anuncian un alto el fuego temporal para ayudar en los esfuerzos tras el terremoto","author":"","date":"abril 2, 2025","format":false,"excerpt":"El gobierno militar de Myanmar anunci\u00f3 un alto al fuego temporal en sus operaciones contra los grupos armados de oposici\u00f3n para facilitar los esfuerzos de recuperaci\u00f3n tras el devastador terremoto ocurrido el viernes.\u201cPara expresar solidaridad con las v\u00edctimas del terremoto en todo el pa\u00eds y para brindar una efectiva operaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1450736"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450736\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1450736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1450736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1450736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}