{"id":1450740,"date":"2024-06-27T09:03:40","date_gmt":"2024-06-27T16:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/"},"modified":"2024-06-27T09:03:40","modified_gmt":"2024-06-27T16:03:40","slug":"walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","title":{"rendered":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU."},"content":{"rendered":"<p>(CNN) &#8212; Walgreens cerrar\u00e1 un n\u00famero considerable de sus aproximadamente 8.600 establecimientos en todo Estados Unidos,\u00a0en un intento de restablecer el negocio de la cadena farmac\u00e9utica, que atraviesa dificultades.<\/p>\n<p>La empresa no anunci\u00f3 el n\u00famero concreto de tiendas que cerrar\u00e1, pero dijo este jueves que est\u00e1 planeando cierres &#171;significativos&#187; de tiendas de bajo rendimiento en todo Estados Unidos como parte de un programa de optimizaci\u00f3n plurianual.<\/p>\n<p>El CEO Tim Wentworth dijo en una llamada con analistas el jueves que &#171;los cambios son inminentes&#187; para el aproximadamente 25% de las tiendas que no son rentables y la revisi\u00f3n estrat\u00e9gica de Walgreens &#171;incluir\u00e1 el cierre de una parte significativa de estas tiendas de bajo rendimiento&#187;.<\/p>\n<p>Las acciones de Walgreens (WBA) cayeron casi un 17% en las operaciones previas a la apertura del mercado.<\/p>\n<p>\u00bfPor qu\u00e9 est\u00e1n cerrando las tiendas de todo a un d\u00f3lar en Estados Unidos?<\/p>\n<p>&#171;Seguimos enfrent\u00e1ndonos a un entorno operativo dif\u00edcil, que incluye presiones persistentes sobre el consumidor estadounidense y el impacto de la reciente din\u00e1mica del mercado, que ha erosionado los m\u00e1rgenes de las farmacias&#187;, dijo Wentworth en un comunicado de prensa. &#171;Nuestros resultados y perspectivas reflejan estos vientos en contra&#187;.<\/p>\n<p>Las ventas aumentaron un 2,6%, hasta US$ 36.400 millones en el trimestre. Esto podr\u00eda &#171;no parecer descabellado, pero est\u00e1 por debajo de la inflaci\u00f3n y, en algunos segmentos del negocio, representa una p\u00e9rdida de cuota de mercado&#187;, dijo Neil Saunders, director gerente de GlobalData, en una nota.<\/p>\n<p>Especialmente preocupante para Walgreens fue la ca\u00edda de sus ventas minoristas en un 4% durante el trimestre. Pero no es de extra\u00f1ar, ya que sus dificultades en el punto de venta se han visto &#171;exacerbadas por la crisis del coste de la vida, que ha hecho que los clientes reduzcan el volumen de productos que compran y busquen las mejores ofertas y gangas&#187;, a\u00f1adi\u00f3 Saunders.<\/p>\n<p>Walgreens cerrar\u00e1 una cantidad sustancial de sus sucursales en Estados Unidos en los pr\u00f3ximos a\u00f1os. (Foto: Scott Olson\/Getty Images).<\/p>\n<p>Walgreens recort\u00f3 los precios de m\u00e1s de 1.000 art\u00edculos en mayo, siguiendo los pasos de sus rivales en un esfuerzo por atraer de nuevo a los compradores cansados de la inflaci\u00f3n y desanimados por los altos precios.<\/p>\n<p>Las principales cadenas de farmacias, incluidas CVS (CVS) y Rite Aid, han tenido problemas en los \u00faltimos a\u00f1os debido a la disminuci\u00f3n de los beneficios procedentes de la prescripci\u00f3n de medicamentos. Disminuyeron debido a las tasas de reembolso m\u00e1s bajas para los medicamentos recetados y la nueva competencia de Amazon.<\/p>\n<p>La parte delantera de las farmacias, donde venden refrigerios y productos b\u00e1sicos para el hogar, tambi\u00e9n se enfrenta a la presi\u00f3n de competidores m\u00e1s grandes, incluidos Target y las tiendas de d\u00f3lar.<\/p>\n<p>Dollar Tree se muda a las tiendas de 99 Cents Only<\/p>\n<p>Aunque las farmacias se beneficiaron durante la pandemia de las vacunas contra el covid-19, cada vez son menos los consumidores que acuden a comprar. El volumen de recetas tambi\u00e9n est\u00e1 cayendo porque la gente se somete a menos procedimientos electivos.<\/p>\n<p>Los medicamentos GLP-1, que incluyen Ozempic y Mounjaro para tratar la p\u00e9rdida de peso y la diabetes, no han sido una bendici\u00f3n para la cadena. Wentworth declar\u00f3 al Journal que est\u00e1 perdiendo dinero con esas recetas.<\/p>\n<p>En los \u00faltimos a\u00f1os, CVS cerr\u00f3 unos 900 establecimientos y Rite Aid, que entr\u00f3 en quiebra en octubre, cerr\u00f3 m\u00e1s de 100.<\/p>\n<p>Nathaniel Meyersohn de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Walgreens cerrar\u00e1 un n\u00famero considerable de sus aproximadamente 8.600 establecimientos en todo Estados Unidos,\u00a0en un intento de restablecer el negocio de la cadena farmac\u00e9utica, que atraviesa dificultades. La empresa no anunci\u00f3 el n\u00famero concreto de tiendas que cerrar\u00e1, pero dijo este jueves que est\u00e1 planeando cierres &#171;significativos&#187; de tiendas de bajo rendimiento en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450740","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &quot;significativo&quot; de sus cerca de 8.600 establecimientos en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &quot;significativo&quot; de sus cerca de 8.600 establecimientos en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Walgreens cerrar\u00e1 un n\u00famero considerable de sus aproximadamente 8.600 establecimientos en todo Estados Unidos,\u00a0en un intento de restablecer el negocio de la cadena farmac\u00e9utica, que atraviesa dificultades. La empresa no anunci\u00f3 el n\u00famero concreto de tiendas que cerrar\u00e1, pero dijo este jueves que est\u00e1 planeando cierres &#171;significativos&#187; de tiendas de bajo rendimiento en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T16:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU.\",\"datePublished\":\"2024-06-27T16:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\"},\"wordCount\":623,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\",\"name\":\"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero \\\"significativo\\\" de sus cerca de 8.600 establecimientos en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-27T16:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero \"significativo\" de sus cerca de 8.600 establecimientos en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero \"significativo\" de sus cerca de 8.600 establecimientos en EE.UU. - Noticias","og_description":"(CNN) &#8212; Walgreens cerrar\u00e1 un n\u00famero considerable de sus aproximadamente 8.600 establecimientos en todo Estados Unidos,\u00a0en un intento de restablecer el negocio de la cadena farmac\u00e9utica, que atraviesa dificultades. La empresa no anunci\u00f3 el n\u00famero concreto de tiendas que cerrar\u00e1, pero dijo este jueves que est\u00e1 planeando cierres &#171;significativos&#187; de tiendas de bajo rendimiento en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-27T16:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/"},"author":{"name":"","@id":""},"headline":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU.","datePublished":"2024-06-27T16:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/"},"wordCount":623,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","name":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero \"significativo\" de sus cerca de 8.600 establecimientos en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-27T16:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La cadena farmac\u00e9utica Walgreens cerrar\u00e1 un n\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU.","url":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/27\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-27T16:03:40Z","datePublished":"2024-06-27T16:03:40Z","dateModified":"2024-06-27T16:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La cadena farmac\\u00e9utica Walgreens cerrar\\u00e1 un n\\u00famero &#171;significativo&#187; de sus cerca de 8.600 establecimientos en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/27\\\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/27\\\/walgreens-cerrara-numero-significativo-8-000-establecimientos-ee-uu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-27T16:03:40Z\",\"datePublished\":\"2024-06-27T16:03:40Z\",\"dateModified\":\"2024-06-27T16:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455105,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/10\/15\/walgreens-cerrara-1-200-tiendas-trax\/","url_meta":{"origin":1450740,"position":0},"title":"Walgreens cerrar\u00e1 1.200 tiendas en Estados Unidos","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN) -- Walgreens cerrar\u00e1 aproximadamente 1.200 sucursales mientras la cadena de farmacias lucha contra los competidores en l\u00ednea y los pagos decrecientes de medicamentos recetados.Para 2027, aproximadamente una de cada siete tiendas Walgreens actualmente abiertas cerrar\u00e1 sus puertas. Alrededor de 500 Walgreens cerrar\u00e1n sus puertas durante el pr\u00f3ximo a\u00f1o, anunci\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468136,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/11\/07\/wendys-cerrara-cientos-restaurantes-trax\/","url_meta":{"origin":1450740,"position":1},"title":"Wendy&#8217;s cerrar\u00e1 cientos de restaurantes en EE.UU, anunci\u00f3 su CEO","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"Wendy\u2019s cerrar\u00e1 cientos de locales en todo Estados Unidos como parte de su plan de reestructuraci\u00f3n.El CEO interino, Ken Cook, anunci\u00f3 este viernes que un \u201cporcentaje de un solo d\u00edgito medio\u201d de los aproximadamente 6.000 locales de Wendy\u2019s en EE.UU. podr\u00eda cerrar, lo que equivaldr\u00eda a entre 200 y 350\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456884,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/23\/horarios-tiendas-supermercados-bancos-eeuu-nochebuena-navidad-trax\/","url_meta":{"origin":1450740,"position":2},"title":"Horarios de tiendas, supermercados y bancos en EE.UU en Nochebuena y Navidad: \u00bfQu\u00e9 abre y qu\u00e9 cierra?","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Los recados de \u00faltimo minuto a menudo parecen aparecer en Navidad y Nochebuena, ya sea para comprar un regalo r\u00e1pido o recoger un \u00faltimo ingrediente.Muchas tiendas y oficinas est\u00e1n cerradas en estas dos festividades para dar a los empleados la oportunidad de pasar tiempo con sus seres queridos durante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457481,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/13\/kohl-cerrara-27-tiendas-ee-uu-trax\/","url_meta":{"origin":1450740,"position":3},"title":"Kohl cerrar\u00e1 27 tiendas en EE.UU. Estas son las que se ver\u00e1n afectadas por estado","author":"","date":"enero 13, 2025","format":false,"excerpt":"Kohl\u2019s cerrar\u00e1 27 tiendas en m\u00e1s de una decena de estados mientras busca mejorar su rentabilidad.Los cierres, que se completar\u00e1n en abril, son de una peque\u00f1a fracci\u00f3n de las 1.150 tiendas de la cadena que fueron catalogadas como de \u201cbajo rendimiento\u201d, seg\u00fan un comunicado de prensa. Kohl\u2019s dijo que \u201csigue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460439,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/26\/gamestop-numero-tiendas-invertira-bitcoin-trax\/","url_meta":{"origin":1450740,"position":4},"title":"GameStop cerrar\u00e1 un &#8216;n\u00famero significativo&#8217; de tiendas e invertir\u00e1 fuertemente en bitcoin","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Tras el cierre de aproximadamente una cuarta parte de sus sucursales durante el \u00faltimo a\u00f1o, alrededor de 1.000 tiendas en todo el mundo, GameStop afirma que a\u00fan no ha terminado. A medida que la empresa en dificultades clausura locales, anuncia que invertir\u00e1 su dinero en criptomonedas.GameStop revel\u00f3 en una presentaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446924,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/13\/family-dollar-y-dollar-tree-cerraran-1-000-tiendas-inflacion-apoyos-a-familias-trax\/","url_meta":{"origin":1450740,"position":5},"title":"Family Dollar y Dollar Tree cerrar\u00e1n 1.000 tiendas en Estados Unidos","author":"","date":"marzo 13, 2024","format":false,"excerpt":"Nueva York (CNN) \u2014 Family Dollar, la cadena de descuentos que abastece principalmente a clientes de bajos ingresos en las ciudades, anunci\u00f3 este mi\u00e9rcoles que cerrar\u00e1 casi 1.000 tiendas en Estados Unidos.A\u00f1os de mala gesti\u00f3n y condiciones dif\u00edciles en las tiendas perjudicaron la marca Family Dollar. De hecho, esta cadena,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1450740"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450740\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1450740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1450740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1450740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}