{"id":1450810,"date":"2024-06-30T16:03:49","date_gmt":"2024-06-30T23:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/"},"modified":"2024-06-30T16:03:49","modified_gmt":"2024-06-30T23:03:49","slug":"resultado-mexico-ecuador-copa-america-goles-en-vivo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","title":{"rendered":"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo"},"content":{"rendered":"<p>\u26bd Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes<\/p>\n<p>El bal\u00f3n oficial de la Copa Am\u00e9rica se muestra durante una conferencia de prensa antes del partido entre M\u00e9xico y Ecuador en el State Farm Stadium, el 29 de junio de 2024 en Glendale, Arizona. (Cr\u00e9dito: Omar Vega\/Getty Images)<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u26bd Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes El bal\u00f3n oficial de la Copa Am\u00e9rica se muestra durante una conferencia de prensa antes del partido entre M\u00e9xico y Ecuador en el State Farm Stadium, el 29 de junio de 2024 en Glendale, Arizona. (Cr\u00e9dito: Omar Vega\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450810","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u26bd Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes El bal\u00f3n oficial de la Copa Am\u00e9rica se muestra durante una conferencia de prensa antes del partido entre M\u00e9xico y Ecuador en el State Farm Stadium, el 29 de junio de 2024 en Glendale, Arizona. (Cr\u00e9dito: Omar Vega\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-30T23:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo\",\"datePublished\":\"2024-06-30T23:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\"},\"wordCount\":83,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\",\"name\":\"M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-30T23:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias","og_description":"\u26bd Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientes El bal\u00f3n oficial de la Copa Am\u00e9rica se muestra durante una conferencia de prensa antes del partido entre M\u00e9xico y Ecuador en el State Farm Stadium, el 29 de junio de 2024 en Glendale, Arizona. (Cr\u00e9dito: Omar Vega\/Getty Images) The-CNN-Wire&trade; &amp; &copy; 2024 Cable News [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-30T23:03:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo","datePublished":"2024-06-30T23:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/"},"wordCount":83,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","name":"M\u00e9xico - Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-30T23:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico &#8211; Ecuador de Copa Am\u00e9rica 2024 en vivo: resultado y datos en directo","url":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2024\/06\/30\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-30T23:03:49Z","datePublished":"2024-06-30T23:03:49Z","dateModified":"2024-06-30T23:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9xico &#8211; Ecuador de Copa Am\\u00e9rica 2024 en vivo: resultado y datos en directo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/30\\\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2024\\\/06\\\/30\\\/resultado-mexico-ecuador-copa-america-goles-en-vivo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-30T23:03:49Z\",\"datePublished\":\"2024-06-30T23:03:49Z\",\"dateModified\":\"2024-06-30T23:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450565,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/20\/mejores-participaciones-mexico-copa-america-orix\/","url_meta":{"origin":1450810,"position":0},"title":"Las mejores participaciones de M\u00e9xico en la Copa Am\u00e9rica","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La selecci\u00f3n mayor masculina de M\u00e9xico es una de las 16 que participar\u00e1n en la Copa Am\u00e9rica 2024, que este a\u00f1o celebra su edici\u00f3n n\u00famero 48.Gracias al t\u00edtulo de Copa Oro obtenido en 2023, M\u00e9xico es cabeza de serie del Grupo B de la Copa Am\u00e9rica, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450238,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/11\/seleccion-mexico-copa-america-convocados-mejores-jugadores-formacion-trayectoria-orix\/","url_meta":{"origin":1450810,"position":1},"title":"As\u00ed es la selecci\u00f3n de M\u00e9xico para la Copa Am\u00e9rica: convocados, mejores jugadores, formaci\u00f3n y trayectoria","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Copa Am\u00e9rica 2024 est\u00e1 a unos d\u00edas de comenzar y ver\u00e1 enfrentarse a 16 selecciones masculinas mayores por el trofeo m\u00e1s codiciado del continente americano. De los 16 equipos que disputar\u00e1n el torneo, 10 pertenecen a la Conmebol y seis m\u00e1s son de la Concacaf, entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467322,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/12\/seleccion-mexico-derrota-argentina-sub20-mayor-orix\/","url_meta":{"origin":1450810,"position":2},"title":"Todas las selecciones que han derrotado a Argentina durante la sequ\u00eda de victorias de M\u00e9xico ante la albiceleste","author":"","date":"octubre 12, 2025","format":false,"excerpt":"La selecci\u00f3n argentina Sub-20 derrot\u00f3 este s\u00e1bado por 2 a 0 a su similar de M\u00e9xico por la Copa del Mundo Sub-20, extendiendo as\u00ed su invicto sobre el seleccionado norteamericano, que no la puede derrotar en un partido oficial en esta categor\u00eda juvenil desde 1999.Esta sequ\u00eda en el historial tambi\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450501,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/19\/copa-america-favorito-ganar-orix\/","url_meta":{"origin":1450810,"position":3},"title":"\u00bfCu\u00e1l es la selecci\u00f3n favorita para ganar la Copa Am\u00e9rica?","author":"","date":"junio 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Elegir un equipo entre 16 para ganar una competencia como la Copa Am\u00e9rica no es tarea f\u00e1cil. Surgen preguntas sin respuestas o preguntas que solo generan m\u00e1s interrogantes. \u00bfPodr\u00e1 Brasil volver a ser el gigante del continente? Eso nos abre otra duda: \u00bfcuenta con material para hacerlo?\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450892,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/07\/05\/cruces-copa-america-2024-cuartos-final-partidos-fechas-horarios-fixture-orix\/","url_meta":{"origin":1450810,"position":4},"title":"Los cruces de la Copa Am\u00e9rica 2024 desde cuartos hasta la final: partidos, fechas y horarios","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Copa Am\u00e9rica entra en la fase en la que no se puede fallar. Una derrota significa despedirse del torneo de selecciones m\u00e1s antiguo del mundo.Argentina es el primer semifinalista tras un pase ag\u00f3nico y emocionante en penaltis sobre Ecuador y sigue hasta ahora con \u00e9xito en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450353,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/06\/14\/guatemala-seleccion-argentina-copa-america-2024-orix\/","url_meta":{"origin":1450810,"position":5},"title":"Guatemala, la \u00faltima prueba de Scaloni para definir la lista de la selecci\u00f3n argentina para la Copa Am\u00e9rica 2024","author":"","date":"junio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Argentina juega su \u00faltimo partido amistoso previo a la defensa del t\u00edtulo de la Copa Am\u00e9rica cuya edici\u00f3n 2024 ser\u00e1 en Estados Unidos desde el 20 de junio al 14 de julio. Los dirigidos por Lionel Scaloni enfrentan a Guatemala este viernes en el FedExField en Maryland\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1450810"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1450810\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1450810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1450810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1450810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}