{"id":1459388,"date":"2025-03-02T04:03:38","date_gmt":"2025-03-02T12:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/"},"modified":"2025-03-02T04:03:38","modified_gmt":"2025-03-02T12:03:38","slug":"tarjeta-dorada-complicaciones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","title":{"rendered":"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece"},"content":{"rendered":"<p>El presidente Donald Trump, conocido por sus planes de deportaci\u00f3n masiva, propuso la semana pasada una nueva forma de atraer a extranjeros ricos a EE.UU.: una \u201ctarjeta dorada\u201d que ofrece a los inversores una v\u00eda hacia la ciudadan\u00eda estadounidense por US$ 5 millones.<\/p>\n<p>\u201cCreo que va a ser muy apreciada.\u202fCreo que va a ir muy bien. Y vamos a empezar a vender, con suerte, en unas dos semanas\u201d, dijo el presidente Donald Trump el mi\u00e9rcoles.<\/p>\n<p>El secretario de Comercio, Howard Lutnick, dijo que el plan podr\u00eda recaudar un bill\u00f3n de d\u00f3lares para pagar la deuda nacional, y que reemplazar\u00eda al actual visado para inversores EB-5.<\/p>\n<p>El anuncio desde el Despacho Oval tom\u00f3 por sorpresa a muchos expertos en inmigraci\u00f3n, que dicen que la propuesta de la \u201ctarjeta dorada\u201d es mucho m\u00e1s complicada e incierta de lo que Trump y Lutnick hicieron parecer. He aqu\u00ed varias razones:<\/p>\n<p>La tarjeta dorada descrita por Trump ser\u00eda un nuevo visado que conceder\u00eda el estatus de residente permanente legal en EE.UU. y una v\u00eda hacia la ciudadan\u00eda. Pero un presidente por s\u00ed solo no puede crear una v\u00eda hacia la ciudadan\u00eda, un hecho que tambi\u00e9n ha frustrado los deseos de los predecesores de Trump de llevar a cabo importantes reformas en materia de inmigraci\u00f3n.<\/p>\n<p>Tanto los presidentes Barack Obama como Joe Biden recurrieron a acciones ejecutivas para proteger a determinadas personas de la deportaci\u00f3n, iniciativas frecuentemente criticadas por Trump y otros republicanos. Pero el programa de Obama de Acci\u00f3n Diferida para los Llegados en la Infancia, conocido como DACA, y el programa de Biden de <em>parole <\/em>humanitario para inmigrantes de Cuba, Hait\u00ed, Nicaragua y Venezuela, conocido como CHNV, no llegaron a conferir un estatus legal ni a proporcionar una v\u00eda hacia la ciudadan\u00eda.<\/p>\n<p>Los expertos en leyes de inmigraci\u00f3n dicen que un nuevo visado requerir\u00eda una nueva ley, algo que un presidente no puede crear por s\u00ed solo.<\/p>\n<p>\u201cEl Congreso tendr\u00eda que legislar un nuevo programa. Realmente no s\u00e9 qu\u00e9 autoridad legal se tendr\u00eda para crear este nuevo programa de la nada\u201d, dice Sharvari Dalal-Dheini, director s\u00e9nior de relaciones gubernamentales de la Asociaci\u00f3n Estadounidense de Abogados de Inmigraci\u00f3n.<\/p>\n<p>En otras palabras, los legisladores tendr\u00edan que aprobar una ley para crear el programa que Trump ha descrito.<\/p>\n<p>La administraci\u00f3n Trump \u201cno tiene literalmente ning\u00fan poder legal para crear una categor\u00eda de visado\u201d, dice Charles Kuck, abogado de inmigraci\u00f3n en Atlanta.<\/p>\n<p>No es la primera vez que Trump intenta vincular la riqueza a los privilegios de inmigraci\u00f3n. Durante su primer mandato, la administraci\u00f3n Trump intent\u00f3 remodelar la inmigraci\u00f3n legal a EE.UU. ampliando la definici\u00f3n de carga p\u00fablica y penalizando a quienes dependen de la asistencia p\u00fablica en las solicitudes de la green card.<\/p>\n<p>Los cr\u00edticos dijeron que esa medida, que finalmente fue revocada por la administraci\u00f3n Biden, equival\u00eda a una injusta \u201cprueba de riqueza\u201d, mientras que los funcionarios de la administraci\u00f3n Trump defendieron la medida, argumentando que la autosuficiencia es un valor estadounidense fundamental.<\/p>\n<p>Esta \u00faltima iniciativa de Trump se ha ganado los elogios de sus partidarios, que han alabado el pensamiento innovador del presidente, y las cr\u00edticas de los defensores de los derechos de los inmigrantes, que dicen que est\u00e1 enviando un mensaje equivocado.<\/p>\n<p>\u201cLo \u00fanico que dice es que queremos a los m\u00e1s ricos en Estados Unidos, en vez de a los mejores y m\u00e1s brillantes, o a los que realmente van a servir al inter\u00e9s nacional de Estados Unidos\u2026 mejorando nuestra econom\u00eda en general\u201d, afirma Dalal-Dheini.<\/p>\n<p>Lutnick dijo el martes que la tarjeta dorada sustituir\u00eda al programa gubernamental de visados para inversores inmigrantes EB-5, que permite a los inversores extranjeros inyectar dinero en proyectos estadounidenses que crean puestos de trabajo y luego solicitar visados para inmigrar a Estados Unidos.<\/p>\n<p>Los expertos en leyes de inmigraci\u00f3n afirman que poner fin al programa EB-5 o modificarlo significativamente tambi\u00e9n requerir\u00eda la actuaci\u00f3n del Congreso.<\/p>\n<p>El mi\u00e9rcoles, Lutnick sugiri\u00f3 que el programa ser\u00eda modificado en lugar de sustituido.<\/p>\n<p>\u201cModificaremos el acuerdo EB-5\u201d, dijo Lutnick. \u201c(La secretaria de Seguridad Nacional) Kristi (Noem) y yo estamos trabajando en ello juntos. Por 5 millones de d\u00f3lares, obtendr\u00e1n una licencia del Departamento de Comercio. Entonces har\u00e1n una inversi\u00f3n adecuada\u201d.<\/p>\n<p>El Congreso cre\u00f3 el visado EB-5 en 1990. Los estatutos definen cu\u00e1ntos visados pueden concederse cada a\u00f1o en el marco del programa y cu\u00e1nto dinero deben aportar los inversores para participar. La ley permite la admisi\u00f3n de unos 10.000 inversores y familiares cualificados al a\u00f1o, <a href=\"https:\/\/crsreports.congress.gov\/product\/pdf\/IN\/IN11989\">seg\u00fan el Servicio de Investigaci\u00f3n del Congreso<\/a>.<\/p>\n<p>Los solicitantes que hayan presentado su solicitud antes del 15 de marzo de 2022 deben haber invertido al menos un mill\u00f3n de d\u00f3lares, o 500.000 d\u00f3lares en zonas econ\u00f3micamente desfavorecidas conocidas como \u00e1reas de empleo espec\u00edficas, <a href=\"https:\/\/www.uscis.gov\/working-in-the-united-states\/permanent-workers\/employment-based-immigration-fifth-preference-eb-5\/about-the-eb-5-visa-classification\">seg\u00fan el Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de EE.UU<\/a>. Los solicitantes posteriores a esa fecha deben invertir al menos 1.050.000 d\u00f3lares, u 800.000 d\u00f3lares en zonas econ\u00f3micamente desfavorecidas.<\/p>\n<p>Kuck, que afirma haber ayudado a cientos de clientes a navegar por el proceso de la EB-5, dice que ve \u201ccero posibilidades\u201d de que el Congreso elimine el programa y lo sustituya por la propuesta de la tarjeta dorada.<\/p>\n<p>\u201cLa cantidad de dinero que el programa EB-5 ha aportado en el transcurso de los \u00faltimos 30 a\u00f1os empeque\u00f1ecer\u00eda el n\u00famero de personas que realmente podr\u00edan permitirse y querer utilizar un visado dorado de 5 millones de d\u00f3lares\u201d, dice. \u201cLa gente con esa cantidad de dinero no quiere necesariamente estar sujeta a la fiscalidad estadounidense\u201d.<\/p>\n<p>\u00bfPodr\u00edan los legisladores aprobar cambios al programa en el proceso de reconciliaci\u00f3n presupuestaria?<\/p>\n<p>Nicolette Glazer, abogada de inmigraci\u00f3n en California, dice que no ser\u00eda posible poner fin o cambiar significativamente el programa EB-5 de esa manera. Pero es posible que se a\u00f1ada una disposici\u00f3n de \u201ctarjeta dorada\u201d, dice, si se presenta como una simple tarifa de inmigraci\u00f3n.<\/p>\n<p>\u201cPodr\u00eda verles intentando introducir algo as\u00ed solo para demostrar que est\u00e1n haciendo algo\u201d, afirma.<\/p>\n<p>En el pasado, los dem\u00f3cratas intentaron cambiar la pol\u00edtica de inmigraci\u00f3n durante el proceso de conciliaci\u00f3n, pero<a href=\"https:\/\/www.cnn.com\/2021\/09\/29\/politics\/senate-parliamentarian-immigration-budget-economy\/index.html\"> el parlamentario del Senado lo rechaz\u00f3<\/a>, explica Kuck.<\/p>\n<p>\u201cNo pueden cambiar la ley de inmigraci\u00f3n en la conciliaci\u00f3n\u201d, afirma.<\/p>\n<p>\u00bfQu\u00e9 pasa con los miles de personas que ya han solicitado visados EB-5 y est\u00e1n esperando decisiones del Gobierno?<\/p>\n<p>Las autoridades no han dicho lo que les suceder\u00eda bajo el plan de la tarjeta dorada.<\/p>\n<p>Seg\u00fan Dalal-Dheini, de la Asociaci\u00f3n Estadounidense de Abogados de Inmigraci\u00f3n, muchas de estas personas se han puesto en contacto con abogados ante la incertidumbre de lo que la nueva medida podr\u00eda significar para sus solicitudes.<\/p>\n<p>\u201cYa han invertido su dinero en esto mientras esperan que se apruebe su green card\u2026 Es un proceso de varios pasos y pueden pasar a\u00f1os, si no d\u00e9cadas, hasta que se apruebe\u201d, dice Dalal-Dheini. \u201cAs\u00ed que quitar el apoyo a  esos inversores sin previo aviso o sin ninguna oportunidad de salvar su inversi\u00f3n o de poder finalizar su proceso ser\u00eda realmente injusto y perjudicar\u00eda realmente a nuestra econom\u00eda\u201d.<\/p>\n<p>Tambi\u00e9n quedan sin respuesta otras preguntas sobre la propuesta de la tarjeta dorada, como si ayudar\u00eda o no a los licenciados extranjeros de las universidades estadounidenses. Eso es algo que Trump sugiri\u00f3 la semana pasada, aunque ofreciendo pocos detalles, <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-administration-news-02-26-25#cm7m62xtd000d3b6sr91l26pj\">diciendo que las empresas podr\u00edan comprar tarjetas doradas<\/a> y d\u00e1rselas a los extranjeros como herramienta de contrataci\u00f3n.<\/p>\n<p>Tampoco est\u00e1 claro c\u00f3mo se investigar\u00e1 a los solicitantes, aunque Lutnick insisti\u00f3 en que ser\u00eda una prioridad. Los cr\u00edticos ya advierten que la tarjeta dorada podr\u00eda atraer a delincuentes deseosos conseguir un acceso a Estados Unidos pagando.<\/p>\n<p>\u201cVender la ciudadan\u00eda estadounidense al mejor postor atraer\u00e1 a actores corruptos que buscan un refugio seguro para ellos y su dinero sucio\u201d, <a href=\"https:\/\/x.com\/anticorruption\/status\/1894795871994155206\">dijo la directora ejecutiva de Transparencia Internacional, Ma\u00edra Martini.<\/a><\/p>\n<p>Por su parte, Trump mantuvo que la creaci\u00f3n de las tarjetas doradas ser\u00eda \u201ctotalmente legal\u201d. A la pregunta de si considerar\u00eda vender las tarjetas a oligarcas rusos, Trump respondi\u00f3: \u201cS\u00ed, posiblemente. Conozco a algunos oligarcas rusos que son muy buena gente\u201d.<\/p>\n<p>A pesar de la confusi\u00f3n que caus\u00f3 el anuncio de Trump, Dalal-Dheini dice que ve una oportunidad en los recientes comentarios del presidente.<\/p>\n<p>\u201cNecesitamos aumentar el n\u00famero de tarjetas de residencia que tenemos a disposici\u00f3n de la gente. No hay suficientes\u201d, dice. \u201cY creo que lo que el presidente est\u00e1 subrayando es que los inmigrantes contribuyen realmente a nuestra econom\u00eda\u2026 Varios de nuestros grandes empresarios que han tenido mucho \u00e9xito vinieron aqu\u00ed como inmigrantes\u201d.<\/p>\n<p>Y eso, dice, es algo en lo que mucha gente de todos los sectores puede estar de acuerdo, se haga realidad o no la propuesta de la tarjeta dorada de Trump.<\/p>\n<p><em>Michael Williams y Piper Hudspeth Blackburn contribuyeron a este reporte.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump, conocido por sus planes de deportaci\u00f3n masiva, propuso la semana pasada una nueva forma de atraer a extranjeros ricos a EE.UU.: una \u201ctarjeta dorada\u201d que ofrece a los inversores una v\u00eda hacia la ciudadan\u00eda estadounidense por US$ 5 millones. \u201cCreo que va a ser muy apreciada.\u202fCreo que va a ir muy [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459388","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 la propuesta de Trump de una &quot;tarjeta dorada&quot; es m\u00e1s complicada de lo que parece - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 la propuesta de Trump de una &quot;tarjeta dorada&quot; es m\u00e1s complicada de lo que parece - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump, conocido por sus planes de deportaci\u00f3n masiva, propuso la semana pasada una nueva forma de atraer a extranjeros ricos a EE.UU.: una \u201ctarjeta dorada\u201d que ofrece a los inversores una v\u00eda hacia la ciudadan\u00eda estadounidense por US$ 5 millones. \u201cCreo que va a ser muy apreciada.\u202fCreo que va a ir muy [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-02T12:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece\",\"datePublished\":\"2025-03-02T12:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\"},\"wordCount\":1579,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\",\"name\":\"Por qu\u00e9 la propuesta de Trump de una \\\"tarjeta dorada\\\" es m\u00e1s complicada de lo que parece - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-02T12:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 la propuesta de Trump de una \"tarjeta dorada\" es m\u00e1s complicada de lo que parece - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 la propuesta de Trump de una \"tarjeta dorada\" es m\u00e1s complicada de lo que parece - Noticias","og_description":"El presidente Donald Trump, conocido por sus planes de deportaci\u00f3n masiva, propuso la semana pasada una nueva forma de atraer a extranjeros ricos a EE.UU.: una \u201ctarjeta dorada\u201d que ofrece a los inversores una v\u00eda hacia la ciudadan\u00eda estadounidense por US$ 5 millones. \u201cCreo que va a ser muy apreciada.\u202fCreo que va a ir muy [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-02T12:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece","datePublished":"2025-03-02T12:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/"},"wordCount":1579,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","name":"Por qu\u00e9 la propuesta de Trump de una \"tarjeta dorada\" es m\u00e1s complicada de lo que parece - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-02T12:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\u00e1s complicada de lo que parece","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/tarjeta-dorada-complicaciones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-02T12:03:38Z","datePublished":"2025-03-02T12:03:38Z","dateModified":"2025-03-02T12:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 la propuesta de Trump de una &#171;tarjeta dorada&#187; es m\\u00e1s complicada de lo que parece\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/02\\\/tarjeta-dorada-complicaciones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/02\\\/tarjeta-dorada-complicaciones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-02T12:03:38Z\",\"datePublished\":\"2025-03-02T12:03:38Z\",\"dateModified\":\"2025-03-02T12:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469156,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/10\/trump-visa-tarjeta-dorada-miercoles-trax\/","url_meta":{"origin":1459388,"position":0},"title":"Trump anuncia que la visa &#171;tarjeta dorada&#187; se lanzar\u00e1 este mi\u00e9rcoles","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, anunci\u00f3 en un evento de mesa redonda que su pol\u00edtica de inmigraci\u00f3n de \u201ctarjeta dorada\u201d, la cual dijo que acelerar\u00eda las visas para ciertos inmigrantes a cambio de una tarifa considerable, se lanzar\u00e1 oficialmente este mi\u00e9rcoles.\u201cEs muy emocionante, para m\u00ed y para el pa\u00eds,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459253,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/02\/26\/tarjeta-dorada-trump-diferencias-eb5-orix\/","url_meta":{"origin":1459388,"position":1},"title":"\u00bfQu\u00e9 es la &#171;tarjeta dorada&#187; de residencia que anunci\u00f3 Trump? \u00bfCu\u00e1les son sus diferencias con la visa EB-5?","author":"","date":"febrero 26, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, anunci\u00f3 que su Gobierno lanzar\u00e1 una \u201ctarjeta dorada\u201d (\u201cgold card\u201d, en ingl\u00e9s) para extranjeros adinerados, que les otorgar\u00e1 el derecho a vivir y trabajar en el pa\u00eds, as\u00ed como un camino a la ciudadan\u00eda por un precio de US$ 5 millones.Trump equipar\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466626,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/09\/19\/trump-presenta-tarjeta-dorada-acelera-visas-trax\/","url_meta":{"origin":1459388,"position":2},"title":"Trump presenta programa de &#171;tarjeta dorada&#187; que acelera visas de inmigrantes por una tarifa elevada","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"El presidente Donald Trump present\u00f3 hoy su pol\u00edtica de inmigraci\u00f3n de \u201ctarjeta dorada\u201d largamente prometida que, seg\u00fan dijo, acelerar\u00eda las visas para ciertos inmigrantes a cambio de una tarifa elevada.La nueva v\u00eda permitir\u00e1 a extranjeros pagar US$ 1 mill\u00f3n para acelerar su solicitud de visa, o que las empresas paguen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462663,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/21\/extranjeros-registrarse-visa-tarjeta-dorada-trump-trax\/","url_meta":{"origin":1459388,"position":3},"title":"Los extranjeros podr\u00e1n registrarse para tener la visa &#171;tarjeta dorada&#187; de US$ 5 millones en una semana, dice Lutnick","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Los ciudadanos extranjeros con US$ 5 millones disponibles pronto podr\u00e1n registrarse para una nueva visa \u201ctarjeta dorada\u201d que les dar\u00eda derecho a vivir y trabajar permanentemente en Estados Unidos, declar\u00f3 el mi\u00e9rcoles el secretario de Comercio, Howard Lutnick.\u201cEspero que haya un sitio web llamado \u2018Trumpcard.gov\u2019\u201d, declar\u00f3 Lutnick en el evento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459421,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/5-cosas-3-marzo-ucrania-inmigracion-tarjeta-dorada-aranceles-israel-orix\/","url_meta":{"origin":1459388,"position":4},"title":"Las 5 cosas que debes saber este 3 de marzo: Ucrania, inmigraci\u00f3n, premios Oscar, aranceles, Israel","author":"","date":"marzo 3, 2025","format":false,"excerpt":"La mano dura de Trump con la inmigraci\u00f3n podr\u00eda resultar contraproducente para EE.UU. Israel detuvo la ayuda humanitaria a Gaza. \u201cAnora\u201d, gran ganadora de los Oscar 2025. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459268,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/02\/27\/5-cosas-27-febrero-registro-indocumentados-tarjeta-dorada-trachtenberg-orix\/","url_meta":{"origin":1459388,"position":5},"title":"Las 5 cosas que debes saber este 27 de febrero: Registro de indocumentados, tarjeta dorada y muerte de Michelle Trachtenberg","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Trump prorroga aranceles al 1 de abril. \u00bfQu\u00e9 es la tarjeta dorada de residencia que anunci\u00f3 Trump? Muere Michelle Trachtenberg de \u201cGossip Girl\u201d y \u201cBuffy, la cazavampiros\u201d. Israel recibi\u00f3 cuatro ata\u00fades que contendr\u00edan cuerpos de rehenes. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459388"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459388\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}