{"id":1459410,"date":"2025-03-02T22:03:53","date_gmt":"2025-03-03T06:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/"},"modified":"2025-03-02T22:03:53","modified_gmt":"2025-03-03T06:03:53","slug":"halle-berry-adrien-brody-beso-oscar-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","title":{"rendered":"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)"},"content":{"rendered":"<p>Adrien Brody entr\u00f3 en la infamia de los Oscar en 2003, cuando tir\u00f3 de Halle Berry para darle un beso improvisado en el escenario.<\/p>\n<p>Este domingo, en la alfombra roja de los Oscar, Halle Berry se veng\u00f3.<\/p>\n<p>En broma, por supuesto. Berry, <a href=\"https:\/\/www.cnn.com\/2024\/03\/06\/entertainment\/oscars-speeches-memorable\/index.html\">ganadora de un Oscar por \u201cMonster\u2019s Ball\u201d<\/a>, bes\u00f3 a Brody antes de que comenzara la ceremonia. La pareja se abraz\u00f3 y ri\u00f3 junto a la acompa\u00f1ante de Brody, Georgina Chapman.<\/p>\n<p>Brody <a href=\"https:\/\/www.cnn.com\/2014\/02\/28\/showbiz\/gallery\/oscars-upsets-shockers-snubs\/index.html\">bes\u00f3 <\/a>a Berry al recoger el Oscar al mejor actor por su interpretaci\u00f3n de un superviviente del Holocausto en \u201cEl pianista\u201d. Berry, que gan\u00f3 el premio a la mejor actriz del a\u00f1o en 2002, pareci\u00f3 sorprendida mientras \u00e9l la abrazaba y le daba un beso.<\/p>\n<p>Pero Berry no parece guardarle rencor por el incidente.<\/p>\n<p>\u201cTen\u00eda que vengarme\u201d, escribi\u00f3 de subtitulo en un video de su \u00faltimo beso, junto con un emoji gui\u00f1ando un ojo.<\/p>\n<p>Brody gan\u00f3 el domingo su segundo Oscar al mejor actor, esta vez por su papel del ficticio arquitecto h\u00fangaro L\u00e1szl\u00f3 T\u00f3th en \u201cThe Brutalist\u201d. Berry, por su parte, sigue siendo la \u00fanica mujer negra en ganar un Oscar a la mejor actriz.<\/p>\n<p>\u201cEspero que este a\u00f1o alguien est\u00e9 a mi lado\u201d, dijo recientemente en el podcast \u201cWhat Now?\u201d de Trevor Noah. \u201cEste a\u00f1o, espero que ocurra porque estoy cansada de ocupar ese espacio sola\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adrien Brody entr\u00f3 en la infamia de los Oscar en 2003, cuando tir\u00f3 de Halle Berry para darle un beso improvisado en el escenario. Este domingo, en la alfombra roja de los Oscar, Halle Berry se veng\u00f3. En broma, por supuesto. Berry, ganadora de un Oscar por \u201cMonster\u2019s Ball\u201d, bes\u00f3 a Brody antes de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459410","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Halle Berry &quot;se venga&quot; de Adrien Brody en los Oscar (con un beso) - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halle Berry &quot;se venga&quot; de Adrien Brody en los Oscar (con un beso) - Noticias\" \/>\n<meta property=\"og:description\" content=\"Adrien Brody entr\u00f3 en la infamia de los Oscar en 2003, cuando tir\u00f3 de Halle Berry para darle un beso improvisado en el escenario. Este domingo, en la alfombra roja de los Oscar, Halle Berry se veng\u00f3. En broma, por supuesto. Berry, ganadora de un Oscar por \u201cMonster\u2019s Ball\u201d, bes\u00f3 a Brody antes de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-03T06:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)\",\"datePublished\":\"2025-03-03T06:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\",\"name\":\"Halle Berry \\\"se venga\\\" de Adrien Brody en los Oscar (con un beso) - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-03T06:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halle Berry \"se venga\" de Adrien Brody en los Oscar (con un beso) - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Halle Berry \"se venga\" de Adrien Brody en los Oscar (con un beso) - Noticias","og_description":"Adrien Brody entr\u00f3 en la infamia de los Oscar en 2003, cuando tir\u00f3 de Halle Berry para darle un beso improvisado en el escenario. Este domingo, en la alfombra roja de los Oscar, Halle Berry se veng\u00f3. En broma, por supuesto. Berry, ganadora de un Oscar por \u201cMonster\u2019s Ball\u201d, bes\u00f3 a Brody antes de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-03T06:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/"},"author":{"name":"","@id":""},"headline":"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)","datePublished":"2025-03-03T06:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","name":"Halle Berry \"se venga\" de Adrien Brody en los Oscar (con un beso) - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-03T06:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/halle-berry-adrien-brody-beso-oscar-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-03T06:03:53Z","datePublished":"2025-03-03T06:03:53Z","dateModified":"2025-03-03T06:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Halle Berry &#171;se venga&#187; de Adrien Brody en los Oscar (con un beso)\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/02\\\/halle-berry-adrien-brody-beso-oscar-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/02\\\/halle-berry-adrien-brody-beso-oscar-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-03T06:03:53Z\",\"datePublished\":\"2025-03-03T06:03:53Z\",\"dateModified\":\"2025-03-03T06:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459419,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/adrien-brody-segundo-oscar-actor-trax\/","url_meta":{"origin":1459410,"position":0},"title":"Adrien Brody gana su segundo Oscar a mejor actor dos d\u00e9cadas despu\u00e9s de alzarse con la estatuilla por primera vez","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Adrien Brody volvi\u00f3 a ganar un Oscar, esta vez por su trabajo en la \u00e9pica \u201cThe Brutalist\u201d, de Brady Corbet.En esta pel\u00edcula de tres horas y media, Brody interpreta a un ficticio inmigrante jud\u00edo h\u00fangaro que huye de la Europa posterior a la Segunda Guerra Mundial para perseguir el sue\u00f1o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457255,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/06\/adrien-brody-dedica-globo-de-oro-the-brutalist-antepasados-inmigrantes-trax\/","url_meta":{"origin":1459410,"position":1},"title":"Adrien Brody dedica su Globo de Oro por &#8216;The Brutalist&#8217; a sus antepasados \u200b\u200binmigrantes","author":"","date":"enero 6, 2025","format":false,"excerpt":"\u201cThe Brutalist\u201d, una pel\u00edcula sobre un arquitecto jud\u00edo que sobrevive al Holocausto y emigra a Estados Unidos para alcanzar el sue\u00f1o americano, tuvo una gran noche en los premios Globo de Oro este domingo.La pel\u00edcula, protagonizada por Adrien Brody, fue nominada en siete categor\u00edas y gan\u00f3 cuatro Globos en total.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459374,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/01\/premios-oscar-2025-presentadores-cuando-hora-y-como-ver-tv-internet-orix\/","url_meta":{"origin":1459410,"position":2},"title":"Premios Oscar 2025: presentadores, cu\u00e1ndo, a qu\u00e9 hora y c\u00f3mo ver por TV e internet","author":"","date":"marzo 1, 2025","format":false,"excerpt":"La edici\u00f3n 2025 de los premios Oscar promete ser una noche llena de emoci\u00f3n, glamour y reconocimientos para los mejores exponentes del cine. Aqu\u00ed te dejamos todos los detalles para que no te pierdas ni un segundo de este evento tan esperado.Las pel\u00edculas que lideran las nominaciones incluyen \u201cEmilia P\u00e9rez\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459403,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/02\/ganadores-premios-oscar-2025-lista-completa-trax\/","url_meta":{"origin":1459410,"position":3},"title":"Premios Oscar 2025: la lista completa de ganadores","author":"","date":"marzo 2, 2025","format":false,"excerpt":"La 97.\u00aa edici\u00f3n de los premios Oscar se celebra en Hollywood y todas las miradas est\u00e1n puestas en qui\u00e9n se llevar\u00e1 a casa la preciada estatuilla.La ceremonia de los Oscar, presentada por primera vez por Conan O\u2019Brien, pondr\u00e1 fin a una temporada de premios ensombrecida por los incendios forestales de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457190,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/03\/globo-oro-golden-globes-favoritos-ojo-critico-orix\/","url_meta":{"origin":1459410,"position":4},"title":"Los favoritos para ganar los Globo de Oro 2025, seg\u00fan Ojo Cr\u00edtico","author":"","date":"enero 3, 2025","format":false,"excerpt":"Este domingo es la ceremonia de entrega de los premios Globos de Oro de 2025, que se emitir\u00e1 en directo por CBS y en streaming por Paramount+. Juan Carlos Arciniegas, el Ojo Cr\u00edtico de CNN, analiza los nominados y da sus proyecciones de los posibles ganadores en las categor\u00edas principales.\u201cThe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459330,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/02\/28\/oscar-favoritas-peliculas-nominadas-2025-orix\/","url_meta":{"origin":1459410,"position":5},"title":"Las favoritas de los Premios \u00d3scar 2025, la temporada de premios con m\u00e1s incertidumbre y volatilidad","author":"","date":"febrero 28, 2025","format":false,"excerpt":"Tras las premiaciones en Hollywood, \u00bfhay favoritas para el Oscar este a\u00f1o? Tras veinticinco a\u00f1os cubriendo el premio, estoy confundido con la edici\u00f3n 2025.La tarea de pronosticar a los ganadores del Oscar es una que no debe tomarse a la ligera, especialmente cuando los amigos est\u00e1n esperando que las apreciaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459410"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459410\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}