{"id":1459422,"date":"2025-03-03T06:03:37","date_gmt":"2025-03-03T14:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/"},"modified":"2025-03-03T06:03:37","modified_gmt":"2025-03-03T14:03:37","slug":"ataque-coche-mannheim-alemania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","title":{"rendered":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda"},"content":{"rendered":"<p>Al menos una persona muri\u00f3 y varias resultaron heridas despu\u00e9s de que un autom\u00f3vil embistiera a peatones en la ciudad de Mannheim, en el suroeste de Alemania, dijo este lunes la polic\u00eda local.<\/p>\n<p>El incidente ocurri\u00f3 poco despu\u00e9s del mediod\u00eda, hora local (6 a.m. ET), dijo Stefan Wilhelm, portavoz de la polic\u00eda de Mannheim. Un sospechoso fue arrestado, agreg\u00f3.<\/p>\n<p>El gobierno federal de Alemania emiti\u00f3 una advertencia de \u201cpeligro extremo\u201d en la ciudad y dijo que se est\u00e1 llevando a cabo una operaci\u00f3n policial a gran escala.<\/p>\n<p>Mikla Cela, un trabajador de un restaurante en el centro de la ciudad, dijo a CNN que vio un autom\u00f3vil negro pasar a alta velocidad. Dijo que luego escuch\u00f3 a varias personas gritar y vio a un hombre con una chaqueta blanca tirado en el piso.<\/p>\n<p>Ferry Overdevest, el propietario de una florister\u00eda en el centro de Mannheim, dijo a CNN que alrededor de 30 personas buscaban refugio en su tienda y que hab\u00eda ambulancias en las calles afuera.<\/p>\n<p>Alemania se ha visto sacudida por una serie de ataques mortales con autom\u00f3viles embestidos en los \u00faltimos meses.<\/p>\n<p>En diciembre, un veh\u00edculo se estrell\u00f3 contra un mercado navide\u00f1o en Magdeburgo, matando a seis personas, entre ellas un ni\u00f1o de 9 a\u00f1os. El sospechoso es un ciudadano saud\u00ed de 50 a\u00f1os que hab\u00eda vivido en Alemania durante m\u00e1s de una d\u00e9cada y trabajaba para ayudar a los saud\u00edes a abandonar su pa\u00eds de origen. Las publicaciones en las redes sociales mostraron que era un ferviente cr\u00edtico del Islam.<\/p>\n<p>En febrero, una persona condujo un Mini Cooper contra manifestantes en M\u00fanich, matando a una madre y a su hijo e hiriendo a m\u00e1s de 30 personas m\u00e1s. El sospechoso es un hombre afgano de 24 a\u00f1os.<\/p>\n<p>Ese ataque se produjo en v\u00edsperas de la Conferencia de Seguridad de M\u00fanich y apenas unos d\u00edas antes de las elecciones federales del pa\u00eds, donde las preocupaciones sobre la inmigraci\u00f3n y la seguridad ayudaron a impulsar al partido de extrema derecha Alternativa para Alemania (AfD) al segundo lugar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos una persona muri\u00f3 y varias resultaron heridas despu\u00e9s de que un autom\u00f3vil embistiera a peatones en la ciudad de Mannheim, en el suroeste de Alemania, dijo este lunes la polic\u00eda local. El incidente ocurri\u00f3 poco despu\u00e9s del mediod\u00eda, hora local (6 a.m. ET), dijo Stefan Wilhelm, portavoz de la polic\u00eda de Mannheim. Un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459422","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos una persona muri\u00f3 y varias resultaron heridas despu\u00e9s de que un autom\u00f3vil embistiera a peatones en la ciudad de Mannheim, en el suroeste de Alemania, dijo este lunes la polic\u00eda local. El incidente ocurri\u00f3 poco despu\u00e9s del mediod\u00eda, hora local (6 a.m. ET), dijo Stefan Wilhelm, portavoz de la polic\u00eda de Mannheim. Un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-03T14:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda\",\"datePublished\":\"2025-03-03T14:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\",\"name\":\"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-03T14:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias","og_description":"Al menos una persona muri\u00f3 y varias resultaron heridas despu\u00e9s de que un autom\u00f3vil embistiera a peatones en la ciudad de Mannheim, en el suroeste de Alemania, dijo este lunes la polic\u00eda local. El incidente ocurri\u00f3 poco despu\u00e9s del mediod\u00eda, hora local (6 a.m. ET), dijo Stefan Wilhelm, portavoz de la polic\u00eda de Mannheim. Un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-03T14:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/"},"author":{"name":"","@id":""},"headline":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda","datePublished":"2025-03-03T14:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","name":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-03T14:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos una persona muri\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\u00fan la polic\u00eda","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/ataque-coche-mannheim-alemania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-03T14:03:37Z","datePublished":"2025-03-03T14:03:37Z","dateModified":"2025-03-03T14:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos una persona muri\\u00f3 en un ataque con coche en la ciudad alemana de Mannheim, seg\\u00fan la polic\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/03\\\/ataque-coche-mannheim-alemania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/03\\\/ataque-coche-mannheim-alemania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-03T14:03:37Z\",\"datePublished\":\"2025-03-03T14:03:37Z\",\"dateModified\":\"2025-03-03T14:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452128,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/08\/24\/policia-alemania-detiene-sospechoso-apunalar-tres-personas-trax\/","url_meta":{"origin":1459422,"position":0},"title":"La polic\u00eda de Alemania detiene a un sospechoso acusado de apu\u00f1alar hasta la muerte a tres personas en un festival de m\u00fasica","author":"","date":"agosto 24, 2024","format":false,"excerpt":"(CNN) -- La polic\u00eda de Alemania detuvo a un sospechoso acusado de apu\u00f1alar hasta la muerte a tres personas en un festival de m\u00fasica en la ciudad de Solingen el viernes, en un ataque que conmocion\u00f3 a todo el pa\u00eds.El sospechoso fue detenido en un centro de refugiados tras una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456828,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/21\/automovil-mercado-navideno-alemania-trax\/","url_meta":{"origin":1459422,"position":1},"title":"Cuatro muertos y decenas de heridos tras un atropellamiento masivo en un mercado navide\u00f1o en Alemania","author":"","date":"diciembre 21, 2024","format":false,"excerpt":"Al menos cuatro personas murieron y decenas resultaron heridas este viernes despu\u00e9s de que un coche arrollara a una multitud en un mercadillo navide\u00f1o en la ciudad alemana de Magdeburgo, seg\u00fan informaron las autoridades locales.Un adulto y un ni\u00f1o de corta edad murieron en el atentado y el conductor sospechoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452139,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/08\/25\/se-entrego-sospechoso-ataque-arma-blanca-alemania-trax\/","url_meta":{"origin":1459422,"position":2},"title":"Un hombre sirio de 26 a\u00f1os confes\u00f3 haber perpretado ataque con arma blanca en Alemania","author":"","date":"agosto 25, 2024","format":false,"excerpt":"(CNN) --\u00a0Un hombre sirio se entreg\u00f3 y confes\u00f3 haber apu\u00f1alado hasta la muerte a tres personas y herido a otras ocho en un festival este viernes en la ciudad de Solingen, en el oeste de Alemania, inform\u00f3 la polic\u00eda.Las autoridades investigan si el sospechoso, de 26 a\u00f1os, ten\u00eda alguna conexi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461729,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/28\/automovil-se-estrella-campamento-escolar-illiniois-trax\/","url_meta":{"origin":1459422,"position":3},"title":"Mueren cuatro personas, entre ellas ni\u00f1os, despu\u00e9s de que un autom\u00f3vil se estrellara contra un campamento escolar en Illinois","author":"","date":"abril 28, 2025","format":false,"excerpt":"Cuatro personas fallecieron, entre ellas ni\u00f1os, y varias otras est\u00e1n heridas despu\u00e9s de que un autom\u00f3vil se estrellara contra un campamento escolar en Chatham, Illinois, dijeron las autoridades.Alrededor de las 3:20 p.m. del lunes, la polic\u00eda respondi\u00f3 despu\u00e9s de que un veh\u00edculo atravesara el lado este del YNOT After School\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452303,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/08\/30\/alemania-deporta-28-afganos-medidas-seguridad-trax\/","url_meta":{"origin":1459422,"position":4},"title":"Alemania deporta a 28 afganos tras presentar un nuevo paquete de medidas de seguridad","author":"","date":"agosto 30, 2024","format":false,"excerpt":"Berl\u00edn (CNN) -- Un vuelo de deportaci\u00f3n con destino a Afganist\u00e1n que transportaba a 28 ciudadanos afganos parti\u00f3 de Alemania el viernes por la ma\u00f1ana, un d\u00eda despu\u00e9s de que el gobierno alem\u00e1n se comprometiera a reforzar su normativa de asilo tras un ataque mortal con cuchillo.Un portavoz del Ministerio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464931,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","url_meta":{"origin":1459422,"position":5},"title":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes","author":"","date":"julio 28, 2025","format":false,"excerpt":"Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459422"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459422\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}