{"id":1459459,"date":"2025-03-03T19:04:02","date_gmt":"2025-03-04T03:04:02","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/"},"modified":"2025-03-03T19:04:02","modified_gmt":"2025-03-04T03:04:02","slug":"panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","title":{"rendered":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU."},"content":{"rendered":"<p>Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos.<\/p>\n<p>Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica, el ministro de Seguridad de ese pa\u00eds, Mario Zamora, anunci\u00f3 que este lunes comenz\u00f3 una ruta de autob\u00fas en la frontera costarricense que, al llegar a Panam\u00e1, har\u00e1 transferencia a otro autob\u00fas que llevar\u00e1 a los pasajeros a la frontera con Colombia.<\/p>\n<p>\u201cHoy se estableci\u00f3 de manera oficial el sistema de autobuses que saldr\u00e1n desde Pe\u00f1as Blancas y Tablillas en direcci\u00f3n frontera a frontera a nuestro Catem sur (Centro de Atenci\u00f3n Temporal para Migrantes), y desde ah\u00ed abordar\u00e1n despu\u00e9s buses de la hermana Rep\u00fablica de Panam\u00e1, que los llevar\u00e1n a la frontera Panam\u00e1-Colombia para que esas personas puedan retornar de manera segura a sus pa\u00edses de origen\u201d, explic\u00f3 Zamora.<\/p>\n<p>CNN ha solicitado m\u00e1s informaci\u00f3n a los gobiernos de Costa Rica y Panam\u00e1 para saber las frecuencias de las rutas de autob\u00fas, el n\u00famero de migrantes que podr\u00e1n atender y est\u00e1 a la espera de esa informaci\u00f3n.<\/p>\n<p>El Ministerio de Seguridad de Panam\u00e1 confirm\u00f3 a CNN que en este operativo autoridades migratorias recogen en Pe\u00f1as Blancas, frontera de Nicaragua y Costa Rica, a los migrantes para de ah\u00ed trasladarlos al Catem de la frontera con Panam\u00e1. Despu\u00e9s, en territorio paname\u00f1o los trasladan al centro de atenci\u00f3n a migrantes de Lajas Blancas, en el tap\u00f3n del Dari\u00e9n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos. Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica, el ministro de Seguridad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459459","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos. Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica, el ministro de Seguridad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-04T03:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.\",\"datePublished\":\"2025-03-04T03:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\",\"name\":\"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-04T03:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias","og_description":"Los ministros de Seguridad de Costa Rica y Panam\u00e1 anunciaron este lunes la implementaci\u00f3n de rutas de autobuses como estrategia \u201chumanitaria y regulada\u201d para atender en sus pa\u00edses el regreso de migrantes, ante las pol\u00edticas implementadas por el Gobierno de Estados Unidos. Al inaugurar una aduana en Pe\u00f1as Blancas, Costa Rica, el ministro de Seguridad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-04T03:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.","datePublished":"2025-03-04T03:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","name":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-04T03:04:02+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Panam\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/03\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-04T03:04:02Z","datePublished":"2025-03-04T03:04:02Z","dateModified":"2025-03-04T03:04:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Panam\\u00e1 y Costa Rica acuerdan protocolo para atender retorno de migrantes desde EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/03\\\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/03\\\/panama-costa-rica-protocolo-retorno-migrantes-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-04T03:04:02Z\",\"datePublished\":\"2025-03-04T03:04:02Z\",\"dateModified\":\"2025-03-04T03:04:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447163,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/20\/obispos-costa-rica-panama-colombia-zona-darien-orix\/","url_meta":{"origin":1459459,"position":0},"title":"Obispos de Costa Rica, Panam\u00e1 y Colombia visitan zona del Dari\u00e9n por tema migratorio","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Obispos de Panam\u00e1, Costa Rica y Colombia visitaron este martes la zona del tap\u00f3n del Dari\u00e9n, en el lado paname\u00f1o, como parte de las actividades del encuentro Pascua con nuestros hermanos migrantes, reuni\u00f3n promovida por el papa Francisco, inform\u00f3 la Conferencia Episcopal de Costa Rica.A trav\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446099,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/29\/migrantes-ecuador-rio-frontera-costa-rica-nicaragua-orix\/","url_meta":{"origin":1459459,"position":1},"title":"Mueren dos migrantes ecuatorianas que viajaban en veh\u00edculo que cay\u00f3 a r\u00edo fronterizo de Costa Rica con Nicaragua","author":"","date":"febrero 29, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) --El Organismo de Investigaci\u00f3n Judicial (OIJ) de Costa Rica confirm\u00f3 la muerte de una mujer de 33 a\u00f1os de edad y una ni\u00f1a de 6 a\u00f1os, ambas ecuatorianas, que viajaban en un veh\u00edculo cerca de la frontera de este pa\u00eds con Nicaragua, en la zona norte costarricense.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443082,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/03\/la-casa-blanca-se-enfoca-en-la-disminucion-de-los-cruces-fronterizos-mientras-el-presidente-de-la-camara-se-dirige-a-la-frontera-entre-texas-y-mexico\/","url_meta":{"origin":1459459,"position":2},"title":"La Casa Blanca se enfoca en la disminuci\u00f3n de los cruces fronterizos mientras el presidente de la C\u00e1mara se dirige a la frontera entre Texas y M\u00e9xico","author":"","date":"enero 3, 2024","format":false,"excerpt":"(CNN) -- Mientras el presidente de la C\u00e1mara de Representantes, Mike Johnson, se dirige a la frontera entre Estados Unidos y M\u00e9xico, los funcionarios de la administraci\u00f3n de Joe Biden destacaron una ca\u00edda importante en los cruces fronterizos esta semana inmediatamente despu\u00e9s de las conversaciones de alto nivel entre Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458606,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/02\/11\/panama-costa-rica-mecanismos-atencion-migrantes-orix\/","url_meta":{"origin":1459459,"position":3},"title":"Panam\u00e1 y Costa Rica establecen mecanismos para la atenci\u00f3n de los migrantes en &#171;su retorno al sur&#187;","author":"","date":"febrero 11, 2025","format":false,"excerpt":"El Ministerio de Seguridad P\u00fablica de Panam\u00e1 anunci\u00f3 este martes que las autoridades paname\u00f1as y costarricenses han establecido mecanismos conjuntos para \u201canalizar y optimizar\u201d lo que describieron como \u201cflujo de retorno inverso de norte a sur\u201d de migrantes irregulares.Frank Alexis \u00c1brego, ministro de Seguridad P\u00fablica de Panam\u00e1, sostuvo una reuni\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442921,"url":"https:\/\/noticiasya.com\/el-paso\/2023\/12\/30\/texas-envia-solicitantes-de-asilo-a-las-principales-ciudades-en-autobus-sin-previo-aviso-estos-alcaldes-quieren-pisar-el-freno\/","url_meta":{"origin":1459459,"position":4},"title":"Texas env\u00eda solicitantes de asilo a las principales ciudades en autob\u00fas sin previo aviso. Estos alcaldes quieren pisar el freno","author":"","date":"diciembre 30, 2023","format":false,"excerpt":"(CNN) -- Frustrados por los \u201cautobuses deshonestos\u201d de Texas que dejan a miles de inmigrantes, los alcaldes de Nueva York, Chicago y Denver est\u00e1n tratando de frenar el aumento exigiendo a los operadores de autobuses que coordinen las llegadas bajo la amenaza de confiscaciones, multas e incluso penas de c\u00e1rcel.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462931,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/28\/desmantelan-red-criminal-costa-rica-trafico-migrantes-asiaticos-trax\/","url_meta":{"origin":1459459,"position":5},"title":"La polic\u00eda de Costa Rica asegura que desmantel\u00f3 una red criminal que traficaba migrantes asi\u00e1ticos hacia EE.UU.","author":"","date":"mayo 28, 2025","format":false,"excerpt":"Las autoridades costarricenses dijeron que arrestaron a 19 personas acusadas de traficar a cientos de migrantes, predominantemente asi\u00e1ticos, a Estados Unidos.Los arrestos del mi\u00e9rcoles ocurrieron durante redadas en varias ciudades destinadas a desmantelar lo que la polic\u00eda de inmigraci\u00f3n de Costa Rica llama \u201cuna estructura de crimen organizado transnacional\u201d dedicada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459459"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459459\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}