{"id":1459487,"date":"2025-03-04T12:03:53","date_gmt":"2025-03-04T20:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/"},"modified":"2025-03-04T12:03:53","modified_gmt":"2025-03-04T20:03:53","slug":"la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","title":{"rendered":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro"},"content":{"rendered":"<p>Roberto Novo es fil\u00e1ntropo, fot\u00f3grafo y peluquero, entre otras profesiones. Hace a\u00f1os vive en Nueva York y Par\u00eds y ahora est\u00e1 en Buenos Aires, donde visit\u00f3 los estudios de CNN Radio junto a su perro Machito, que tiene una historia espectacular.<\/p>\n<p>En el programa Los Primeros de la Tarde, Novo record\u00f3: \u201cEmpec\u00e9 trabajando con Norma Fern\u00e1ndez en Ituzaing\u00f3 y de casualidad encontr\u00e9 mi profesi\u00f3n. Con un corte de pelo hac\u00e9s feliz a tanta gente. Te llena el alma\u201d.<\/p>\n<p>\u201cPas\u00e9 de ituzaing\u00f3 a trabajar con Miguel Romano. Me fui a Par\u00eds sacando fotos en un sal\u00f3n y me ofrecieron trabajar en Francia. Mi vida fue de Par\u00eds a Jap\u00f3n, luego a Nueva York. Mis cortes hablaron de m\u00ed\u2026 Llegu\u00e9 a tener tres salones en Nueva York. Y un d\u00eda entr\u00f3 por ejemplo a cortarse el pelo Calvin Klein\u201d, record\u00f3, quien tambi\u00e9n hizo lo propio con Britney Spears\u201d.<\/p>\n<p>Sin embargo, aclar\u00f3: \u201cTodos mis clientes son celebridades. Trat\u00e9 siempre a todos de la misma forma\u201d.<\/p>\n<p><strong>Su perro clonado<\/strong><\/p>\n<p>\u201cLa clonaci\u00f3n fue muy fuerte. Cuando ten\u00eda 13 a\u00f1os ya ten\u00eda dolor en el pecho y para un bulldog franc\u00e9s es much\u00edsimo. Llegado el momento contrat\u00e9 una empresa para embalsamarlo. Cuando vi en la televisi\u00f3n que B\u00e1rbara Strasser clon\u00f3 a su perro y estaba permitido en Nueva York. Llam\u00e9 a la compa\u00f1\u00eda y de ah\u00ed le extrajeron un pedacito de piel que es la parte m\u00e1s fuerte del ADN. Separaron las c\u00e9lulas y crearon un embri\u00f3n\u201d, cont\u00f3.<\/p>\n<p>Y expres\u00f3: \u201cEs hijo que nunca tuve. Naci\u00f3 el mismo d\u00eda que Machito muri\u00f3\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roberto Novo es fil\u00e1ntropo, fot\u00f3grafo y peluquero, entre otras profesiones. Hace a\u00f1os vive en Nueva York y Par\u00eds y ahora est\u00e1 en Buenos Aires, donde visit\u00f3 los estudios de CNN Radio junto a su perro Machito, que tiene una historia espectacular. En el programa Los Primeros de la Tarde, Novo record\u00f3: \u201cEmpec\u00e9 trabajando con Norma [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459487","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias\" \/>\n<meta property=\"og:description\" content=\"Roberto Novo es fil\u00e1ntropo, fot\u00f3grafo y peluquero, entre otras profesiones. Hace a\u00f1os vive en Nueva York y Par\u00eds y ahora est\u00e1 en Buenos Aires, donde visit\u00f3 los estudios de CNN Radio junto a su perro Machito, que tiene una historia espectacular. En el programa Los Primeros de la Tarde, Novo record\u00f3: \u201cEmpec\u00e9 trabajando con Norma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-04T20:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro\",\"datePublished\":\"2025-03-04T20:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\",\"name\":\"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-04T20:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","og_locale":"es_ES","og_type":"article","og_title":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias","og_description":"Roberto Novo es fil\u00e1ntropo, fot\u00f3grafo y peluquero, entre otras profesiones. Hace a\u00f1os vive en Nueva York y Par\u00eds y ahora est\u00e1 en Buenos Aires, donde visit\u00f3 los estudios de CNN Radio junto a su perro Machito, que tiene una historia espectacular. En el programa Los Primeros de la Tarde, Novo record\u00f3: \u201cEmpec\u00e9 trabajando con Norma [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","og_site_name":"Noticias","article_published_time":"2025-03-04T20:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/"},"author":{"name":"","@id":""},"headline":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro","datePublished":"2025-03-04T20:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","url":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","name":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-04T20:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La historia de Roberto Novo, el peluquero de las estrellas que clon\u00f3 a su perro","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/04\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-04T20:03:53Z","datePublished":"2025-03-04T20:03:53Z","dateModified":"2025-03-04T20:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La historia de Roberto Novo, el peluquero de las estrellas que clon\\u00f3 a su perro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/04\\\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/04\\\/la-historia-de-roberto-novo-el-peluquero-de-las-estrellas-que-clono-a-su-perro\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-04T20:03:53Z\",\"datePublished\":\"2025-03-04T20:03:53Z\",\"dateModified\":\"2025-03-04T20:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465872,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/26\/terrible-rapado-carlos-alcaraz-us-open-trax\/","url_meta":{"origin":1459487,"position":0},"title":"&#171;Es definitivamente terrible&#187;: el rapado de Carlos Alcaraz sorprende en el US Open","author":"","date":"agosto 26, 2025","format":false,"excerpt":"Solo ha jugado un partido en el US Open de este a\u00f1o, pero Carlos Alcaraz ya ha causado sensaci\u00f3n.El espa\u00f1ol, segundo cabeza de serie, lleg\u00f3 a la pista para su partido de primera ronda contra el estadounidense Reilly Opelka luciendo un nuevo y bastante radical corte de pelo.Qued\u00f3 claro que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465056,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/01\/empleada-limpieza-atacante-nueva-york-mortal-ataque-trax\/","url_meta":{"origin":1459487,"position":1},"title":"Empleada de limpieza que se enfrent\u00f3 cara a cara con el atacante de Nueva York relata c\u00f3mo fue el mortal ataque","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Sebije Nelovic siempre se sinti\u00f3 segura en el 345 de Park Avenue. Durante casi tres d\u00e9cadas, esta originaria de Albania limpi\u00f3 el elegante rascacielos de Manhattan que alberga varias sedes corporativas en uno de los barrios m\u00e1s exclusivos de Nueva York.Esa sensaci\u00f3n de tranquilidad se rompi\u00f3 el lunes, cuando un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472755,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/01\/hospitalizan-megan-thee-stallion-moulin-rouge-orix\/","url_meta":{"origin":1459487,"position":2},"title":"Hospitalizan a Megan Thee Stallion tras actuar en el musical &#171;Moulin Rouge!&#187; en Nueva York","author":"","date":"abril 1, 2026","format":false,"excerpt":"La rapera y actriz Megan Jovon Ruth Pete, mejor conocida como Megan Thee Stallion, fue hospitalizada tras su actuaci\u00f3n en el musical \u201cMoulin Rouge! The Musical!\u201d en Nueva York, confirm\u00f3 el representante de la artista a Variety y The Hollywood Reporter.\u201cDurante la funci\u00f3n de la noche del martes, Megan comenz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466773,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/09\/24\/nueva-york-pueblo-italiano-marido-familia-trax\/","url_meta":{"origin":1459487,"position":3},"title":"Nueva York se volvi\u00f3 &#171;demasiado loca&#187; as\u00ed que se mud\u00f3 a un pueblo italiano, conoci\u00f3 a su marido y form\u00f3 una familia","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"A veces, mudarse al extranjero puede parecer una apuesta arriesgada, un salto a lo desconocido.Para Caroline Chirichella, neoyorquina de 36 a\u00f1os, mudarse a un tranquilo rinc\u00f3n del centro de Italia fue m\u00e1s que una escapada. Signific\u00f3 formar una familia, comprar una vivienda asequible y empezar una nueva vida, a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467904,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/31\/amor-nueva-york-halloween-orix\/","url_meta":{"origin":1459487,"position":4},"title":"Una joven parisina lleg\u00f3 a Nueva York el d\u00eda de Halloween. All\u00ed conoci\u00f3 al hombre de sus sue\u00f1os","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Claire Chabaud-Trop\u00e9ano lleg\u00f3 a Nueva York en octubre de 2019, justo para Halloween, con la esperanza de que la ciudad de sus sue\u00f1os le diera un giro a su vida. \u201cRecuerdo caminar por las calles de Nueva York y pensar: \u2018Esta fiesta podr\u00eda serlo todo. Tal vez pueda ser un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462784,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/25\/rafael-nadal-homenaje-roland-garros-efe\/","url_meta":{"origin":1459487,"position":5},"title":"Nadal tras homenaje en Roland Garros: Ha sido el momento m\u00e1s emocionante de mi carrera","author":"","date":"mayo 25, 2025","format":false,"excerpt":"El espa\u00f1ol Rafael Nadal asegur\u00f3 que el homenaje que recibi\u00f3 este domingo en Roland Garros supuso \u201cel momento m\u00e1s emocionante\u201d de su carrera.\u201cNo me gusta ser el centro de atenci\u00f3n, he sufrido un poco por eso, pero lo he disfrutado mucho\u201d, asegur\u00f3 el exjugador en una rueda de prensa minutos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459487"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459487\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}