{"id":1459542,"date":"2025-03-05T13:03:48","date_gmt":"2025-03-05T21:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/"},"modified":"2025-03-05T13:03:48","modified_gmt":"2025-03-05T21:03:48","slug":"nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","title":{"rendered":"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;"},"content":{"rendered":"<p><strong>(CNN Radio Argentina) \u2013 Nicol\u00e1s Gadano,<\/strong> licenciado en Econom\u00eda de la UBA y especialista en la industria de hidrocarburos, analiz\u00f3 este mi\u00e9rcoles en <em>Regreso CNN<\/em> <em>con Mariana Arias y Pepe Gil Vidal <\/em>la situaci\u00f3n del sistema energ\u00e9tico en Argentina y los cortes de luz en la Ciudad de Buenos Aires.<\/p>\n<p>\u201cEstamos atravesando un d\u00eda con una secuencia de cortes importantes en el AMBA. Hubo uno muy temprano a la ma\u00f1ana, parec\u00eda que estaba solucionado, pero cerca del mediod\u00eda volvieron a producirse interrupciones con much\u00edsimos usuarios afectados\u201d, explic\u00f3 Gadano.<\/p>\n<p>El especialista aclar\u00f3 que <strong>\u201cno estamos en un d\u00eda de m\u00e1ximos de potencia en el pa\u00eds, es decir, no falta electricidad en t\u00e9rminos de demanda y oferta, sino que el problema est\u00e1 en la infraestructura: <\/strong>en las subestaciones, en el transporte, en la media tensi\u00f3n y en las redes de distribuci\u00f3n\u201d.<\/p>\n<p>En ese sentido, detall\u00f3 que \u201cestas redes son las que llegan a los hogares y, en situaciones de alta temperatura, no solo presentan fallas, sino que la capacidad de respuesta de las compa\u00f1\u00edas distribuidoras suele ser deficiente\u201d.<\/p>\n<p>Gadano enfatiz\u00f3 que <strong>\u201clo m\u00e1s da\u00f1ino no es tanto un corte, sino un corte de larga duraci\u00f3n, que puede extenderse por varias horas\u201d.<\/strong> Adem\u00e1s, subray\u00f3 que el sistema el\u00e9ctrico <strong>\u201ces fr\u00e1gil y est\u00e1 sobreexigido para atender estos eventos\u201d.<\/strong><\/p>\n<p>Consultado sobre las inversiones en el sector, Gadano afirm\u00f3 que <strong>\u201chace mucho que hay inversiones pendientes en transporte, transmisi\u00f3n y distribuci\u00f3n\u201d.<\/strong> En esta l\u00ednea, se\u00f1al\u00f3 que \u201caunque haya generaci\u00f3n disponible, la electricidad no siempre est\u00e1 en el lugar donde deber\u00eda estar\u201d y destac\u00f3 que \u201csi fallan la transmisi\u00f3n y la distribuci\u00f3n, es cuando se producen los cortes\u201d.<\/p>\n<p>Sobre la posible soluci\u00f3n, Gadano sostuvo que <strong>\u201cno hay forma de que la infraestructura mejore si no es con inversiones que llevan tiempo\u201d<\/strong> y asegur\u00f3 que \u201cel gobierno deber\u00eda exigirles a las compa\u00f1\u00edas que lo hagan, ya que las tarifas son relativamente razonables\u201d.<\/p>\n<p>En relaci\u00f3n con las estrategias a futuro, el economista destac\u00f3 que<strong> \u201chay que invertir en generaci\u00f3n de energ\u00eda, ya sea renovable, no renovable o hidroel\u00e9ctrica, y tambi\u00e9n en redes de distribuci\u00f3n\u201d.<\/strong> En este contexto, mencion\u00f3 una reciente licitaci\u00f3n que \u201capunta a resolver problemas cr\u00edticos como los de hoy, con inversi\u00f3n del sector privado\u201d. No obstante, advirti\u00f3 que \u201cel sector privado debe confiar en que las condiciones del pliego se cumplir\u00e1n y que recibir\u00e1n los pagos correspondientes\u201d.<\/p>\n<p>Finalmente, Gadano se refiri\u00f3 a la distribuci\u00f3n privada del servicio el\u00e9ctrico y consider\u00f3 que \u201cdividir por zonas para evitar un monopolio tan grande es una medida acertada\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Radio Argentina) \u2013 Nicol\u00e1s Gadano, licenciado en Econom\u00eda de la UBA y especialista en la industria de hidrocarburos, analiz\u00f3 este mi\u00e9rcoles en Regreso CNN con Mariana Arias y Pepe Gil Vidal la situaci\u00f3n del sistema energ\u00e9tico en Argentina y los cortes de luz en la Ciudad de Buenos Aires. \u201cEstamos atravesando un d\u00eda con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459542","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nicol\u00e1s Gadano: &quot;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicol\u00e1s Gadano: &quot;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Radio Argentina) \u2013 Nicol\u00e1s Gadano, licenciado en Econom\u00eda de la UBA y especialista en la industria de hidrocarburos, analiz\u00f3 este mi\u00e9rcoles en Regreso CNN con Mariana Arias y Pepe Gil Vidal la situaci\u00f3n del sistema energ\u00e9tico en Argentina y los cortes de luz en la Ciudad de Buenos Aires. \u201cEstamos atravesando un d\u00eda con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T21:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;\",\"datePublished\":\"2025-03-05T21:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\",\"name\":\"Nicol\u00e1s Gadano: \\\"El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-05T21:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nicol\u00e1s Gadano: \"El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","og_locale":"es_ES","og_type":"article","og_title":"Nicol\u00e1s Gadano: \"El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido\" - Noticias","og_description":"(CNN Radio Argentina) \u2013 Nicol\u00e1s Gadano, licenciado en Econom\u00eda de la UBA y especialista en la industria de hidrocarburos, analiz\u00f3 este mi\u00e9rcoles en Regreso CNN con Mariana Arias y Pepe Gil Vidal la situaci\u00f3n del sistema energ\u00e9tico en Argentina y los cortes de luz en la Ciudad de Buenos Aires. \u201cEstamos atravesando un d\u00eda con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","og_site_name":"Noticias","article_published_time":"2025-03-05T21:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/"},"author":{"name":"","@id":""},"headline":"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;","datePublished":"2025-03-05T21:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","url":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","name":"Nicol\u00e1s Gadano: \"El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-05T21:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nicol\u00e1s Gadano: &#171;El sistema el\u00e9ctrico es fr\u00e1gil y est\u00e1 sobreexigido&#187;","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-05T21:03:48Z","datePublished":"2025-03-05T21:03:48Z","dateModified":"2025-03-05T21:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nicol\\u00e1s Gadano: &#171;El sistema el\\u00e9ctrico es fr\\u00e1gil y est\\u00e1 sobreexigido&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/05\\\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/05\\\/nicolas-gadano-el-sistema-electrico-es-fragil-y-esta-sobreexigido\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-05T21:03:48Z\",\"datePublished\":\"2025-03-05T21:03:48Z\",\"dateModified\":\"2025-03-05T21:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462996,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/30\/nicolas-machuca-especialista-en-temas-previsionales-ser-jubilado-en-argentina-es-casi-una-sentencia-de-pobreza\/","url_meta":{"origin":1459542,"position":0},"title":"Nicol\u00e1s Machuca, especialista en temas previsionales: &#171;Ser jubilado en Argentina es casi una sentencia de pobreza&#187;","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Nicol\u00e1s Machuca, periodista especializado en temas previsionales, analiz\u00f3 el actual jubilatorio y las caracter\u00edsticas de una posible reforma.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cel sistema previsional argentino atraviesa una de sus peores crisis estructurales. Mientras el gobierno insiste con el ajuste fiscal y la contenci\u00f3n del gasto, los jubilados siguen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459784,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/el-rol-del-seguro-tras-las-inundaciones-estamos-muy-lejos-en-conciencia-aseguradora\/","url_meta":{"origin":1459542,"position":1},"title":"El rol del seguro tras las inundaciones: &#171;Estamos muy lejos en conciencia aseguradora&#187;","author":"","date":"marzo 11, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Nicol\u00e1s Saurit, presidente de la Asociaci\u00f3n de Productores de Seguros, habl\u00f3 este martes con CNN Radio sobre el impacto de las recientes inundaciones y c\u00f3mo las empresas aseguradoras han puesto el foco en las cat\u00e1strofes naturales.En Regreso CNN con Mariana Arias y Pepe Gil Vidal, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460947,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/08\/diego-martinez-burzaco-ante-la-crisis-mundial-por-los-aranceles-en-ee-uu-es-imposible-que-argentina-no-tenga-repercusiones\/","url_meta":{"origin":1459542,"position":2},"title":"Diego Mart\u00ednez Burzaco: &#171;Es imposible que Argentina no tenga repercusiones&#187;","author":"","date":"abril 8, 2025","format":false,"excerpt":"Diego Mart\u00ednez Burzaco, economista y especialista en mercado de capitales, analiz\u00f3 el contexto econ\u00f3mico mundial y c\u00f3mo afecta a Argentina.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201ces un d\u00eda bastante clave, ayer las autoridades chinas volvieron a se\u00f1alar de chantaje la posici\u00f3n de Donald Trump y dijeron que no iban a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462491,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/18\/nicolas-henricksen-hay-que-setear-un-poco-las-nuevas-politicas-para-que-argentina-se-convierta-en-un-pais-competitivo\/","url_meta":{"origin":1459542,"position":3},"title":"Nicol\u00e1s Henricksen: &#171;Hay que setear un poco las nuevas pol\u00edticas para que Argentina se convierta en un pa\u00eds competitivo&#187;","author":"","date":"mayo 18, 2025","format":false,"excerpt":"Nicol\u00e1s Henricksen, director de comunicaciones de AmCham, la C\u00e1mara de Comercio de Estados Unidos en Argentina, habl\u00f3 este domingo con CNN Radio sobre los objetivos para la realizaci\u00f3n de este evento.En CNN Campo con Mart\u00edn Melo indic\u00f3: \u201dRealmente el core de AmCham es articular entre el sector p\u00fablico y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459572,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/especialista-en-energia-afirmo-que-es-una-responsabilidad-compartida-entre-las-empresas-y-los-usuarios-evitar-los-cortes-de-luz\/","url_meta":{"origin":1459542,"position":4},"title":"Especialista en energ\u00eda afirm\u00f3 que &#171;es una responsabilidad compartida, entre las empresas y los usuarios&#187; evitar los cortes","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Salvador Gil, director de la carrera de Ingenier\u00eda en Energ\u00eda de la Universidad de San Mart\u00edn, analiz\u00f3 los cortes masivos de luz de ayer y los picos de tensi\u00f3n y explica algunas alternativas para el uso eficiente de la energ\u00eda.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cm\u00e1s all\u00e1 de la situaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459796,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/el-lenguaje-crea-realidades-como-la-neurociencia-puede-mejorar-la-productividad-y-el-aprendizaje\/","url_meta":{"origin":1459542,"position":5},"title":"&#171;El lenguaje crea realidades&#187;: c\u00f3mo la neurociencia puede mejorar la productividad y el aprendizaje","author":"","date":"marzo 11, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2014 Nicol\u00e1s Fern\u00e1ndez Miranda, divulgador especializado en neurociencia aplicada a la productividad y el aprendizaje, habl\u00f3 este martes con Mar\u00eda Areces en Al Fin y Al Cabo sobre c\u00f3mo el lenguaje y peque\u00f1os h\u00e1bitos pueden generar cambios significativos en la vida diaria.\u201cEstamos sesgados cuando le decimos a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459542"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459542\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}