{"id":1459546,"date":"2025-03-05T14:03:47","date_gmt":"2025-03-05T22:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/"},"modified":"2025-03-05T14:03:47","modified_gmt":"2025-03-05T22:03:47","slug":"gasolina-nuevas-tarifas-canada-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","title":{"rendered":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas"},"content":{"rendered":"<p>Los aranceles estadounidenses a las importaciones de combustible canadiense podr\u00edan afectar a algunas partes del pa\u00eds m\u00e1s que a otras.<\/p>\n<p>Seg\u00fan los expertos, el Noreste podr\u00eda ser el primero en sufrirlo, y los precios tambi\u00e9n podr\u00edan aumentar en la Costa Oeste. Pero incluso es improbable que esas posibles subidas se produzcan de inmediato.<\/p>\n<p>Los aranceles establecidos el martes eran del 25% para la mayor\u00eda de las importaciones, pero solo del 10% para los productos energ\u00e9ticos.<\/p>\n<p>Aunque la producci\u00f3n nacional estadounidense de petr\u00f3leo alcanz\u00f3 un r\u00e9cord mundial de 4.700 millones de barriles en 2024, Canad\u00e1 sigue siendo una importante fuente de petr\u00f3leo para Estados Unidos, ya que el a\u00f1o pasado envi\u00f3 1.500 millones de barriles de crudo al mercado estadounidense. M\u00e9xico, cuyas exportaciones energ\u00e9ticas a Estados Unidos tambi\u00e9n se enfrentan a un arancel del 25%, es la segunda mayor fuente de petr\u00f3leo para Estados Unidos, enviando 166 millones de barriles al norte de la frontera. Eso supone aproximadamente dos tercios m\u00e1s de lo que EE.UU. importa de Arabia Saudita.<\/p>\n<p>Cualquier subida de los precios de la gasolina podr\u00eda sumarse a las preocupaciones de que los aranceles del presidente Donald Trump disparen la inflaci\u00f3n para los estadounidenses, ya cansados de a\u00f1os de subidas de precios, que prometi\u00f3 durante y despu\u00e9s de su campa\u00f1a presidencial reducir en su primer d\u00eda en el cargo.<\/p>\n<p>La buena noticia para los conductores es que los precios de la gasolina son relativamente bajos ahora, una media de US$ 3,11 el gal\u00f3n en todo el pa\u00eds seg\u00fan la AAA, solo un centavo m\u00e1s que en los \u00faltimos d\u00edas y unos dos centavos menos desde que Trump asumi\u00f3 el cargo. Eso podr\u00eda amortiguar el impacto cuando las gasolineras empiecen a subir los precios. El precio medio en Massachusetts se mantuvo sin cambios en US$ 3,01 por gal\u00f3n. Los precios bajaron un centavo tanto en el estado de Washington como en California, aunque ambos superan los US$ 4 por gal\u00f3n, muy por encima ya de la media nacional.<\/p>\n<p>El dolor en las gasolineras afectar\u00e1 de forma diferente en todo el pa\u00eds, porque no existe un mercado \u00fanico para la gasolina. Diferentes partes del pa\u00eds obtienen el crudo, la gasolina o el di\u00e9sel de diferentes lugares a trav\u00e9s de diferentes m\u00e9todos de suministro.<\/p>\n<p>Por ejemplo, gran parte del suministro de gasolina del Noreste procede de la mayor refiner\u00eda de Canad\u00e1, en Saint John, Nuevo Brunswick, gestionada por Irving Oil. Irving ha dicho a sus clientes que no cubrir\u00e1 el mayor costo de los aranceles, que podr\u00edan a\u00f1adir entre 20 y 25 centavos al gal\u00f3n de gasolina. Los expertos dijeron a CNN que, como Irving env\u00eda su gasolina a EE.UU. por barco, puede redirigir f\u00e1cilmente los env\u00edos a mercados donde no tendr\u00e1 que hacer frente a los aranceles.<\/p>\n<p>\u201cDonde est\u00e1n en Canad\u00e1, el mundo es su ostra\u201d, dijo Tom Kloza, jefe global de an\u00e1lisis energ\u00e9tico de OPIS.<\/p>\n<p>Menos petr\u00f3leo de Irving significa menor oferta, lo que probablemente har\u00eda subir los precios. Incluso las gasolineras que no obtienen su gasolina de Irving podr\u00edan subir los precios si observan subidas de precios de sus rivales que s\u00ed obtienen su combustible de dicha refiner\u00eda, dijo Andy Lipow, analista de Lipow Oil Associates.<\/p>\n<p>Pero gran parte de los productos energ\u00e9ticos de Canad\u00e1 se transportan por oleoductos desde los campos petrol\u00edferos hasta las refiner\u00edas estadounidenses del Medio Oeste y los estados de las Monta\u00f1as Rocosas. Y la falta de compradores alternativos para ese crudo podr\u00eda significar que esos productores canadienses lo tendr\u00e1n mucho m\u00e1s dif\u00edcil para reorientar su petr\u00f3leo.<\/p>\n<p>\u201cEstamos importando unos 3 millones de barriles diarios de crudo canadiense a la regi\u00f3n del Medio Oeste y las Monta\u00f1as Rocosas\u201d, dijo Lipow, quien a\u00f1adi\u00f3 que las refiner\u00edas estadounidenses que utilizan ese crudo canadiense lo prefieren al petr\u00f3leo estadounidense porque es un grado m\u00e1s pesado que requiere menos petr\u00f3leo para fabricar el mismo gal\u00f3n de gasolina.<\/p>\n<p>\u201cEs una relaci\u00f3n simbi\u00f3tica\u201d, afirm\u00f3. Pero a\u00f1adi\u00f3 que la mayor\u00eda de esas refiner\u00edas se alejar\u00e1n de las petroleras canadienses, a menos que los productores acepten proteger a sus compradores estadounidenses del costo de los aranceles mediante una reducci\u00f3n de los precios.<\/p>\n<p>Las refiner\u00edas estadounidenses de toda la costa oeste tambi\u00e9n podr\u00edan ver c\u00f3mo su suministro normal de crudo canadiense se traslada al extranjero, lo que dar\u00eda lugar a una oferta m\u00e1s reducida y, por tanto, a unos costos m\u00e1s elevados.<\/p>\n<p>Pero, de todos modos, la gasolina podr\u00eda ser solo unos centavos por gal\u00f3n m\u00e1s cara, porque los mercados mundiales del petr\u00f3leo est\u00e1n presionando a la baja el precio del petr\u00f3leo en estos momentos, dijo Kloza. En parte, esto se debe a que la OPEP+, un grupo que incluye pa\u00edses de la OPEP y otros exportadores de petr\u00f3leo no pertenecientes a la OPEP, como Rusia y M\u00e9xico, acord\u00f3 a principios de esta semana aumentar la producci\u00f3n.<\/p>\n<p>A los operadores petroleros tambi\u00e9n les preocupa que las posibles guerras comerciales de EE.UU. con sus principales socios comerciales puedan empujar a varios pa\u00edses a la recesi\u00f3n, dijo Kloza. Nada hace caer el consumo de petr\u00f3leo, y los precios del petr\u00f3leo, m\u00e1s r\u00e1pidamente que una recesi\u00f3n.<\/p>\n<p>Los precios del crudo Brent cerraron el martes con una ca\u00edda del 1%, el quinto descenso en seis d\u00edas de negociaci\u00f3n y un m\u00ednimo de seis meses para ese \u00edndice de referencia mundial. El petr\u00f3leo West Texas Intermediary, una mejor medida de los precios norteamericanos, ha tenido un descenso similar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los aranceles estadounidenses a las importaciones de combustible canadiense podr\u00edan afectar a algunas partes del pa\u00eds m\u00e1s que a otras. Seg\u00fan los expertos, el Noreste podr\u00eda ser el primero en sufrirlo, y los precios tambi\u00e9n podr\u00edan aumentar en la Costa Oeste. Pero incluso es improbable que esas posibles subidas se produzcan de inmediato. Los aranceles [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459546","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los aranceles estadounidenses a las importaciones de combustible canadiense podr\u00edan afectar a algunas partes del pa\u00eds m\u00e1s que a otras. Seg\u00fan los expertos, el Noreste podr\u00eda ser el primero en sufrirlo, y los precios tambi\u00e9n podr\u00edan aumentar en la Costa Oeste. Pero incluso es improbable que esas posibles subidas se produzcan de inmediato. Los aranceles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T22:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas\",\"datePublished\":\"2025-03-05T22:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\"},\"wordCount\":1018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\",\"name\":\"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-05T22:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias","og_description":"Los aranceles estadounidenses a las importaciones de combustible canadiense podr\u00edan afectar a algunas partes del pa\u00eds m\u00e1s que a otras. Seg\u00fan los expertos, el Noreste podr\u00eda ser el primero en sufrirlo, y los precios tambi\u00e9n podr\u00edan aumentar en la Costa Oeste. Pero incluso es improbable que esas posibles subidas se produzcan de inmediato. Los aranceles [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-05T22:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas","datePublished":"2025-03-05T22:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/"},"wordCount":1018,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","name":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-05T22:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPagar\u00e1s m\u00e1s por la gasolina con las nuevas tarifas de Canad\u00e1? Depende de d\u00f3nde vivas","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/05\/gasolina-nuevas-tarifas-canada-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-05T22:03:47Z","datePublished":"2025-03-05T22:03:47Z","dateModified":"2025-03-05T22:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPagar\\u00e1s m\\u00e1s por la gasolina con las nuevas tarifas de Canad\\u00e1? Depende de d\\u00f3nde vivas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/05\\\/gasolina-nuevas-tarifas-canada-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/05\\\/gasolina-nuevas-tarifas-canada-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-05T22:03:47Z\",\"datePublished\":\"2025-03-05T22:03:47Z\",\"dateModified\":\"2025-03-05T22:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463844,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/22\/futuros-petroleo-suben-ataques-eeuu-iran-trax\/","url_meta":{"origin":1459546,"position":0},"title":"Los futuros del petr\u00f3leo suben tras los ataques estadounidenses a Ir\u00e1n","author":"","date":"junio 22, 2025","format":false,"excerpt":"Los precios del petr\u00f3leo subieron el domingo por la noche, la primera reacci\u00f3n de Wall Street a los ataques de Estados Unidos contra tres centrales nucleares iran\u00edes la noche del s\u00e1bado, lo que supone una importante escalada del conflicto entre Ir\u00e1n e Israel.Los futuros del petr\u00f3leo estadounidense subieron un 3,6\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457690,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/21\/trump-aranceles-a-mexico-y-canada-1-de-febrero-trax\/","url_meta":{"origin":1459546,"position":1},"title":"Trump dice que se impondr\u00e1n aranceles a M\u00e9xico y Canad\u00e1 el 1 de febrero","author":"","date":"enero 21, 2025","format":false,"excerpt":"El presidente Donald Trump dijo que cree que aplicar\u00e1 nuevos aranceles a Canad\u00e1 y M\u00e9xico el 1 de febrero.Trump dijo a los periodistas en la oficina oval que estaba pensando en un arancel del 25% sobre las importaciones de los vecinos norteamericanos de Estados Unidos.Esto equivale a un respiro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465682,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/20\/china-adquiere-petroleo-ruso-cae-demanda-india-aranceles-trump-trax\/","url_meta":{"origin":1459546,"position":2},"title":"China adquiere petr\u00f3leo ruso mientras cae la demanda india tras los aranceles de Trump","author":"","date":"agosto 20, 2025","format":false,"excerpt":"Las refiner\u00edas chinas han realizado nuevos pedidos de crudo ruso que se enviar\u00e1 desde puertos que normalmente abastecen a India, ya que la demanda del petr\u00f3leo de Mosc\u00fa por parte del pa\u00eds del sur de Asia cae tras los aranceles del presidente Donald Trump.Las refiner\u00edas chinas han asegurado al menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456570,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/13\/canada-amenaza-cortar-energia-estados-unidos-trax\/","url_meta":{"origin":1459546,"position":3},"title":"Un funcionario canadiense amenaza con cortar el suministro de energ\u00eda a Estados Unidos","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"Canad\u00e1 podr\u00eda tomar represalias contra la amenaza de aranceles del presidente electo de EE.UU., Donald Trump, al cortar los flujos de energ\u00eda hacia Estados Unidos, advirti\u00f3 un alto funcionario canadiense.\u201cLlegaremos al extremo de cortar la energ\u00eda que va hacia Michigan, hacia el estado de Nueva York y hacia Wisconsin\u201d, amenaz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472052,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/10\/trum-india-petroleo-ruso-iran-socava-objetivo-trax\/","url_meta":{"origin":1459546,"position":4},"title":"Trump quer\u00eda que la India se alejara del petr\u00f3leo ruso. Su guerra con Ir\u00e1n ahora est\u00e1 socavando ese objetivo","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Durante gran parte del a\u00f1o pasado, Washington intent\u00f3 dejar sin dinero a la maquinaria de guerra de Mosc\u00fa, en parte eliminando a uno de sus clientes m\u00e1s leales: la India.Bajo la campa\u00f1a de presi\u00f3n del presidente Donald Trump, la Casa Blanca impuso altos aranceles a muchas de las exportaciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465165,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/06\/sanciones-secundarias-trump-rusia-ee-uu-analisis-trax\/","url_meta":{"origin":1459546,"position":5},"title":"Las &#8216;sanciones secundarias&#8217; de Trump dirigidas a Rusia da\u00f1ar\u00edan la propia econom\u00eda de EE.UU.","author":"","date":"agosto 6, 2025","format":false,"excerpt":"Esta semana se cumple un nuevo plazo fijado por el presidente de EE.UU. Donald Trump para su plan de obligar a Rusia a hacer la paz en Ucrania: afectar con nuevos aranceles a los pa\u00edses que todav\u00eda compran petr\u00f3leo de Mosc\u00fa.El enviado exterior de Trump, Steve Witkoff, viajar\u00e1 a Rusia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459546"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459546\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}