{"id":1459595,"date":"2025-03-06T14:03:47","date_gmt":"2025-03-06T22:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/"},"modified":"2025-03-06T14:03:47","modified_gmt":"2025-03-06T22:03:47","slug":"cnn-verifica-trump-exagera-deficits-comerciales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","title":{"rendered":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE"},"content":{"rendered":"<p>Durante a\u00f1os, el presidente Donald Trump ha exagerado la magnitud de los d\u00e9ficits comerciales de Estados Unidos con otros pa\u00edses. Ahora, cuando Trump los cita como una justificaci\u00f3n clave para sus pol\u00edticas arancelarias, las estad\u00edsticas federales <a href=\"https:\/\/www.bea.gov\/sites\/default\/files\/2025-03\/trad0125.pdf\">publicadas recientemente <\/a>muestran cu\u00e1n err\u00f3neas son las cifras que maneja Trump.<\/p>\n<p>Las cifras federales publicadas anteriormente para 2023 y parte de 2024 ya hab\u00edan demostrado que las afirmaciones de Trump sobre los d\u00e9ficits de EE.UU. con Canad\u00e1, M\u00e9xico, China y la Uni\u00f3n Europea estaban muy equivocadas. Ahora, el Departamento de Comercio ha publicado las cifras de todo el a\u00f1o 2024 que nos permiten decir con precisi\u00f3n hasta qu\u00e9 punto.<\/p>\n<p>Antes de entrar en los datos, un breve recordatorio: tener un d\u00e9ficit comercial con otro pa\u00eds significa que Estados Unidos importa m\u00e1s bienes y servicios de ese pa\u00eds de los que exporta. Aunque Trump a menudo describe los d\u00e9ficits comerciales como subsidios o p\u00e9rdidas, tener un d\u00e9ficit no significa que EE.UU. est\u00e9 regalando dinero a cambio de nada.<\/p>\n<p>Por ejemplo, el d\u00e9ficit comercial de EE.UU. con Canad\u00e1 existe en gran medida porque EE.UU.<a href=\"https:\/\/www.eia.gov\/todayinenergy\/detail.php?id=62183\"> importa <\/a>una gran cantidad de crudo pesado canadiense barato que ayuda a mantener bajos los precios de la gasolina para los conductores estadounidenses.<\/p>\n<p>Trump, que ha impuesto aranceles del 25% a casi todos los productos importados de Canad\u00e1, ha dicho <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-press-conference-mar-a-lago-january-7-2025\/\">repetidamente<\/a> este a\u00f1o que Estados Unidos tiene un d\u00e9ficit comercial de \u201cUS$ 200.000 millones\u201d con Canad\u00e1, a veces haciendo la afirmaci\u00f3n <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-press-conference-mar-a-lago-january-7-2025\/#210\">expl\u00edcitamente<\/a> y a veces utilizando un lenguaje m\u00e1s vago sobre una supuesta <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-press-gaggle-after-air-force-one-arrival-february-2-2025\/#12\">subvenci\u00f3n<\/a> o <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-remarks-cabinet-meeting-february-26-2025\/#194\">p\u00e9rdida<\/a> de US$ 200.000 millones ante Canad\u00e1.<\/p>\n<p>La cifra de Trump ni siquiera est\u00e1 cerca de ser correcta. Las nuevas estad\u00edsticas federales muestran que el d\u00e9ficit de 2024 con Canad\u00e1 en el comercio de bienes y servicios fue de US$ 35.700 millones, por debajo de los US$ 40.600 millones de 2023.<\/p>\n<p>Incluso si solo se tiene en cuenta el comercio de bienes y se ignora el comercio de servicios, en el que Estados Unidos destaca, el d\u00e9ficit con Canad\u00e1 en 2024 fue de US$ 70.600 millones. En 2023 fue de US$ 72.300 millones.<\/p>\n<p>Trump tambi\u00e9n impuso aranceles del 25% a los productos importados de M\u00e9xico, aunque el jueves<a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/114116432894994278\"> anunci\u00f3<\/a> una suspensi\u00f3n, hasta el 2 de abril, en los aranceles a cualquier art\u00edculo mexicano que \u201centre\u201d en el Acuerdo EE.UU.-M\u00e9xico-Canad\u00e1 que firm\u00f3 en su primer mandato. En febrero<a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-interview-bret-baier-fox-news-february-9-2025\/#96\"> dijo<\/a> en una entrevista en Fox News: \u201cTenemos un d\u00e9ficit con M\u00e9xico de US$ 350.000 millones\u201d.<\/p>\n<p>De nuevo, eso est\u00e1 alejado de la realidad. Las nuevas cifras federales muestran que el d\u00e9ficit con M\u00e9xico en 2024 en el comercio de bienes y servicios fue de US$ 179.000 millones, por encima de los US$ 162.100 millones de 2023.<\/p>\n<p>El d\u00e9ficit de 2024 con M\u00e9xico solo en el comercio de bienes fue de US$ 181.500 millones, por encima de los US$ 161.400 millones de 2023.<\/p>\n<p>Trump, que ha impuesto una serie de aranceles en su primer y segundo mandato presidencial a productos importados de China, dijo en una <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-interview-brian-kilmeade-fox-news-radio-february-21-2025\/#125\">entrevista <\/a>en Fox News Radio en febrero que \u201ctenemos un d\u00e9ficit con China de m\u00e1s de US$ 1 bill\u00f3n\u201d. Repiti\u00f3 la cifra de \u201c1 bill\u00f3n de d\u00f3lares\u201d en un <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-speech-cpac-convention-national-harbor-maryland-february-22-2025\/#66\">discurso en febrero<\/a>.<\/p>\n<p>Eso tambi\u00e9n es una exageraci\u00f3n total. Las nuevas cifras federales muestran que el d\u00e9ficit de 2024 con China en el comercio de bienes y servicios fue de US$ 263.300 millones. Esa cifra es superior a los US$ 252.100 millones de 2023, pero inferior a la de <a href=\"https:\/\/www.bea.gov\/sites\/default\/files\/2021-05\/trad0321.pdf\">todos<\/a> los <a href=\"https:\/\/www.bea.gov\/system\/files\/2020-05\/trad0320.pdf\">a\u00f1os<\/a> de la primera presidencia de Trump.<\/p>\n<p>Los d\u00e9ficits comerciales fluct\u00faan por numerosas razones distintas de la pol\u00edtica presidencial. Mencionamos el hecho de que los d\u00e9ficits de la era Biden eran m\u00e1s bajos que los d\u00e9ficits de la era Trump, sin embargo, porque Trump <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-speech-virtual-world-economic-forum-january-23-2025\/#102\">ha afirmado<\/a> que Biden dej\u00f3 que el d\u00e9ficit con China \u201cse le fuera de las manos\u201d.<\/p>\n<p>El d\u00e9ficit con China en 2024 solo en comercio de bienes fue de US$ 295.200 millones, frente a los US$ 278.700 millones de 2023.<\/p>\n<p>Trump ha arremetido regularmente, y de forma incorrecta, contra la Uni\u00f3n Europea por sus pr\u00e1cticas comerciales. Dijo a los periodistas <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-press-gaggle-after-air-force-one-arrival-february-2-2025\/#28\">en febrero<\/a> que \u201ccon la Uni\u00f3n Europea, es, ya sabes, US$ 350.000 millones de d\u00e9ficit\u201d. Dijo en un <a href=\"https:\/\/rollcall.com\/factbase\/trump\/transcript\/donald-trump-remarks-cabinet-meeting-february-26-2025\/#198\">evento posterior<\/a> de febrero que es \u201calrededor de un d\u00e9ficit de US$ 300.000 millones con la Uni\u00f3n Europea\u201d.<\/p>\n<p>Equivocado una vez m\u00e1s. Las nuevas cifras federales muestran que el d\u00e9ficit de 2024 con la Uni\u00f3n Europea en el comercio de bienes y servicios fue de US$ 161.100 millones, por encima de los US$ 125.100 millones de 2023.<\/p>\n<p>El d\u00e9ficit de 2024 con la Uni\u00f3n Europea solo en el comercio de bienes fue de US$ 236.700 millones, frente a los US$ 201.600 millones de 2023. Por lo tanto, teniendo en cuenta solo el comercio de bienes, las afirmaciones de Trump sobre el d\u00e9ficit con la Uni\u00f3n Europea se acercan un poco m\u00e1s a la verdad que sus afirmaciones sobre los d\u00e9ficits con Canad\u00e1, M\u00e9xico y China, pero siguen lejos de ser ciertos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a\u00f1os, el presidente Donald Trump ha exagerado la magnitud de los d\u00e9ficits comerciales de Estados Unidos con otros pa\u00edses. Ahora, cuando Trump los cita como una justificaci\u00f3n clave para sus pol\u00edticas arancelarias, las estad\u00edsticas federales publicadas recientemente muestran cu\u00e1n err\u00f3neas son las cifras que maneja Trump. Las cifras federales publicadas anteriormente para 2023 y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459595","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias\" \/>\n<meta property=\"og:description\" content=\"Durante a\u00f1os, el presidente Donald Trump ha exagerado la magnitud de los d\u00e9ficits comerciales de Estados Unidos con otros pa\u00edses. Ahora, cuando Trump los cita como una justificaci\u00f3n clave para sus pol\u00edticas arancelarias, las estad\u00edsticas federales publicadas recientemente muestran cu\u00e1n err\u00f3neas son las cifras que maneja Trump. Las cifras federales publicadas anteriormente para 2023 y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-06T22:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE\",\"datePublished\":\"2025-03-06T22:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\"},\"wordCount\":899,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\",\"name\":\"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-06T22:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias","og_description":"Durante a\u00f1os, el presidente Donald Trump ha exagerado la magnitud de los d\u00e9ficits comerciales de Estados Unidos con otros pa\u00edses. Ahora, cuando Trump los cita como una justificaci\u00f3n clave para sus pol\u00edticas arancelarias, las estad\u00edsticas federales publicadas recientemente muestran cu\u00e1n err\u00f3neas son las cifras que maneja Trump. Las cifras federales publicadas anteriormente para 2023 y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-06T22:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/"},"author":{"name":"","@id":""},"headline":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE","datePublished":"2025-03-06T22:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/"},"wordCount":899,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","name":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-06T22:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"CNN verifica: Trump exagera enormemente los d\u00e9ficits comerciales con Canad\u00e1, M\u00e9xico, China y la UE","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/cnn-verifica-trump-exagera-deficits-comerciales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-06T22:03:47Z","datePublished":"2025-03-06T22:03:47Z","dateModified":"2025-03-06T22:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"CNN verifica: Trump exagera enormemente los d\\u00e9ficits comerciales con Canad\\u00e1, M\\u00e9xico, China y la UE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/06\\\/cnn-verifica-trump-exagera-deficits-comerciales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/06\\\/cnn-verifica-trump-exagera-deficits-comerciales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-06T22:03:47Z\",\"datePublished\":\"2025-03-06T22:03:47Z\",\"dateModified\":\"2025-03-06T22:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456807,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/20\/trump-europa-compren-aranceles-trax\/","url_meta":{"origin":1459595,"position":0},"title":"Trump amenaza a Europa: compren m\u00e1s de nuestro petr\u00f3leo y gas o enfrenten aranceles","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"El presidente electo de EE.UU., Donald Trump, redobl\u00f3 sus amenazas de aranceles en la noche del jueves, al prometer un aumento de los aranceles a pa\u00edses de la Uni\u00f3n Europea (UE) a menos que aumenten sus compras de petr\u00f3leo y gas estadounidenses para reducir el d\u00e9ficit comercial con Estados Unidos.\u201cLe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465026,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/01\/aranceles-comercio-trump-fecha-limite-trax\/","url_meta":{"origin":1459595,"position":1},"title":"Trump acaba de revelar su nuevo plan arancelario. Estos son los puntos principales","author":"","date":"agosto 1, 2025","format":false,"excerpt":"El presidente Donald Trump acaba de imponer nuevos aranceles para todos los pa\u00edses del mundo, consolidando su ruptura extrema con la pol\u00edtica comercial de larga data de Estados Unidos.Se prev\u00e9 que aumenten los aranceles sobre la gran mayor\u00eda de los bienes que importa Estados Unidos, incluso los de los pocos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460862,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/05\/aranceles-reciprocos-no-son-lo-que-parecen-trax\/","url_meta":{"origin":1459595,"position":2},"title":"Los aranceles &#171;rec\u00edprocos&#187; de Trump no son lo que parecen. Esta es la verdadera historia","author":"","date":"abril 5, 2025","format":false,"excerpt":"Los aranceles masivos que el presidente de Estados Unidos, Donald Trump, anunci\u00f3 el mi\u00e9rcoles para docenas de socios comerciales se presentaron como \u201crec\u00edprocos\u201d, por su simple objetivo de igualar los aranceles que otros pa\u00edses imponen a Estados Unidos.Pero la metodolog\u00eda detr\u00e1s del intento de Trump de reequilibrar el comercio no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471574,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/02\/23\/analisis-problemas-arancelarios-trump-no-terminan-trax\/","url_meta":{"origin":1459595,"position":3},"title":"Los problemas arancelarios de Trump podr\u00edan no haber terminado","author":"","date":"febrero 23, 2026","format":false,"excerpt":"Horas despu\u00e9s de que este viernes la Corte Suprema anulara su pol\u00edtica arancelaria, el presidente Donald Trump insisti\u00f3 en que, en realidad, el fallo de alguna manera lo hab\u00eda hecho \u201cm\u00e1s fuerte\u201d.Estaba exagerando. Sus otras opciones potenciales resultaban objetivamente m\u00e1s d\u00e9biles.Y su alternativa declarada, aquella por la que instaurar\u00eda un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460937,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/07\/cnn-verifica-trump-europa-deficit-comercial-china-trax\/","url_meta":{"origin":1459595,"position":4},"title":"CNN verifica: Trump afirma falsamente que Europa no compra nada de EE.UU. y exagera el d\u00e9ficit comercial con China","author":"","date":"abril 7, 2025","format":false,"excerpt":"El domingo, al hablar con los periodistas en el Air Force One, el presidente Donald Trump defendi\u00f3 sus nuevos aranceles globales con una serie de afirmaciones falsas sobre los aranceles y el comercio. El domingo, al hablar con los periodistas en el Air Force One, el presidente Donald Trump defendi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457582,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/16\/trump-deficit-canada-otros-paises-trax\/","url_meta":{"origin":1459595,"position":5},"title":"\u00bfQu\u00e9 quiere decir Trump cuando afirma que Estados Unidos &#171;pierde&#187; miles de millones frente a Canad\u00e1 y otros pa\u00edses?","author":"","date":"enero 16, 2025","format":false,"excerpt":"Cuando el presidente electo Donald Trump plante\u00f3 recientemente la idea de una anexi\u00f3n de Canad\u00e1, una raz\u00f3n clave que dio fue que Estados Unidos estaba \u201cperdiendo US$ 200.000 millones al a\u00f1o\u201d respecto a su vecino del norte.En un discurso pronunciado la semana pasada en Mar-a-Lago, Trump no especific\u00f3 en qu\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459595"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459595\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}