{"id":1459604,"date":"2025-03-06T18:03:40","date_gmt":"2025-03-07T02:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/"},"modified":"2025-03-06T18:03:40","modified_gmt":"2025-03-07T02:03:40","slug":"el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","title":{"rendered":"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;"},"content":{"rendered":"<p><strong>(CNN Radio Argentina) \u2013<\/strong> La escritora <strong>Andrea Loren<\/strong> habl\u00f3 este jueves con <strong>CNN Radio <\/strong>sobre su libro \u2018<em>El murmullo de las damas\u2019:<\/em> cuando la patria libre, era para ellas, el \u00fanico destino posible.<\/p>\n<p>En di\u00e1logo con<em> Mar\u00eda Areces en<\/em> <em>Al Fin y Al Cabo<\/em> , Loren explic\u00f3 que su libro aborda las vidas de distintas mujeres cuyas historias se entrelazan en la b\u00fasqueda de su propia libertad. <strong>\u201cLas dos protagonistas principales son dos hermanas, Julia y Elena, oriundas de C\u00f3rdoba, que por un matrimonio arreglado por su hermano \u2013un hombre violento que las somete a una vida muy dif\u00edcil\u2013 deben viajar a Salta, cuna de nuestra independencia\u201d,<\/strong> relat\u00f3 la autora.<\/p>\n<p>All\u00ed, su destino cambia al llegar a la casa de un coronel espa\u00f1ol viudo, un hombre que, tras la muerte de su esposa, debe criar solo a sus cuatro hijos. \u201cDe pronto, \u00e9l siente que tiene una familia por la mitad, un hombre que sufre much\u00edsimo la p\u00e9rdida de su mujer, una mujer que tiene sus secretos\u2026\u201d, describi\u00f3 Loren. <strong>En ese punto, la novela adquiere un tinte m\u00edstico, que seg\u00fan la escritora, refleja la esencia de la Argentina, \u201cesa fuerza, esa pasi\u00f3n que siempre encontramos\u201d.<\/strong><\/p>\n<p><strong>La autora destac\u00f3 que su principal motivaci\u00f3n para escribir el libro fue dar visibilidad a estas mujeres,<\/strong> cuya historia ha comenzado a conocerse con mayor profundidad en los \u00faltimos a\u00f1os. \u201cMuchas eran mujeres acomodadas, otras eran abor\u00edgenes, esclavas, campesinas. \u00bfPero qu\u00e9 las llev\u00f3 a dejar las comodidades en pos de una revoluci\u00f3n? Tal vez ni siquiera ver\u00edan la independencia, perdi\u00e9ndolo todo, incluso su propia libertad\u201d, reflexion\u00f3.<\/p>\n<p>A lo largo de la novela, se explora el crecimiento de cada una de estas mujeres, no solo en su participaci\u00f3n en la revoluci\u00f3n, sino en su camino personal hacia la emancipaci\u00f3n. <strong>\u201cSiempre en el libro vas a encontrar que lo que las despierta es el amor:<\/strong> el amor hacia ellas mismas, hacia la patria, hacia sus seres queridos, sus hijos\u201d, sostuvo Loren.<\/p>\n<p>Por \u00faltimo, la autora subray\u00f3 que el prop\u00f3sito de su obra es mostrar a estas guerreras que luego se convirtieron en hero\u00ednas, pero desde una mirada humana. <strong>\u201cQuise retratarlas como mujeres, como madres, como hijas, como esposas. Mostrar qu\u00e9 les pasaba y, sobre todo, que no son tan distintos a nosotras\u201d,<\/strong> concluy\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Radio Argentina) \u2013 La escritora Andrea Loren habl\u00f3 este jueves con CNN Radio sobre su libro \u2018El murmullo de las damas\u2019: cuando la patria libre, era para ellas, el \u00fanico destino posible. En di\u00e1logo con Mar\u00eda Areces en Al Fin y Al Cabo , Loren explic\u00f3 que su libro aborda las vidas de distintas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459604","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u2018El murmullo de las damas\u2019: &quot;La novela tiene un poco de m\u00edstica como nuestra Argentina&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018El murmullo de las damas\u2019: &quot;La novela tiene un poco de m\u00edstica como nuestra Argentina&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Radio Argentina) \u2013 La escritora Andrea Loren habl\u00f3 este jueves con CNN Radio sobre su libro \u2018El murmullo de las damas\u2019: cuando la patria libre, era para ellas, el \u00fanico destino posible. En di\u00e1logo con Mar\u00eda Areces en Al Fin y Al Cabo , Loren explic\u00f3 que su libro aborda las vidas de distintas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T02:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;\",\"datePublished\":\"2025-03-07T02:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\",\"name\":\"\u2018El murmullo de las damas\u2019: \\\"La novela tiene un poco de m\u00edstica como nuestra Argentina\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-07T02:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018El murmullo de las damas\u2019: \"La novela tiene un poco de m\u00edstica como nuestra Argentina\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"\u2018El murmullo de las damas\u2019: \"La novela tiene un poco de m\u00edstica como nuestra Argentina\" - Noticias","og_description":"(CNN Radio Argentina) \u2013 La escritora Andrea Loren habl\u00f3 este jueves con CNN Radio sobre su libro \u2018El murmullo de las damas\u2019: cuando la patria libre, era para ellas, el \u00fanico destino posible. En di\u00e1logo con Mar\u00eda Areces en Al Fin y Al Cabo , Loren explic\u00f3 que su libro aborda las vidas de distintas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","og_site_name":"Noticias","article_published_time":"2025-03-07T02:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/"},"author":{"name":"","@id":""},"headline":"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;","datePublished":"2025-03-07T02:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","url":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","name":"\u2018El murmullo de las damas\u2019: \"La novela tiene un poco de m\u00edstica como nuestra Argentina\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-07T02:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u2018El murmullo de las damas\u2019: &#171;La novela tiene un poco de m\u00edstica como nuestra Argentina&#187;","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/06\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-07T02:03:40Z","datePublished":"2025-03-07T02:03:40Z","dateModified":"2025-03-07T02:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u2018El murmullo de las damas\\u2019: &#171;La novela tiene un poco de m\\u00edstica como nuestra Argentina&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/06\\\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/06\\\/el-murmullo-de-las-damas-la-novela-tiene-un-poco-de-mistica-como-nuestra-argentina\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-07T02:03:40Z\",\"datePublished\":\"2025-03-07T02:03:40Z\",\"dateModified\":\"2025-03-07T02:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445943,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/22\/muere-hydeia-broadbent-trax\/","url_meta":{"origin":1459604,"position":0},"title":"Muere a los 39 a\u00f1os Hydeia Broadbent, activista contra el VIH\/sida desde su ni\u00f1ez","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN) -- Hydeia Broadbent, conocida por generar consciencia sobre el VIH\/sida desde que era una ni\u00f1a, falleci\u00f3, seg\u00fan anunci\u00f3 su padre en Facebook. Ten\u00eda 39 a\u00f1os.\"Con gran tristeza debo informarles a todos que nuestra querida amiga, mentora e hija Hydeia falleci\u00f3 hoy tras vivir con VIH desde su nacimiento. A\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462963,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/29\/jueves-de-estrenos-las-recomendaciones-de-catalina-dlugi-en-cnn-radio\/","url_meta":{"origin":1459604,"position":1},"title":"Jueves de estrenos: las recomendaciones de Catalina Dlugi en CNN Radio","author":"","date":"mayo 29, 2025","format":false,"excerpt":"La reconocida periodista y columnista de CNN Radio Argentina Catalina Dlugi realiz\u00f3 este jueves 29 de mayo sus recomendaciones sobre cine y series.ESTRENOS EN CINESLA B\u00daSQUEDA DE MARTINA. Una pel\u00edcula que protagoniza Mercedes Mor\u00e1n. Es una abuela de plaza de mayo que busca a su nieto y tiene s\u00edntomas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462640,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/21\/hugo-alconada-mon-y-su-nuevo-libro-topos-detecte-el-caso-en-un-medio-esloveno-en-2023\/","url_meta":{"origin":1459604,"position":2},"title":"Hugo Alconada Mon y su nuevo libro \u2018Topos\u2019: &#171;Detect\u00e9 el caso en un medio esloveno en 2023&#187;","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Hugo Alconada Mon, periodista y autor de, entre otros libros,\u201cTopos: La historia real de los esp\u00edas rusos que tomaron Buenos Aires como base de operaciones\u201d, visit\u00f3 este mi\u00e9rcoles los estudios de CNN Radio para conversar sobre su apasionante nueva publicaci\u00f3n y las repercusiones de un caso que recorri\u00f3 el mundo.\u201cEs\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460931,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/07\/mujer-embarazada-detencion-ruso-supuesto-lider-secta-orix\/","url_meta":{"origin":1459604,"position":3},"title":"C\u00f3mo una mujer a punto de dar a luz llev\u00f3 en Argentina a la detenci\u00f3n de un ruso, supuesto l\u00edder de una secta","author":"","date":"abril 7, 2025","format":false,"excerpt":"Una joven rusa de 22 a\u00f1os lleg\u00f3 al hospital de Bariloche lista para dar a luz. Los m\u00e9dicos que la hab\u00edan atendido previamente, prepararon el quir\u00f3fano y la guiaron durante la ces\u00e1rea. Afuera quedaron las dos mujeres que la acompa\u00f1aban.No era la primera vez que el personal del hospital las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463249,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/05\/daniel-balmaceda-presento-su-nuevo-libro-el-crimen-de-ano-nuevo-en-regreso-cnn\/","url_meta":{"origin":1459604,"position":4},"title":"Daniel Balmaceda present\u00f3 su nuevo libro &#8216;El Crimen de A\u00f1o Nuevo&#8217; en Regreso CNN","author":"","date":"junio 5, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2014 El periodista y escritor Daniel Balmaceda dialog\u00f3 este jueves con Regreso CNN, el programa de Mariana Arias y Pepe Gil Vidal, donde present\u00f3 su nuevo libro El Crimen de A\u00f1o Nuevo, una novela que entrelaza una investigaci\u00f3n policial con la efervescencia social de fines del siglo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446891,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/12\/venezuela-prohibe-sobrevuelos-empresas-argentinas-orix\/","url_meta":{"origin":1459604,"position":5},"title":"Venezuela proh\u00edbe los permisos de sobrevuelo a empresas argentinas","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Venezuela ratific\u00f3 este lunes su decisi\u00f3n de prohibir los permisos de sobrevuelo de empresas a\u00e9reas argentinas sobre su espacio a\u00e9reo, de acuerdo con fuentes con conocimiento del tema consultadas por CNN.El Gobierno de Argentina hab\u00eda presentado una nota de protesta el viernes a Venezuela por la decisi\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459604"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459604\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}