{"id":1459618,"date":"2025-03-07T05:03:44","date_gmt":"2025-03-07T13:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/"},"modified":"2025-03-07T05:03:44","modified_gmt":"2025-03-07T13:03:44","slug":"dependencia-comercial-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","title":{"rendered":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?"},"content":{"rendered":"<p>M\u00e9xico logr\u00f3 este jueves un mes m\u00e1s sin que Estados Unidos imponga aranceles a sus productos. Tras una llamada entre la presidenta mexicana, Claudia Sheinbaum, y el mandatario estadounidense, Donald Trump, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/06\/eeuu\/retraso-aranceles-eeuu-mexico-canada-trax\">se acord\u00f3 que por el momento no entrar\u00e1n en vigor los aranceles de 25%<\/a> a los productos provenientes de M\u00e9xico que est\u00e9n dentro del acuerdo comercial que incluye a los tres pa\u00edses de Norteam\u00e9rica, el T-MEC.<\/p>\n<p>\u201cEntonces, le dije: \u2018Estamos teniendo resultados, presidente Trump. \u00bfPor qu\u00e9 ahora que puso las tarifas, pues c\u00f3mo vamos a seguir cooperando, colaborando, con algo que da\u00f1a al pueblo de M\u00e9xico?\u2019\u201d, expuso la mandataria en su conferencia matutina.<\/p>\n<p>Este jueves, Trump firm\u00f3 acciones ejecutivas para echar atr\u00e1s los aranceles del 25% sobre todos los productos de M\u00e9xico y Canad\u00e1 que est\u00e1n dentro del tratado. As\u00ed que no habr\u00e1 aranceles al menos hasta el 2 de abril, cuando EE.UU. tiene programado implementar los aranceles rec\u00edprocos a todos los pa\u00edses.<\/p>\n<p>Estos anuncios de aranceles han generado incertidumbre en M\u00e9xico, al nivel de que la presidenta Sheinbaum puso en la mesa la posibilidad de diversificar sus socios comerciales.<\/p>\n<p>\u201cSi permanecen (los aranceles), pues nosotros tambi\u00e9n tenemos que tomar decisiones. (\u2026) Se va a buscar si es necesario otros socios comerciales. Todo para proteger a M\u00e9xico y a los mexicanos\u201d, dijo la mandataria en su conferencia matutina del martes.<\/p>\n<p>Pero \u00bfes viable que M\u00e9xico encuentre mercados alternativos que sustituyan a Estados Unidos?<\/p>\n<p>Ildefonso Guajardo, exsecretario de Econom\u00eda de M\u00e9xico, destac\u00f3 lo que catalog\u00f3 como una falta de seriedad del gobierno de Donald Trump en las negociaciones. \u201cParece que est\u00e1s negociando con tus hijos adolescentes los t\u00e9rminos de la salida la fiesta el s\u00e1bado en la noche; o sea, cambian pr\u00e1cticamente conforme van avanzando las horas\u201d, dijo.<\/p>\n<p>Trump ha amenazado con imponer aranceles a M\u00e9xico y Canad\u00e1 para presionarlos a redoblar sus esfuerzos en el combate al tr\u00e1fico de drogas y en la inmigraci\u00f3n irregular hacia Estados Unidos.<\/p>\n<p>En cuanto a la posibilidad de que M\u00e9xico pueda voltear hacia otros mercados, Guajardo es esc\u00e9ptico y dice que ser\u00eda \u201cmuy dif\u00edcil\u201d reemplazar a Estados Unidos como socio comercial.<\/p>\n<p>Alejandra Cullen, analista econ\u00f3mica, coincide: \u201cPor m\u00e1s que tengas mercados locales, son demasiado peque\u00f1os para que puedan sustituir la dimensi\u00f3n del mercado estadounidense\u201d.<\/p>\n<p>Cullen a\u00f1adi\u00f3 que \u201cno hay en toda Am\u00e9rica Latina junto un mercado del tama\u00f1o del de Estados Unidos y que, adem\u00e1s, tenga la cercan\u00eda, la capacidad de compra y la integraci\u00f3n que tenemos (con EE.UU.)\u201d.<\/p>\n<p>El principal mercado de M\u00e9xico para la exportaci\u00f3n de frutas y verduras, por ejemplo, es Estados Unidos. En 2024 se vendieron productos agr\u00edcolas mexicanos por un valor de US$ 46.000 millones, seg\u00fan datos del Departamento de Agricultura de los Estados Unidos (USDA).<\/p>\n<p>En 2023, M\u00e9xico se posicion\u00f3 como el s\u00e9ptimo mayor productor de autos del mundo, con la fabricaci\u00f3n de 3,5 millones al a\u00f1o. El 76% de estos autos se exportaron a Estados Unidos.<\/p>\n<p>Ese a\u00f1o, la principal venta de M\u00e9xico a Estados Unidos fue de partes y accesorios para veh\u00edculos con un valor de US$ 35.979 millones.<\/p>\n<p>M\u00e9xico export\u00f3 a EE.UU. en 2024 productos por un valor de US$ 469.603 millones; en tanto que Estados Unidos compr\u00f3 bienes y servicios a M\u00e9xico por un valor de US$ 231.680 millones, seg\u00fan cifras de la Secretar\u00eda de Econom\u00eda mexicana.<\/p>\n<p>Francisco Gonz\u00e1lez, presidente de la Industria Nacional de Autopartes, advierte sobre el riesgo para la integraci\u00f3n de la regi\u00f3n: \u201cM\u00e9xico exporta el 43% de las piezas importadas que tiene Estados Unidos en la manufactura de los autom\u00f3viles all\u00e1 y nosotros tenemos un 74% de las piezas que importamos de Estados Unidos. Es un mercado demasiado interrelacionado\u201d.<\/p>\n<p>M\u00e9xico tiene vigentes 14 tratados de Libre Comercio con 52 pa\u00edses, 30 acuerdos para la Promoci\u00f3n y Protecci\u00f3n Rec\u00edproca de las Inversiones con 31 pa\u00edses o regiones administrativas y nueve acuerdos de alcance limitado, seg\u00fan el Gobierno.<\/p>\n<p>Sin embargo, EE.UU. concentra 65% del flujo comercial mexicano, le sigue con el 22% Asia, 8% la Uni\u00f3n Europea y 4% Latinoam\u00e9rica, de acuerdo con datos del Banco de M\u00e9xico publicados por el Instituto Mexicano para la Competitividad (IMCO).<\/p>\n<p>En 2022, el intercambio comercial de M\u00e9xico con el resto del mundo fue de casi US$ 1. 2 billones, de los cuales con EE.UU. fue de US$ 700.000 millones, poco m\u00e1s de la mitad para un solo pa\u00eds, seg\u00fan datos del IMCO y la Secretar\u00eda de Econom\u00eda.<\/p>\n<p>Sof\u00eda Ram\u00edrez, directora de la organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, destac\u00f3 que, en caso de prosperar la imposici\u00f3n de los aranceles, \u201cdel lado de la producci\u00f3n, sin duda nos hace perder competitividad debido a que los aranceles que nos ponen, de entrada, hacen que seamos menos competitivos en t\u00e9rminos de precio. Por supuesto, M\u00e9xico necesita una nueva energ\u00eda econ\u00f3mica\u201d.<\/p>\n<p>Ram\u00edrez sugiere que M\u00e9xico debe actuar con prudencia y que, aunque el Gobierno de Sheinbaum hace bien en esperar, \u201cyo sugerir\u00eda que no esperara demasiado\u201d y perfile cu\u00e1les van a ser los sectores o las industrias sobre las cuales se piensa poner aranceles retaliatorios o de castigo.<\/p>\n<p>\u201cJustamente para que empiece a haber presi\u00f3n para el Gobierno estadounidense y entonces, como ocurri\u00f3 en el caso de los autom\u00f3viles, pues se levanten las medidas arancelarias\u201d, explica Ram\u00edrez.<\/p>\n<p>El presidente de Estados Unidos, Donald Trump, otorg\u00f3 a M\u00e9xico y Canad\u00e1 una exenci\u00f3n de un mes sobre los aranceles automotrices, confirm\u00f3 la Casa Blanca este mi\u00e9rcoles, esto despu\u00e9s de que los tres grandes fabricantes de autom\u00f3viles de EE.UU. \u2013Stellantis, Ford y General Motors\u2013 lo solicitaran al Gobierno.<\/p>\n<p>\u00bfQu\u00e9 pasar\u00e1 con la econom\u00eda en M\u00e9xico si se imponen los aranceles?<\/p>\n<p>Las medidas arancelarias han generado incertidumbre econ\u00f3mica. Sof\u00eda Ram\u00edrez, directora de la organizaci\u00f3n M\u00e9xico \u00bfC\u00f3mo vamos?, advierte de que los aranceles podr\u00edan causar una contracci\u00f3n de entre \u201c1,5 y 2,3 puntos porcentuales del PIB\u201d de M\u00e9xico, aunque el mercado espera que sean temporales. En 2023, el PIB mexicano fue de unos US$ 1.7 billones seg\u00fan cifras del Banco Mundial.<\/p>\n<p>Si los aranceles entran en efecto y se mantienen, las afectaciones podr\u00edan ser graves, detalla Ram\u00edrez, pues podr\u00edan causar estanflaci\u00f3n en M\u00e9xico.<\/p>\n<p>La estanflaci\u00f3n \u2013combinaci\u00f3n de los t\u00e9rminos estancamiento e inflaci\u00f3n\u2013 se da cuando hay una alta inflaci\u00f3n y un estancamiento en el crecimiento econ\u00f3mico.<\/p>\n<p>Gonz\u00e1lez ilustra la incertidumbre con una met\u00e1fora clim\u00e1tica: \u201cSi esto fuera un pron\u00f3stico de tiempo, tendr\u00edamos muchas tormentas por entrar. No sabemos cu\u00e1nta agua y aire traen. No sabemos el impacto concretamente de los aranceles ni cu\u00e1nto tiempo vayan a permanecer. Lo que s\u00ed puedo decir es que entre m\u00e1s tiempo resulte, m\u00e1s catastr\u00f3fico\u201d.<\/p>\n<p>Guajardo, adem\u00e1s, subraya el peligro de lo que considera es una renegociaci\u00f3n anticipada del T-MEC: \u201cClaramente, nos est\u00e1 diciendo que la renegociaci\u00f3n ya empez\u00f3. Lo que tenemos que hacer M\u00e9xico y Canad\u00e1 es que no sea de un solo lado y que solo est\u00e9 exprimiendo como concesiones de M\u00e9xico y Canad\u00e1 sin poner absolutamente nada en la mesa\u201d.<\/p>\n<p>Guajardo resalta tambi\u00e9n que Donald Trump se enfrentar\u00e1 a elecciones intermedias en 2026 en Estados Unidos. \u201cHay mucho que perder, pero hay mucho que perder para todos y no se nos olvide que Trump va a una elecci\u00f3n intermedia a la cual no puede llegar con inflaci\u00f3n y con p\u00e9rdidas de empleos en Estados Unidos\u201d.<\/p>\n<p><em>Con informaci\u00f3n de Gabriela Fr\u00edas, Mario Gonz\u00e1lez y Valeria Le\u00f3n.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico logr\u00f3 este jueves un mes m\u00e1s sin que Estados Unidos imponga aranceles a sus productos. Tras una llamada entre la presidenta mexicana, Claudia Sheinbaum, y el mandatario estadounidense, Donald Trump, se acord\u00f3 que por el momento no entrar\u00e1n en vigor los aranceles de 25% a los productos provenientes de M\u00e9xico que est\u00e9n dentro del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459618","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico logr\u00f3 este jueves un mes m\u00e1s sin que Estados Unidos imponga aranceles a sus productos. Tras una llamada entre la presidenta mexicana, Claudia Sheinbaum, y el mandatario estadounidense, Donald Trump, se acord\u00f3 que por el momento no entrar\u00e1n en vigor los aranceles de 25% a los productos provenientes de M\u00e9xico que est\u00e9n dentro del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-07T13:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?\",\"datePublished\":\"2025-03-07T13:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\"},\"wordCount\":1346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\",\"name\":\"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-07T13:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias","og_description":"M\u00e9xico logr\u00f3 este jueves un mes m\u00e1s sin que Estados Unidos imponga aranceles a sus productos. Tras una llamada entre la presidenta mexicana, Claudia Sheinbaum, y el mandatario estadounidense, Donald Trump, se acord\u00f3 que por el momento no entrar\u00e1n en vigor los aranceles de 25% a los productos provenientes de M\u00e9xico que est\u00e9n dentro del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-07T13:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?","datePublished":"2025-03-07T13:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/"},"wordCount":1346,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","name":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-07T13:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPuede M\u00e9xico reducir su dependencia comercial de EE.UU.?","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/07\/dependencia-comercial-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-07T13:03:44Z","datePublished":"2025-03-07T13:03:44Z","dateModified":"2025-03-07T13:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPuede M\\u00e9xico reducir su dependencia comercial de EE.UU.?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/07\\\/dependencia-comercial-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/07\\\/dependencia-comercial-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-07T13:03:44Z\",\"datePublished\":\"2025-03-07T13:03:44Z\",\"dateModified\":\"2025-03-07T13:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465009,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/07\/31\/trump-sheinbaum-acuerdo-aranceles-90-dias-trax\/","url_meta":{"origin":1459618,"position":0},"title":"Trump y Sheinbaum anuncian un acuerdo para suspender el aumento de aranceles a M\u00e9xico por 90 d\u00edas","author":"","date":"julio 31, 2025","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 este jueves la extensi\u00f3n de los aranceles vigentes con M\u00e9xico, el principal socio comercial de Estados Unidos, y la suspensi\u00f3n de los aranceles que deb\u00edan entrar en vigor el viernes. Minutos despu\u00e9s, la presidenta de M\u00e9xico, Claudia Sheinbaum, confirm\u00f3 el acuerdo en una publicaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465026,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/01\/aranceles-comercio-trump-fecha-limite-trax\/","url_meta":{"origin":1459618,"position":1},"title":"Trump acaba de revelar su nuevo plan arancelario. Estos son los puntos principales","author":"","date":"agosto 1, 2025","format":false,"excerpt":"El presidente Donald Trump acaba de imponer nuevos aranceles para todos los pa\u00edses del mundo, consolidando su ruptura extrema con la pol\u00edtica comercial de larga data de Estados Unidos.Se prev\u00e9 que aumenten los aranceles sobre la gran mayor\u00eda de los bienes que importa Estados Unidos, incluso los de los pocos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455773,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/12\/mexico-aranceles-eeuu-trump-orix\/","url_meta":{"origin":1459618,"position":2},"title":"M\u00e9xico podr\u00eda responder rec\u00edprocamente a los aranceles anunciados en campa\u00f1a por Trump; se advierte de \u201ccosto gigante\u201d para EE.UU.","author":"","date":"noviembre 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e9xico podr\u00eda responder rec\u00edprocamente si Donald Trump cumple su propuesta de campa\u00f1a de imponer un arancel generalizado de 25% a las importaciones de productos mexicanos cuando asuma su segundo mandato como presidente de Estados Unidos, dijo este lunes el secretario de Econom\u00eda, Marcelo Ebrard.\u201cSi t\u00fa me aplicas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465008,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/07\/31\/cuantos-acuerdos-comerciales-cerro-trump-anunciarse-trax\/","url_meta":{"origin":1459618,"position":3},"title":"\u00bfCu\u00e1ntos acuerdos comerciales ha cerrado Trump y cu\u00e1les podr\u00edan anunciarse hoy?","author":"","date":"julio 31, 2025","format":false,"excerpt":"El presidente Donald Trump y miembros de su Gobierno prometieron concretar una serie de acuerdos comerciales tras pausar los aranceles \u201crec\u00edprocos\u201d en abril. Desde entonces, solo se han anunciado unos pocos, de los cuales solo dos han sido finalizados. Sobre muchos de los acuerdos se conocen pocos detalles, m\u00e1s all\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460794,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/03\/tabla-aranceles-trump-pais-orix\/","url_meta":{"origin":1459618,"position":4},"title":"As\u00ed queda la tabla de aranceles de Trump para cada pa\u00eds: qui\u00e9nes pagar\u00e1n m\u00e1s y qui\u00e9nes menos","author":"","date":"abril 3, 2025","format":false,"excerpt":"Donald Trump impuso el mi\u00e9rcoles aranceles globales a las importaciones de bienes hacia Estados Unidos, lanzando una hist\u00f3rica guerra comercial.Si bien todos los pa\u00edses del mundo se ver\u00e1n afectados por un gravamen base del 10% a los productos, m\u00e1s de 60 Estados o bloques comerciales se enfrentar\u00e1n a aranceles m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464417,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/07\/10\/aranceles-canada-20-por-ciento-amenaza-trump-trax\/","url_meta":{"origin":1459618,"position":5},"title":"Trump amenaza con un arancel del 35 % a productos importados desde Canad\u00e1, mientras que otras naciones pagar\u00e1n hasta un 20 %","author":"","date":"julio 10, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, amenaz\u00f3 este jueves por la noche con imponer un arancel del 35 % a los productos importados desde Canad\u00e1, una escalada dram\u00e1tica en la intermitente guerra comercial con su vecino del norte y uno de sus socios comerciales m\u00e1s importantes.Y, en una entrevista aparte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459618"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459618\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}