{"id":1459707,"date":"2025-03-09T20:03:48","date_gmt":"2025-03-10T03:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/"},"modified":"2025-03-09T20:03:48","modified_gmt":"2025-03-10T03:03:48","slug":"suben-recompensa-alias-fito-ecuador-millon-dolares-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","title":{"rendered":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds"},"content":{"rendered":"<p>El Ministerio del Interior de Ecuador inform\u00f3 este domingo que subi\u00f3 a U$ 1 mill\u00f3n el monto de la recompensa para quien proporcione informaci\u00f3n sobre el paradero de Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la banda delictiva de Los Choneros y el pr\u00f3fugo m\u00e1s buscado de Ecuador desde enero de 2024 cuando se agrav\u00f3 la crisis de seguridad en el pa\u00eds y el Gobierno decret\u00f3 el estado de conflicto interno armado.<\/p>\n<p>\u201cUn mill\u00f3n de d\u00f3lares para quien proporcione informaci\u00f3n sobre Adolfo Mac\u00edas, alias \u2018Fito\u2019. Llama al 1-800 (DELITO) 335486 o al 331. Se garantiza absoluta reserva\u201d, precis\u00f3 el Ministerio del Interior en un anuncio publicado en sus cuentas de redes sociales que est\u00e1 acompa\u00f1ado de una fotograf\u00eda de Fito y letras rojas que se\u00f1alan \u201cse busca\u201d.<\/p>\n<p>En enero de 2024, el Ministerio del Interior y la Polic\u00eda ofrec\u00edan una recompensa por U$ 100.000. M\u00e1s de un a\u00f1o despu\u00e9s el Gobierno refuerza la b\u00fasqueda del l\u00edder de Los Choneros y sube su oferta a quien proporcione informaci\u00f3n valiosa. Esto ocurre tres d\u00edas despu\u00e9s de que se registr\u00f3 un ataque armado en el sector de Nueva Prosperina en Guayaquil que dej\u00f3 22 muertos y 6 heridos.<\/p>\n<p>Las autoridades ecuatorianas confirmaron en enero de 2024 que Fito se fug\u00f3 de la c\u00e1rcel regional de Guayaquil, donde cumpl\u00eda una condena de 34 a\u00f1os por delitos que incluyen homicidio y tr\u00e1fico de drogas, sin que hasta el momento hayan identificado la fecha exacta en que evadi\u00f3 los controles penitenciarios.<\/p>\n<p>La fuga del l\u00edder de Los Choneros desat\u00f3 una ola de violencia en Ecuador que deriv\u00f3, en enero de ese a\u00f1o, a que el presidente Noboa declarara un conflicto armado interno en el pa\u00eds por grave conmoci\u00f3n interna y emprendi\u00f3 una lucha contra Los Choneros y otras 21 bandas criminales que calific\u00f3 como \u201cterroristas\u201d.<\/p>\n<p>Interpol emiti\u00f3 en julio 2024 una ficha roja para la b\u00fasqueda y captura de Jos\u00e9 Adolfo Mac\u00edas. La ficha roja de Interpol ampl\u00eda la b\u00fasqueda por alias \u201cFito\u201d, de 44 a\u00f1os, a 196 pa\u00edses, seg\u00fan la polic\u00eda ecuatoriana. Hasta el momento, se desconoce su paradero.<\/p>\n<p>En febrero de 2024, el Departamento del Tesoro de Estados Unidos sancion\u00f3 a la organizaci\u00f3n de Los Choneros y a su l\u00edder Fito por sus actividades de narcotr\u00e1fico y violencia en Ecuador y en todo el continente. Las sanciones, emitidas a trav\u00e9s de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), consisten en bloquear las propiedades vinculadas con los Choneros o con Mac\u00edas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio del Interior de Ecuador inform\u00f3 este domingo que subi\u00f3 a U$ 1 mill\u00f3n el monto de la recompensa para quien proporcione informaci\u00f3n sobre el paradero de Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la banda delictiva de Los Choneros y el pr\u00f3fugo m\u00e1s buscado de Ecuador desde enero de 2024 cuando se agrav\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459707","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &quot;Fito&quot;, el m\u00e1s buscado del pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &quot;Fito&quot;, el m\u00e1s buscado del pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Ministerio del Interior de Ecuador inform\u00f3 este domingo que subi\u00f3 a U$ 1 mill\u00f3n el monto de la recompensa para quien proporcione informaci\u00f3n sobre el paradero de Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la banda delictiva de Los Choneros y el pr\u00f3fugo m\u00e1s buscado de Ecuador desde enero de 2024 cuando se agrav\u00f3 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T03:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds\",\"datePublished\":\"2025-03-10T03:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\",\"name\":\"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias \\\"Fito\\\", el m\u00e1s buscado del pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-10T03:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias \"Fito\", el m\u00e1s buscado del pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias \"Fito\", el m\u00e1s buscado del pa\u00eds - Noticias","og_description":"El Ministerio del Interior de Ecuador inform\u00f3 este domingo que subi\u00f3 a U$ 1 mill\u00f3n el monto de la recompensa para quien proporcione informaci\u00f3n sobre el paradero de Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la banda delictiva de Los Choneros y el pr\u00f3fugo m\u00e1s buscado de Ecuador desde enero de 2024 cuando se agrav\u00f3 la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-10T03:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/"},"author":{"name":"","@id":""},"headline":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds","datePublished":"2025-03-10T03:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","name":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias \"Fito\", el m\u00e1s buscado del pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-10T03:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobierno de Ecuador sube a U$ 1 mill\u00f3n la recompensa por informaci\u00f3n relacionada a alias &#171;Fito&#187;, el m\u00e1s buscado del pa\u00eds","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/09\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-10T03:03:48Z","datePublished":"2025-03-10T03:03:48Z","dateModified":"2025-03-10T03:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobierno de Ecuador sube a U$ 1 mill\\u00f3n la recompensa por informaci\\u00f3n relacionada a alias &#171;Fito&#187;, el m\\u00e1s buscado del pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/09\\\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/09\\\/suben-recompensa-alias-fito-ecuador-millon-dolares-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-10T03:03:48Z\",\"datePublished\":\"2025-03-10T03:03:48Z\",\"dateModified\":\"2025-03-10T03:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460754,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/02\/alias-fito-eeuu-lider-ecuafor-drogas-armas-orix\/","url_meta":{"origin":1459707,"position":0},"title":"Acusan en EE.UU. a alias &#171;Fito&#187;, l\u00edder de violenta banda ecuatoriana, por cargos de drogas y armas","author":"","date":"abril 2, 2025","format":false,"excerpt":"Jos\u00e9 Adolfo Mac\u00edas Villamar, alias \u201cFito\u201d, l\u00edder de una de las bandas delictivas m\u00e1s violentas de Ecuador, ha sido acusado en Estados Unidos de cargos relacionados con drogas y armas.El jefe de la organizaci\u00f3n de narcotr\u00e1fico de Los Choneros enfrenta en un tribunal federal de Brooklyn, en ausencia, acusaciones por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449417,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/05\/12\/argentina-expulsa-personas-vinculadas-fito-profugo-orix\/","url_meta":{"origin":1459707,"position":1},"title":"Argentina expulsa a dos personas presuntamente vinculadas a alias &#171;Fito&#187;, el pr\u00f3fugo m\u00e1s buscado de Ecuador","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- Argentina expuls\u00f3 hacia Ecuador a dos personas por presuntamente estar vinculadas directamente con Jos\u00e9 Adolfo Mac\u00edas Villamar, alias \u201cFito\u201d, el l\u00edder de la banda criminal Los Choneros y considerado como el pr\u00f3fugo m\u00e1s buscado en territorio ecuatoriano tras fugarse de una prisi\u00f3n en enero.En un comunicado conjunto, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463987,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/26\/asi-capturaron-alias-fito-ecuador-orix\/","url_meta":{"origin":1459707,"position":2},"title":"En una lujosa casa que ocultaba un b\u00fanker capturaron a alias &#171;Fito&#187;. \u00bfC\u00f3mo localizaron al hombre m\u00e1s buscado de Ecuador?","author":"","date":"junio 26, 2025","format":false,"excerpt":"La Polic\u00eda Nacional y las Fuerzas Armadas de Ecuador llevaban casi 18 meses intentando localizar a Adolfo Mac\u00edas, alias \u201cFito\u201d, quien se fug\u00f3 de la C\u00e1rcel Regional de Guayaquil en enero de 2024 y se convirti\u00f3 en el hombre m\u00e1s buscado de Ecuador dentro y fuera de sus fronteras.El l\u00edder\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444133,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/19\/detienen-a-familiares-de-fito-macias-el-profugo-mas-buscado-de-ecuador-en-cordoba-argentina\/","url_meta":{"origin":1459707,"position":3},"title":"Detienen a familiares de \u201dFito\u201d Mac\u00edas, el pr\u00f3fugo m\u00e1s buscado de Ecuador, en C\u00f3rdoba, Argentina","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) - - Las autoridades de Argentina detuvieron la noche del jueves a quienes identificaron como la esposa e hijos de Jos\u00e9 Adolfo Mac\u00edas Villamar, alias Fito, el pr\u00f3fugo m\u00e1s buscado de Ecuador, en un barrio privado de C\u00f3rdoba, Argentina, confirm\u00f3 a CNN este viernes una alta fuente del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444124,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/19\/las-autoridades-de-argentina-detienen-a-individuos-identificados-como-familiares-defito-macias-el-profugo-mas-buscado-de-ecuador-en-un-barrio-privado-de-cordoba\/","url_meta":{"origin":1459707,"position":4},"title":"Las autoridades de Argentina detienen a individuos identificados como familiares de&#187;Fito&#187; Mac\u00edas, el pr\u00f3fugo m\u00e1s buscado de Ecuador, en un barrio privado de C\u00f3rdoba","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) - - Las autoridades de Argentina detuvieron la noche del jueves a quienes identificaron como la esposa e hijos de Jos\u00e9 Adolfo Mac\u00edas Villamar, alias Fito, el pr\u00f3fugo m\u00e1s buscado de Ecuador, en un barrio privado de C\u00f3rdoba, Argentina, confirm\u00f3 a CNN este viernes una alta fuente del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463983,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/26\/delitos-fito-ecuador-choneros-orix\/","url_meta":{"origin":1459707,"position":5},"title":"\u00bfCu\u00e1les son los delitos por los que condenaron a Fito y por qu\u00e9 lo sancion\u00f3 Estados Unidos?","author":"","date":"junio 26, 2025","format":false,"excerpt":"Este mi\u00e9rcoles, Adolfo Mac\u00edas, alias \u201cFito\u201d, l\u00edder de la temida banda delictiva Los Choneros y uno de los hombres m\u00e1s buscados de Ecuador, fue capturado. Fue encontrado escondido en un b\u00fanker en la localidad de Manta. \u00bfDe qu\u00e9 cr\u00edmenes lo condenaron?En enero de 2024, Fito se fug\u00f3 de la C\u00e1rcel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459707"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459707\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}