{"id":1459714,"date":"2025-03-10T03:03:41","date_gmt":"2025-03-10T10:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/"},"modified":"2025-03-10T03:03:41","modified_gmt":"2025-03-10T10:03:41","slug":"principe-federico-luxemburgo-muere-enfermedad-rara-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","title":{"rendered":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara"},"content":{"rendered":"<p>El pr\u00edncipe Federico de Luxemburgo muri\u00f3 tras una larga batalla contra un raro trastorno gen\u00e9tico conocido como enfermedad mitocondrial POLG.<\/p>\n<p>Falleci\u00f3 el 1 de marzo en Par\u00eds, anunci\u00f3 su familia en el sitio web de la Fundaci\u00f3n POLG, que Frederik inici\u00f3 en 2022.<\/p>\n<p>\u201cCon gran pesar, mi esposa y yo queremos informarles del fallecimiento de nuestro hijo, el fundador y director creativo de la Fundaci\u00f3n POLG, Frederik\u201d, escribi\u00f3 su padre, el pr\u00edncipe Roberto de Luxemburgo.<\/p>\n<p>La fundaci\u00f3n describe la POLG como un \u201ctrastorno mitocondrial gen\u00e9tico que priva de energ\u00eda a las c\u00e9lulas del cuerpo, lo que a su vez provoca disfunci\u00f3n y falla progresiva de m\u00faltiples \u00f3rganos\u201d.<\/p>\n<p>Dijo que la enfermedad no tiene tratamiento ni cura.<\/p>\n<p>\u201cFrederik y la Fundaci\u00f3n POLG\u2026 est\u00e1n comprometidos a encontrar terapias y una cura para evitar que otros pacientes sufran lo que Frederik y nuestra familia han padecido\u201d, escribi\u00f3 su padre.<\/p>\n<p>El pr\u00edncipe Federico muri\u00f3 un d\u00eda despu\u00e9s del D\u00eda de las Enfermedades Raras. Ten\u00eda poco m\u00e1s de 20 a\u00f1os.<\/p>\n<p>A pesar de su condici\u00f3n, \u201cencontr\u00f3 la fuerza y \u200b\u200bel coraje para decir adi\u00f3s a cada uno de nosotros por turno: a su hermano, Alexander; a su hermana, Charlotte; a m\u00ed; a sus tres primos, Charly, Louis y Donall; a su cu\u00f1ado, Mansour; y, finalmente, a su t\u00eda Charlotte y a su t\u00edo Mark\u201d, escribi\u00f3 el pr\u00edncipe Roberto.<\/p>\n<p>Frederik era \u201cdisciplinado y organizado m\u00e1s all\u00e1 de lo cre\u00edble\u201d, afirma el comunicado.<\/p>\n<p>\u201cEl viernes [el d\u00eda antes de morir], su alarma de Duolingo y de ejercicios en italiano son\u00f3 como cualquier otro d\u00eda\u201d.<\/p>\n<p>Al pr\u00edncipe Federico le diagnosticaron POLG a los 14 a\u00f1os, una enfermedad que provoca una amplia gama de s\u00edntomas y afecta a muchos sistemas org\u00e1nicos diferentes, lo que hace que sea muy dif\u00edcil de diagnosticar y no tiene tratamiento ni cura, seg\u00fan el comunicado.<\/p>\n<p>\u201cComo ocurre con 300 millones de personas como Frederik en todo el mundo, estas enfermedades suelen ser dif\u00edciles de reconocer incluso para los m\u00e9dicos, y las familias de los pacientes pueden no saber nunca de qu\u00e9 padecen, ya que es posible que solo se las identifique muy tarde en su progresi\u00f3n\u201d, escribi\u00f3 su padre.<\/p>\n<p>\u201cSe podr\u00eda comparar con tener una bater\u00eda defectuosa que nunca se recarga por completo, est\u00e1 en un estado constante de agotamiento y eventualmente pierde energ\u00eda\u201d, escribi\u00f3 el pr\u00edncipe Robert.<\/p>\n<p>El pr\u00edncipe Federico hab\u00eda expresado su gratitud por haber padecido esta enfermedad durante a\u00f1os. Y recientemente se supo que una vez le dijo a un amigo cercano (desconocido para la familia de Federico hasta ahora): \u201cMe alegro de ser yo quien naci\u00f3 con esta enfermedad. Aunque muera por ella\u2026 y aunque mis padres no tengan tiempo para salvarme, s\u00e9 que podr\u00e1n salvar a otros ni\u00f1os\u201d.<\/p>\n<p>\u201cAunque el pr\u00edncipe Federico siempre dej\u00f3 muy claro que no quer\u00eda que esta terrible enfermedad lo definiera, se dedic\u00f3 a difundir la conciencia sobre esta rara enfermedad\u201d, afirma el comunicado, lo que incluye participar en ensayos m\u00e9dicos \u201ccon el objetivo de encontrar tratamientos y, tal vez, formas de reutilizar mol\u00e9culas para ayudar a los pacientes con su condici\u00f3n\u201d.<\/p>\n<p>\u201cFrederik falleci\u00f3 el 1 de marzo de 2025 en Par\u00eds, Francia, la Ciudad de las Luces. Una luz se apag\u00f3, pero quedan muchas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00edncipe Federico de Luxemburgo muri\u00f3 tras una larga batalla contra un raro trastorno gen\u00e9tico conocido como enfermedad mitocondrial POLG. Falleci\u00f3 el 1 de marzo en Par\u00eds, anunci\u00f3 su familia en el sitio web de la Fundaci\u00f3n POLG, que Frederik inici\u00f3 en 2022. \u201cCon gran pesar, mi esposa y yo queremos informarles del fallecimiento de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459714","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias\" \/>\n<meta property=\"og:description\" content=\"El pr\u00edncipe Federico de Luxemburgo muri\u00f3 tras una larga batalla contra un raro trastorno gen\u00e9tico conocido como enfermedad mitocondrial POLG. Falleci\u00f3 el 1 de marzo en Par\u00eds, anunci\u00f3 su familia en el sitio web de la Fundaci\u00f3n POLG, que Frederik inici\u00f3 en 2022. \u201cCon gran pesar, mi esposa y yo queremos informarles del fallecimiento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T10:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara\",\"datePublished\":\"2025-03-10T10:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\"},\"wordCount\":607,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\",\"name\":\"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-10T10:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias","og_description":"El pr\u00edncipe Federico de Luxemburgo muri\u00f3 tras una larga batalla contra un raro trastorno gen\u00e9tico conocido como enfermedad mitocondrial POLG. Falleci\u00f3 el 1 de marzo en Par\u00eds, anunci\u00f3 su familia en el sitio web de la Fundaci\u00f3n POLG, que Frederik inici\u00f3 en 2022. \u201cCon gran pesar, mi esposa y yo queremos informarles del fallecimiento de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-10T10:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/"},"author":{"name":"","@id":""},"headline":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara","datePublished":"2025-03-10T10:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/"},"wordCount":607,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","name":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-10T10:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-10T10:03:41Z","datePublished":"2025-03-10T10:03:41Z","dateModified":"2025-03-10T10:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El pr\\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/10\\\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/10\\\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-10T10:03:41Z\",\"datePublished\":\"2025-03-10T10:03:41Z\",\"dateModified\":\"2025-03-10T10:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1443679,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/el-principe-heredero-frederik-se-convertira-en-rey-de-dinamarca-tras-la-abdicacion-de-la-reina\/","url_meta":{"origin":1459714,"position":0},"title":"El pr\u00edncipe heredero Frederik se convertir\u00e1 en rey de Dinamarca tras la abdicaci\u00f3n de la reina","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) -- Para muchos en Dinamarca, la reina Margarita II es la \u00fanica monarca que conocieron. Pero este domingo comenzar\u00e1 una nueva era cuando entregue el poder a su hijo, el pr\u00edncipe heredero Frederik .La miembro de la realeza de 83 a\u00f1os, la monarca con el reinado m\u00e1s largo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443627,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/13\/quien-es-el-principe-heredero-federico-que-pronto-sera-el-nuevo-rey-de-dinamarca\/","url_meta":{"origin":1459714,"position":1},"title":"\u00bfQui\u00e9n es el pr\u00edncipe heredero Federico, que pronto ser\u00e1 el nuevo rey de Dinamarca?","author":"","date":"enero 13, 2024","format":false,"excerpt":"(CNN) -- Desde los tres a\u00f1os se le conoce como pr\u00edncipe heredero de Dinamarca, pero el domingo saldr\u00e1 del Palacio de Christiansborg de Copenhague como el rey Federico X, soberano de la monarqu\u00eda m\u00e1s antigua de Europa.La transici\u00f3n real en Dinamarca se desencaden\u00f3 hace apenas unas semanas con el anuncio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443628,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/13\/quien-es-el-principe-heredero-federico-que-pronto-sera-el-nuevo-rey-de-dinamarca-2\/","url_meta":{"origin":1459714,"position":2},"title":"\u00bfQui\u00e9n es el pr\u00edncipe heredero Federico, que pronto ser\u00e1 el nuevo rey de Dinamarca?","author":"","date":"enero 13, 2024","format":false,"excerpt":"(CNN) -- Desde los tres a\u00f1os se le conoce como pr\u00edncipe heredero de Dinamarca, pero el domingo saldr\u00e1 del Palacio de Christiansborg de Copenhague como el rey Federico X, soberano de la monarqu\u00eda m\u00e1s antigua de Europa.La transici\u00f3n real en Dinamarca se desencaden\u00f3 hace apenas unas semanas con el anuncio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443694,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/14\/quien-es-federico-x-nuevo-rey-de-dinamarca-tras-la-abdicacion-de-su-madre-margarita-ii\/","url_meta":{"origin":1459714,"position":3},"title":"\u00bfQui\u00e9n es Federico X, nuevo rey de Dinamarca tras la abdicaci\u00f3n de su madre Margarita II?","author":"","date":"enero 14, 2024","format":false,"excerpt":"(CNN) -- Desde los tres a\u00f1os se le conoce como pr\u00edncipe heredero de Dinamarca, pero este domingo sali\u00f3 del Palacio de Christiansborg de Copenhague convertido en el rey Federico X, soberano de la monarqu\u00eda m\u00e1s antigua de Europa.La transici\u00f3n real en Dinamarca se desencaden\u00f3 hace apenas unas semanas con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451655,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/08\/07\/colin-farrell-lanza-fundacion-honor-hijo-padece-raro-trastorno-neurogenetico-trax\/","url_meta":{"origin":1459714,"position":4},"title":"Colin Farrell lanza fundaci\u00f3n en honor a su hijo que padece un raro trastorno neurogen\u00e9tico","author":"","date":"agosto 7, 2024","format":false,"excerpt":"(CNN) -- Colin Farrell espera poder ayudar a familias como la suya.James, el hijo de 20 a\u00f1os de Farrell, padece el s\u00edndrome de Angelman, un raro trastorno neurogen\u00e9tico. Se lo diagnosticaron de ni\u00f1o, no habla y recibe atenci\u00f3n en su casa, seg\u00fan Farrell, que se habl\u00f3 por primera vez en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460123,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/19\/principe-harry-demanda-registros-inmigracion-trax\/","url_meta":{"origin":1459714,"position":5},"title":"Demanda sobre los registros de inmigraci\u00f3n del pr\u00edncipe Harry: publican documentos con grandes ediciones que revelan poco","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Los documentos revelados este martes en el caso de un grupo de expertos conservador contra el pr\u00edncipe Harry no difunden informaci\u00f3n sobre sus antecedentes de inmigraci\u00f3n.\u201cRevelar su estado exacto podr\u00eda exponerlo a un da\u00f1o razonablemente previsible en forma de acoso, as\u00ed como a contactos no deseados por parte de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459714"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459714\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}