{"id":1459764,"date":"2025-03-11T07:03:45","date_gmt":"2025-03-11T14:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/"},"modified":"2025-03-11T07:03:45","modified_gmt":"2025-03-11T14:03:45","slug":"economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","title":{"rendered":"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;"},"content":{"rendered":"<p>Mart\u00edn Piccato, analista financiero, se refiri\u00f3 a la actualidad econ\u00f3mica argentina y la negociaci\u00f3n del gobierno nacional con el FMI.<\/p>\n<p>En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201chay dos cosas muy importantes. Primero, cada dos a\u00f1os o tres a\u00f1os en la bolsa de Estados Unidos hay una correcci\u00f3n de aproximadamente del 10% de las acciones y eso no deber\u00eda asustar. Eso es estad\u00edstica pura. Son correcciones de mercado. Y lo segundo, es la incertidumbre que producen las pol\u00edticas del presidente Trump\u201d.<\/p>\n<p>En este sentido, se pregunt\u00f3 \u201csi ten\u00e9s acciones o ten\u00e9s bonos, \u00bfqu\u00e9 haces? Dec\u00eds yo no s\u00e9 cu\u00e1nto tiempo m\u00e1s va a bajar, porque el que est\u00e1 interviniendo el mercado con la palabra por ahora, porque un d\u00eda te pone el arancel y al otro d\u00eda te lo saca, no sabemos cu\u00e1nto tiempo m\u00e1s puede mantener, puede profundizar esta guerra comercial, que adem\u00e1s es asim\u00e9trica\u201d.<\/p>\n<p>El analista financiero asegur\u00f3 que el presidente de Estados Unidos \u201cest\u00e1 usando el factor econ\u00f3mico, el poder que tiene su pa\u00eds como una econom\u00eda abierta al mundo, porque Estados Unidos exporta el 17% de todo lo que produce, Alemania exporta el 50%, Noruega el 95%. O sea, si lo med\u00eds en funci\u00f3n del PBI de Estados Unidos, una econom\u00eda semicerrada, pero el tama\u00f1o de Estados Unidos es tan grande que cualquier movimiento produce estupor. <strong>Donald Trump est\u00e1 interviniendo en el mercado a trav\u00e9s de las palabras<\/strong>\u201d.<\/p>\n<p>Adem\u00e1s, remarc\u00f3 que \u201c<strong>el d\u00f3lar se est\u00e1 debilitando muy fuerte en el mundo<\/strong>. Hay mucho susto respecto a las acciones que ven\u00edan con un rally alcista muy grande, los bonos que ven\u00edan con un rally alcista muy grande, pero no miran, por ejemplo, que hay una intervenci\u00f3n para debilitar el d\u00f3lar. \u00c9l est\u00e1 haciendo una devaluaci\u00f3n competitiva, no devaluaci\u00f3n porque no est\u00e1 dirigido, pues el d\u00f3lar tiene el sistema flotante, como las grandes monedas del mundo, pero est\u00e1 haciendo una depreciaci\u00f3n competitiva\u201d.<\/p>\n<p>Sobre c\u00f3mo afecta esto a Argentina, el economista asegur\u00f3 que provoca \u201cun poco el ruido interno y otro poco el contagio externo\u201d.<\/p>\n<p>Consultado sobre el acuerdo con el FMI, afirm\u00f3 que <strong>\u201ces el \u00faltimo \u00edtem, seg\u00fan el presidente Milei, de las condiciones necesarias, pero no suficientes, condiciones necesarias para poder levantar el cepo. Si nosotros vamos a tener una econom\u00eda pro-exportadora y que requiere por eso mucha inversi\u00f3n, condici\u00f3n sine qua non es levantar el cepo. Y sin un acuerdo con el FMI, no hay posibilidad alguna de levantar el cepo\u201d<\/strong>.<\/p>\n<p>Al respecto, Mart\u00edn Piccato destac\u00f3 que \u201c<strong>eso los inversores, los que ponen guita en las acciones, lo est\u00e1n viendo con mucha preocupaci\u00f3n. Hoy sali\u00f3 el decreto, el DNU, que un poco detalla el acuerdo con el Fondo, y cuidado con la generaci\u00f3n de expectativas. Si bien el decreto no habla de la cantidad de dinero fresco que deber\u00eda ingresar, las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el propio gobierno que, por acci\u00f3n o por omisi\u00f3n, genera la expectativa de que van a ingresar fondos l\u00edquidos, por entre 15.000 y 20.000 millones. Resulta que ahora se habla de 8.000 millones\u201d<\/strong>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mart\u00edn Piccato, analista financiero, se refiri\u00f3 a la actualidad econ\u00f3mica argentina y la negociaci\u00f3n del gobierno nacional con el FMI. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201chay dos cosas muy importantes. Primero, cada dos a\u00f1os o tres a\u00f1os en la bolsa de Estados Unidos hay una correcci\u00f3n de aproximadamente del 10% de las acciones y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459764","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Economista asegura que &quot;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Economista asegura que &quot;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mart\u00edn Piccato, analista financiero, se refiri\u00f3 a la actualidad econ\u00f3mica argentina y la negociaci\u00f3n del gobierno nacional con el FMI. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201chay dos cosas muy importantes. Primero, cada dos a\u00f1os o tres a\u00f1os en la bolsa de Estados Unidos hay una correcci\u00f3n de aproximadamente del 10% de las acciones y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T14:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;\",\"datePublished\":\"2025-03-11T14:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\",\"name\":\"Economista asegura que \\\"las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-11T14:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Economista asegura que \"las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","og_locale":"es_ES","og_type":"article","og_title":"Economista asegura que \"las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno\" - Noticias","og_description":"Mart\u00edn Piccato, analista financiero, se refiri\u00f3 a la actualidad econ\u00f3mica argentina y la negociaci\u00f3n del gobierno nacional con el FMI. En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201chay dos cosas muy importantes. Primero, cada dos a\u00f1os o tres a\u00f1os en la bolsa de Estados Unidos hay una correcci\u00f3n de aproximadamente del 10% de las acciones y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","og_site_name":"Noticias","article_published_time":"2025-03-11T14:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/"},"author":{"name":"","@id":""},"headline":"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;","datePublished":"2025-03-11T14:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","url":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","name":"Economista asegura que \"las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-11T14:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Economista asegura que &#171;las especulaciones del mercado est\u00e1n muy por debajo de las expectativas que gener\u00f3 el gobierno&#187;","url":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/03\/11\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-11T14:03:45Z","datePublished":"2025-03-11T14:03:45Z","dateModified":"2025-03-11T14:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Economista asegura que &#171;las especulaciones del mercado est\\u00e1n muy por debajo de las expectativas que gener\\u00f3 el gobierno&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/11\\\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/03\\\/11\\\/economista-asegura-que-las-especulaciones-del-mercado-estan-muy-por-debajo-de-las-expectativas-que-genero-el-gobierno\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-11T14:03:45Z\",\"datePublished\":\"2025-03-11T14:03:45Z\",\"dateModified\":\"2025-03-11T14:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460588,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/29\/salvador-distefano-el-sistema-se-autorregula-tan-es-asi-que-si-vos-ves-los-precios-desaceleraron-su-crecimiento\/","url_meta":{"origin":1459764,"position":0},"title":"Salvador Distefano: &#171;El sistema se autorregula tan es as\u00ed que si vos ves los precios desaceleraron su crecimiento&#187;","author":"","date":"marzo 29, 2025","format":false,"excerpt":"En de Ida y Vuelta con Laura Di Marco indic\u00f3: \u201cEl tema es que la econom\u00eda argentina est\u00e1 en un circuito cerrado, o sea vos ten\u00e9s X cantidad de d\u00f3lares en la reserva y X cantidad de pesos en el mercado y despu\u00e9s ten\u00e9s pesos atrapados en plazo fijo, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460171,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/20\/diego-bossio-el-escandalo-usdlibra-dano-la-confianza-y-redujo-el-acceso-a-los-mercados-del-gobierno\/","url_meta":{"origin":1459764,"position":1},"title":"Diego Bossio: El esc\u00e1ndalo &#171;$Libra da\u00f1\u00f3 la confianza y redujo el acceso a los mercados&#187; del gobierno","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Diego Bossio, economista, exdiputado y socio Fundador Equilibra, visit\u00f3 los estudios de CNN Radio para analizar la situaci\u00f3n econ\u00f3mica y el acuerdo del gobierno con el FMI.En CNN Primera Ma\u00f1ana, afirm\u00f3 que la relaci\u00f3n de Argentina con el FMI es \u201cuna historia de encuentro y desencuentros. El Fondo Monetario es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463855,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/23\/la-reactivacion-de-creditos-hipotecarios-analizada-por-el-especialista-fernando-alvarez-de-celis\/","url_meta":{"origin":1459764,"position":2},"title":"La reactivaci\u00f3n de cr\u00e9ditos hipotecarios, analizada por el especialista Fernando \u00c1lvarez de Celis","author":"","date":"junio 23, 2025","format":false,"excerpt":"Fernando \u00c1lvarez de Celis, director de la Fundaci\u00f3n Tejido Urbano, visit\u00f3 los estudios de CNN Radio, donde analiz\u00f3 el escenario actual del mercado inmobiliario argentino y la incipiente reactivaci\u00f3n de los cr\u00e9ditos hipotecarios.En CNN Primera Ma\u00f1ana, afirm\u00f3 que la posibilidad de acceder a una vivienda propia contin\u00faa siendo un desaf\u00edo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460897,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/06\/luis-mogni-necesitamos-tener-un-canal-potente-y-necesitamos-mostrarlo-en-un-congreso\/","url_meta":{"origin":1459764,"position":3},"title":"Luis Mogni: &#171;Necesitamos tener un canal potente y necesitamos mostrarlo en un congreso&#187;","author":"","date":"abril 6, 2025","format":false,"excerpt":"Luis Mogni - Consultor en Gesti\u00f3n y Estrategia de Negocios, habl\u00f3 este domingo con CNN Radio sobre la tercera edici\u00f3n del Congreso de Distribuidores del Agro.En CNN Campo con Mart\u00edn Melo indic\u00f3: \u201cEs un espacio relacional donde logramos compartir experiencias y miradas para el futuro. Creo que este a\u00f1o es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459969,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/03\/15\/gustavo-lazari-este-gobierno-tecnicamente-se-esta-comportando-muy-bien-en-terminos-de-inflacion\/","url_meta":{"origin":1459764,"position":4},"title":"Gustavo Lazzari: &#171;Este gobierno t\u00e9cnicamente se est\u00e1 comportando muy bien en t\u00e9rminos de inflaci\u00f3n&#187;","author":"","date":"marzo 15, 2025","format":false,"excerpt":"Gustavo Lazzari, economista, habl\u00f3 este s\u00e1bado con CNN Radio sobre el panorama que tiene actualmente la inflaci\u00f3n en el pa\u00eds.En de Ida y Vuelta con Laura Di Marco indic\u00f3: \u201cEs una gran noticia que estemos discutiendo un precio como causante de la inflaci\u00f3n de un \u00edndice\u201d, dijo.\u201cCuando te dicen inflaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460876,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/05\/sergio-benestain-es-un-gobierno-que-cometio-un-error-que-es-muy-muy-importante-y-es-el-de-la-soberbia\/","url_meta":{"origin":1459764,"position":5},"title":"Sergio Berensztein: &#171;Es un Gobierno que cometi\u00f3 un error que es muy, muy importante y es el de la soberbia&#187;","author":"","date":"abril 5, 2025","format":false,"excerpt":"Sergio Berensztein, analista habl\u00f3 este s\u00e1bado con CNN Radio sobre los \u00faltimos acontecimientos pol\u00edticos que sucedieron en el pa\u00edsEn Dicen que dicen con Alberto Lotuf indic\u00f3: \u201cErrores no forzados, cometemos todos, como en todos los gobiernos, que es lo que est\u00e1 pasando en el mundo con la decisi\u00f3n de Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1459764"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1459764\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1459764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1459764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1459764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}