{"id":1465141,"date":"2025-08-05T08:03:51","date_gmt":"2025-08-05T15:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/"},"modified":"2025-08-05T08:03:51","modified_gmt":"2025-08-05T15:03:51","slug":"trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","title":{"rendered":"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados"},"content":{"rendered":"<p>El presidente Donald Trump dijo que su Gobierno est\u00e1 trabajando en el establecimiento de \u201creglas y regulaciones\u201d para las granjas que dependen de la mano de obra de trabajadores indocumentados.<\/p>\n<p>\u201cYo cuido a los granjeros. Amo a los granjeros. Son una parte muy importante de este pa\u00eds y no queremos hacer nada que los perjudique\u201d, dijo Trump en una entrevista telef\u00f3nica con CNBC.<\/p>\n<p>\u201cEstamos trabajando en eso, y vamos a anunciar reglas y regulaciones. Quiero decir, uno ve a un granjero con la misma persona trabajando para \u00e9l desde hace 20 a\u00f1os. Esa persona incluso paga impuestos y otras cosas\u201d, a\u00f1adi\u00f3 Trump, haciendo una distinci\u00f3n entre los inmigrantes indocumentados que trabajan arduamente en el campo y quienes cometen cr\u00edmenes violentos.<\/p>\n<p>El tema de los trabajadores agr\u00edcolas ha generado ciertas cr\u00edticas entre la base electoral de Trump, en momentos en que los votantes de MAGA presionan a su Gobierno para que mantenga la l\u00ednea dura contra los inmigrantes indocumentados. El mes pasado, el vicepresidente J. D. Vance dijo que la automatizaci\u00f3n es su \u201csoluci\u00f3n favorita\u201d a las necesidades de mano de obra en la agricultura y otras industrias, y reiter\u00f3 la postura del Gobierno de Trump de que no permitir\u00e1n una amnist\u00eda para los trabajadores indocumentados.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump dijo que su Gobierno est\u00e1 trabajando en el establecimiento de \u201creglas y regulaciones\u201d para las granjas que dependen de la mano de obra de trabajadores indocumentados. \u201cYo cuido a los granjeros. Amo a los granjeros. Son una parte muy importante de este pa\u00eds y no queremos hacer nada que los perjudique\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465141","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump dice que su Gobierno trabaja en &quot;reglas y regulaciones&quot; para trabajadores agr\u00edcolas indocumentados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump dice que su Gobierno trabaja en &quot;reglas y regulaciones&quot; para trabajadores agr\u00edcolas indocumentados - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump dijo que su Gobierno est\u00e1 trabajando en el establecimiento de \u201creglas y regulaciones\u201d para las granjas que dependen de la mano de obra de trabajadores indocumentados. \u201cYo cuido a los granjeros. Amo a los granjeros. Son una parte muy importante de este pa\u00eds y no queremos hacer nada que los perjudique\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-05T15:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados\",\"datePublished\":\"2025-08-05T15:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\"},\"wordCount\":248,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\",\"name\":\"Trump dice que su Gobierno trabaja en \\\"reglas y regulaciones\\\" para trabajadores agr\u00edcolas indocumentados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-05T15:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump dice que su Gobierno trabaja en \"reglas y regulaciones\" para trabajadores agr\u00edcolas indocumentados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump dice que su Gobierno trabaja en \"reglas y regulaciones\" para trabajadores agr\u00edcolas indocumentados - Noticias","og_description":"El presidente Donald Trump dijo que su Gobierno est\u00e1 trabajando en el establecimiento de \u201creglas y regulaciones\u201d para las granjas que dependen de la mano de obra de trabajadores indocumentados. \u201cYo cuido a los granjeros. Amo a los granjeros. Son una parte muy importante de este pa\u00eds y no queremos hacer nada que los perjudique\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-05T15:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/"},"author":{"name":"","@id":""},"headline":"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados","datePublished":"2025-08-05T15:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/"},"wordCount":248,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","name":"Trump dice que su Gobierno trabaja en \"reglas y regulaciones\" para trabajadores agr\u00edcolas indocumentados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-05T15:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\u00edcolas indocumentados","url":"http:\/\/noticiasya.com\/el-paso\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/08\/05\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-05T15:03:51Z","datePublished":"2025-08-05T15:03:51Z","dateModified":"2025-08-05T15:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump dice que su Gobierno trabaja en &#171;reglas y regulaciones&#187; para trabajadores agr\\u00edcolas indocumentados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/08\\\/05\\\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/08\\\/05\\\/trump-reglas-regulaciones-trabajadores-agricolas-indocumentados-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-05T15:03:51Z\",\"datePublished\":\"2025-08-05T15:03:51Z\",\"dateModified\":\"2025-08-05T15:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467020,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/01\/uscis-agiliza-visas-trabajadores-agricolas-orix\/","url_meta":{"origin":1465141,"position":0},"title":"EE.UU. agiliza el tr\u00e1mite de visas para trabajadores agr\u00edcolas, un sector fuertemente golpeado por la pol\u00edtica migratoria","author":"","date":"octubre 1, 2025","format":false,"excerpt":"El Departamento de Seguridad Nacional de EE.UU. anunci\u00f3 un cambio que agiliza el tr\u00e1mite de visado temporal para trabajadores agr\u00edcolas, al permitir a los empleadores presentar su solicitud sin esperar a que termine la revisi\u00f3n laboral del Departamento de Trabajo.La disposici\u00f3n, que entra en vigencia este jueves 2, implica que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464178,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/07\/03\/trump-preocupaciones-deportaciones-trabajadores-inmigrantes-trax\/","url_meta":{"origin":1465141,"position":1},"title":"La Casa Blanca intenta calmar las preocupaciones de la industria sobre las deportaciones de los trabajadores migrantes","author":"","date":"julio 3, 2025","format":false,"excerpt":"A medida que el Gobierno de Trump redobla sus esfuerzos en su plan de deportaciones, tras bastidores los altos funcionarios del Gobierno y el propio presidente han lidiado con las consecuencias de esa represi\u00f3n contra un segmento clave de la fuerza laboral: los trabajadores inmigrantes.El presidente Donald Trump ha dudado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461073,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/11\/trump-agricultores-granjeros-inmigrantes-trax\/","url_meta":{"origin":1465141,"position":2},"title":"Trump sobre los agricultores inmigrantes: &#171;Vamos a dejar que se queden por un tiempo&#187;","author":"","date":"abril 11, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, dijo que su Gobierno trabajar\u00e1 con los inmigrantes agricultores que est\u00e1n en el pa\u00eds ilegalmente y que si tienen \u201cfuertes recomendaciones para sus granjas\u201d, podr\u00e1n permanecer en Estados Unidos \u201cpor un tiempo\u201d.\u201cTambi\u00e9n vamos a trabajar con los agricultores, que si tienen fuertes recomendaciones para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456129,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/28\/doge-musk-ramaswamy-regulaciones-federales-trax\/","url_meta":{"origin":1465141,"position":3},"title":"Musk y Ramaswamy creen que tienen un nuevo poder para recortar las regulaciones federales. He aqu\u00ed por qu\u00e9 no es tan sencillo","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) -- Elon Musk y Vivek Ramaswamy pretenden apoyarse en dos recientes sentencias de la Corte Suprema de Justicia que, seg\u00fan ellos, facilitar\u00e1n la eliminaci\u00f3n de multitud de normativas federales.El d\u00fao, que el presidente electo Donald Trump escogi\u00f3 para dirigir el reci\u00e9n propuesto \"Departamento de Eficiencia Gubernamental\", conocido como DOGE\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463523,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/13\/ice-redadas-deportaciones-migrantes-trabajo-trax\/","url_meta":{"origin":1465141,"position":4},"title":"Los trabajadores migrantes de Estados Unidos tienen miedo de ir a trabajar, pero no pueden quedarse en casa","author":"","date":"junio 13, 2025","format":false,"excerpt":"En la madrugada del martes, agentes de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) persiguieron a trabajadores agr\u00edcolas a trav\u00e9s de un campo en Oxnard, California. Los agentes derribaron y retuvieron a los trabajadores entre filas de productos agr\u00edcolas, seg\u00fan se ve en un video de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465695,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/20\/california-redadas-caida-empleo-inmigracion-orix\/","url_meta":{"origin":1465141,"position":5},"title":"Como en la pandemia o en la Gran Recesi\u00f3n: as\u00ed impacta el miedo a las redadas de ICE en la ca\u00edda de empleos en California","author":"","date":"agosto 20, 2025","format":false,"excerpt":"El endurecimiento de las medidas de control migratorio del Gobierno de Donald Trump ha tenido un \u201cefecto disruptivo\u201d en la econom\u00eda de California, la cuarta mayor del mundo, seg\u00fan un an\u00e1lisis del Centro Comunitario y Laboral de Universidad de California Merced. Trump pidi\u00f3, meses atr\u00e1s, \u201credoblar los esfuerzos\u201d para detener\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1465141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1465141"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1465141\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1465141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1465141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1465141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}