{"id":1469265,"date":"2025-12-15T03:03:48","date_gmt":"2025-12-15T11:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/"},"modified":"2025-12-15T03:03:48","modified_gmt":"2025-12-15T11:03:48","slug":"comunidad-judia-australia-bondi-beach-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","title":{"rendered":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach"},"content":{"rendered":"<p><a href=\"https:\/\/www.cnn.com\/world\/australia\">El tiroteo masivo m\u00e1s mort\u00edfero ocurrido en Australia<\/a> en casi 30 a\u00f1os tuvo como objetivo familias jud\u00edas en la playa Bondi de Sydney, uno de los lugares m\u00e1s emblem\u00e1ticos del pa\u00eds, en uno de los d\u00edas m\u00e1s festivos del calendario jud\u00edo.<\/p>\n<p>Multitudes de personas se hab\u00edan reunido cerca de la playa para celebrar Januc\u00e1, la fiesta de las luces, en un evento ampliamente publicitado como un festival familiar de la comunidad jud\u00eda que promet\u00eda donas y pintura facial gratis y llenar Bondi de \u201calegr\u00eda y luz\u201d.<\/p>\n<p>Pero una hora antes del atardecer, dos hombres armados (los sospechosos revelados eran padre e hijo) abrieron fuego desde un puente cerca de Archer Park, una zona verde cerca de la famosa playa, mientras turistas y residentes paseaban por Campbell Parade, disfrutando de los minutos finales de lo que de otro modo habr\u00eda sido un domingo glorioso.<\/p>\n<p>Los testigos afirmaron haber o\u00eddo lo que parec\u00edan fuegos artificiales, antes de darse cuenta, con horror, de que se trataba de disparos, un sonido poco com\u00fan en Australia, donde <a href=\"https:\/\/www.cnn.com\/2025\/12\/14\/australia\/australia-bondi-shooting-gun-laws-hnk-intl\">las estrictas leyes sobre armas de fuego<\/a> hacen que los tiroteos sean poco frecuentes. La \u00faltima vez que tantas personas murieron fue en 1996, en la masacre de Port Arthur, cuando un hombre armado con m\u00faltiples armas abri\u00f3 fuego en un sitio tur\u00edstico de Tasmania.<\/p>\n<p>Este ataque ocurri\u00f3 mucho m\u00e1s cerca de casa. Ocurri\u00f3 en Sydney, uno de los principales centros de la vida jud\u00eda en Australia, hogar de una comunidad de unas 120.000 personas en una poblaci\u00f3n de 27 millones.<\/p>\n<p>La masacre indiscriminada <a href=\"https:\/\/www.cnn.com\/2025\/12\/15\/australia\/australia-bondi-beach-shooting-victims-intl-hnk\">se cobr\u00f3 la vida de varias generaciones<\/a>, desde una ni\u00f1a de 10 a\u00f1os hasta un sobreviviente del Holocausto.<\/p>\n<p>La famosa playa de arena blanca de Bondi se promociona como un lugar donde los visitantes pueden disfrutar del sol y desconectar del mundo exterior con amigos. Tras el ataque, los cochecitos de beb\u00e9 quedaron abandonados en el c\u00e9sped, tirados mientras los padres agarraban a sus hijos y corr\u00edan, quit\u00e1ndose las chanclas, para huir de las balas y buscar refugio.<\/p>\n<p>El domingo por la noche, ante la naci\u00f3n, el primer ministro Anthony Albanese calific\u00f3 el ataque como \u201cun acto de maldad\u201d.<\/p>\n<p>\u201cNo hay cabida para este odio, esta violencia y este terrorismo en nuestra naci\u00f3n. Seamos claros: lo erradicaremos\u201d, afirm\u00f3.<\/p>\n<p>Los l\u00edderes jud\u00edos de Australia han estado instando al Gobierno australiano durante a\u00f1os a hacer m\u00e1s para abordar el creciente antisemitismo en el pa\u00eds.<\/p>\n<p>Australia ha sido testigo de <a href=\"https:\/\/www.cnn.com\/2025\/08\/08\/australia\/australia-gaza-protest-sydney-harbour-dst-intl-hnk\">enormes protestas p\u00fablicas<\/a> por la magnitud de la guerra de Israel en Gaza y, tras un aumento en los informes de ataques contra sitios y propiedades jud\u00edas, Albanese nombr\u00f3 el a\u00f1o pasado un enviado especial para combatir el antisemitismo, entregando el cargo a Jillian Segal.<\/p>\n<p>Se incrementaron las patrullas de seguridad en los lugares jud\u00edos de Sydney, pero el Consejo Ejecutivo del Juda\u00edsmo de Australia (ECAJ), que representa a 200 organizaciones jud\u00edas, dijo que el ataque del domingo demostr\u00f3 que es necesario hacer m\u00e1s para garantizar la seguridad del pueblo jud\u00edo.<\/p>\n<p>\u201cYa se ve\u00eda venir\u201d, dijo Alex Ryvchin, coCEO de ECAJ, refiri\u00e9ndose a las estad\u00edsticas que muestran que el a\u00f1o pasado se denunciaron 1.654 ataques antisemitas en Australia.<\/p>\n<p>\u201cEste tipo de cosas siempre han estado destinadas a ocurrir. Pero, al mismo tiempo, no somos un pa\u00eds con un alto \u00edndice de delitos con armas de fuego\u2026 Este tipo de cosas simplemente no ocurren aqu\u00ed\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El domingo le preguntaron directamente a Albanese si se hab\u00eda tomado el antisemitismo lo suficientemente en serio. \u201cS\u00ed, nos lo hemos tomado en serio y hemos seguido actuando\u201d, respondi\u00f3.<\/p>\n<p>Este lunes, enumer\u00f3 las medidas adoptadas con base en un informe presentado por Segal en julio. Estas incluyeron millones de d\u00f3lares invertidos en proyectos de cohesi\u00f3n social y mejoras en museos y centros educativos jud\u00edos. Tambi\u00e9n se est\u00e1n revisando los programas universitarios para promover la inclusi\u00f3n del alumnado y el personal jud\u00edo, afirm\u00f3.<\/p>\n<p>Algunas de las recomendaciones de Segal hab\u00edan sido criticadas anteriormente por ser demasiado amplias y constituir una violaci\u00f3n del derecho a la libertad de expresi\u00f3n.<\/p>\n<p>El Gobierno de Albanese ha procurado mantener una l\u00ednea muy fina para evitar que las tensiones internacionales se trasladen a Australia. Adem\u00e1s del enviado para el antisemitismo, nombr\u00f3 a un enviado contra la islamofobia para abordar las represalias contra la comunidad palestina y sus partidarios.<\/p>\n<p>En agosto, el Gobierno tom\u00f3 la medida extraordinaria de <a href=\"https:\/\/www.cnn.com\/2025\/08\/26\/australia\/australia-iran-antisemitic-attacks-intl-hnk\">expulsar al embajador iran\u00ed en Australia<\/a> despu\u00e9s de que la agencia de seguridad del pa\u00eds vincul\u00f3 al Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n (CGRI) con dos ataques incendiarios contra propiedades jud\u00edas en 2024. Fue la primera vez que Australia expuls\u00f3 a un embajador extranjero desde la Segunda Guerra Mundial.<\/p>\n<p>\u201cHan buscado da\u00f1ar y aterrorizar a los jud\u00edos australianos y sembrar el odio y la divisi\u00f3n en nuestra comunidad\u201d, declar\u00f3 Albanese en aquel momento. Sin embargo, en la misma rueda de prensa, el director general de la Organizaci\u00f3n Australiana de Inteligencia de Seguridad, Mike Burgess, afirm\u00f3 que Ir\u00e1n no pod\u00eda ser considerado responsable de todos los ataques antisemitas en suelo australiano.<\/p>\n<p>La masacre en Bondi Beach marca una escalada inimaginable de violencia para un pa\u00eds con una de las tasas de homicidios con armas de fuego m\u00e1s bajas del mundo, donde los tiroteos masivos son algo que sucede en otros lugares.<\/p>\n<p>Las estrictas leyes sobre armas dificultan el acceso legal a ellas, pero parece que estas normas se endurecer\u00e1n a\u00fan m\u00e1s, con las promesas de Albanese de acelerar la creaci\u00f3n de un Registro Nacional de Armas de Fuego e implementar plazos para las licencias de armas. El primer ministro de Nueva Gales del Sur, Chris Minns, anunci\u00f3 este lunes que las leyes estatales tambi\u00e9n cambiar\u00edan.<\/p>\n<p>El mayor de los dos sospechosos, un hombre de 50 a\u00f1os, era miembro de un club de tiro y ten\u00eda una licencia de caza recreativa que le daba derecho a poseer las armas largas utilizadas en el ataque, dijo el comisionado de Polic\u00eda de Nueva Gales del Sur, Mal Lanyon.<\/p>\n<p>\u201cEl padre tiene licencia de armas desde 2015. Estamos investigando a fondo los antecedentes de ambas personas. En este momento, sabemos muy poco sobre ellas\u201d, dijo Lanyon.<\/p>\n<p>El hombre fue asesinado por la Polic\u00eda en el lugar, mientras que su hijo de 24 a\u00f1os permanece en el hospital y es probable que enfrente cargos, dijo la Polic\u00eda.<\/p>\n<p>Los investigadores allanaron una vivienda en Bonnyrigg, un suburbio al oeste de Sydney, la cual se cree est\u00e1 relacionada con el ataque de Bondi. Este lunes se vio llegar a un equipo de media decena de expertos forenses con equipo de protecci\u00f3n completo, mientras la propiedad estaba rodeada por una cinta policial.<\/p>\n<p>Los lugare\u00f1os dijeron a CNN que estaban conmocionados porque los sospechosos podr\u00edan haber estado viviendo cerca.<\/p>\n<p>El vecino Renato Padilla dijo que estaba viendo por televisi\u00f3n los sucesos posteriores a la tragedia de Bondi, cuando de repente su calle se llen\u00f3 de autos de Polic\u00eda.<\/p>\n<p>\u201cEst\u00e1bamos muy preocupados anoche por si hab\u00eda un tiroteo o algo as\u00ed. O porque dijeron que en Bondi hab\u00eda explosivos en el coche\u201d, dijo Padilla, refiri\u00e9ndose a un veh\u00edculo encontrado estacionado en la cercana Campbell Parade de Bondi, que estaba equipado con varios artefactos explosivos improvisados.<\/p>\n<p>Lanyon, el comisionado de Polic\u00eda de Nueva Gales del Sur, inst\u00f3 a la cautela ante cualquier miembro de la comunidad que intente perturbar a\u00fan m\u00e1s una ciudad sacudida con actos para vengar el tiroteo del domingo.<\/p>\n<p>\u201cEste es un momento de calma. No se aceptar\u00e1n represalias ni actos contra ning\u00fan sector de la comunidad\u201d, dijo.<\/p>\n<p>Pero el temor ahora es que las tensiones que el Gobierno australiano hab\u00eda estado tratando de mantener fuera de las fronteras del pa\u00eds broten m\u00e1s agresivamente que nunca, mientras las comunidades buscan respuestas sobre qu\u00e9 motiv\u00f3 a dos hombres a cometer un acto tan atroz y qu\u00e9 hicieron las autoridades, o no hicieron, para detenerlo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tiroteo masivo m\u00e1s mort\u00edfero ocurrido en Australia en casi 30 a\u00f1os tuvo como objetivo familias jud\u00edas en la playa Bondi de Sydney, uno de los lugares m\u00e1s emblem\u00e1ticos del pa\u00eds, en uno de los d\u00edas m\u00e1s festivos del calendario jud\u00edo. Multitudes de personas se hab\u00edan reunido cerca de la playa para celebrar Januc\u00e1, la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469265","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias\" \/>\n<meta property=\"og:description\" content=\"El tiroteo masivo m\u00e1s mort\u00edfero ocurrido en Australia en casi 30 a\u00f1os tuvo como objetivo familias jud\u00edas en la playa Bondi de Sydney, uno de los lugares m\u00e1s emblem\u00e1ticos del pa\u00eds, en uno de los d\u00edas m\u00e1s festivos del calendario jud\u00edo. Multitudes de personas se hab\u00edan reunido cerca de la playa para celebrar Januc\u00e1, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T11:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach\",\"datePublished\":\"2025-12-15T11:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\"},\"wordCount\":1423,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\",\"name\":\"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-15T11:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias","og_description":"El tiroteo masivo m\u00e1s mort\u00edfero ocurrido en Australia en casi 30 a\u00f1os tuvo como objetivo familias jud\u00edas en la playa Bondi de Sydney, uno de los lugares m\u00e1s emblem\u00e1ticos del pa\u00eds, en uno de los d\u00edas m\u00e1s festivos del calendario jud\u00edo. Multitudes de personas se hab\u00edan reunido cerca de la playa para celebrar Januc\u00e1, la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-15T11:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/"},"author":{"name":"","@id":""},"headline":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach","datePublished":"2025-12-15T11:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/"},"wordCount":1423,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","name":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-15T11:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La comunidad jud\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach","url":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/comunidad-judia-australia-bondi-beach-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-15T11:03:48Z","datePublished":"2025-12-15T11:03:48Z","dateModified":"2025-12-15T11:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La comunidad jud\\u00eda de Australia vio venir un ataque, pero nadie esperaba el horror de Bondi Beach\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/15\\\/comunidad-judia-australia-bondi-beach-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/15\\\/comunidad-judia-australia-bondi-beach-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-15T11:03:48Z\",\"datePublished\":\"2025-12-15T11:03:48Z\",\"dateModified\":\"2025-12-15T11:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469267,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/bondi-beach-nina-10-anos-sobreviviente-holocausto-trax\/","url_meta":{"origin":1469265,"position":0},"title":"Una ni\u00f1a de 10 a\u00f1os y un sobreviviente del Holocausto \u00bfQui\u00e9nes son las v\u00edctimas del tiroteo en Bondi Beach?","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Una ni\u00f1a de 10 a\u00f1os, un sobreviviente del Holocausto y un joven ciudadano franc\u00e9s estaban entre al menos 15 personas muertas cuando dos hombres armados abrieron fuego contra familias que celebraban la primera noche de Januc\u00e1 en la famosa playa Bondi de Sydney el domingo, un ataque que la Polic\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469271,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/tiroteo-sydney-australia-que-paso-trax\/","url_meta":{"origin":1469265,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 en el tiroteo de Sydney, Australia, en el que murieron 15 personas?","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Al menos 15 personas murieron el domingo en un atentado terrorista contra la comunidad jud\u00eda que celebraba la primera noche de Januc\u00e1 en la famosa playa Bondi de Sydney.Unas 1.000 personas se hab\u00edan reunido en una zona verde del Parque Archer cuando al menos dos hombres armados abrieron fuego a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469332,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/17\/funerales-bondi-terrorismo-sidney-trax\/","url_meta":{"origin":1469265,"position":2},"title":"Comienzan los funerales de las v\u00edctimas de Bondi Beach mientras acusan al presunto atacante de homicidio y terrorismo","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"El mi\u00e9rcoles se realizaron los primeros funerales de algunas de las 15 personas murieron en el peor tiroteo masivo ocurrido en Australia en casi tres d\u00e9cadas, mientras la polic\u00eda presentaba cargos de homicidio y terrorismo contra uno de los presuntos atacantes.Se produjeron escenas emotivas fuera del Jabad de Bondi en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469303,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/16\/heroe-ataque-bondi-refugiados-trax\/","url_meta":{"origin":1469265,"position":3},"title":"El &#171;h\u00e9roe&#187; que le arrebat\u00f3 el arma al atacante de Bondi Beach, en Australia, es hijo de refugiados y padre de dos hijas","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"El transe\u00fante que le arrebat\u00f3 el arma a uno de los presuntos atacantes durante el tiroteo masivo en Bondi Beach fue identificado como Ahmed al Ahmed, cuyos padres, refugiados, acababan de llegar de Siria, seg\u00fan funcionarios y medios de comunicaci\u00f3n australianos.Ahmed, de 43 a\u00f1os y padre de dos ni\u00f1as, arriesg\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469510,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/23\/bondi-australia-atacantes-solitarios-trax\/","url_meta":{"origin":1469265,"position":4},"title":"La mayor\u00eda de autores de masacres act\u00faan solos. La de Bondi fue una atrocidad inusual entre padre e hijo, afirman expertos","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"Mientras las autoridades investigan los motivos detr\u00e1s del mortal ataque de Bondi Beach la semana pasada, los principales crimin\u00f3logos notan una caracter\u00edstica inusual que diferencia este tiroteo masivo de otros: los presuntos atacantes eran miembros de una familia que se confabularon.Sajid Akram y su hijo Naveed Akram est\u00e1n acusados \u200b\u200bde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469266,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/15\/5-cosas-15-diciembre-orix\/","url_meta":{"origin":1469265,"position":5},"title":"Las 5 cosas que debes saber este 15 de diciembre: Triunfo de Kast, tiroteo en Sydney, avi\u00f3n de JetBlue y m\u00e1s","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Al menos 15 muertos tras el ataque en una playa de Sydney durante una celebraci\u00f3n de Januc\u00e1. Incidente entre un avi\u00f3n de JetBlue y una aeronave militar de EE.UU. Muere el director de Hollywood Rob Reiner. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1469265"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469265\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1469265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1469265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1469265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}