{"id":1469661,"date":"2025-12-30T08:03:51","date_gmt":"2025-12-30T16:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/"},"modified":"2025-12-30T08:03:51","modified_gmt":"2025-12-30T16:03:51","slug":"chavismo-riquezas-aliados-tensiones-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","title":{"rendered":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU."},"content":{"rendered":"<p>En una Am\u00e9rica Latina donde los gobiernos cambian con cada elecci\u00f3n y d\u00f3nde nada parecer durar, hubo una sola certeza en estos \u00faltimos 25 a\u00f1os: la Venezuela chavista \u2013y petrolera\u2013 y su constante enfrentamiento con Estados Unidos.<\/p>\n<p>Este a\u00f1o, la tensi\u00f3n alcanz\u00f3 niveles no antes vistos, tras el despliegue militar estadounidense en el Caribe, los ataques a botes presuntamente cargados con drogas \u2013 y ligados por Washington a Venezuela\u2013 y la estrategia del presidente Donald Trump de ejercer presi\u00f3n m\u00e1xima sobre su par, Nicol\u00e1s Maduro, y sobre el petr\u00f3leo, la l\u00ednea de vida venezolana.<\/p>\n<p>\u00bfC\u00f3mo llegamos hasta aqu\u00ed?<\/p>\n<p>A continuaci\u00f3n, una radiograf\u00eda para entender la Venezuela contempor\u00e1nea; su historia, sus riquezas, sus alianzas y su delicado equilibrio interno de poder, mientras crece la tensi\u00f3n con Estados Unidos un d\u00eda despu\u00e9s de conocerse el primer ataque de la CIA en tierra venezolana.<\/p>\n<p>Nombre oficial: Rep\u00fablica Bolivariana de Venezuela<\/p>\n<p>Geograf\u00eda: Venezuela tiene una extensi\u00f3n territorial de 912.050 kil\u00f3metros cuadrados, <a href=\"https:\/\/datos.bancomundial.org\/indicador\/AG.SRF.TOTL.K2?locations=VE\">seg\u00fan el Banco Mundial<\/a>. Colinda al norte con el Caribe y el oc\u00e9ano Atl\u00e1ntico; al oeste, con Colombia; al sur, con Brasil, y al este, con Guyana.<\/p>\n<p>Poblaci\u00f3n: Al cierre de 2023, el pa\u00eds ten\u00eda una poblaci\u00f3n de 33.800.393 personas, <a href=\"https:\/\/ine.gob.ve\/wp-content\/uploads\/2024\/08\/Resumen_de_estadisticas_1999-2023.pdf\">seg\u00fan el Instituto Nacional de Estad\u00edstica<\/a>. El Instituto prev\u00e9 que 2025 termine con 34,4 millones de habitantes.<\/p>\n<p>Migraci\u00f3n: Al menos 7,9 millones de venezolanos han migrado del pa\u00eds en busca de protecci\u00f3n o de mejores condiciones de vida, <a href=\"https:\/\/www.unhcr.org\/emergencies\/venezuela-situation\">seg\u00fan cifras de la ONU<\/a>. La mayor\u00eda de esos migrantes se han establecido en pa\u00edses de Sudam\u00e9rica como Colombia, Per\u00fa o Chile.<\/p>\n<p>El presidente Nicol\u00e1s Maduro jurament\u00f3 en enero de 2024 un nuevo mandato hasta 2031, luego de unas elecciones cuestionadas por la oposici\u00f3n y por varios gobiernos de la regi\u00f3n. Lleva casi 13 a\u00f1os en el poder desde la muerte de su \u201cpadre pol\u00edtico\u201d, Hugo Ch\u00e1vez, quien gobern\u00f3 por casi 14 a\u00f1os.<\/p>\n<p>Estos son los presidentes que gobernaron el pa\u00eds desde 1958, cuando cay\u00f3 la dictadura de Marcos P\u00e9rez Jim\u00e9nez.<\/p>\n<p>La principal fuente econ\u00f3mica de Venezuela es el petr\u00f3leo, en un modelo productivo poco diversificado. El pa\u00eds cuenta con la <a href=\"https:\/\/www.eia.gov\/international\/content\/analysis\/countries_long\/Venezuela\/\">mayor reserva<\/a> de crudo extrapesado del mundo, una variedad que requiere un proceso m\u00e1s complejo y costoso, pero que es tambi\u00e9n compatible con las refiner\u00edas estadounidenses.<\/p>\n<p>A pesar de las sanciones, las exportaciones de crudo subieron en 2025 a un promedio de m\u00e1s 900.000 barriles diarios, <a href=\"https:\/\/www.opec.org\/monthly-oil-market-report.html\">seg\u00fan la OPEP<\/a>, por encima de lo producido en los \u00faltimos tres a\u00f1os. Sin embargo, la ca\u00edda de inversi\u00f3n y mantenimiento es notoria, ya que esa cifra es menos de la mitad de lo que bombeaba Venezuela en 2013, y menos de un tercio de los 3,5 millones de barriles diarios producidos antes de la llegada de Ch\u00e1vez en 1999.<\/p>\n<p>Asociada a esta industria (y tambi\u00e9n con baja inversi\u00f3n y exploraci\u00f3n) est\u00e1 la exportaci\u00f3n de gas. La Administraci\u00f3n de Informaci\u00f3n Energ\u00e9tica de EE.UU. (EIA) <a href=\"https:\/\/www.eia.gov\/international\/content\/analysis\/countries_long\/Venezuela\/#:~:text=Venezuela%20has%20significant,for%20residential%20supply.\">estima<\/a> que Venezuela tiene reservas de 5,5 billones de metros c\u00fabicos de gas natural, lo que representa el 73 % de los yacimientos en Sudam\u00e9rica.<\/p>\n<p>En la \u00faltima d\u00e9cada, ante la ca\u00edda de la renta petrolera, el Gobierno intent\u00f3 dar mayor vuelo a la miner\u00eda y estableci\u00f3 el Arco Minero del Orinoco como una \u201czona de desarrollo estrat\u00e9gico\u201d para impulsar la explotaci\u00f3n de la zona, con grandes reservas de oro, colt\u00e1n, hierro y bauxita.<\/p>\n<p>Sin embargo, es una zona con m\u00e1s actividad artesanal que industrial y con amplia presencia de <a href=\"https:\/\/cnnespanol.cnn.com\/2019\/08\/20\/un-rastro-de-oro-sangriento-conduce-al-gobierno-de-venezuela\/\">grupos criminales y contrabandistas<\/a>.<\/p>\n<p>Hasta 2023, Estados Unidos era el principal destino de las exportaciones de Venezuela, con USD 3.810 millones anuales (principalmente petr\u00f3leo), seg\u00fan el <a href=\"https:\/\/oec.world\/en\/profile\/country\/ven?yearlyTradeFlowSelector=flow1\">Observatorio de Complejidad Econ\u00f3mica<\/a>, un puesto que no ocupaba desde el 2018; era seguido de China (US$ 739 millones) y Espa\u00f1a (US$ 670 millones).<\/p>\n<p>Sin embargo, la ecuaci\u00f3n volvi\u00f3 a cambiar a mediados de 2024, cuando Washington endureci\u00f3 las sanciones comerciales sobre Caracas, con la excepci\u00f3n de algunas licencias petroleras. Desde entonces, Venezuela se apoy\u00f3 m\u00e1s en otros socios como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/23\/venezuela\/maduro-china-tension-venezuela-estados-unidos-orix\">China<\/a>, Rusia, India y Turqu\u00eda, aunque el Gobierno no ha publicado cifras oficiales recientes que reflejen ese giro. Por ejemplo, el presidente de Rusia, Vladimir Putin, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/05\/07\/mundo\/intercambio-comercial-rusia-venezuela-putin-maduro-orix\">dijo<\/a> en mayo que el intercambio comercial con Venezuela creci\u00f3 un 64 % en 2024.<\/p>\n<p>Por su parte, China inform\u00f3 que en 2024 las exportaciones de Venezuela tuvieron un crecimiento interanual del 119 %, seg\u00fan <a href=\"https:\/\/www.mfa.gov.cn\/web\/gjhdq_676201\/gj_676203\/nmz_680924\/1206_681168\/sbgx_681172\/\">cifras<\/a> de la Administraci\u00f3n General de Aduanas china, con un descenso moderado en el primer semestre de 2025.<\/p>\n<p>Desde inicios del siglo XXI, Venezuela ha establecido alianzas y estrechos v\u00ednculos con pa\u00edses que manifiestan una oposici\u00f3n al liderazgo regional y global de Estados Unidos, con los que forma parte de un eje revisionista.<\/p>\n<p>En Am\u00e9rica Latina, sus aliados m\u00e1s estrechos son Cuba y Nicaragua y forman un conjunto de tres de los pa\u00edses m\u00e1s autoritarios y pol\u00edticamente aislados de la regi\u00f3n. \u201cSe perciben como necesarios mutuamente\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/06\/venezuela\/venezuela-aliados-cuba-nicaragua-presion-eeuu-orix\">dijo<\/a> a CNN el polit\u00f3logo venezolano \u00c1ngel \u00c1lvarez. Caracas tuvoi v\u00ednculos m\u00e1s s\u00f3lidos con otros gobiernos izquierdistas, como el del presidente de Brasil, Luiz In\u00e1cio Lula da Silva, y el mandatario de Colombia, Gustavo Petro, pero estas naciones tomaron distancia tras las elecciones presidenciales de 2024. Sin embargo, algunos puentes volvieron a tenderse con muestras de apoyo de Brasilia y Bogot\u00e1 frente al despliegue militar de EE.UU. en torno a las costas de Venezuela.<\/p>\n<p>Caracas tambi\u00e9n tiene otros aliados de menor tama\u00f1o en el Caribe, forjados en la \u00e9poca de mayor bonanza petrolera, aunque en noviembre <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/01\/venezuela\/maduro-pierde-aliados-venezuela-orix\">sufri\u00f3<\/a> dos reveses con la derrota del oficialismo en Honduras y en el archipi\u00e9lago de San Vicente y las Granadinas. Unos meses antes tambi\u00e9n lament\u00f3 la derrota en Bolivia del gobernante Movimiento al Socialismo, con el que ten\u00eda un v\u00ednculo estrecho.<\/p>\n<p>Por fuera de la regi\u00f3n, Maduro ha consolidado las relaciones con dos potencias como China y Rusia. En noviembre, el l\u00edder chavista <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/24\/venezuela\/maduro-china-rusia-despliegue-caribe-orix\">asegur\u00f3<\/a> que el v\u00ednculo con Beijing es de \u201cconfianza profunda, amplia y estable\u201d y agreg\u00f3 que est\u00e1 trabajando para profundizar la cooperaci\u00f3n con Mosc\u00fa. Adem\u00e1s, Venezuela ha afianzado la diplomacia con Ir\u00e1n, otro pa\u00eds que se opone a la Casa Blanca. Sin embargo, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/13\/venezuela\/iran-aliado-militar-venezuela-eeuu-maduro-orix\">analistas consultados<\/a> por CNN ven remota la posibilidad de que estos actores se involucren en un eventual conflicto militar con Washington.<\/p>\n<p>Las principales posiciones de poder en el oficialismo de Venezuela, pilares en la estructura de Gobierno de Maduro, son ocupadas por personas que tienen a\u00f1os jugando un rol protag\u00f3nico en la pol\u00edtica del pa\u00eds sudamericano. Algunas de ellas, como Diosdado Cabello o Jorge Rodr\u00edguez, desempe\u00f1an papeles clave desde tiempos del fallecido presidente Hugo Ch\u00e1vez.<\/p>\n<p>Las tensiones entre Venezuela y Estados Unidos se han extendido a lo largo de todo 2025. El 10 de enero, Maduro inici\u00f3 su tercer mandato presidencial luego de las controvertidas elecciones de julio de 2024. Trump comenz\u00f3 su segunda presidencia unos d\u00edas despu\u00e9s, el 20 de enero, y desde entonces ha ejercido diversas presiones.<\/p>\n<p>Tras llegar a la Casa Blanca, Trump dijo que considera que Maduro no es un gobernante democr\u00e1ticamente electo. Tambi\u00e9n anunci\u00f3 una pol\u00edtica de deportaciones masivas, con el argumento de que muchos migrantes que llegan a EE.UU. \u2014incluyendo a los venezolanos\u2014 llevan crimen y otros males a su pa\u00eds, y design\u00f3 al Tren de Aragua como organizaci\u00f3n terrorista transnacional.<\/p>\n<p>Maduro, por su parte, dijo que su Gobierno es leg\u00edtimo, rechaz\u00f3 que los migrantes venezolanos sean criminales y afirm\u00f3 que las autoridades venezolanas combaten al Tren de Aragua. El mandatario incluso asegura que esta agrupaci\u00f3n delictiva ya est\u00e1 desmantelada, aunque no ha presentado prueba de sus dichos.<\/p>\n<p>En marzo, las tensiones entre ambos gobiernos tuvieron una primera escalada, cuando EE.UU. deport\u00f3 al Centro de Confinamiento del Terrorismo de El Salvador (Cecot) a 238 migrantes venezolanos a quienes se\u00f1al\u00f3 como delincuentes. Venezuela critic\u00f3 la medida, que tach\u00f3 de \u201csecuestro\u201d, e inici\u00f3 una campa\u00f1a para exigir que fueran devueltos al pa\u00eds sudamericano. En julio, tras negociaciones, Washington y Caracas <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/18\/eeuu\/estados-unidos-venezuela-intercambio-prisioneros-trax\">concretaron un intercambio<\/a> que implic\u00f3 el regreso a Venezuela de los hombres enviados al Cecot  y la liberaci\u00f3n de 10 estadounidenses detenidos en territorio venezolano.<\/p>\n<p>El mismo mes de julio, sin embargo, EE.UU. volvi\u00f3 a aumentar la presi\u00f3n sobre Venezuela. El Departamento del Tesoro <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/26\/eeuu\/eeuu-cartel-soles-organizacion-terrorista-orix\">acus\u00f3 a Maduro de ser l\u00edder del C\u00e1rtel de los Soles<\/a>, una supuesta organizaci\u00f3n criminal que, seg\u00fan Washington, realiza actividades de narcotr\u00e1fico y lavado de dinero. En agosto, adem\u00e1s, EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/07\/eeuu\/gobierno-trump-duplica-recompensa-nicolas-maduro-50-millones-trax\">aument\u00f3 a US$ 50 millones la recompensa por la captura de Maduro<\/a>, mientras el mandatario venezolano neg\u00f3 ser responsable de actividades il\u00edcitas.<\/p>\n<p>Para septiembre, pese a algunos acercamientos y llamados al di\u00e1logo, las tensiones aumentaron a\u00fan m\u00e1s. EE.UU. realiz\u00f3 un despliegue de buques y aviones militares en el Caribe con el argumento de combatir al narcotr\u00e1fico, y comenz\u00f3 una serie de ataques contra botes que, dice, buscaban transportar drogas hacia su territorio. Hasta mediados de diciembre, al menos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/05\/eeuu\/caribe-pacifico-ataques-eeuu-narcotrafico-cronologia-orix\">30 embarcaciones han sido destruidas<\/a> en el Caribe y el Pac\u00edfico, lo que ha causado la muerte de m\u00e1s de 100 personas.<\/p>\n<p>Venezuela dice que estas acciones son ilegales y solo buscan desestabilizar al Gobierno de Maduro, una postura que comparte Colombia, en cuyas costas se han realizado algunas de estas maniobras. Sin embargo, EE.UU. sostiene que busca frenar el flujo de narc\u00f3ticos hacia su territorio. M\u00e1s a\u00fan, EE.UU. dice que estos ataques continuar\u00e1n e incluso contempla una ofensiva por tierra contra los narcotraficantes.<\/p>\n<p>En diciembre, Trump orden\u00f3 un \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/16\/eeuu\/trump-ordena-bloqueo-petroleros-sancionados-venezuela-trax\">bloqueo total<\/a>\u201d a los buques petroleros sancionados por EE.UU. y la Guardia Costera comenz\u00f3 a intervenir embarcaciones que salen o llegan a la costa venezolana.<\/p>\n<p>Trump \u2014quien ya hab\u00eda autorizado operaciones de la CIA dentro de Venezuela\u2014 dijo el 12 de diciembre que las acciones militares terrestres en Venezuela <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/13\/eeuu\/trump-ataques-venezuela-empezar-suceder-trax\">\u201cvan a empezar a suceder\u201d<\/a> porque, asegur\u00f3, Washington no permitir\u00e1 que traficantes de drogas \u201cdestruyan a nuestra juventud\u201d.<\/p>\n<p>El hito fundacional del chavismo, movimiento que lleva <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/08\/02\/veinticinco-anios-chavismo-venezuela-cronologia-orix\">m\u00e1s de un cuarto siglo<\/a> gobernando Venezuela, es el fallido intento de golpe del 4 de febrero de 1992, liderado por el entonces teniente coronel del Ej\u00e9rcito Hugo Ch\u00e1vez, contra el presidente Carlos Andr\u00e9s P\u00e9rez. Ch\u00e1vez fue detenido, indultado en 1994 y elegido presidente a fines de 1998.<\/p>\n<p>Desde su primer d\u00eda de Gobierno, Ch\u00e1vez impuls\u00f3 una nueva Constituci\u00f3n que fue aprobada por refer\u00e9ndum a fines de 1999, y gan\u00f3 a mediados del 2000 las elecciones convocadas para relegitimar los poderes p\u00fablicos.<\/p>\n<p>En 2002 el mandatario fue derrocado con un golpe de Estado tras una multitudinaria marcha que exig\u00eda su renuncia, pero vuelve al poder tras 48 horas con el apoyo de militares leales. En 2004 enfrent\u00f3 un refer\u00e9ndum revocatorio impulsado por la oposici\u00f3n, pero el 59 % de los venezolanos votaron para mantenerlo en la presidencia.<\/p>\n<p>En el plano regional, Ch\u00e1vez fue uno de los l\u00edderes del movimiento \u201cNo al ALCA\u201d, el tratado comercial que propon\u00eda Estados Unidos y que fue rechazado en 2005. Al a\u00f1o siguiente pronunci\u00f3 uno de sus discursos m\u00e1s famosos en la ONU, cuando se refiri\u00f3 al presidente de Estados Unidos, George W. Bush, como \u201cel diablo\u201d.<\/p>\n<p>Ch\u00e1vez fue reelegido por amplia ventaja a finales de 2006 y la Asamblea nacional aprob\u00f3 una ley que autoriz\u00f3 al presidente a gobernar por decreto por 18 meses (y otro proyecto similar fue aprobado en 2010). Es el inicio de la era socialista autodenominada Revoluci\u00f3n Bolivariana. En 2007 sac\u00f3 a Venezuela del Banco Mundial y del Fondo Monetario Internacional y decret\u00f3 una de las nacionalizaciones m\u00e1s importantes: la de la Faja Petrolera del Orinoco, que concentra los mayores yacimientos del pa\u00eds.<\/p>\n<p>Pero ese a\u00f1o tambi\u00e9n sufri\u00f3 su primera derrota en las urnas, cuando los venezolanos rechazaron un refer\u00e9ndum que otorgaba amplios poderes a la presidencia y establec\u00eda la reelecci\u00f3n indefinida, una disposici\u00f3n que ser\u00eda aprobada en una votaci\u00f3n de 2009 y que le permitir\u00eda competir en 2012. En esa votaci\u00f3n presidencial, venci\u00f3 a Henrique Capriles y nombra al excanciller Nicol\u00e1s Maduro como su vicepresidente.<\/p>\n<p>Antes de asumir su tercer per\u00edodo, anuncia que debe viajar a Cuba para seguir su tratamiento contra el c\u00e1ncer y unge a Maduro como su sucesor. Muere el 5 de marzo de 2013.<\/p>\n<p>Maduro asumi\u00f3 como presidente interino y venci\u00f3 por estrecho margen a Capriles. Al a\u00f1o siguiente, enfrenta la primera gran ola de protestas opositoras, que dejan un saldo de m\u00e1s de 40 muertos, seg\u00fan la ONG Foro Penal. Al a\u00f1o siguiente, Estados Unidos comienza a aplicar sanciones contra funcionarios venezolanos.<\/p>\n<p>La oposici\u00f3n consigui\u00f3 a finales de 2015 ganar la mayor\u00eda de los esca\u00f1os de la Asamblea Nacional, el primer cambio importante en el Legislativo desde 1999. Pero el Tribunal Supremo declar\u00f3 al \u00f3rgano en \u201cdesacato\u201d y le despoj\u00f3 de sus competencias.<\/p>\n<p>En 2018, con una hiperinflaci\u00f3n desatada y un \u00e9xodo migratorio en marcha, Maduro es reelegido presidente en una votaci\u00f3n boicoteada por la oposici\u00f3n por falta de garant\u00edas.<\/p>\n<p>Asume su segundo per\u00edodo entre crisis energ\u00e9tica, protestas y varias denuncias internacionales de represi\u00f3n. Maduro enfrenta la presi\u00f3n de pa\u00edses que reconocen como presidente interino al titular de la Asamblea, Juan Guaid\u00f3.<\/p>\n<p>Para 2022, Venezuela sali\u00f3 del ciclo hiperinflacionario con una dolarizaci\u00f3n de facto y apertura a inversiones extranjeras. M\u00e1s de 7 millones de personas ya hab\u00edan salido del pa\u00eds y un informe de la ONU document\u00f3 cr\u00edmenes de lesa humanidad de las fuerzas de seguridad.<\/p>\n<p>El chavismo particip\u00f3 de varias mesas de negociaci\u00f3n con la oposici\u00f3n, sin que ninguna llegue a acuerdos duraderos.<\/p>\n<p>De cara a las elecciones de 2024, la Justicia ratific\u00f3 la inhabilitaci\u00f3n de Mar\u00eda Corina Machado, quien gan\u00f3 ampliamente las primarias de la oposici\u00f3n. El Consejo Nacional Electoral declar\u00f3 ganador a Maduro frente Edmundo Gonz\u00e1lez, pero no mostr\u00f3 el detalle de los resultados.<\/p>\n<p>En 2025, tras el inicio del segundo mandato de Donald Trump en EE.UU., el Palacio de Miraflores enfrenta una presi\u00f3n sin precedentes. A las sanciones individuales y sectoriales, acusaciones y ofrecimientos de recompensa, se suma un despliegue militar de Washington en el Caribe, con amenazas de ataques en territorio venezolano.<\/p>\n<p>La Fuerza Armada Nacional de Bolivariana de Venezuela (FANB) lleg\u00f3 a posicionarse como una potencia militar regional, en gran parte a trav\u00e9s de la compra sostenida de equipamiento ruso a partir del Gobierno de Hugo Ch\u00e1vez. Sin embargo, el estado de los equipos y el entrenamiento del personal es una inc\u00f3gnita en un pa\u00eds que lleva ya una d\u00e9cada de penurias econ\u00f3micas.<\/p>\n<p>Venezuela ocupa el puesto 50 de 145 en el ranking 2025 del sitio <a href=\"https:\/\/www.globalfirepower.com\/countries-listing.php\">Global Fire Power<\/a> en base a estad\u00edsticas oficiales y estimaciones. Estados Unidos ocupa el 1, y algunos vecinos de Venezuela, como Colombia (46) y Brasil (11), la superan en el listado.<\/p>\n<p>La FANB cuenta con cerca de 123.000 soldados activos, entre el Ej\u00e9rcito (63.000), la Armada (25.500), la Aviaci\u00f3n Militar (11.500) y la Guardia Nacional (23.000), de acuerdo con datos del International Institute for Strategic Studies (IISS), suplementados por 8.000 reservistas. Despu\u00e9s de a\u00f1os de paralizaci\u00f3n, Venezuela \u201creanud\u00f3 recientemente modestos esfuerzos de mantenimiento y modernizaci\u00f3n\u201d, indic\u00f3 el Balance Militar 2024 realizado por IISS. La inc\u00f3gnita es el tama\u00f1o y la capacidad de las milicias, convocadas en los \u00faltimos meses a ra\u00edz del despliegue naval de Estados Unidos. Estimadas previamente en unos cientos de miles, Maduro dijo que esperaba llegar a m\u00e1s de 8 millones.<\/p>\n<p>El Ej\u00e9rcito compr\u00f3 a Rusia 92 tanques T-72B1 y 123 transportes blindados de tropas BMP-3, que equipan a las brigadas blindadas junto a 81 tanques AMX-30 adquiridos anteriormente a Francia. Tambi\u00e9n en la artiller\u00eda destacan sistemas rusos como los ca\u00f1ones autopropulsados Msta-S y los lanzacohetes Smerch.<\/p>\n<p>La aviaci\u00f3n militar concentra la tecnolog\u00eda. Los cazabombarderos bimotores Sukhoi Su-30MK2, de fabricaci\u00f3n rusa, son el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/18\/venezuela\/venezuela-muestra-cazas-misiles-maniobras-orix\">emblema<\/a> del sistema de defensa venezolano y est\u00e1n entre las aeronaves m\u00e1s potentes del continente. Entre accidentes y problemas log\u00edsticos no est\u00e1 claro cu\u00e1ntos a\u00fan vuelan de las 25 unidades que compr\u00f3, seg\u00fan un <a href=\"https:\/\/www.controlciudadano.org\/noticias\/en-2021-aumentaron-accidentes-de-aeronaves-militares-en-venezuela-control-ciudadano-publica-informe-con-registro-de-accidentes-de-aeronaves-de-la-fanb-en-dos-decadas\">informe<\/a> de la ONG venezolana Control Ciudadano.<\/p>\n<p>Por otro lado, entre sus muchos <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/31\/venezuela\/defensas-aereas-venezuela-ataque-orix\">sistemas antia\u00e9reos de misiles<\/a> destacan las 12 bater\u00edas S-300 (con un alcance m\u00e1ximo de 200 kil\u00f3metros), 9 sistemas Buk y 44 sistemas Pechora (de mediano alcance), todos de fabricaci\u00f3n rusa, un conjunto que la FANB llama \u201cDefensa Aeroespacial Multicapa\u201d. Estos tres sistemas de armas son m\u00f3viles: est\u00e1n montados en veh\u00edculos para ser trasladados r\u00e1pidamente, y superan en capacidad y tecnolog\u00eda a cualquier otro desplegado en Am\u00e9rica Latina.<\/p>\n<p>Adicionalmente, Venezuela dice contar con 5.000 <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/22\/venezuela\/maduro-misiles-antiaereos-rusos-igla-orix\">misiles port\u00e1tiles Igla-S<\/a> \u2014tambi\u00e9n rusos\u2014, operados por una sola persona y con capacidad de abatir blancos a baja altitud y corta distancia.<\/p>\n<p>Por su parte, la Armada qued\u00f3 rezagada en la compra de armamentos. Opera una fragata clase Mariscal Sucre (fabricada en Italia) y un submarino tipo-209 (fabricado en Alemania) en su flota de Mar, seg\u00fan el IISS, y cuenta adem\u00e1s con nueve buques de patrullaje oce\u00e1nico y costero, entre estos cuatro comprados a Espa\u00f1a.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una Am\u00e9rica Latina donde los gobiernos cambian con cada elecci\u00f3n y d\u00f3nde nada parecer durar, hubo una sola certeza en estos \u00faltimos 25 a\u00f1os: la Venezuela chavista \u2013y petrolera\u2013 y su constante enfrentamiento con Estados Unidos. Este a\u00f1o, la tensi\u00f3n alcanz\u00f3 niveles no antes vistos, tras el despliegue militar estadounidense en el Caribe, los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469661","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"En una Am\u00e9rica Latina donde los gobiernos cambian con cada elecci\u00f3n y d\u00f3nde nada parecer durar, hubo una sola certeza en estos \u00faltimos 25 a\u00f1os: la Venezuela chavista \u2013y petrolera\u2013 y su constante enfrentamiento con Estados Unidos. Este a\u00f1o, la tensi\u00f3n alcanz\u00f3 niveles no antes vistos, tras el despliegue militar estadounidense en el Caribe, los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T16:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU.\",\"datePublished\":\"2025-12-30T16:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\"},\"wordCount\":2965,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\",\"name\":\"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-30T16:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias","og_description":"En una Am\u00e9rica Latina donde los gobiernos cambian con cada elecci\u00f3n y d\u00f3nde nada parecer durar, hubo una sola certeza en estos \u00faltimos 25 a\u00f1os: la Venezuela chavista \u2013y petrolera\u2013 y su constante enfrentamiento con Estados Unidos. Este a\u00f1o, la tensi\u00f3n alcanz\u00f3 niveles no antes vistos, tras el despliegue militar estadounidense en el Caribe, los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-30T16:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU.","datePublished":"2025-12-30T16:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/"},"wordCount":2965,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","name":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-30T16:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\u00f3n con EE.UU.","url":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/chavismo-riquezas-aliados-tensiones-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-30T16:03:51Z","datePublished":"2025-12-30T16:03:51Z","dateModified":"2025-12-30T16:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela en plena tensi\\u00f3n con EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/30\\\/chavismo-riquezas-aliados-tensiones-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/30\\\/chavismo-riquezas-aliados-tensiones-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-30T16:03:51Z\",\"datePublished\":\"2025-12-30T16:03:51Z\",\"dateModified\":\"2025-12-30T16:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467812,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/28\/venezuela-petroleo-riquezas-maduro-trump-orix\/","url_meta":{"origin":1469661,"position":0},"title":"Trump dijo que Maduro le ofreci\u00f3 petr\u00f3leo y otros recursos: \u00bfqu\u00e9 riquezas tiene Venezuela que podr\u00edan interesarle a EE.UU.?","author":"","date":"octubre 28, 2025","format":false,"excerpt":"\u201cHa ofrecido todo, \u00e9l ofreci\u00f3 todo\u201d, asegur\u00f3 d\u00edas atr\u00e1s el presidente de EE.UU., Donald Trump. El jefe de la Casa Blanca se refer\u00eda al mandatario de Venezuela, Nicol\u00e1s Maduro y los valiosos recursos naturales del pa\u00eds sudamericano, en medio de la tensi\u00f3n entre ambos pa\u00edses y la escalada militar en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469749,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/03\/chavismo-riquezas-aliados-tensiones-eeuu-historia-orix\/","url_meta":{"origin":1469661,"position":1},"title":"Historia, riquezas, rivales, aliados, armas y divisiones: esto debes saber sobre Venezuela tras el ataque de EE.UU.","author":"","date":"enero 3, 2026","format":false,"excerpt":"En una Am\u00e9rica Latina donde los gobiernos cambian con cada elecci\u00f3n y d\u00f3nde nada parecer durar, hubo una sola certeza en estos \u00faltimos 25 a\u00f1os: la Venezuela chavista \u2014y petrolera\u2014 y su constante enfrentamiento con Estados Unidos. \u00bfEs el fin del r\u00e9gimen chavista tras las acciones de EE.UU. y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469763,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/03\/venezuela-aislada-captura-maduro-fronteras-vuelos-orix\/","url_meta":{"origin":1469661,"position":2},"title":"\u00bfQu\u00e9 tan aislada est\u00e1 Venezuela tras la captura de Maduro? El estado de las fronteras y los vuelos","author":"","date":"enero 3, 2026","format":false,"excerpt":"A medida que la tensi\u00f3n escalaba durante los \u00faltimos meses entre Estados Unidos y Venezuela, el espacio a\u00e9reo del pa\u00eds sudamericano fue quedando cada vez m\u00e1s aislado. Ahora, con los ataques de EE.UU. en la madrugada del s\u00e1bado y la posterior captura del presidente Nicol\u00e1s Maduro, cientos de vuelos han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466119,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/09\/03\/venezolanos-exterior-cuestionan-tension-militar-eeuu-orix\/","url_meta":{"origin":1469661,"position":3},"title":"&#171;Nos usan como peones en su tablero pol\u00edtico&#187;: venezolanos en el exterior critican la escalada de tensi\u00f3n militar con EE.UU.","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"\u201cNos utilizan, algunos nos usan como peones en su tablero pol\u00edtico, y otros como un da\u00f1o colateral\u201d. As\u00ed resume Adelys Ferro el sentir de muchos venezolanos que emigraron de su pa\u00eds al ver la tensi\u00f3n creciente entre Venezuela y Estados Unidos, en medio de los gestos de guerra de Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468299,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/11\/13\/venezuela-rusia-acuerdo-cooperacion-tension-eeuu-efe\/","url_meta":{"origin":1469661,"position":4},"title":"Entra en vigor el Acuerdo de Asociaci\u00f3n Estrat\u00e9gica y Cooperaci\u00f3n entre Rusia y Venezuela","author":"","date":"noviembre 13, 2025","format":false,"excerpt":"El Acuerdo de Asociaci\u00f3n Estrat\u00e9gica y Cooperaci\u00f3n entre Rusia y Venezuela entr\u00f3 en vigor este mi\u00e9rcoles tras su promulgaci\u00f3n por ambos presidentes, seg\u00fan inform\u00f3 hoy el Portal de Informaci\u00f3n Legal del Estado ruso.Las dos c\u00e1maras del Parlamento ruso instaron esta semana a la comunidad internacional a condenar las \u201cacciones provocadoras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468823,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/11\/29\/eeuu-venezuela-crisis-aerea-tension-mas-aislada-orix\/","url_meta":{"origin":1469661,"position":5},"title":"Por la tensi\u00f3n con EE.UU., Venezuela enfrenta una crisis a\u00e9rea y queda a\u00fan m\u00e1s aislada","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Mientras recrudece la tensi\u00f3n por el despliegue militar de Estados Unidos en el Caribe, se complica cada vez m\u00e1s la situaci\u00f3n relacionada con el espacio a\u00e9reo de Venezuela.Este s\u00e1bado, el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a aerol\u00edneas, pilotos y redes criminales que consideraran el \u201cespacio a\u00e9reo sobre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1469661"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469661\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1469661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1469661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1469661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}