{"id":1469664,"date":"2025-12-30T10:03:50","date_gmt":"2025-12-30T18:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/"},"modified":"2025-12-30T10:03:50","modified_gmt":"2025-12-30T18:03:50","slug":"video-viral-despliegue-federal-fraude-guarderias-minnesota-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","title":{"rendered":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota"},"content":{"rendered":"<p>El FBI y el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) afirman que est\u00e1n desplegando recursos adicionales en Minnesota para investigar denuncias de fraude, incluso en guarder\u00edas infantiles, en la m\u00e1s reciente demostraci\u00f3n de fuerza federal en el estado, hogar de la mayor poblaci\u00f3n somal\u00ed del pa\u00eds.<\/p>\n<p>La investigaci\u00f3n se produce semanas despu\u00e9s de que ICE comenzara con operaciones en el \u00e1rea de Minneapolis-St. Paul dirigidas espec\u00edficamente a inmigrantes somal\u00edes indocumentados, a ra\u00edz de las revelaciones sobre un fraude generalizado contra el estado, as\u00ed como de los comentarios del presidente de EE.UU., Donald Trump, de que \u201cno quiere\u201d a somal\u00edes en el pa\u00eds.<\/p>\n<p>Esta campa\u00f1a intensificada tambi\u00e9n se produce pocos d\u00edas despu\u00e9s de que el creador de contenido de YouTube Nick Shirley, quien ha publicado videos antiinmigrantes y antimusulmanes en el pasado, publicara un video viral en el que afirmaba haber encontrado fraude generalizado en guarder\u00edas administradas por somal\u00edes. El video, que incluye pruebas limitadas de las acusaciones del creador, hab\u00eda recibido m\u00e1s de 1,5 millones de visitas en YouTube hasta el lunes por la noche y fue retuiteado por el vicepresidente de EE.UU., J. D. Vance, y el exdirector del Departamento de Eficiencia Gubernamental, Elon Musk.<\/p>\n<p>Un funcionario policial declar\u00f3 a CNN que el despliegue de agentes del DHS en Minneapolis el lunes, que incluy\u00f3 visitas a unos 30 negocios, se debi\u00f3 en parte al video.<\/p>\n<p>En respuesta <a href=\"https:\/\/x.com\/JDVance\/status\/2005041100860354975?s=20\">a una publicaci\u00f3n en X<\/a> sobre el presunto fraude, el vicepresidente de EE.UU., J. D. Vance, cada vez m\u00e1s a la vanguardia de la ret\u00f3rica antiinmigrante de la administraci\u00f3n, dijo: \u201cEst\u00e1n robando dinero y poder pol\u00edtico a los habitantes de Minnesota\u201d.<\/p>\n<p>El lunes, el DHS comenz\u00f3 a publicar videos que muestran a agentes de Investigaciones de Seguridad Nacional entrando en lo que denominaron \u201clugares sospechosos de fraude\u201d.<\/p>\n<p>Esto es lo que sabemos sobre las investigaciones y el video viral.<\/p>\n<p>Lo que las autoridades calificaron como un aumento de recursos federales se produce tras la viralizaci\u00f3n de un video de YouTube de Shirley, un joven, de 23 a\u00f1os, que se autodenomina periodista independiente y publica contenido en redes sociales con una inclinaci\u00f3n conservadora. En el video viral sobre un supuesto fraude en Minnesota, Shirley visita e intenta entrar en varios centros de cuidado infantil en Minnesota que, seg\u00fan \u00e9l, no est\u00e1n realmente operativos, aunque afirma que reciben financiaci\u00f3n gubernamental a trav\u00e9s de CCAP, un programa que proporciona fondos para el cuidado de ni\u00f1os a familias de bajos ingresos.<\/p>\n<p>Shirley no especifica los d\u00edas en que visit\u00f3 la mayor\u00eda de los centros que, seg\u00fan \u00e9l, estaban dirigidos por personas de origen somal\u00ed, limit\u00e1ndose a decir que visit\u00f3 uno al \u201cmediod\u00eda\u201d.<\/p>\n<p>CNN est\u00e1 investigando los centros identificados en el video y contact\u00f3 a varios de ellos. El video tambi\u00e9n muestra a Shirley escoltado fuera de un edificio por la Polic\u00eda tras reportes de que estaba invadiendo propiedad privada y acosando a personas.<\/p>\n<p>\u201cAunque tenemos preguntas sobre algunos de los m\u00e9todos utilizados en el video, s\u00ed tomamos muy en serio las preocupaciones que plantea sobre el fraude\u201d, dijo la comisionada del Departamento de Ni\u00f1ez, Juventud y Familias de Minnesota, Tikki Brown, en una conferencia de prensa el lunes, inform\u00f3 la afiliada de CNN, KARE.<\/p>\n<p>CNN se ha puesto en contacto con Shirley para obtener comentarios sobre el video.<\/p>\n<p>Un portavoz del gobernador de Minnesota, Tim Walz, dijo a CNN que dos de los centros que aparecen en el video estaban cerrados. Sin embargo, posteriormente un portavoz del Departamento de Ni\u00f1ez, Juventud y Familias de Minnesota aclar\u00f3 que uno de ellos \u2014Quality Learning Center\u2014 decidi\u00f3 finalmente permanecer abierto, seg\u00fan el Minnesota Star Tribune.<\/p>\n<p>Ibrahim Ali, gerente de Quality Learning Center, quien dijo que sus padres son due\u00f1os del lugar, declar\u00f3 a KARE el lunes que el video de Shirley se grab\u00f3 cuando el negocio estaba programado para estar cerrado. Un aviso en la puerta indica que el horario de atenci\u00f3n es de 2:00 p.m. a 10:00 p.m.<\/p>\n<p>\u201cNo hay ning\u00fan fraude en absoluto\u201d, dijo Ali a KARE.<\/p>\n<p>Uno de los aspectos m\u00e1s virales de la visita de Shirley a Quality Learning Center \u2014la palabra Learning mal escrita como \u201cLearing\u201d en el letrero\u2014 fue un error del fabricante del r\u00f3tulo y ya se est\u00e1 corrigiendo, dijo Ali.<\/p>\n<p>Una revisi\u00f3n estatal de licencias del negocio, realizada en junio, enumera varias infracciones \u2014incluida la falta de capacitaci\u00f3n requerida para parte del personal y documentaci\u00f3n inadecuada de medicamentos\u2014, pero nada que sugiera que el centro estuviera desocupado.<\/p>\n<p>El Departamento de Servicios Humanos del estado se\u00f1ala que los pagos del CCAP a guarder\u00edas pueden retenerse por fraude, pero no por \u201cviolaciones de licencia por s\u00ed solas\u201d.<\/p>\n<p>CNN intent\u00f3 comunicarse con Quality Learning Center el lunes a los n\u00fameros telef\u00f3nicos del negocio y del contacto listados en registros estatales, pero no obtuvo respuesta.<\/p>\n<p>No es inusual que las guarder\u00edas mantengan sus puertas cerradas o exijan una tarjeta de acceso por razones de seguridad, explic\u00f3 a CNN Clare Sanford, vicepresidenta de Relaciones Gubernamentales y Comunitarias de la Asociaci\u00f3n de Cuidado Infantil de Minnesota. Adem\u00e1s, dijo, la mayor\u00eda de los centros ser\u00eda especialmente cautelosa al permitir el ingreso de alguien que est\u00e9 filmando, por preocupaciones sobre la privacidad de los ni\u00f1os.<\/p>\n<p>Sanford a\u00f1adi\u00f3 que, aunque ser\u00eda inusual que un centro opere sin ning\u00fan ni\u00f1o, no es raro que funcionen por debajo de su capacidad oficial. Los fondos del CCAP \u2014el tipo de financiamiento que Shirley afirma que se estar\u00eda robando\u2014 se basan en los ni\u00f1os elegibles inscritos en un centro, no en su capacidad total.<\/p>\n<p>Las guarder\u00edas en Minnesota enfrentan regulaciones estrictas, dijo Sanford a CNN. Por ley, cada centro con licencia debe recibir al menos una visita anual sin previo aviso de un inspector, quien pasa horas revisando una lista de verificaci\u00f3n de unos 400 \u00edtems. Los centros reci\u00e9n abiertos enfrentan un escrutinio a\u00fan mayor como parte de un esfuerzo reciente para combatir el fraude: pueden esperar cuatro visitas en su primer a\u00f1o de operaci\u00f3n, tres de ellas sin previo aviso.<\/p>\n<p>El video no aborda esas regulaciones. Su impacto explosivo es un ejemplo del creciente poder del ecosistema medi\u00e1tico de derecha, impulsado en gran medida por creadores independientes a quienes el presidente ha favorecido sobre las redes tradicionales. Shirley fue invitado a la Casa Blanca en octubre para una mesa redonda con Trump sobre Antifa junto a otros creadores conservadores. Antes, film\u00f3 un video durante el asalto al Capitolio del 6 de enero de 2021, otro sobre \u201cestafadores inmigrantes deportados en Nueva York\u201d y una entrevista con la secretaria de Justicia de EE.UU., Pam Bondi.<\/p>\n<p>Whitney Phillips, profesora asociada de Pol\u00edtica de la Informaci\u00f3n y Medios en la Universidad de Oregon, dijo que le resulta \u201cdif\u00edcil imaginar\u201d que el FBI u otra agencia gubernamental bajo Trump desplegara recursos en una zona si un periodista independiente de izquierda hiciera acusaciones similares.<\/p>\n<p>Pero, agreg\u00f3, \u201cel Gobierno no est\u00e1 siendo dirigido hacia lugares a los que no quiera ir. Los influencers de derecha le dan al Gobierno una raz\u00f3n para hacer lo que ya planeaba hacer\u201d.<\/p>\n<p>Otros funcionarios del Gobierno, incluidos el Departamento de Trabajo, el secretario de Educaci\u00f3n y miembros del Congreso, tambi\u00e9n compartieron el video de Shirley en redes sociales.<\/p>\n<p>Un funcionario de las fuerzas del orden dijo a CNN que las investigaciones anunciadas el lunes se activaron en parte por el video y abarcan indagaciones tanto de inmigraci\u00f3n como de fraude.<\/p>\n<p>El domingo, el director del FBI, Kash Patel, dijo que la agencia ya hab\u00eda desplegado recursos en Minnesota incluso \u201cantes de que la conversaci\u00f3n p\u00fablica se intensificara en l\u00ednea\u201d.<\/p>\n<p>\u201cEl fraude que roba a los contribuyentes y perjudica a ni\u00f1os vulnerables seguir\u00e1 siendo una prioridad m\u00e1xima del FBI en Minnesota y en todo el pa\u00eds\u201d, escribi\u00f3 en una publicaci\u00f3n en X. \u201cEl FBI cree que esto es solo la punta de un iceberg muy grande. Seguiremos la pista del dinero y protegeremos a los ni\u00f1os, y esta investigaci\u00f3n sigue muy activa\u201d.<\/p>\n<p>Funcionarios del DHS tambi\u00e9n anunciaron su propia investigaci\u00f3n sobre presunto fraude.<\/p>\n<p>\u201cEl DHS est\u00e1 en el terreno en Minneapolis, yendo PUERTA POR PUERTA en sitios sospechosos de fraude\u201d, dijo la agencia en X, junto a un video de personas con chaquetas marcadas como \u201cPolice &#8211; HSI\u201d. \u201cEl pueblo estadounidense merece respuestas sobre c\u00f3mo se usa el dinero de los contribuyentes y ARRESTOS cuando se detecten abusos\u201d.<\/p>\n<p>Ninguna de las dos agencias dijo en sus publicaciones si se hab\u00edan realizado arrestos en esta m\u00e1s reciente ofensiva.<\/p>\n<p>Mientras tanto, el gobernador de Minnesota, Tim Walz, rechaz\u00f3 las acusaciones de que las autoridades estatales pasaron por alto el fraude. El gobernador \u201cha trabajado durante a\u00f1os para combatir el fraude y pidi\u00f3 a la Legislatura estatal m\u00e1s facultades para tomar acciones agresivas\u201d, dijo un portavoz a CNN.<\/p>\n<p>Cinco republicanos en la Legislatura estatal pidieron la renuncia de Walz.<\/p>\n<p>\u201cLa gente en nuestros distritos plantea este tema constantemente. Es el principal asunto del que escuchamos\u201d, dijeron en un comunicado este lunes. \u201cQuieren saber por qu\u00e9 nadie est\u00e1 rindiendo cuentas. Quieren saber cu\u00e1ndo alguien va a arreglar esto. Y quieren saber por qu\u00e9 el gobernador no renuncia\u201d.<\/p>\n<p>La presidenta de la C\u00e1mara de Representantes estatal, Lisa Demuth, dijo que la Comisi\u00f3n de Prevenci\u00f3n del Fraude ha investigado durante meses las acusaciones de fraude relacionadas con los fondos del CCAP.<\/p>\n<p>\u201cNadie ha perdido su empleo\u201d, dijo Demuth en una conferencia de prensa este lunes. \u201cNadie ha sido disciplinado p\u00fablicamente de ninguna manera\u201d.<\/p>\n<p>Las autoridades ya hab\u00edan apuntado antes al fraude en el estado, incluso en julio, cuando el FBI allan\u00f3 cinco empresas en las llamadas Ciudades Gemelas que presuntamente cometieron fraude en programas de asistencia de vivienda de Medicaid, seg\u00fan el Minnesota Star Tribune.<\/p>\n<p>Un fiscal federal dijo el 18 de diciembre que la mitad o m\u00e1s de los aproximadamente US$ 18.000 millones en fondos federales que respaldaron 14 programas administrados por Minnesota desde 2018 podr\u00edan haber sido robados, seg\u00fan The Associated Press. \u201cLa magnitud no puede subestimarse\u201d, dijo el primer fiscal federal adjunto Joe Thompson. \u201cLo que vemos en Minnesota no es un pu\u00f1ado de malos actores cometiendo delitos. Es un fraude industrial a gran escala, asombroso\u201d.<\/p>\n<p>Las investigaciones de amplio alcance sobre fraude contra el estado se basan en indagaciones previas sobre fraude relacionado con programas de alivio tras la pandemia de covid-19 durante el Gobierno de Biden.<\/p>\n<p>Gran parte de la indignaci\u00f3n por las acusaciones de fraude en la comunidad somal\u00ed se ha centrado en Feeding Our Future, una organizaci\u00f3n sin fines de lucro que, seg\u00fan los fiscales, afirm\u00f3 falsamente que proporcionaba comidas a ni\u00f1os necesitados durante la pandemia de covid-19. A partir de 2022, se presentaron cargos federales contra decenas de personas \u2014la gran mayor\u00eda de ellas somal\u00edes\u2014.<\/p>\n<p>Una serie de auditor\u00edas estatales sobre la falta de supervisi\u00f3n de fondos en Minnesota fue desestimada por Walz, un dem\u00f3crata, inform\u00f3 CNN el a\u00f1o pasado. Esto ocurri\u00f3 en medio de acusaciones de que el fuerte apoyo de la comunidad somal\u00ed \u2014y sus aportes\u2014 a los dem\u00f3cratas ayudaron a protegerla del escrutinio.<\/p>\n<p>Una investigaci\u00f3n inicial del Departamento de Educaci\u00f3n de Minnesota sobre presunto fraude por parte de Feeding Our Future se vio obstaculizada en parte por una demanda presentada por la organizaci\u00f3n y su fundadora, Aimee Bock \u2014quien no es somal\u00ed\u2014, en la que alegaba que la investigaci\u00f3n era discriminatoria. Posteriormente retir\u00f3 voluntariamente la demanda una semana despu\u00e9s de que agentes federales allanaran su casa y las oficinas de la organizaci\u00f3n.<\/p>\n<p>Bock fue luego condenada por siete cargos federales, incluido soborno. A\u00fan no ha sido sentenciada, pero un juez neg\u00f3 su solicitud de un nuevo juicio.<\/p>\n<p>Thompson, el fiscal federal principal del caso, dijo que las autoridades solo han recuperado unos US$ 60 millones de los US$ 250 millones robados en la conspiraci\u00f3n de Feeding Our Future, seg\u00fan AP.<\/p>\n<p>\u201cHe o\u00eddo que saquearon \u2014los somal\u00edes saquearon\u2014 a ese estado por miles de millones de d\u00f3lares\u201d, dijo Trump. \u201cMiles de millones. Cada a\u00f1o, miles de millones de d\u00f3lares, y no aportan nada\u201d.<\/p>\n<p>Las acusaciones de fraude \u2014que han derivado en m\u00e1s de 40 condenas solo en el caso de Feeding Our Future\u2014 se han convertido en un detonante de las invectivas de Trump contra los somal\u00edes. El presidente ha arremetido durante a\u00f1os contra la di\u00e1spora somal\u00ed de Minnesota, cuya gran mayor\u00eda son ciudadanos estadounidenses. Alrededor de 84.000 personas de origen somal\u00ed viven en el \u00e1rea de Minneapolis\u2013St. Paul, muchas de ellas reasentadas tras huir de una cruenta y prolongada guerra civil en su pa\u00eds de origen.<\/p>\n<p>La atenci\u00f3n de Trump hacia los inmigrantes somal\u00edes y los estadounidenses de ascendencia somal\u00ed se remonta a su primer mandato presidencial, cuando incluy\u00f3 a Somalia en un veto inmigratorio junto con otros pa\u00edses de mayor\u00eda musulmana.<\/p>\n<p>La representante de EE.UU. Ilhan Omar, ciudadana naturalizada que lleg\u00f3 al pa\u00eds desde Somalia como refugiada, ha sido un blanco frecuente de su enojo.<\/p>\n<p>A principios de diciembre, Trump dijo que Omar y \u201csus amigos\u201d no deber\u00edan poder servir como miembros del Congreso. Tambi\u00e9n calific\u00f3 a los somal\u00edes de Minnesota de \u201cbasura\u201d que deber\u00edan \u201cregresar a donde vinieron\u201d.<\/p>\n<p>\u201cCuando vienen del infierno, y se quejan y no hacen nada m\u00e1s que quejarse, no los queremos en nuestro pa\u00eds. Que regresen a donde vinieron y lo arreglen\u201d, dijo Trump en una reuni\u00f3n de gabinete este mes. El vicepresidente J. D. Vance golpe\u00f3 con fuerza la mesa de conferencias en se\u00f1al de apoyo.<\/p>\n<p>Los somal\u00edes y sus defensores, sin embargo, se\u00f1alan que el grupo condenado por fraude no representa a toda la comunidad.<\/p>\n<p>\u201cLa comunidad somal\u00ed en las Ciudades Gemelas est\u00e1 compuesta en su gran mayor\u00eda por familias trabajadoras, peque\u00f1os empresarios, personal de salud, estudiantes y contribuyentes que aportan todos los d\u00edas a la econom\u00eda y a la vida c\u00edvica de Minnesota\u201d, dijo a CNN por correo electr\u00f3nico Jaylani Hussein, director ejecutivo del cap\u00edtulo de Minnesota del Consejo de Relaciones Estadounidenses-Isl\u00e1micas.<\/p>\n<p>\u201cCuando se estigmatiza a toda una comunidad, el impacto es inmediato: las familias viven con miedo, los negocios se resienten y la confianza en las instituciones p\u00fablicas se erosiona\u201d.<\/p>\n<p>\u201cHay unas pocas manzanas podridas, ya sabes, que cometieron delitos y violaron la ley\u201d, dijo anteriormente a CNN Kamali Ali, de 39 a\u00f1os, quien lleg\u00f3 a EE.UU. desde Somalia cuando era ni\u00f1o, tras anunciarse el operativo de ICE dirigido a somal\u00edes. \u201cPero al mismo tiempo, no se puede aplicar un castigo colectivo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El FBI y el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) afirman que est\u00e1n desplegando recursos adicionales en Minnesota para investigar denuncias de fraude, incluso en guarder\u00edas infantiles, en la m\u00e1s reciente demostraci\u00f3n de fuerza federal en el estado, hogar de la mayor poblaci\u00f3n somal\u00ed del pa\u00eds. La investigaci\u00f3n se produce semanas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469664","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias\" \/>\n<meta property=\"og:description\" content=\"El FBI y el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) afirman que est\u00e1n desplegando recursos adicionales en Minnesota para investigar denuncias de fraude, incluso en guarder\u00edas infantiles, en la m\u00e1s reciente demostraci\u00f3n de fuerza federal en el estado, hogar de la mayor poblaci\u00f3n somal\u00ed del pa\u00eds. La investigaci\u00f3n se produce semanas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T18:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota\",\"datePublished\":\"2025-12-30T18:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\"},\"wordCount\":2563,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\",\"name\":\"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-30T18:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias","og_description":"El FBI y el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) afirman que est\u00e1n desplegando recursos adicionales en Minnesota para investigar denuncias de fraude, incluso en guarder\u00edas infantiles, en la m\u00e1s reciente demostraci\u00f3n de fuerza federal en el estado, hogar de la mayor poblaci\u00f3n somal\u00ed del pa\u00eds. La investigaci\u00f3n se produce semanas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-30T18:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/"},"author":{"name":"","@id":""},"headline":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota","datePublished":"2025-12-30T18:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/"},"wordCount":2563,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","name":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-30T18:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\u00edas en Minnesota","url":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2025\/12\/30\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-30T18:03:50Z","datePublished":"2025-12-30T18:03:50Z","dateModified":"2025-12-30T18:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Primero, un video viral. Luego, un despliegue federal para investigar un presunto fraude en guarder\\u00edas en Minnesota\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/30\\\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2025\\\/12\\\/30\\\/video-viral-despliegue-federal-fraude-guarderias-minnesota-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-30T18:03:50Z\",\"datePublished\":\"2025-12-30T18:03:50Z\",\"dateModified\":\"2025-12-30T18:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469786,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/04\/acoso-restaurante-somali-minneapolis-video-fraude-trax\/","url_meta":{"origin":1469664,"position":0},"title":"La comunidad somal\u00ed de Minneapolis se encuentra bajo asedio tras la difusi\u00f3n de un video viral en redes sociales","author":"","date":"enero 4, 2026","format":false,"excerpt":"El ambiente de hospitalidad en el restaurante Albi Kitchen, en Minneapolis, ha sido fracturado por el miedo. Fardowsa Ali, propietaria del establecimiento, denunci\u00f3 que el flujo constante de clientes que buscaban sus tradicionales sambusas ha desaparecido, siendo reemplazado por una ola de llamadas telef\u00f3nicas violentas y amenazas de vandalismo.La hostilidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473566,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/28\/redadas-minnesota-investigacion-fraude-trax\/","url_meta":{"origin":1469664,"position":1},"title":"Las fuerzas del orden federales realizan redadas en empresas en Minnesota en el marco de una investigaci\u00f3n por fraude","author":"","date":"abril 28, 2026","format":false,"excerpt":"Funcionarios federales est\u00e1n ejecutando \u00f3rdenes de registro en el \u00e1rea de Minneapolis relacionadas con una investigaci\u00f3n por fraude, seg\u00fan informaron este martes por la ma\u00f1ana el Departamento de Seguridad Nacional y un portavoz del Departamento de Justicia.\u201cHoy, el FBI, junto con las fuerzas del orden federales, estatales y locales, participa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469821,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","url_meta":{"origin":1469664,"position":2},"title":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo","author":"","date":"enero 6, 2026","format":false,"excerpt":"La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de 2.000 agentes federales en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales.Mientras, la ciudad y sus autoridades lidian con un esc\u00e1ndalo de fraude de asistencia social que ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469813,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/05\/trump-ofensiva-ice-minnesota-escandalo-fraude-trax\/","url_meta":{"origin":1469664,"position":3},"title":"Trump planea una gran ofensiva de control inmigratorio en Minnesota en medio de un esc\u00e1ndalo de fraude de asistencia social","author":"","date":"enero 5, 2026","format":false,"excerpt":"El Gobierno de Donald Trump est\u00e1 desplegando alrededor de 2.000 agentes federales en Minneapolis como parte de una ofensiva de control inmigratorio tras un esc\u00e1ndalo de fraude de asistencia social en Minnesota, seg\u00fan informaron dos funcionarios.Altos funcionarios de Trump se han enfocado en Minnesota y su comunidad somal\u00ed tras acusaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469741,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/02\/centros-cuidado-infantil-minnesota-acusados-irregularidades-informe-trax\/","url_meta":{"origin":1469664,"position":4},"title":"Centros de cuidado infantil de Minnesota acusados de irregularidades operaban seg\u00fan lo esperado, dice un informe","author":"","date":"enero 2, 2026","format":false,"excerpt":"Los centros de cuidado infantil de Minnesota en el centro de amplias acusaciones de fraude alimentadas por un video viral estaban operando seg\u00fan lo esperado cuando fueron visitados por investigadores, dijo el Departamento de Ni\u00f1os, J\u00f3venes y Familias (DCYF, por sus siglas en ingl\u00e9s) del estado en un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470305,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/20\/exclusivo-doj-fbi-investigar-funcionarios-minnesota-trax\/","url_meta":{"origin":1469664,"position":5},"title":"Exclusivo: Departamento de Justicia presion\u00f3 al FBI para investigar contribuciones de campa\u00f1a a funcionarios de Minnesota","author":"","date":"enero 20, 2026","format":false,"excerpt":"Altos funcionarios del Gobierno de Estados Unidos presionaron al FBI para investigar campa\u00f1as pol\u00edticas en Minnesota sobre si se beneficiaron ilegalmente de fraudes en organizaciones de servicios p\u00fablicos, de acuerdo con dos personas familiarizadas con las discusiones internas.Parte del inter\u00e9s del Gobierno, seg\u00fan una de las fuentes, proviene de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1469664"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1469664\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1469664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1469664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1469664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}