{"id":1472998,"date":"2026-04-09T08:03:46","date_gmt":"2026-04-09T15:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/"},"modified":"2026-04-09T08:03:46","modified_gmt":"2026-04-09T15:03:46","slug":"estudiante-proyectil-disparado-agente-los-angeles-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","title":{"rendered":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles"},"content":{"rendered":"<p>Un joven de 18 a\u00f1os fue presuntamente alcanzado por un proyectil disparado por un agente federal mientras asist\u00eda y documentaba una protesta el mes pasado, lo que provoc\u00f3 que el estudiante de primer a\u00f1o de la Universidad del Sur de California perdiera un ojo, seg\u00fan detall\u00f3 su abogado.<\/p>\n<p>Miles de personas, entre ellas Tucker Collins, participaron el 28 de marzo en manifestaciones bajo el lema \u201cNo Kings\u201d en todo el pa\u00eds, <a href=\"https:\/\/www.cnn.com\/2026\/03\/27\/us\/no-kings-protests\">protestando contra<\/a> las pol\u00edticas del presidente Donald Trump, <a href=\"https:\/\/www.cnn.com\/2026\/03\/23\/economy\/4-gallon-gas-economic-impact\">el aumento del costo de vida<\/a> y la <a href=\"https:\/\/www.cnn.com\/2026\/03\/28\/business\/diesel-trucking-iran-war\">guerra con Ir\u00e1n<\/a>.<\/p>\n<p>Collins fue alcanzado en su ojo derecho por un proyectil no letal disparado por un agente del Departamento de Seguridad Nacional (DHS) mientras documentaba la protesta frente al Centro de Detenci\u00f3n Metropolitano en Los \u00c1ngeles, \u201cdestruy\u00e9ndole el globo ocular y fractur\u00e1ndole los huesos de la \u00f3rbita ocular\u201d, seg\u00fan declar\u00f3 su abogado, V. James DeSimone, a CNN.<\/p>\n<p>Al pregunt\u00e1rsele sobre lo sucedido y por qu\u00e9 se dispar\u00f3 el proyectil, el DHS respondi\u00f3: \u201cLa Primera Enmienda protege la libertad de expresi\u00f3n y la reuni\u00f3n pac\u00edfica, no los disturbios\u201d.<\/p>\n<p>La agencia declar\u00f3 que \u201clos alborotadores arrojaron piedras, botellas y bloques de cemento a los agentes\u201d y que se emitieron siete advertencias antes de que se implementaran las medidas de control de multitudes. Seg\u00fan el DHS, tres manifestantes tambi\u00e9n fueron arrestados.<\/p>\n<p>\u201cEl DHS est\u00e1 tomando las medidas apropiadas y constitucionales para defender el estado de derecho y proteger a nuestros agentes y al p\u00fablico de los alborotadores peligrosos. Nuestros agentes del orden han seguido su entrenamiento y han utilizado la m\u00ednima fuerza necesaria para protegerse a s\u00ed mismos, al p\u00fablico y a la propiedad federal\u201d, dec\u00eda su comunicado.<\/p>\n<p>El DHS no respondi\u00f3 si la agencia le proporcion\u00f3 tratamiento o si ha estado en contacto con Collins desde su lesi\u00f3n.<\/p>\n<p>Collins sigui\u00f3 al grupo de manifestantes hasta el centro de detenci\u00f3n tras participar en la manifestaci\u00f3n local \u201cNo Kings\u201d en Los \u00c1ngeles, con la intenci\u00f3n de documentarla, dado su inter\u00e9s por la fotograf\u00eda y los cortometrajes, seg\u00fan declar\u00f3 DeSimone. Aunque la multitud de manifestantes y los agentes de la ley estaban separados por una alta barrera met\u00e1lica negra, y Collins se mantuvo alejado de la primera l\u00ednea de la protesta, aun as\u00ed recibi\u00f3 un impacto en el ojo, seg\u00fan afirm\u00f3 su abogado.<\/p>\n<p>Seg\u00fan DeSimone, una enfermera presente en la protesta le cur\u00f3 la herida. Collins fue trasladado al hospital, pero los m\u00e9dicos no pudieron salvarle el ojo y tuvieron que extirp\u00e1rselo quir\u00fargicamente.<\/p>\n<p>\u201cTucker sufri\u00f3 una lesi\u00f3n que le cambi\u00f3 la vida mientras documentaba una protesta, no mientras participaba en la violencia. Eso deber\u00eda alarmar a cualquiera que se preocupe por los derechos civiles, la libertad de prensa y la rendici\u00f3n de cuentas\u201d, dijo DeSimone en un comunicado. \u201cNo estaba amenazando a nadie. No estaba atacando a nadie\u201d.<\/p>\n<p>El estudiante de primer a\u00f1o de la USC estudia ingenier\u00eda astron\u00e1utica con una subespecializaci\u00f3n en artes cinematogr\u00e1ficas y, a pesar de su ceguera parcial, ha continuado con sus estudios durante su recuperaci\u00f3n, seg\u00fan DeSimone. Collins se est\u00e1 acostumbrando a leer con un solo ojo, lo que afecta su capacidad de estudio, pero \u201csigue decidido a intentarlo\u201d, afirm\u00f3 su abogado.<\/p>\n<p>\u201cTomar fotograf\u00edas no es un disturbio\u201d, dijo DeSimone. \u201cEso es una completa tonter\u00eda, y adem\u00e1s es una crueldad\u201d.<\/p>\n<p>Tras las protestas generalizadas contra las acciones del Servicio de Inmigraci\u00f3n y Control de Aduanas en Los \u00c1ngeles el verano pasado, un juez federal emiti\u00f3 una orden judicial preliminar en septiembre de 2025, que limitaba el uso excesivo de la fuerza por parte de los agentes federales. El Noveno Circuito confirm\u00f3 la decisi\u00f3n de emitir la orden judicial, pero la anul\u00f3 y la devolvi\u00f3 al tribunal inferior, argumentando que era demasiado amplia.<\/p>\n<p>Este incidente se produce tras una serie de casos en los que manifestantes resultaron heridos por agentes federales mientras protestaban contra los esfuerzos de Trump por deportar masivamente, incluyendo algunos en los que los manifestantes perdieron la vista, sufrieron fracturas de huesos y graves problemas respiratorios, entre otras lesiones.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/10\/us\/ice-federal-agents-less-lethal-weapons\">Un an\u00e1lisis de CNN de m\u00e1s de dos decenas de videos<\/a> de agentes federales utilizando armas menos letales, como aerosoles qu\u00edmicos, pistolas de bolas de pimienta y balas de goma, revel\u00f3 que los agentes violaban sistem\u00e1ticamente las pol\u00edticas de uso de la fuerza tanto federales como locales.<\/p>\n<p>El uso de la fuerza por parte de los agentes federales tambi\u00e9n ha sido motivo de controversia en la reforma federal, especialmente tras las <a href=\"https:\/\/www.cnn.com\/2026\/03\/24\/us\/minnesota-lawsuit-shooting-deaths\">muertes de Renee Good y Alex Pretti<\/a> en Minneapolis, Minnesota, a principios de este a\u00f1o. La disputa entre los funcionarios electos sobre c\u00f3mo reformar el DHS <a href=\"https:\/\/www.cnn.com\/2026\/04\/01\/politics\/dhs-shutdown-republican-leaders-plan\">ha provocado el cierre parcial del Gobierno m\u00e1s prolongado de la historia<\/a>.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/10\/us\/ice-federal-agents-less-lethal-weapons\">Las normas del Servicio de Aduanas y Protecci\u00f3n Fronteriza establecen<\/a> que las balas de pimienta y otros proyectiles no deben apuntarse a zonas vulnerables como la cabeza o la columna vertebral, a menos que est\u00e9 justificado el uso de fuerza letal.<\/p>\n<p>DeSimone, que planea presentar una demanda federal por da\u00f1os y perjuicios la pr\u00f3xima semana, pide a cualquier persona que haya presenciado el incidente o tenga informaci\u00f3n que se comunique con su oficina.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven de 18 a\u00f1os fue presuntamente alcanzado por un proyectil disparado por un agente federal mientras asist\u00eda y documentaba una protesta el mes pasado, lo que provoc\u00f3 que el estudiante de primer a\u00f1o de la Universidad del Sur de California perdiera un ojo, seg\u00fan detall\u00f3 su abogado. Miles de personas, entre ellas Tucker Collins, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472998","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un joven de 18 a\u00f1os fue presuntamente alcanzado por un proyectil disparado por un agente federal mientras asist\u00eda y documentaba una protesta el mes pasado, lo que provoc\u00f3 que el estudiante de primer a\u00f1o de la Universidad del Sur de California perdiera un ojo, seg\u00fan detall\u00f3 su abogado. Miles de personas, entre ellas Tucker Collins, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T15:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles\",\"datePublished\":\"2026-04-09T15:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\"},\"wordCount\":936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\",\"name\":\"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-09T15:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias","og_description":"Un joven de 18 a\u00f1os fue presuntamente alcanzado por un proyectil disparado por un agente federal mientras asist\u00eda y documentaba una protesta el mes pasado, lo que provoc\u00f3 que el estudiante de primer a\u00f1o de la Universidad del Sur de California perdiera un ojo, seg\u00fan detall\u00f3 su abogado. Miles de personas, entre ellas Tucker Collins, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-09T15:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/"},"author":{"name":"","@id":""},"headline":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles","datePublished":"2026-04-09T15:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/"},"wordCount":936,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","name":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-09T15:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \u00c1ngeles","url":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/estudiante-proyectil-disparado-agente-los-angeles-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-09T15:03:46Z","datePublished":"2026-04-09T15:03:46Z","dateModified":"2026-04-09T15:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estudiante pierde ojo tras ser alcanzado por proyectil disparado por un agente federal durante protesta en Los \\u00c1ngeles\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/estudiante-proyectil-disparado-agente-los-angeles-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/estudiante-proyectil-disparado-agente-los-angeles-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-09T15:03:46Z\",\"datePublished\":\"2026-04-09T15:03:46Z\",\"dateModified\":\"2026-04-09T15:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456827,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/12\/21\/proyectil-lanzado-yemen-alcanza-tel-aviv-jaffa-trax\/","url_meta":{"origin":1472998,"position":0},"title":"Un proyectil disparado desde Yemen alcanza Tel Aviv, seg\u00fan las autoridades israel\u00edes","author":"","date":"diciembre 21, 2024","format":false,"excerpt":"Un proyectil disparado desde Yemen alcanz\u00f3 Tel Aviv durante la madrugada de este s\u00e1bado, seg\u00fan informaron las autoridades israel\u00edes, en un raro caso de interceptaci\u00f3n fallida sobre la ciudad.El proyectil cay\u00f3 en la zona de Jaffa, en el sur de Tel Aviv, informaron las Fuerzas de Defensa de Israel, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472046,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/10\/mamdani-gracie-mansion-protesta-detenidos-trax\/","url_meta":{"origin":1472998,"position":1},"title":"Qui\u00e9nes son los dos acusados \u200b\u200bde lanzar bombas improvisadas cerca de la casa de Mamdani en Nueva York","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Este s\u00e1bado, dos hombres de Pensilvania siguieron la ruta de miles de personas al cruzar el puente George Washington hacia la ciudad de Nueva York. Pero menos de una hora despu\u00e9s, su trayectoria dio un giro sombr\u00edo al ser arrestados por lanzar bombas caseras durante una protesta antimusulmana frente a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461239,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/04\/15\/avion-israeli-bomba-cerca-comunidad-frontera-gaza-trax\/","url_meta":{"origin":1472998,"position":2},"title":"Avi\u00f3n israel\u00ed lanza bomba cerca de comunidad en la frontera con Gaza por &#171;falla t\u00e9cnica&#187;, seg\u00fan las FDI","author":"","date":"abril 15, 2025","format":false,"excerpt":"Un avi\u00f3n de combate israel\u00ed lanz\u00f3 una bomba cerca de una comunidad israel\u00ed en la frontera de Gaza el martes por la noche como resultado de lo que las Fuerzas de Defensa de Israel (FDI) llamaron un \u201cfallo t\u00e9cnico\u201d.La bomba cay\u00f3 cerca del kibutz Nir Yithzak, adyacente al sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470484,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/26\/dichos-funcionarios-trump-alex-pretti-trax\/","url_meta":{"origin":1472998,"position":3},"title":"Lo que dijeron los funcionarios de Trump sobre Alex Pretti, y lo que realmente muestran las pruebas","author":"","date":"enero 26, 2026","format":false,"excerpt":"Los altos funcionarios de la administraci\u00f3n del presidente Donald Trump han respondido a la muerte de Alex Pretti a manos de la Patrulla Fronteriza en Minneapolis el s\u00e1bado con una avalancha de afirmaciones que est\u00e1n contradichas por videos o no cuentan con pruebas presentadas hasta ahora.La secretaria de Seguridad Nacional,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473376,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/21\/victimas-tiroteo-teotihuacan-esto-sabemos-orix\/","url_meta":{"origin":1472998,"position":4},"title":"Una mujer fallecida y 13 personas heridas: lo que sabemos de las v\u00edctimas del tiroteo en Teotihuac\u00e1n","author":"","date":"abril 21, 2026","format":false,"excerpt":"Trece son las personas extranjeras que resultaron heridas en diversos grados durante el ataque con arma de fuego ocurrido en la ma\u00f1ana del lunes en la concurrida zona arqueol\u00f3gica de Teotihuac\u00e1n, en el Estado de M\u00e9xico. Se trata de tres ciudadanos colombianos \u2014entre ellos, un menor\u2014, seis estadounidenses, un hombre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467433,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/10\/16\/muerte-manifestante-protesta-peru-orix\/","url_meta":{"origin":1472998,"position":5},"title":"Muere un manifestante durante multitudinaria protesta en Per\u00fa contra el Gobierno y el Congreso","author":"","date":"octubre 16, 2025","format":false,"excerpt":"Al menos un manifestante muri\u00f3 presuntamente por un disparo de arma de fuego durante la multitudinaria protesta del mi\u00e9rcoles en Lima contra el Gobierno y el Congreso de Per\u00fa, seg\u00fan confirm\u00f3 la Defensor\u00eda del Pueblo, que tambi\u00e9n reporta m\u00e1s de 100 heridos, entre ellos 78 polic\u00edas y 24 manifestantes, as\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1472998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1472998"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1472998\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1472998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1472998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1472998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}