{"id":1472999,"date":"2026-04-09T09:04:01","date_gmt":"2026-04-09T16:04:01","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/"},"modified":"2026-04-09T09:04:01","modified_gmt":"2026-04-09T16:04:01","slug":"venezuela-economia-salario-minimo-pensionados-desafios-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","title":{"rendered":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez"},"content":{"rendered":"<p>El <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/08\/venezuela\/delcy-rodriguez-aumento-salarios-jovenes-regresen-orix\">anuncio<\/a> de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de un \u201cincremento responsable\u201d del salario m\u00ednimo en el pa\u00eds no estuvo acompa\u00f1ado por cifras concretas, sino con promesas que quedan matizadas por una realidad econ\u00f3mica dram\u00e1tica para los trabajadores y pensionados.<\/p>\n<p>Pese a una lenta recuperaci\u00f3n de la producci\u00f3n petrolera y al restablecimiento de relaciones con EE.UU., la situaci\u00f3n todav\u00eda no invita a volver a millones de personas que salieron al extranjero a buscar un mejor futuro.<\/p>\n<p>La mandataria dijo que el pr\u00f3ximo 1 de mayo, D\u00eda del Trabajador, detallar\u00e1 \u201cun incremento responsable\u201d de mejora del salario, que est\u00e1 congelado desde hace cuatro a\u00f1os y hoy se ubica en torno a los 130 bol\u00edvares, US$ 0,27, seg\u00fan la tasa de cambio oficial.<\/p>\n<p>En primer lugar, no est\u00e1 confirmado que el incremento vaya a ser para esa base y no en forma de bonos, que s\u00ed han aumentado en los \u00faltimos a\u00f1os.<\/p>\n<p>La Central Bolivariana Socialista de Trabajadores <a href=\"https:\/\/cbolivariana.org.ve\/2026\/03\/12\/cbst-presenta-propuesta-de-ingreso-salario-y-seguridad-social\/\">propuso<\/a> en marzo un ajuste trimestral de US$ 50, junto con bonos de US$ 100 para vacaciones y aguinaldos.<\/p>\n<p>\u201cEl anuncio es m\u00e1s de lo mismo\u201d, dijo a CNN el economista venezolano Andr\u00e9s Giussepe, director de la consultora Polidata. \u201cPareciera que fue para tratar de calmar la tensi\u00f3n social, con la movilizaci\u00f3n programada para hoy\u201d, convocada por gremios y estudiantes hacia el Palacio de Miraflores para exigir mejoras salariales, agreg\u00f3.<\/p>\n<p>El analista dijo que el Gobierno \u201cest\u00e1 entrampado\u201d por la falta de recursos y estim\u00f3 que el aumento podr\u00eda rondar los US$ 20. \u201cEn la pr\u00e1ctica, no es nada\u201d, asegur\u00f3, ya que la canasta b\u00e1sica familiar est\u00e1 en US$ 677, seg\u00fan el c\u00e1lculo de febrero del Centro de Documentaci\u00f3n y An\u00e1lisis Social de la Federaci\u00f3n Venezolana de Maestros. Adem\u00e1s, advirti\u00f3 que una reforma a la ley org\u00e1nica de trabajo, como piden algunas c\u00e1maras empresariales, ser\u00eda \u201cechar m\u00e1s le\u00f1a al problema social\u201d.<\/p>\n<p>La propia presidenta puso pa\u00f1os fr\u00edos durante su alocuci\u00f3n este mi\u00e9rcoles, al mencionar que un aumento desbocado acelerar\u00eda el aumento de precios. \u201cM\u00e1s ingresos al trabajador, realizados sin respaldo, disparan la inflaci\u00f3n y destruyen su poder de compra\u201d, dijo en la conferencia. El \u00edndice de precios al consumidor cerr\u00f3 2025 en 475 % y solo en los dos primeros meses de 2026 lleg\u00f3 al 51,9 %, seg\u00fan estad\u00edsticas oficiales.<\/p>\n<p>Entre otras cifras, Rodr\u00edguez reconoci\u00f3 que el PBI real de 2025, aunque considerablemente m\u00e1s alto que en 2020, es apenas el 36 % de lo que fue en 2012, a\u00f1o de bonanza petrolera.<\/p>\n<p>Rodr\u00edguez prometi\u00f3 que \u201cla recuperaci\u00f3n de activos y recursos bloqueados\u201d se destinar\u00e1n a rehabilitar la \u201cinfraestructura b\u00e1sica e inversi\u00f3n productiva que garantice ingresos suficientes para mejores pensiones e ingresos de los trabajadores\u201d.<\/p>\n<p>Para ello, es clave el aumento de la producci\u00f3n petrolera, que en febrero aument\u00f3 un 10 % y volvi\u00f3 a superar el mill\u00f3n de barriles diarios, seg\u00fan cifras divulgadas por la Organizaci\u00f3n de Pa\u00edses Exportadores de Petr\u00f3leo (OPEP). El Gobierno impuls\u00f3 y promulg\u00f3 una nueva ley de hidrocarburos, un legado del chavismo, para incentivar la inversi\u00f3n extranjera.<\/p>\n<p>Sin embargo, har\u00e1 falta mucho m\u00e1s que eso para aliviar el enorme desbalance del sistema previsional.<\/p>\n<p>\u201cHay m\u00e1s pensionados que cotizantes a las pensiones\u201d, reconoci\u00f3 el Gobierno, que estima 5,3 millones de trabajadores activos (la mayor\u00eda del sector p\u00fablico) y 5,7 millones de pensionados. Esa situaci\u00f3n lleva a que el estado est\u00e9 financiando el 91 % del pago de pensiones.<\/p>\n<p>\u201cAc\u00e1 le pagan US$ 30 o US$ 40 a los pensionados, la poblaci\u00f3n est\u00e1 muy afectada por inanici\u00f3n laboral\u201d, dijo Giussepe.<\/p>\n<p>Al sistema, que sufre los altos niveles de informalidad, tambi\u00e9n le impacta el congelamiento del salario, ya que los bonos no entran al c\u00e1lculo de aportes. Adem\u00e1s, en el sector privado, con una dolarizaci\u00f3n de facto, muchas empresas pagan parte de los sueldos por fuera de lo declarado.<\/p>\n<p>A eso se suma el \u00e9xodo de casi 8 millones de venezolanos en los \u00faltimos a\u00f1os, muchos de ellos en edad laboral, situaci\u00f3n que agrav\u00f3 el desbalance.<\/p>\n<p>Rodr\u00edguez tambi\u00e9n invoc\u00f3 a los migrantes a que regresen al pa\u00eds, remarcando la idea de una nueva etapa tras la captura del derrocado presidente Nicol\u00e1s Maduro. \u201cDebemos construir una nueva institucionalidad del Estado: un Estado digital, transparente, moderno, eficiente y profesional. Convoco a los j\u00f3venes a incorporarse a este esfuerzo, e invito a los que migraron buscando mejores opciones de vida\u201d, dijo la mandataria. Hasta ahora, las expectativas de muchos venezolanos que quisieran volver a su patria <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/27\/venezuela\/desvanece-expectativa-transicion-ruptura-chavismo-orix\">todav\u00eda est\u00e1n marcadas por el escepticismo<\/a>.<\/p>\n<p>Para el economista Giussepe, todav\u00eda no est\u00e1n dadas las condiciones para que la opci\u00f3n del retorno sea atractiva. \u201cNo van a venir sin una mejora salarial\u201d, asegur\u00f3. Entre otras medidas, dijo que es necesaria la reactivaci\u00f3n de cr\u00e9ditos a empresas y combatir la inflaci\u00f3n.<\/p>\n<p>\u201c\u00bfQu\u00e9 sentido tiene que traigas a dos millones de venezolanos si van a estar desempleados? Si llegan y tienes las m\u00e1quinas paradas, la situaci\u00f3n se complica. El est\u00edmulo de la industria es el consumo\u201d, explic\u00f3. \u201cNadie va a venir a pelear en una econom\u00eda informal\u201d, agreg\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El anuncio de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de un \u201cincremento responsable\u201d del salario m\u00ednimo en el pa\u00eds no estuvo acompa\u00f1ado por cifras concretas, sino con promesas que quedan matizadas por una realidad econ\u00f3mica dram\u00e1tica para los trabajadores y pensionados. Pese a una lenta recuperaci\u00f3n de la producci\u00f3n petrolera y al restablecimiento de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472999","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias\" \/>\n<meta property=\"og:description\" content=\"El anuncio de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de un \u201cincremento responsable\u201d del salario m\u00ednimo en el pa\u00eds no estuvo acompa\u00f1ado por cifras concretas, sino con promesas que quedan matizadas por una realidad econ\u00f3mica dram\u00e1tica para los trabajadores y pensionados. Pese a una lenta recuperaci\u00f3n de la producci\u00f3n petrolera y al restablecimiento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T16:04:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez\",\"datePublished\":\"2026-04-09T16:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\"},\"wordCount\":933,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\",\"name\":\"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-09T16:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias","og_description":"El anuncio de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de un \u201cincremento responsable\u201d del salario m\u00ednimo en el pa\u00eds no estuvo acompa\u00f1ado por cifras concretas, sino con promesas que quedan matizadas por una realidad econ\u00f3mica dram\u00e1tica para los trabajadores y pensionados. Pese a una lenta recuperaci\u00f3n de la producci\u00f3n petrolera y al restablecimiento de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-09T16:04:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/"},"author":{"name":"","@id":""},"headline":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez","datePublished":"2026-04-09T16:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/"},"wordCount":933,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","name":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-09T16:04:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una econom\u00eda por el suelo y con m\u00e1s pensionados que aportantes: los dram\u00e1ticos n\u00fameros detr\u00e1s del anuncio de Delcy Rodr\u00edguez","url":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/venezuela-economia-salario-minimo-pensionados-desafios-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-09T16:04:01Z","datePublished":"2026-04-09T16:04:01Z","dateModified":"2026-04-09T16:04:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una econom\\u00eda por el suelo y con m\\u00e1s pensionados que aportantes: los dram\\u00e1ticos n\\u00fameros detr\\u00e1s del anuncio de Delcy Rodr\\u00edguez\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/venezuela-economia-salario-minimo-pensionados-desafios-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/venezuela-economia-salario-minimo-pensionados-desafios-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-09T16:04:01Z\",\"datePublished\":\"2026-04-09T16:04:01Z\",\"dateModified\":\"2026-04-09T16:04:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472981,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/08\/delcy-rodriguez-aumento-salarios-jovenes-regresen-orix\/","url_meta":{"origin":1472999,"position":0},"title":"Delcy Rodr\u00edguez anuncia un aumento de salarios e insiste en llamado a que los jovenes migrantes regresen a Venezuela","author":"","date":"abril 8, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este mi\u00e9rcoles que a partir de 1 de mayo se aplicar\u00e1 un incremento salarial, aunque no detall\u00f3 el monto ni especific\u00f3 si se trata del salario m\u00ednimo, congelado desde marzo de 2022, o de otros ingresos que reciben los trabajadores p\u00fablicos.\u201cAnuncio que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473684,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/30\/delcy-rodriguez-incremento-ingreso-minimo-integral-orix\/","url_meta":{"origin":1472999,"position":1},"title":"Delcy Rodr\u00edguez anuncia incremento del ingreso m\u00ednimo integral a US$ 240, en medio de reclamos por la econom\u00eda de Venezuela","author":"","date":"abril 30, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este jueves que el ingreso m\u00ednimo integral en el pa\u00eds aumentar\u00e1 a unos US$ 240 mensuales, en medio de reclamos de muchos ciudadanos sobre que la econom\u00eda del pa\u00eds sigue sin mejorar significativamente tras la captura del derrocado presidente Nicol\u00e1s Maduro.Rodr\u00edguez hizo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473031,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/10\/marcha-venezuela-trabajadores-salario-bloqueo-policial-efe\/","url_meta":{"origin":1472999,"position":2},"title":"Volvieron las marchas a las calles de Venezuela y tambi\u00e9n el bloqueo policial","author":"","date":"abril 10, 2026","format":false,"excerpt":"Un fuerte cerco de la Polic\u00eda Nacional Bolivariana (PNB) de Venezuela bloque\u00f3 y dispers\u00f3 con gas pimienta a cientos de trabajadores que intentaban marchan este jueves hacia el palacio presidencial de Miraflores, en el centro de Caracas, para exigir un aumento de salario, congelado desde 2022.En su intento por llegar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473204,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/15\/eeuu-sanciones-banco-central-venezuela-delcy-orix\/","url_meta":{"origin":1472999,"position":3},"title":"EE.UU. alivi\u00f3 las sanciones al Banco Central de Venezuela. \u00bfPor qu\u00e9 es una medida clave para la gesti\u00f3n de Delcy Rodr\u00edguez?","author":"","date":"abril 15, 2026","format":false,"excerpt":"El levantamiento parcial de las sanciones de EE.UU. sobre bancos de Venezuela es una medida clave para la estabilizaci\u00f3n de la econom\u00eda del pa\u00eds en un momento en que algunos indicadores permanecen fuera de control, seg\u00fan analistas que destacaron que la decisi\u00f3n debe estar acompa\u00f1ada por reformas fiscales que permitan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472225,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/15\/delcy-rodriguez-venta-fueloil-300-millones-rechaza-propuesta-petro-arancel-cero-orix\/","url_meta":{"origin":1472999,"position":4},"title":"Delcy Rodriguez anuncia venta de fueloil por US$ 300 millones y rechaza propuesta de Petro sobre arancel cero","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 el ingreso de US$ 300 millones a un fondo reci\u00e9n creado para la \u201cprotecci\u00f3n social\u201d, recursos que se obtuvieron a partir de una \u201cventa extraordinaria\u201d de fueloil, un combustible derivado del petr\u00f3leo.Durante un acto transmitido por el canal estatal Venezolana de Televisi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470384,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/01\/22\/delcy-rodriguez-consulta-popular-ley-petrolera-venezuela-orix\/","url_meta":{"origin":1472999,"position":5},"title":"Delcy Rodr\u00edguez lanza una consulta popular de econom\u00eda y pone en marcha el debate para reformar la ley petrolera en Venezuela","author":"","date":"enero 22, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 que se realizar\u00e1 una consulta popular el 8 de marzo \u201cpara elegir proyectos de las transformaciones y producci\u00f3n, y ciudad humana, infraestructura, obras y servicios\u201d y puso en marcha una serie de reformas legislativas destinadas a abrir la econom\u00eda.El anunci\u00f3 se dio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1472999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1472999"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1472999\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1472999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1472999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1472999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}