{"id":1473010,"date":"2026-04-09T15:04:03","date_gmt":"2026-04-09T22:04:03","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/"},"modified":"2026-04-09T15:04:03","modified_gmt":"2026-04-09T22:04:03","slug":"rescate-minero-sinaloa-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","title":{"rendered":"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa"},"content":{"rendered":"<p>A las 13:50 del martes, hora local de M\u00e9xico, y luego de 13 d\u00edas atrapado, Francisco Zapata N\u00e1jera, de 42 a\u00f1os, fue localizado con vida dentro de la mina en el municipio de El Rosario, Sinaloa.<\/p>\n<p>El siguiente di\u00e1logo entre los buzos del Batall\u00f3n de Atenci\u00f3n de Emergencias del Ej\u00e9rcito mexicano y Francisco qued\u00f3 registrado en un video que grabaron los rescatistas y fue dado<a href=\"https:\/\/x.com\/Defensamx1\/status\/2042084285130170482\"> a conocer<\/a> este jueves la Secretar\u00eda de Defensa Nacional de M\u00e9xico:<\/p>\n<p>\u2014\u00bfC\u00f3mo te llamas?<\/p>\n<p>\u2014Francisco Zapata N\u00e1jera.<\/p>\n<p>\u2014Muy bien, Zapata, venimos a tu ayuda.<\/p>\n<p>\u2014\u00bfC\u00f3mo te sientes?<\/p>\n<p>\u2014Bien.<\/p>\n<p>\u2014Muy bien, Zapata, todo va a estar bien. Te vamos a sacar de aqu\u00ed.<\/p>\n<p>En el video se ve que el personal militar le cuenta a Zapata algunos pormenores de su b\u00fasqueda antes de proceder con el rescate. Mientras tanto \u00e9l, a quien se lo ve con el agua a la cintura, sin camiseta y con un casco rojo, apenas alumbrado por la luz de algunas linternas, responde a las preguntas de al menos dos rescatistas. El agua \u201clleg\u00f3 ac\u00e1 hasta arriba, hasta all\u00e1\u201d, dice el minero al se\u00f1alar en direcci\u00f3n ascendente parte del lugar donde sobrevivi\u00f3 durante casi 14 d\u00edas.<\/p>\n<p>Cuando se registr\u00f3 ese di\u00e1logo, Zapata hab\u00eda pasado m\u00e1s de 300 horas atrapado en la mina \u201cMinerales de Sinaloa\u201d, luego de un derrumbe ocurrido el 25 de marzo pasado.<\/p>\n<p>Cuatro mineros, inclu\u00eddo \u00e9l, quedaron atrapados luego del incidente y tres ya fueron localizados: antes de Zapata, un primer minero que fue rescatado el 30 de marzo, y otro minero que fue hallado sin vida, dijeron las autoridades mexicanas.<\/p>\n<p>Oriundo <a href=\"https:\/\/www.gob.mx\/sspc\/prensa\/rescatan-al-minero-francisco-zapata-najera?idiom=es\">de Santiago Papasquiaro, Durango<\/a><strong>,<\/strong> Zapata fue localizado el martes por un equipo de buzos de rescate. Pero su salida de la mina ocurri\u00f3 el mi\u00e9rcoles a las 10:36, cerca de 24 horas m\u00e1s tarde, momento en las que los equipos llevaron adelante operaciones de bombeo para disminuir el nivel de agua del lugar donde estaba el hombre para lograr sacarlo.<\/p>\n<p>Entre martes y mi\u00e9rcoles, personal militar rescatista realiz\u00f3 inmersiones en la mina para darle alimentos, agua y ox\u00edgeno al minero, a quien luego extrajeron hacia la entrada de la mina, explic\u00f3 la  Secretar\u00eda de Defensa Nacional en un comunicado.<\/p>\n<p>El hombre ten\u00eda \u201c\u00fanicamente signos de deshidrataci\u00f3n\u201d, y luego de salir a la superficie fue atendido por personal param\u00e9dico que procedi\u00f3 a su estabilizaci\u00f3n inmediata. Luego fue trasladado en un helic\u00f3ptero de la Fuerza A\u00e9rea mexicana hacia el Hospital General de Mazatl\u00e1n, donde recibi\u00f3 atenci\u00f3n m\u00e9dica.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, confirm\u00f3 la noticia el mi\u00e9rcoles en <a href=\"https:\/\/www.gob.mx\/presidencia\/articulos\/version-estenografica-conferencia-de-prensa-de-la-presidenta-claudia-sheinbaum-pardo-del-08-de-abril-de-2026?idiom=es\">su habitual conferencia de prensa<\/a> y asegur\u00f3 que las tareas de rescate \u201cno pararon\u201d desde el primer momento.<\/p>\n<p>\u201c13 d\u00edas permaneci\u00f3 en este lugar e incre\u00edblemente y afortunadamente se encontr\u00f3 con vida\u201d, dijo Sheinbaum sobre Zapata. La mandataria de M\u00e9xico agreg\u00f3 que a\u00fan los cuerpos de rescate buscan localizar al cuarto minero.<\/p>\n<p>En la mina contin\u00faan los trabajos de desalojo de agua y de lajes, dijo la secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de M\u00e9xico <a href=\"https:\/\/www.gob.mx\/sspc\/prensa\/rescatan-al-minero-francisco-zapata-najera?idiom=es%7D\">en un comunicado<\/a>. \u201cEl equipo t\u00e9cnico y humano mantiene sus operaciones en el sitio con el firme compromiso de localizar al \u00faltimo trabajador\u201d, asegur\u00f3 el Gobierno mexicano.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las 13:50 del martes, hora local de M\u00e9xico, y luego de 13 d\u00edas atrapado, Francisco Zapata N\u00e1jera, de 42 a\u00f1os, fue localizado con vida dentro de la mina en el municipio de El Rosario, Sinaloa. El siguiente di\u00e1logo entre los buzos del Batall\u00f3n de Atenci\u00f3n de Emergencias del Ej\u00e9rcito mexicano y Francisco qued\u00f3 registrado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473010","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Te vamos a sacar de aqu\u00ed&quot;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Te vamos a sacar de aqu\u00ed&quot;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias\" \/>\n<meta property=\"og:description\" content=\"A las 13:50 del martes, hora local de M\u00e9xico, y luego de 13 d\u00edas atrapado, Francisco Zapata N\u00e1jera, de 42 a\u00f1os, fue localizado con vida dentro de la mina en el municipio de El Rosario, Sinaloa. El siguiente di\u00e1logo entre los buzos del Batall\u00f3n de Atenci\u00f3n de Emergencias del Ej\u00e9rcito mexicano y Francisco qued\u00f3 registrado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T22:04:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa\",\"datePublished\":\"2026-04-09T22:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\"},\"wordCount\":594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\",\"name\":\"\\\"Te vamos a sacar de aqu\u00ed\\\". Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-09T22:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Te vamos a sacar de aqu\u00ed\". Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"Te vamos a sacar de aqu\u00ed\". Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias","og_description":"A las 13:50 del martes, hora local de M\u00e9xico, y luego de 13 d\u00edas atrapado, Francisco Zapata N\u00e1jera, de 42 a\u00f1os, fue localizado con vida dentro de la mina en el municipio de El Rosario, Sinaloa. El siguiente di\u00e1logo entre los buzos del Batall\u00f3n de Atenci\u00f3n de Emergencias del Ej\u00e9rcito mexicano y Francisco qued\u00f3 registrado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-09T22:04:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa","datePublished":"2026-04-09T22:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/"},"wordCount":594,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","name":"\"Te vamos a sacar de aqu\u00ed\". Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-09T22:04:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/09\/rescate-minero-sinaloa-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Te vamos a sacar de aqu\u00ed&#187;. Luego de 13 d\u00edas atrapado, as\u00ed fue el rescate de un minero en Sinaloa","url":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/rescate-minero-sinaloa-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/09\/rescate-minero-sinaloa-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-09T22:04:03Z","datePublished":"2026-04-09T22:04:03Z","dateModified":"2026-04-09T22:04:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Te vamos a sacar de aqu\\u00ed&#187;. Luego de 13 d\\u00edas atrapado, as\\u00ed fue el rescate de un minero en Sinaloa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/rescate-minero-sinaloa-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/09\\\/rescate-minero-sinaloa-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-09T22:04:03Z\",\"datePublished\":\"2026-04-09T22:04:03Z\",\"dateModified\":\"2026-04-09T22:04:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1434550,"url":"https:\/\/noticiasya.com\/el-paso\/2022\/10\/27\/cbp-entregan-premio-al-joven-del-mes-de-agosto-y-septiembre\/","url_meta":{"origin":1473010,"position":0},"title":"CBP entrega premio al joven del mes de agosto y septiembre","author":"agomez","date":"octubre 27, 2022","format":false,"excerpt":"La entrega se realiz\u00f3 el 21 de octubre, ambos estudiantes de \u00faltimo a\u00f1o de la preparatoria Zapata.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447033,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/03\/16\/matan-alcalde-estado-jalisco-orix\/","url_meta":{"origin":1473010,"position":1},"title":"Matan a un alcalde de una comunidad del estado mexicano de Jalisco","author":"agomez","date":"marzo 16, 2024","format":false,"excerpt":"(CNN) --\u00a0\u00a0El gobernador de Jalisco, Enrique Alfaro, inform\u00f3 este s\u00e1bado en su cuenta de la red social\u00a0 X,\u00a0 lo que calific\u00f3 de \"asesinato de Humberto Amezcua, el alcalde con licencia de Pihuamo\".Alfaro agreg\u00f3 que se trat\u00f3 de un presunto ataque directo y que la investigaci\u00f3n \"no cesar\u00e1 hasta dar con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462786,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/05\/25\/arrestan-alias-chucky-homicidio-sara-millerey-orix\/","url_meta":{"origin":1473010,"position":2},"title":"Arrestan en Colombia a un segundo hombre presuntamente implicado en el homicidio de Sara Millerey","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Un segundo hombre presuntamente involucrado en el homicidio de Sara Millerey, una mujer trans cuya muerte gener\u00f3 indignaci\u00f3n en Colombia, fue arrestado en el municipio de Bello, departamento de Antioquia, inform\u00f3 el director general de la Polic\u00eda Nacional Carlos Triana Beltr\u00e1n el domingo en su cuenta de X.Beltr\u00e1n identific\u00f3 al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455945,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/11\/20\/revolucion-mexicana-20-noviembre-historia-origen-orix\/","url_meta":{"origin":1473010,"position":3},"title":"\u00bfPor qu\u00e9 se celebra el 20 de noviembre la Revoluci\u00f3n mexicana? \u00bfCu\u00e1l es su origen?","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"El 20 de noviembre, desde las seis de la tarde en adelante, todos los ciudadanos de la Rep\u00fablica tomar\u00e1n las armas para arrojar del poder a las autoridades que actualmente nos gobiernan\". Este llamado de Francisco I. Madero marca lo que se considera como el inicio oficial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443408,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/09\/fuga-de-alias-fito-lider-de-una-banda-criminal-de-ecuador-tensa-la-seguridad-mientras-se-intensifica-su-busqueda\/","url_meta":{"origin":1473010,"position":4},"title":"Fuga de alias \u201cFito\u201d, l\u00edder de una banda criminal de Ecuador, tensa la seguridad mientras se intensifica su b\u00fasqueda","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Luego de que la Fiscal\u00eda y el Gobierno de Ecuador confirmaran el domingo la fuga de Adolfo Mac\u00edas, alias \u201cFito\u201d, de la c\u00e1rcel regional de Guayaquil, m\u00e1s de 3.000 integrantes de la Polic\u00eda y las Fuerzas Armadas se han desplegado para dar con su paradero, seg\u00fan el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448378,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/04\/22\/recaptura-fabricio-colon-pico-ecuador-orix\/","url_meta":{"origin":1473010,"position":5},"title":"As\u00ed fue la recaptura de Fabricio Col\u00f3n Pico, el sospechoso de maquinar un supuesto plan para matar a la fiscal de Ecuador","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Polic\u00eda de Ecuador y el Ministerio del Interior dieron detalles este lunes de c\u00f3mo fue la recaptura de Fabricio Col\u00f3n Pico, alias \u201cCapit\u00e1n Pico\u201d, uno de los presuntos cabecillas de la banda de Los Lobos y sospechoso de liderar un supuesto plan para matar a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1473010"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473010\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1473010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1473010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1473010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}