{"id":1473027,"date":"2026-04-10T05:03:49","date_gmt":"2026-04-10T12:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/"},"modified":"2026-04-10T05:03:49","modified_gmt":"2026-04-10T12:03:49","slug":"trump-video-explicito-mortal-ataque-florida-inmigracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","title":{"rendered":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n"},"content":{"rendered":"<p>Un hombre haitiano indocumentado ha sido acusado de homicidio tras golpear repetidamente a una mujer la semana pasada con un martillo frente a una tienda de conveniencia en Florida, en el caso m\u00e1s reciente relacionado con inmigraci\u00f3n que ha acaparado la atenci\u00f3n nacional gracias al presidente Donald Trump.<\/p>\n<p>Rolbert Joachin, de 40 a\u00f1os, se encuentra bajo custodia y est\u00e1 acusado por las autoridades de haber matado a la mujer, cuya identidad no ha sido revelada p\u00fablicamente, durante un incidente en una gasolinera de Fort Myers el 2 de abril, seg\u00fan documentos judiciales.<\/p>\n<p>De acuerdo con los documentos, la v\u00edctima trabajaba como dependienta en la gasolinera. Un hombre que la conoc\u00eda declar\u00f3 a <a href=\"https:\/\/www.gulfcoastnewsnow.com\/article\/fort-myers-community-mourns-mother-killed-gas-station\/70930881\">WBBH, afiliada de CNN,<\/a> que ella pertenec\u00eda a la comunidad banglades\u00ed de Fort Myers.<\/p>\n<p>En una <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/116377422440266990\">publicaci\u00f3n<\/a> en Truth Social el jueves por la noche, Trump comparti\u00f3 im\u00e1genes de vigilancia impactantes de la agresi\u00f3n, calific\u00e1ndola como resultado de las pol\u00edticas inmigratorias del expresidente Joe Biden y reiterando su ret\u00f3rica incendiaria que asocia a los indocumentados con la delincuencia.<\/p>\n<p>La difusi\u00f3n del video por parte de Trump es el \u00faltimo episodio de una campa\u00f1a que lleva a\u00f1os utilizando ciertos cr\u00edmenes como supuesta evidencia para reforzar la vigilancia fronteriza.<\/p>\n<p>\u201cEl video de su brutal asesinato es una de las cosas m\u00e1s crueles que jam\u00e1s ver\u00e1n\u201d, manifest\u00f3 Trump en su publicaci\u00f3n, refiri\u00e9ndose al sospechoso como un \u201canimal\u201d y criticando las protecciones humanitarias otorgadas anteriormente a los haitianos.<\/p>\n<p>Unas im\u00e1genes espeluznantes de la interacci\u00f3n, tambi\u00e9n compartidas en l\u00ednea por el Departamento de Seguridad Nacional, muestran a un hombre golpeando repetidamente el cap\u00f3 y los laterales de un coche aparcado en el estacionamiento de la gasolinera con un objeto, aparentemente un martillo, que sosten\u00eda en la mano.<\/p>\n<p>En el video, se ve a una mujer salir de la tienda y acercarse al hombre, aparentemente para hablar con \u00e9l. El hombre se da la vuelta y camina hacia ella, seg\u00fan se aprecia en las im\u00e1genes, que luego aparecen ligeramente borrosas debido a la crudeza del ataque.<\/p>\n<p>Inmediatamente, golpea a la mujer en la cabeza con el objeto que sostiene en su mano derecha, provocando que caiga hacia atr\u00e1s sobre la acera de la tienda. Luego se le ve golpe\u00e1ndola otras seis veces en la cabeza y el torso antes de pasar por encima de su cuerpo y alejarse del lugar.<\/p>\n<p>La polic\u00eda recibi\u00f3 llamadas alrededor de las 7:19 de la ma\u00f1ana informando que una mujer hab\u00eda sido golpeada con un martillo, seg\u00fan consta en los documentos judiciales.<\/p>\n<p>Cuando varios agentes llegaron al lugar, encontraron a la mujer inconsciente, tendida en el suelo y sin respirar, recogen los mismos documentos.<\/p>\n<p>De acuerdo con los documentos, gracias al video de vigilancia, las autoridades identificaron al sospechoso, que ten\u00eda antecedentes policiales, y pudieron arrestarlo ese mismo d\u00eda.<\/p>\n<p>Seg\u00fan los documentos judiciales, el sospechoso ha sido acusado de homicidio, vandalismo y da\u00f1os a la propiedad por un valor superior a US$ 1.000, un delito grave de tercer grado.<\/p>\n<p>CNN se ha puesto en contacto con los abogados de Joaqu\u00edn.<\/p>\n<p>El hombre permanece detenido sin derecho a fianza tras una audiencia celebrada el mi\u00e9rcoles en el tribunal del condado de Lee y est\u00e1 previsto que comparezca ante el juez el 4 de mayo.<\/p>\n<p>Seg\u00fan WBBH, se ha erigido un monumento conmemorativo frente a la gasolinera donde falleci\u00f3 la mujer. Sus amigos y familiares la describieron como una madre cari\u00f1osa y devota de su fe.<\/p>\n<p>\u201cAhora mismo, todo el mundo est\u00e1 triste\u2026 no solo yo, no solo mi comunidad banglades\u00ed\u201d, declar\u00f3 MD Islam, miembro de la comunidad de ese pa\u00eds en Fort Myers, a WBBH. \u201cTambi\u00e9n todos nosotros, en todo el mundo. Estamos muy tristes al ver esta noticia\u201d.<\/p>\n<p>En un <a href=\"https:\/\/www.dhs.gov\/news\/2026\/04\/07\/haitian-illegal-alien-violently-kills-innocent-mother-repeatedly-hitting-her-hammer\">comunicado emitido<\/a> el martes, el Departamento de Seguridad Nacional (DHS) inform\u00f3 que agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) ayudaron a la polic\u00eda de Fort Myers a localizar y arrestar a Joaqu\u00edn en la ciudad.<\/p>\n<p>Seg\u00fan el DHS, Joaqu\u00edn entr\u00f3 por primera vez a Estados Unidos en agosto de 2022.<\/p>\n<p>Un juez federal emiti\u00f3 una orden definitiva de expulsi\u00f3n en su contra ese mismo a\u00f1o, pero el Gobierno le concedi\u00f3 el Estatus de Protecci\u00f3n Temporal, que expir\u00f3 en 2024, inform\u00f3 la agencia.<\/p>\n<p>\u201cLa administraci\u00f3n Biden le otorg\u00f3 a \u00e9l, y a todos los haitianos, el \u201cEstatus de Protecci\u00f3n Temporal\u201d, un programa fraudulento y objeto de abusos masivos que mi administraci\u00f3n est\u00e1 trabajando para eliminar\u201d, escribi\u00f3 Trump en su publicaci\u00f3n del jueves.<\/p>\n<p>\u201cEste asesinato deber\u00eda ser suficiente para que estos jueces radicales dejen de obstaculizar las pol\u00edticas inmigratorias de mi administraci\u00f3n y nos permitan acabar con esta estafa de una vez por todas\u201d, agreg\u00f3.<\/p>\n<p>La administraci\u00f3n Trump lleva tiempo intentando poner fin a la protecci\u00f3n de m\u00e1s de 350.000 haitianos, pero sus <a href=\"https:\/\/www.cnn.com\/2026\/02\/02\/politics\/tps-haitians-trump-termination-blocked\">esfuerzos fueron bloqueados<\/a> a principios de este a\u00f1o por un juez federal despu\u00e9s de que los demandantes argumentaran que el Departamento de Seguridad Nacional no realiz\u00f3 la revisi\u00f3n necesaria para determinar si era seguro para ellos regresar a Hait\u00ed.<\/p>\n<p>Desde entonces, la administraci\u00f3n ha <a href=\"https:\/\/www.cnn.com\/2026\/03\/11\/politics\/trump-asks-supreme-court-to-let-protections-for-haitians-expire\" rel=\"noopener noreferrer\" target=\"_blank\">solicitado a la Corte Suprema que intervenga<\/a> en su favor.<\/p>\n<p>En su publicaci\u00f3n en Truth Social, Trump continu\u00f3 acusando a los dem\u00f3cratas de permitir que \u201ccriminales, lun\u00e1ticos y enfermos mentales de todo el mundo entren en nuestro pa\u00eds sin ning\u00fan tipo de control ni verificaci\u00f3n\u201d.<\/p>\n<p>\u201cPor favor, recen por la familia de esta mujer inocente\u201d, escribi\u00f3 en relaci\u00f3n con el crimen. \u201c\u00a1Nos aseguraremos de que se haga justicia de forma r\u00e1pida y contundente en este caso!\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre haitiano indocumentado ha sido acusado de homicidio tras golpear repetidamente a una mujer la semana pasada con un martillo frente a una tienda de conveniencia en Florida, en el caso m\u00e1s reciente relacionado con inmigraci\u00f3n que ha acaparado la atenci\u00f3n nacional gracias al presidente Donald Trump. Rolbert Joachin, de 40 a\u00f1os, se encuentra [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473027","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un hombre haitiano indocumentado ha sido acusado de homicidio tras golpear repetidamente a una mujer la semana pasada con un martillo frente a una tienda de conveniencia en Florida, en el caso m\u00e1s reciente relacionado con inmigraci\u00f3n que ha acaparado la atenci\u00f3n nacional gracias al presidente Donald Trump. Rolbert Joachin, de 40 a\u00f1os, se encuentra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T12:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n\",\"datePublished\":\"2026-04-10T12:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\"},\"wordCount\":1013,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\",\"name\":\"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-10T12:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias","og_description":"Un hombre haitiano indocumentado ha sido acusado de homicidio tras golpear repetidamente a una mujer la semana pasada con un martillo frente a una tienda de conveniencia en Florida, en el caso m\u00e1s reciente relacionado con inmigraci\u00f3n que ha acaparado la atenci\u00f3n nacional gracias al presidente Donald Trump. Rolbert Joachin, de 40 a\u00f1os, se encuentra [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-10T12:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/"},"author":{"name":"","@id":""},"headline":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n","datePublished":"2026-04-10T12:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/"},"wordCount":1013,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","name":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-10T12:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump publica video expl\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\u00f3n","url":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/10\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-10T12:03:49Z","datePublished":"2026-04-10T12:03:49Z","dateModified":"2026-04-10T12:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump publica video expl\\u00edcito de mortal ataque con martillo en Florida y vuelve a poner el foco en debate sobre inmigraci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/10\\\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/10\\\/trump-video-explicito-mortal-ataque-florida-inmigracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-10T12:03:49Z\",\"datePublished\":\"2026-04-10T12:03:49Z\",\"dateModified\":\"2026-04-10T12:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457318,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/01\/07\/sospechoso-mujer-metro-nueva-york-fuego-inocente-homicidio-trax\/","url_meta":{"origin":1473027,"position":0},"title":"El hombre acusado de matar a una mujer en el metro de Nueva York tras prenderle fuego se declara inocente de asesinato","author":"","date":"enero 7, 2025","format":false,"excerpt":"El hombre acusado de matar a una mujer tras prenderle fuego en un vag\u00f3n del metro de la ciudad de Nueva York el mes pasado se declar\u00f3 inocente de los cargos de asesinato este martes y se orden\u00f3 su detenci\u00f3n sin derecho a fianza.Sebasti\u00e1n Zapeta-Calil, un inmigrante indocumentado de 33\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449345,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/05\/09\/fbi-construyo-caso-contra-hombre-acusado-secuestrar-esposa-trax\/","url_meta":{"origin":1473027,"position":1},"title":"Una lata de pintura. Matr\u00edculas robadas. Mensajes extra\u00f1os. C\u00f3mo el FBI construy\u00f3 un caso contra un hombre acusado de secuestrar a su esposa","author":"","date":"mayo 9, 2024","format":false,"excerpt":"(CNN) -- Alrededor de las 21:30 p.m. del 2 de febrero, un hombre con un casco entr\u00f3 en el edificio de departamentos de Ana Mar\u00eda Knezevich Henao, en un barrio exclusivo de Madrid. Henao, que estaba de vacaciones en Espa\u00f1a procedente del sur de Florida, se encontraba en el edificio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463152,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/03\/hombre-admite-incriminar-migrante-amenazar-trump-trax\/","url_meta":{"origin":1473027,"position":2},"title":"Un hombre admiti\u00f3 haber intentado incriminar a migrante acusado de amenazar a Trump, seg\u00fan fiscal\u00eda estatal","author":"","date":"junio 3, 2025","format":false,"excerpt":"Un hombre de Wisconsin, que seg\u00fan los investigadores incrimin\u00f3 a un migrante indocumentado de amenazar de muerte al presidente de EE.UU. Donald Trump para deportarlo, ha sido acusado formalmente.Seg\u00fan la fiscal\u00eda estatal, Demetric Scott admiti\u00f3 haber incriminado al migrante Ram\u00f3n Morales-Reyes, a quien Scott presuntamente apu\u00f1al\u00f3 y rob\u00f3 en 2023\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465790,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/08\/23\/presencie-arresto-ice-busca-detenido-trax\/","url_meta":{"origin":1473027,"position":3},"title":"Par\u00e9 a cargar gasolina y presenci\u00e9 un arresto de ICE. Luego, pas\u00e9 d\u00edas buscando a Samuel, el hombre detenido","author":"","date":"agosto 23, 2025","format":false,"excerpt":"El jueves pasado iba en piloto autom\u00e1tico cuando me detuve en una gasolinera en Takoma Park, Maryland, molesta porque la parada agregar\u00eda tiempo a mi trayecto a la oficina de CNN en Washington.Pero al poner la bomba en el tanque de gasolina, vi a un hombre corriendo hacia m\u00ed a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443130,"url":"https:\/\/noticiasya.com\/el-paso\/2024\/01\/04\/hacen-publicos-documentos-en-caso-de-jeffrey-epstein\/","url_meta":{"origin":1473027,"position":4},"title":"Hacen p\u00fablicos documentos en caso de Jeffrey Epstein","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Documentos de una demanda relacionada a Jeffrey Epstein, acusado de tr\u00e1fico sexual, se hicieron p\u00fablicos este mi\u00e9rcoles. Se espera que los documentos incluyan casi 200 nombres, entre ellos algunas de las personas que acusaron a Epstein, empresarios destacados, pol\u00edticos y posiblemente m\u00e1s figuras.Las identidades de decenas de personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466865,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/09\/26\/agente-empuja-mujer-inmigracion-nueva-york-trax\/","url_meta":{"origin":1473027,"position":5},"title":"Agente federal empuja al suelo a mujer ecuatoriana que suplicaba por su esposo en un tribunal de inmigraci\u00f3n","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"Varios videos que muestran a un agente federal que empuja a una mujer al suelo durante un enfrentamiento en un tribunal de inmigraci\u00f3n en Nueva York el jueves han provocado indignaci\u00f3n y desencadenado llamados a que se apliquen medidas disciplinarias.En un video compartido en redes sociales, se ve a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1473027"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473027\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1473027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1473027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1473027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}