{"id":1473103,"date":"2026-04-13T11:03:38","date_gmt":"2026-04-13T18:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/"},"modified":"2026-04-13T11:03:38","modified_gmt":"2026-04-13T18:03:38","slug":"trump-estrategia-arancelaria-iran-no-funcionando-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","title":{"rendered":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando"},"content":{"rendered":"<p><em>\u201cEstados Unidos tambi\u00e9n tiene posturas, mucho m\u00e1s firmes y de mayor alcance. Simplemente no he optado por utilizarlas; nunca tuve motivos para hacerlo, \u00a1HASTA AHORA!\u201d.<\/em><\/p>\n<p>Esa impactante amenaza de fuerza sin precedentes por parte del presidente de EE.UU., Donald Trump, caus\u00f3 una ca\u00edda de casi el 3 % en la Bolsa de Valores, el 10 de octubre de 2025.<\/p>\n<p>En una publicaci\u00f3n <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/115350455734003647\">de dos partes en <\/a><a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/115351840469973590\">Truth Social<\/a>, hace seis meses, Trump dijo que Estados Unidos cortar\u00eda las exportaciones cruciales a China y aumentar\u00eda los aranceles sobre los productos chinos al 100 %, una amenaza maximalista para recuperar la influencia estadounidense perdida.<\/p>\n<p>Si todo esto te suena familiar, es por una buena raz\u00f3n.<\/p>\n<p>Actualmente, Estados Unidos se enfrenta a una amenaza econ\u00f3mica por parte de Ir\u00e1n sorprendentemente similar a la que sufri\u00f3 por parte de China el a\u00f1o pasado. En respuesta, Trump est\u00e1 empleando la misma estrategia extrema que utiliz\u00f3 contra China y otros socios comerciales: intensificar la amenaza al m\u00e1ximo, exigirle al mundo entero y conformarse solo si consigue algo m\u00e1s de lo que Estados Unidos ten\u00eda inicialmente.<\/p>\n<p>Trump ha amenazado con aplicar duras represalias contra Ir\u00e1n si no abre el estrecho de Ormuz, la v\u00eda mar\u00edtima crucial por donde transita el 20 % del crudo mundial. El domingo, Trump volvi\u00f3 a subir la apuesta cuando anunci\u00f3 que la Marina estadounidense bloquear\u00eda el estrecho.<\/p>\n<p>El problema es que esto no es una guerra comercial; es una guerra real, y el \u00faltimo cambio de estrategia podr\u00eda poner en peligro a m\u00e1s tropas estadounidenses.<\/p>\n<p>Hasta ahora, las amenazas extremas de Trump contra Ir\u00e1n no est\u00e1n surtiendo efecto, lo que conlleva el riesgo de un sufrimiento econ\u00f3mico duradero para los consumidores y una guerra mortal, que ya ha costado la vida a miles de personas.<\/p>\n<p>Durante el \u00faltimo a\u00f1o y medio, Trump lanz\u00f3 con frecuencia amenazas contra diversos socios comerciales, cuyos resultados variaron. Si bien Trump se gan\u00f3 una merecida reputaci\u00f3n por retractarse de sus amenazas m\u00e1s alarmantes (como tomar el control de Groenlandia u obligar a Brasil a retirar la acusaci\u00f3n de fraude electoral contra el expresidente Jair Bolsonaro), muchos socios comerciales cedieron a sus condiciones.<\/p>\n<p>Pero Ir\u00e1n est\u00e1 siguiendo el modelo de China.<\/p>\n<p>La primavera pasada, Trump elev\u00f3 tanto los aranceles a China que pr\u00e1cticamente impusieron un embargo a los productos chinos destinados a Estados Unidos. China respondi\u00f3 restringiendo las exportaciones de minerales de tierras raras, esenciales para una amplia gama de productos electr\u00f3nicos, lo que puso en peligro a las empresas, los consumidores e incluso las Fuerzas Armadas estadounidenses.<\/p>\n<p>Trump cedi\u00f3 y redujo dr\u00e1sticamente los aranceles a cambio de la promesa de China de reabrir las compuertas a los minerales de tierras raras. Pero China nunca dio marcha atr\u00e1s, y se affer\u00f3 a su as bajo la manga, a pesar de las repetidas amenazas de Trump de volver a subir los aranceles, un poder que la Corte Suprema limit\u00f3 recientemente.<\/p>\n<p>De manera similar, Ir\u00e1n considera que el control del estrecho de Ormuz es la \u00fanica baza que puede ejercer sobre Estados Unidos como herramienta para detener una guerra existencial y llevar a Estados Unidos a la mesa de negociaciones.<\/p>\n<p>Tal vez aprendiendo de su aliado, Ir\u00e1n no parece dispuesto a ceder tan f\u00e1cilmente.<\/p>\n<p>\u201cDisfruten del precio actual de la gasolina\u201d, escribi\u00f3 Mohammad Bagher Ghalibaf, presidente del Parlamento iran\u00ed, en una publicaci\u00f3n en X. \u201cCon lo que se denomina un \u2018bloqueo\u2019, pronto echar\u00e1n de menos la gasolina a US$ 4 o 5\u201d.<\/p>\n<p>La amenaza de Trump del domingo de bloquear el estrecho de Ormuz podr\u00eda estrangular las ventas de petr\u00f3leo de Ir\u00e1n y los peajes multimillonarios que estaban ayudando a financiar su guerra contra Estados Unidos.<\/p>\n<p>Pero esas ventas de crudo iran\u00ed, de aproximadamente 2 millones de barriles diarios, tambi\u00e9n contribu\u00edan a mantener los precios del petr\u00f3leo bajo control, al aportar la oferta tan necesaria al mercado mundial.<\/p>\n<p>La respuesta del mercado a la amenaza de bloqueo de Trump fue instant\u00e1nea: los futuros del brent, la referencia internacional, subieron un 8 %, el domingo por la noche, hasta alcanzar los US$ 103 el barril, y el bloqueo de Trump podr\u00eda hacer que los precios suban otros US$ 10, acerc\u00e1ndose a sus m\u00e1ximos recientes, dijo Jay Hatfield, CEO de Infrastructure Capital Advisors.<\/p>\n<p>Seg\u00fan Hatfield, los operadores preferir\u00e1n la amenaza de bloqueo a la promesa anterior de Trump de destruir el petr\u00f3leo y la infraestructura de Ir\u00e1n. Sin embargo, si el mercado cree que la guerra se prolongar\u00e1 durante semanas o meses, los precios del petr\u00f3leo podr\u00edan superar r\u00e1pidamente los US$ 120, alcanzando su valor m\u00e1s alto en cuatro a\u00f1os, afirm\u00f3 Homayoun Falakshahi, analista principal de Investigaci\u00f3n de Crudo en Kpler.<\/p>\n<p>Como consecuencia, los estadounidenses deber\u00edan prepararse para pagar a\u00fan m\u00e1s. En parte debido al aumento del precio del combustible, el hogar estadounidense promedio gasta US$ 233 m\u00e1s al mes en los mismos bienes y servicios que hace un a\u00f1o, seg\u00fan los an\u00e1lisis de Moody\u2019s.<\/p>\n<p>Seg\u00fan Joe Brusuelas, economista jefe para Estados Unidos de RSM, los precios de la gasolina en EE.UU. hab\u00edan comenzado a bajar ligeramente, pero se revirti\u00f3 la tendencia debido al bloqueo de Trump. Lo mismo ocurrir\u00e1 con el di\u00e9sel y el combustible para aviones, afirm\u00f3. Adem\u00e1s, el bloqueo har\u00e1 que los inversores retiren sus bonos, lo que elevar\u00e1 a\u00fan m\u00e1s los rendimientos y amenaza con aumentar las tasas hipotecarias y el costo de los pr\u00e9stamos para millones de estadounidenses. Las expectativas de inflaci\u00f3n continuar\u00e1n en aumento.<\/p>\n<p>El control que Ir\u00e1n mantiene sobre el estrecho le otorga una ventaja significativa en la guerra: si bien sus fuerzas militares y su liderazgo han quedado devastados, conserva su poder econ\u00f3mico sobre Estados Unidos y el mundo.<\/p>\n<p>Por eso, al menos hasta ahora, Ir\u00e1n no est\u00e1 flaqueando.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEstados Unidos tambi\u00e9n tiene posturas, mucho m\u00e1s firmes y de mayor alcance. Simplemente no he optado por utilizarlas; nunca tuve motivos para hacerlo, \u00a1HASTA AHORA!\u201d. Esa impactante amenaza de fuerza sin precedentes por parte del presidente de EE.UU., Donald Trump, caus\u00f3 una ca\u00edda de casi el 3 % en la Bolsa de Valores, el 10 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473103","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u201cEstados Unidos tambi\u00e9n tiene posturas, mucho m\u00e1s firmes y de mayor alcance. Simplemente no he optado por utilizarlas; nunca tuve motivos para hacerlo, \u00a1HASTA AHORA!\u201d. Esa impactante amenaza de fuerza sin precedentes por parte del presidente de EE.UU., Donald Trump, caus\u00f3 una ca\u00edda de casi el 3 % en la Bolsa de Valores, el 10 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T18:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando\",\"datePublished\":\"2026-04-13T18:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\"},\"wordCount\":1035,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\",\"name\":\"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-13T18:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias","og_description":"\u201cEstados Unidos tambi\u00e9n tiene posturas, mucho m\u00e1s firmes y de mayor alcance. Simplemente no he optado por utilizarlas; nunca tuve motivos para hacerlo, \u00a1HASTA AHORA!\u201d. Esa impactante amenaza de fuerza sin precedentes por parte del presidente de EE.UU., Donald Trump, caus\u00f3 una ca\u00edda de casi el 3 % en la Bolsa de Valores, el 10 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-13T18:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/"},"author":{"name":"","@id":""},"headline":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando","datePublished":"2026-04-13T18:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/"},"wordCount":1035,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","name":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-13T18:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump est\u00e1 utilizando su estrategia arancelaria contra Ir\u00e1n, pero no est\u00e1 funcionando","url":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-paso\/2026\/04\/13\/trump-estrategia-arancelaria-iran-no-funcionando-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-13T18:03:38Z","datePublished":"2026-04-13T18:03:38Z","dateModified":"2026-04-13T18:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump est\\u00e1 utilizando su estrategia arancelaria contra Ir\\u00e1n, pero no est\\u00e1 funcionando\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/13\\\/trump-estrategia-arancelaria-iran-no-funcionando-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-paso\\\/2026\\\/04\\\/13\\\/trump-estrategia-arancelaria-iran-no-funcionando-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-13T18:03:38Z\",\"datePublished\":\"2026-04-13T18:03:38Z\",\"dateModified\":\"2026-04-13T18:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471795,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/02\/encuesta-cnn-59-estadounidenses-desaprueba-ataques-iran-trax\/","url_meta":{"origin":1473103,"position":0},"title":"Encuesta CNN: 59 % de los estadounidenses desaprueba los ataques contra Ir\u00e1n","author":"","date":"marzo 2, 2026","format":false,"excerpt":"Casi 6 de cada 10 estadounidenses desaprueban la decisi\u00f3n de Estados Unidos de emprender acciones militares en Ir\u00e1n, y la mayor\u00eda considera probable un conflicto militar a largo plazo entre ambos pa\u00edses, seg\u00fan una nueva encuesta de CNN realizada por SSRS.La encuesta, realizada poco despu\u00e9s del inicio de los ataques\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463804,"url":"https:\/\/noticiasya.com\/el-paso\/2025\/06\/21\/fuerzas-orden-ee-uu-informacion-inteligencia-hezbollah-trax\/","url_meta":{"origin":1473103,"position":1},"title":"Fuerzas del orden de EE.UU. reexaminan la informaci\u00f3n de inteligencia de Hezbollah, pero no hay indicios de amenazas cre\u00edbles","author":"","date":"junio 21, 2025","format":false,"excerpt":"Las agencias de inteligencia y de seguridad est\u00e1n reexaminando a los socios conocidos o presuntos de Hezbollah en Estados Unidos, en busca de posibles amenazas que podr\u00edan surgir a medida que aumentan las tensiones con Ir\u00e1n, aunque no hay indicios de amenazas cre\u00edbles por el momento, seg\u00fan informaron las autoridades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473682,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","url_meta":{"origin":1473103,"position":2},"title":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n","author":"","date":"abril 30, 2026","format":false,"excerpt":"Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n.\u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472145,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/12\/encuestas-guerra-iran-rechazo-estadounidenses-trax\/","url_meta":{"origin":1473103,"position":3},"title":"Encuestas sobre Ir\u00e1n revelan que los estadounidenses no ven el sentido de esta guerra","author":"","date":"marzo 12, 2026","format":false,"excerpt":"La guerra con Ir\u00e1n ya tiene aproximadamente dos semanas. Y estamos recibiendo muchos datos de encuestas sobre c\u00f3mo se sienten los estadounidenses respecto al conflicto militar estadounidense m\u00e1s significativo en dos d\u00e9cadas.Sin embargo, sigue siendo un panorama confuso, y uno que podr\u00eda inclinarse a favor o en contra el Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472790,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/04\/02\/carta-abierta-presidente-iran-guerra-eeuu-trax\/","url_meta":{"origin":1473103,"position":4},"title":"\u00bfEs la guerra de Ir\u00e1n realmente &#171;America First&#187;?, pregunta el presidente de Ir\u00e1n en una carta al p\u00fablico estadounidense","author":"","date":"abril 2, 2026","format":false,"excerpt":"El presidente de Ir\u00e1n escribi\u00f3 una carta abierta a Estados Unidos preguntando si la guerra que libra la administraci\u00f3n Trump contra su pa\u00eds pone a \u201cEstados Unidos primero\u201d\u201c\u00bfA cu\u00e1les de los intereses del pueblo estadounidense se beneficia realmente esta guerra?\u201d, escribi\u00f3 Masoud Pezeshkian en la carta, dirigida \u201cal pueblo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472482,"url":"https:\/\/noticiasya.com\/el-paso\/2026\/03\/24\/que-pasa-dia-25-guerra-estados-unidos-israel-iran-trax\/","url_meta":{"origin":1473103,"position":5},"title":"\u00bfQu\u00e9 est\u00e1 pasando al d\u00eda 25 de la guerra entre Estados Unidos e Israel e Ir\u00e1n?","author":"","date":"marzo 24, 2026","format":false,"excerpt":"El cambio de postura del presidente Donald Trump respecto a su ultim\u00e1tum a Ir\u00e1n ha aliviado la presi\u00f3n sobre los precios del petr\u00f3leo, incluso cuando Teher\u00e1n neg\u00f3 sus afirmaciones de que los dos pa\u00edses hab\u00edan hablado.La pausa de cinco d\u00edas en la amenaza de ataque de Trump ha dado un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-paso\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/comments?post=1473103"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/posts\/1473103\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/media?parent=1473103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/categories?post=1473103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-paso\/wp-json\/wp\/v2\/tags?post=1473103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}