{"id":1444720,"date":"2024-01-31T19:33:36","date_gmt":"2024-02-01T03:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444720"},"modified":"2024-01-31T19:33:36","modified_gmt":"2024-02-01T03:33:36","slug":"directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","title":{"rendered":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0El Congreso interroga a un importante grupo de las redes sociales este mi\u00e9rcoles sobre los riesgos que sus productos representan para los j\u00f3venes, una vez m\u00e1s.<\/p>\n<p>Los directores ejecutivos de Meta, TikTok, Snap, Discord y X, antes conocido como Twitter, testifican ante la Comisi\u00f3n Judicial del Senado.<\/p>\n<p>La audiencia se volvi\u00f3 a\u00fan m\u00e1s relevante el mi\u00e9rcoles, un d\u00eda despu\u00e9s de que se publicara un video espantoso en YouTube que mostraba a un hombre sosteniendo lo que, seg\u00fan \u00e9l, era la cabeza decapitada de su padre. El video circul\u00f3 durante horas en YouTube (obtuvo m\u00e1s de 5.000 visitas) antes de ser eliminado.<\/p>\n<p>Aqu\u00ed est\u00e1n algunas de las principales conclusiones de la audiencia.<\/p>\n<p>La senadora Marsha Blackburn expresa su horror ante la valoraci\u00f3n de Meta de los usuarios adolescentes en US$ 270<\/p>\n<p>La senadora Marsha Blackburn se enfrent\u00f3 a Zuckerberg por los documentos internos de Meta que sugieren que la empresa estima el valor de por vida de un usuario adolescente en US$ 270.<\/p>\n<p>&#171;\u00bfC\u00f3mo es posible que se te ocurra eso? Me parece asombroso&#187;, dijo Blackburn, antes de reconocer a un grupo de defensores de los j\u00f3venes entre el p\u00fablico e invitarles a ponerse en pie.<\/p>\n<p>Cuando lo hicieron, los defensores revelaron que llevaban camisetas con el lema &#171;Valgo m\u00e1s de US$ 270&#187;.<\/p>\n<p>&#171;Los ni\u00f1os no son su prioridad. Los ni\u00f1os son tu producto&#187;, dijo Blackburn a Zuckerberg en el tenso intercambio.<\/p>\n<p>Las plataformas de Meta se convirtieron en un &#171;campo de exterminio de la verdad&#187;, seg\u00fan el senador republicano John Kennedy<\/p>\n<p>John Kennedy, senador republicano por Louisiana, dijo que las plataformas de Meta se convirtieron en un &#171;campo de exterminio de la informaci\u00f3n&#187;, donde los usuarios &#171;solo ven un lado de una cuesti\u00f3n&#187;.<\/p>\n<p>&#171;Convencieron a m\u00e1s de 2.000 millones de personas para que den toda su informaci\u00f3n personal -cada parte de ella- a cambio de poder ver lo que sus amigos del instituto cenaron el s\u00e1bado por la noche&#187;, dijo.<\/p>\n<p>&#171;Y ustedes toman esta informaci\u00f3n, esta abundancia de informaci\u00f3n personal y luego desarrollan algoritmos para tocar los botones calientes de la gente&#8230; una y otra y otra vez, para que vuelvan y se queden m\u00e1s tiempo. Como resultado, los usuarios solo ven un lado de la cuesti\u00f3n y, hasta cierto punto, la plataforma se convirti\u00f3 en un campo de exterminio para la verdad, \u00bfno?&#187;.<\/p>\n<p>Zuckerberg rechaz\u00f3 esta descripci\u00f3n de su negocio.<\/p>\n<p>En este entorno, afirm\u00f3 Kennedy, las plataformas pueden convertirse en un &#171;pozo negro de sarcasmo&#187;.<\/p>\n<p>Preguntando si Facebook deja claro a sus usuarios c\u00f3mo la plataforma monetiza sus datos, Kennedy dijo: &#171;\u00bfSu acuerdo de usuario sigue apestando?&#187;.<\/p>\n<p>Esto provoc\u00f3 algunas risas en la sala.<\/p>\n<p>Zuckerberg dijo que la gente entiende lo b\u00e1sico de c\u00f3mo funcionan las redes sociales.<\/p>\n<p>&#171;Est\u00e1s en las estribaciones de lo espeluznante. Rastreas a personas que ni siquiera son usuarios de Facebook&#187;, dijo Kennedy. &#171;Simplemente me pregunto si nuestra tecnolog\u00eda es mayor que nuestra humanidad en aras de este embudo&#187;.<\/p>\n<p>En conclusi\u00f3n, Kennedy le dijo a Zuckerberg: &#171;Si crees que Instagram no est\u00e1 perjudicando a millones de nuestros j\u00f3venes, en particular a los adolescentes, en particular a las mujeres j\u00f3venes, no deber\u00edas estar al mando&#187;.<\/p>\n<p>Zuckerberg y Spiegel se disculpan personalmente ante familias<\/p>\n<p>Zuckerberg, CEO de Meta, se puso de pie para pedir disculpas a las familias presentes en la sala de audiencias, diciendo que lamentaba &#171;las cosas que sus familias han sufrido. Por eso hemos invertido tanto&#8230; para asegurarnos de que nadie tenga que pasar por el tipo de cosas por las que pasaron sus familias&#187;.<\/p>\n<p>En su respuesta, el senador Josh Hawley pidi\u00f3 a Zuckerberg que, como multimillonario, &#171;compense&#187; a las familias cuyos hijos se han visto afectados por sus plataformas.<\/p>\n<p>En respuesta a la petici\u00f3n de la senadora dem\u00f3crata por California Laphonza Butler, el CEO de Snap, Evan Spiegel, tambi\u00e9n pidi\u00f3 disculpas a las familias cuyos hijos han muerto despu\u00e9s de comprar drogas en Snapchat.<\/p>\n<p>&#171;Siento mucho que no hayamos sido capaces de prevenir estas tragedias&#187;, dijo Spiegel, antes de detallar algunos de los esfuerzos que realiza la compa\u00f1\u00eda para proteger a los j\u00f3venes usuarios.<\/p>\n<p>Los legisladores interrogan al CEO de TikTok sobre la conexi\u00f3n de la plataforma con China<\/p>\n<p>El CEO de TikTok, Shou Chew, fue interrogado varias veces sobre la conexi\u00f3n de la empresa con China, a trav\u00e9s de su empresa matriz ByteDance, y el grado de acceso e influencia que la plataforma concede al Gobierno chino.<\/p>\n<p>En una ocasi\u00f3n, Chew dijo a Tom Cotton, senador republicano por Arkansas, que era &#171;una coincidencia&#187; que fuera nombrado CEO de la plataforma un d\u00eda despu\u00e9s de que el fondo de inversi\u00f3n en internet del Partido Comunista Chino comprara una participaci\u00f3n del 1% en la principal filial china de ByteDance, obteniendo un puesto en el consejo de administraci\u00f3n de la filial.<\/p>\n<p>Josh Hawley, senador republicano por Missouri, tambi\u00e9n interrog\u00f3 a Chew sobre las conexiones de la empresa con China y su partido comunista.<\/p>\n<p>En otro momento, bajo el interrogatorio de Ted Cruz, senador republicano por Texas, Chew describi\u00f3 la masacre de la plaza de Tiananm\u00e9n de 1989 en Beijing como una &#171;protesta masiva&#187;.<\/p>\n<p>Aunque la caracterizaci\u00f3n de Chew del suceso es exacta, omite la sangrienta represi\u00f3n posterior contra los activistas prodemocr\u00e1ticos por parte del Gobierno chino, que hoy est\u00e1 fuertemente censurada en la internet de China. En declaraciones posteriores, Chew se refiri\u00f3 a la plaza de Tiananm\u00e9n como una masacre cuando se le presion\u00f3.<\/p>\n<p>Chew ya hab\u00eda declarado ante el Congreso que TikTok permite en su plataforma contenidos sobre la plaza de Tiananm\u00e9n. TikTok no opera en China. Pero su empresa matriz, ByteDance, distribuye una aplicaci\u00f3n muy similar conocida como Douyin.<\/p>\n<p>El senador republicano Graham: &#171;El lado oscuro de los productos de redes sociales es demasiado grande para vivir con \u00e9l&#187;<\/p>\n<p>El senador republicano Lindsey Graham afirm\u00f3 este mi\u00e9rcoles que las empresas de redes sociales han creado productos con ventajas, pero tambi\u00e9n tienen un lado oscuro &#171;demasiado grande para vivir con \u00e9l&#187;.<\/p>\n<p>Hasta que no se demande a las empresas de redes sociales por el da\u00f1o que est\u00e1n causando, Graham advirti\u00f3 que no habr\u00e1 ning\u00fan cambio.<\/p>\n<p>&#171;Estoy harto de hablar. Estoy harto de discutir&#187;, dijo. &#171;Abran la puerta de los tribunales. Hasta que no lo hagan, nada cambiar\u00e1. Hasta que no se pueda demandar a esta gente por el da\u00f1o que est\u00e1n haciendo, todo es palabrer\u00eda&#187;.<\/p>\n<p>Y a\u00f1adi\u00f3: &#171;Soy un republicano que cree en el libre mercado, pero tambi\u00e9n creo que todo estadounidense que haya sido perjudicado tiene que tener a alguien a quien acudir para quejarse. No hay ninguna comisi\u00f3n a la que acudir que pueda castigarte. No hay una sola ley en el libro porque se oponen a todo lo que hacemos, y no se les puede demandar. Eso tiene que acabar, amigos&#187;.<\/p>\n<p>Graham insisti\u00f3 en la importancia de contar con un marco jur\u00eddico que obligue a las empresas a rendir cuentas.<\/p>\n<p>&#171;Porque a pesar de todas las ventajas, el lado oscuro es demasiado grande para vivir con \u00e9l&#187;, afirm\u00f3.<\/p>\n<p>La senadora Amy Klobuchar se enfad\u00f3 visiblemente al interrogar a los CEO<\/p>\n<p>Hubo elementos dram\u00e1ticos durante la audiencia de este mi\u00e9rcoles.<\/p>\n<p>Amy Klobuchar, senadora dem\u00f3crata por Minnesota, apareci\u00f3 visiblemente alterada mientras relataba las historias de padres cuyos hijos se vieron perjudicados por las plataformas de redes sociales, incluidos j\u00f3venes que se suicidaron tras ser amenazados por depredadores en l\u00ednea.<\/p>\n<p>&#171;Estoy harta de esto&#187;, dijo Klobuchar. &#171;Han pasado 28 a\u00f1os&#8230; desde el inicio de internet. No hemos aprobado ninguno de estos proyectos de ley, porque todo el mundo es &#8216;doble discurso, doble discurso&#8217;. Es hora de aprobarlas de verdad&#187;.<\/p>\n<p>Klobuchar presion\u00f3 a los CEO para que respaldaran varios proyectos de ley propuestos.<\/p>\n<p>El CEO de Snap, Evan Spiegel, accedi\u00f3 a respaldar la Ley Cooper Davis, que exigir\u00eda a las plataformas informar a la Administraci\u00f3n de Control de Drogas (DEA, por sus siglas en ingl\u00e9s) de ciertos casos de tr\u00e1fico il\u00edcito de drogas en sus plataformas.<\/p>\n<p>Una rara fuerza unificadora en el Capitolio: el malestar contra las empresas de redes sociales<\/p>\n<p>La audiencia del mi\u00e9rcoles demuestra nuevamente la amplitud de las cr\u00edticas a las empresas de redes sociales entre los legisladores, un tema bipartidista poco com\u00fan en el Capitolio.<\/p>\n<p>En un primer momento, el senador republicano Lindsey Graham destac\u00f3 que no tiene \u201ccasi nada en com\u00fan\u201d con su colega dem\u00f3crata, la senadora Elizabeth Warren, y que tiene una filosof\u00eda pol\u00edtica diferente a la del senador dem\u00f3crata Dick Durbin. Sin embargo, se\u00f1al\u00f3 que est\u00e1n de acuerdo en c\u00f3mo la tecnolog\u00eda est\u00e1 afectando a la sociedad.<\/p>\n<p>\u201cElizabeth y yo vemos aqu\u00ed un abuso que debe abordarse. El senador Durbin y yo tenemos filosof\u00edas pol\u00edticas diferentes, pero aprecio lo que han hecho en esta comisi\u00f3n. Has sido un gran socio. A todos mis colegas dem\u00f3cratas, muchas, muchas gracias. A mis colegas republicanos, muchas, muchas gracias a todos\u201d, dijo el senador Graham.<\/p>\n<p>Decenas de estados demandan a Meta, empresa matriz de Instagram, por supuestas funciones &#171;adictivas&#187; y da\u00f1os a la salud mental de los j\u00f3venes<\/p>\n<p>Sin embargo, a pesar del apetito de ambos partidos por perseguir las plataformas tecnol\u00f3gicas, el Congreso a\u00fan tiene que aprobar una legislaci\u00f3n significativa para regular las empresas de redes sociales.<\/p>\n<p>La mayor parte de la acci\u00f3n ha tenido lugar en las legislaturas estatales y en los tribunales, que se han convertido en campos de batalla para nuevas pol\u00edticas, incluidas las edades m\u00ednimas para el uso de las redes sociales.<\/p>\n<p>Un legislador de Carolina del Sur demanda a Instagram despu\u00e9s de que su hijo se suicidara<\/p>\n<p>En sus comentarios de apertura, el senador Graham mencion\u00f3 a un legislador estatal que perdi\u00f3 a su hijo mayor y que demandar\u00e1 a Meta. Ese legislador es el representante de la C\u00e1mara Estatal de Carolina del Sur, Brandon Guffey.<\/p>\n<p>Aproximadamente dos semanas despu\u00e9s del funeral de su hijo mayor, Guffey dice que recibi\u00f3 un mensaje privado de Instagram con un emoji de risa.<\/p>\n<p>Gavin Guffey, de 17 a\u00f1os, se mat\u00f3 de un tiro en un ba\u00f1o en julio de 2022, y el afligido padre busc\u00f3 pistas sobre lo que llev\u00f3 a su suicidio.<\/p>\n<p>Luego, Guffey y su hijo menor comenzaron a recibir mensajes exigiendo dinero a cambio de fotograf\u00edas de su difunto hijo desnudo. Cualquiera en la lista de seguidores de Gavin en Instagram que tuviera el apellido Guffey recibi\u00f3 mensajes similares, dice su padre.<\/p>\n<p>\u201cTienen sangre en sus manos\u201d, les dice el senador Graham a los directores ejecutivos de tecnolog\u00eda<\/p>\n<p>El senador republicano de Carolina del Sur, Lindsey Graham, dijo a los directores ejecutivos de tecnolog\u00eda en sus comentarios de apertura: &#171;Tienen sangre en las manos&#187;.<\/p>\n<p>Esto caus\u00f3 aplausos y v\u00edtores de muchos en el p\u00fablico.<\/p>\n<p>\u201cTienen un producto que est\u00e1 matando gente\u2026 \u00a1Si no los pueden demandar, deber\u00edan hacerlo!\u201d a\u00f1adi\u00f3 Graham. &#171;Ha llegado el momento de derogar la Secci\u00f3n 230&#187;.<\/p>\n<p>La Secci\u00f3n 230 es la ley federal que inmuniza a los sitios web y plataformas de redes sociales por sus decisiones de moderaci\u00f3n de contenido y por demandas que surjan del contenido generado por los usuarios.<\/p>\n<p>&#171;No ten\u00edamos ni idea del da\u00f1o que podr\u00edan causar&#187;<\/p>\n<p>Una de las v\u00edctimas de las redes sociales es Rosemarie Calvoni, una mujer que demand\u00f3 a Meta y a otras empresas de redes sociales por la lucha de su hija contra la anorexia.<\/p>\n<p>Calvoni culpa a Meta de enviar a su hija a una madriguera de contenidos sobre trastornos alimentarios, lo que la llev\u00f3 a un tratamiento hospitalario y a m\u00faltiples reca\u00eddas que le han hecho perderse &#171;la mayor parte de la escuela secundaria&#187;.<\/p>\n<p>&#171;Cuando estas plataformas se lanzaron por primera vez, no ten\u00edamos ni idea del da\u00f1o que podr\u00edan causar, no solo a mi hija, sino a nuestra familia como unidad&#187;, dijo Calvoni a periodistas en una llamada el martes.<\/p>\n<p>El a\u00f1o pasado, Arturo B\u00e9jar, denunciante de Facebook, hizo p\u00fablico ante los legisladores estadounidenses que Meta y otros ejecutivos hab\u00edan hecho caso omiso de su investigaci\u00f3n, seg\u00fan la cual, entre otras cosas, m\u00e1s del 25% de los j\u00f3venes de entre 13 y 15 a\u00f1os hab\u00edan denunciado haber recibido insinuaciones sexuales no deseadas en Instagram.<\/p>\n<p>Meta recopil\u00f3 datos de menores de edad en Instagram sin el consentimiento de sus padres<\/p>\n<p>Desde entonces, Meta dijo que ofrece herramientas para que los usuarios personalicen sus experiencias en las plataformas de la empresa y que propuso una legislaci\u00f3n federal que obliga a las tiendas de aplicaciones a verificar la edad de sus usuarios.<\/p>\n<p>En las \u00faltimas semanas, Meta tambi\u00e9n empez\u00f3 a ocultar m\u00e1s contenido &#171;inapropiado para la edad&#187; en los feeds de los adolescentes y a restringirles la recepci\u00f3n de mensajes directos de personas a las que no siguen.<\/p>\n<p>Los directores ejecutivos de cinco grandes empresas tecnol\u00f3gicas testificar\u00e1n este mi\u00e9rcoles en una audiencia de una comisi\u00f3n del Senado sobre el impacto de sus redes sociales en los adolescentes. (Cr\u00e9dito: Samuel Corum\/Getty Images)<\/p>\n<p>Nuevos documentos de Meta cuestionan la responsabilidad de Zuckerberg<\/p>\n<p>Altos ejecutivos de Meta intentaron hacer sonar la alarma internamente sobre la gesti\u00f3n de la seguridad de los ni\u00f1os por parte de Instagram y Facebook en 2021, seg\u00fan los nuevos documentos publicados este mi\u00e9rcoles por Blumenthal y Marsha Blackburn, senadora republicana por Tennessee.<\/p>\n<p>Las nuevas comunicaciones incluyen advertencias a Zuckerberg de que &#171;no vamos por buen camino&#187; y de que la compa\u00f1\u00eda se enfrenta a un &#171;mayor riesgo regulatorio&#187; debido a la escasa inversi\u00f3n en la seguridad de los usuarios.<\/p>\n<p>El asunto puede culminar en un desastre de relaciones p\u00fablicas y perjudicar las futuras ambiciones del metaverso de Meta, advirtieron los ejecutivos, si la empresa no contrata urgentemente a docenas de nuevos empleados para afrontar el reto.<\/p>\n<p>Meta facilit\u00f3 los documentos a los legisladores en respuesta a anteriores solicitudes de informaci\u00f3n.<\/p>\n<p>Sin embargo, dos a\u00f1os despu\u00e9s de las advertencias, Zuckerberg ha despedido a miles de trabajadores, incluido el personal dedicado al bienestar de los usuarios. Y su empresa se enfrenta a una creciente ola de litigios y regulaciones a escala mundial.<\/p>\n<p>Las comunicaciones recientemente publicadas proporcionan algunas de las pruebas m\u00e1s espec\u00edficas y directas hasta la fecha que sugieren que Zuckerberg ignor\u00f3 o rechaz\u00f3 los esfuerzos de los altos funcionarios de la empresa -incluidos la entonces directora de operaciones Sheryl Sandberg y el presidente de Asuntos Globales Nick Clegg- para invertir m\u00e1s en la salud mental de los usuarios de Meta.<\/p>\n<p>Aunque ya se han descrito aspectos de los intercambios de correos electr\u00f3nicos de Meta en 2021 en una demanda presentada por el estado de Massachusetts contra la empresa, la publicaci\u00f3n de este mi\u00e9rcoles inclu\u00eda copias de parte de la correspondencia. En ellas se detalla c\u00f3mo algunos miembros de Meta describieron el asunto como un riesgo inminente para la empresa.<\/p>\n<p>En un correo electr\u00f3nico de agosto de 2021, Clegg -presentando una propuesta desarrollada por el jefe de salud de Meta y otros vicepresidentes- dijo a Zuckerberg que un n\u00famero creciente de responsables pol\u00edticos de todo el mundo hab\u00edan expresado &#171;p\u00fablica y privadamente&#187; su preocupaci\u00f3n por los posibles efectos de Facebook e Instagram en la salud mental de los adolescentes.<\/p>\n<p>Clegg y otros ejecutivos pidieron la contrataci\u00f3n de al menos 45 nuevos empleados en 2022 para ocuparse de cuestiones de seguridad, algunos de los cuales formar\u00edan un equipo dedicado al bienestar en todas las aplicaciones de la empresa.<\/p>\n<p>Lo ideal, seg\u00fan Clegg, ser\u00eda que Zuckerberg autorizara hasta 124 nuevas contrataciones, pero reconoci\u00f3 que las presiones financieras podr\u00edan dificultarlo.<\/p>\n<p>Tras meses de silencio por parte de Zuckerberg, Clegg trat\u00f3 de hacer un seguimiento, esta vez con una propuesta m\u00e1s reducida que contemplaba 25 nuevas contrataciones o, si eso era inviable, solo siete.<\/p>\n<p>Clegg escribi\u00f3 a Zuckerberg el 10 de noviembre de 2021: &#171;Esto ser\u00eda lo m\u00ednimo necesario para responder a las preguntas b\u00e1sicas de los responsables pol\u00edticos&#187;.<\/p>\n<p>Poco despu\u00e9s, Sandberg le dijo a Clegg: &#171;Estoy a favor de esto y le dar\u00e9 seguimiento&#187;.<\/p>\n<p>Pero tambi\u00e9n trat\u00f3 de gestionar sus expectativas, a\u00f1adiendo que &#171;como sabes, tenemos problemas presupuestarios generales en todos los \u00e1mbitos, as\u00ed que no hay promesas sobre lo que ocurrir\u00e1&#187;.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0El Congreso interroga a un importante grupo de las redes sociales este mi\u00e9rcoles sobre los riesgos que sus productos representan para los j\u00f3venes, una vez m\u00e1s. Los directores ejecutivos de Meta, TikTok, Snap, Discord y X, antes conocido como Twitter, testifican ante la Comisi\u00f3n Judicial del Senado. La audiencia se volvi\u00f3 a\u00fan m\u00e1s relevante [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444720","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0El Congreso interroga a un importante grupo de las redes sociales este mi\u00e9rcoles sobre los riesgos que sus productos representan para los j\u00f3venes, una vez m\u00e1s. Los directores ejecutivos de Meta, TikTok, Snap, Discord y X, antes conocido como Twitter, testifican ante la Comisi\u00f3n Judicial del Senado. La audiencia se volvi\u00f3 a\u00fan m\u00e1s relevante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T03:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes\",\"datePublished\":\"2024-02-01T03:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\"},\"wordCount\":2836,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\",\"name\":\"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-01T03:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","og_locale":"es_ES","og_type":"article","og_title":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias","og_description":"(CNN) &#8212;\u00a0El Congreso interroga a un importante grupo de las redes sociales este mi\u00e9rcoles sobre los riesgos que sus productos representan para los j\u00f3venes, una vez m\u00e1s. Los directores ejecutivos de Meta, TikTok, Snap, Discord y X, antes conocido como Twitter, testifican ante la Comisi\u00f3n Judicial del Senado. La audiencia se volvi\u00f3 a\u00fan m\u00e1s relevante [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","og_site_name":"Noticias","article_published_time":"2024-02-01T03:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/"},"author":{"name":"","@id":""},"headline":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes","datePublished":"2024-02-01T03:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/"},"wordCount":2836,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","name":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-01T03:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Directivos de Meta, TikTok y otras grandes tecnol\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes","url":"http:\/\/noticiasya.com\/el-valle\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/01\/31\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-01T03:33:36Z","datePublished":"2024-02-01T03:33:36Z","dateModified":"2024-02-01T03:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Directivos de Meta, TikTok y otras grandes tecnol\\u00f3gicas comparecen en el Senado de EE.UU. para defender el impacto de las redes sociales en los adolescentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/01\\\/31\\\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/01\\\/31\\\/directivos-de-meta-tiktok-y-otras-grandes-tecnologicas-comparecen-en-el-senado-de-ee-uu-para-defender-el-impacto-de-las-redes-sociales-en-los-adolescentes\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-01T03:33:36Z\",\"datePublished\":\"2024-02-01T03:33:36Z\",\"dateModified\":\"2024-02-01T03:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472546,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/25\/jurado-responsables-meta-youtube-adiccion-trax\/","url_meta":{"origin":1444720,"position":0},"title":"Un jurado declara responsables a Meta y YouTube en un juicio por adicci\u00f3n en redes sociales","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Un jurado en California declar\u00f3 a Meta y YouTube responsables en todos los cargos en un caso hist\u00f3rico que acus\u00f3 a los gigantes tecnol\u00f3gicos de volver intencionalmente adicta a una joven y perjudicar su salud mental.Meta y YouTube actuaron con negligencia en el dise\u00f1o de sus plataformas, sab\u00edan que ese\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468481,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/11\/18\/meta-no-es-monopolio-dice-juez-trax\/","url_meta":{"origin":1444720,"position":1},"title":"Victoria para Meta: un juez dictamin\u00f3 que el gigante de las redes sociales no es un monopolio ilegal","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"Meta obtuvo una gran victoria este martes despu\u00e9s de que un juez federal dictaminara que la empresa no es un monopolio de redes sociales, desestimando un argumento de la Comisi\u00f3n Federal de Comercio de EE.UU. que buscaba obligar a la compa\u00f1\u00eda a desprenderse de dos de sus plataformas m\u00e1s populares.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472580,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/26\/veredicto-historico-transformar-redes-sociales-trax\/","url_meta":{"origin":1444720,"position":2},"title":"Este veredicto hist\u00f3rico podr\u00eda transformar las redes sociales (y hay miles de demandas pendientes)","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Una decisi\u00f3n sin precedentes marc\u00f3 un momento crucial sobre la responsabilidad que acarrean las empresas de redes sociales. Esto es solo el principio.Meta, YouTube, TikTok y Snap se enfrentan a miles de demandas de particulares y familias, as\u00ed como de distritos escolares y fiscales generales estatales. Cada caso, algunos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471739,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/27\/adiccion-redes-sociales-demanda-meta-youtube-trax\/","url_meta":{"origin":1444720,"position":3},"title":"\u00bfC\u00f3mo se manifiesta la adicci\u00f3n a las redes sociales, seg\u00fan la joven que demanda a Meta y YouTube?","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Kaley comenz\u00f3 a usar YouTube a los 6 a\u00f1os. Descarg\u00f3 la aplicaci\u00f3n en su iPod Touch para ver videos sobre colecciones de brillo labial y el juego en l\u00ednea para ni\u00f1os Animal Jam. Public\u00f3 su primer video cuando ten\u00eda ocho a\u00f1os: jugaba Animal Jam como una nutria, cantaba con un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471419,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/19\/mark-zuckerberg-testifica-redes-sociales-salud-mental-infantil-trax\/","url_meta":{"origin":1444720,"position":4},"title":"Conclusiones del primer testimonio de Mark Zuckerberg sobre las redes sociales y la salud mental infantil","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El CEO de Meta, Mark Zuckerberg, testific\u00f3 el mi\u00e9rcoles ante un jurado por primera vez sobre las acusaciones de que las redes sociales, incluido Instagram, perjudican la salud mental de los ni\u00f1osKaley, una mujer de 20 a\u00f1os, afirma que Instagram y YouTube de Google fueron dise\u00f1ados intencionalmente para ser adictivos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472572,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/26\/criticos-grandes-tecnologicas-celebran-veredicto-redes-sociales-trax\/","url_meta":{"origin":1444720,"position":5},"title":"Cr\u00edticos de las grandes tecnol\u00f3gicas celebran veredicto sin precedentes sobre las redes sociales","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Para los cr\u00edticos de empresas tecnol\u00f3gicas como Meta y Google, el veredicto del mi\u00e9rcoles en el juicio por adicci\u00f3n a las redes sociales ha sido, literalmente, el resultado de a\u00f1os de trabajo.Padres, expertos en seguridad infantil y algunos legisladores afirmaron que la determinaci\u00f3n de la responsabilidad era un momento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444720"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444720\/revisions"}],"predecessor-version":[{"id":1444736,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444720\/revisions\/1444736"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}