{"id":1444800,"date":"2024-02-02T11:33:36","date_gmt":"2024-02-02T19:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444800"},"modified":"2024-02-02T11:33:36","modified_gmt":"2024-02-02T19:33:36","slug":"logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","title":{"rendered":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele, se presenta a las elecciones presidenciales del domingo en busca de un segundo mandato, con el combate a la delincuencia como su principal bandera.<\/p>\n<p>En las calles, los salvadore\u00f1os reconocen la mejora en la seguridad. Roberto Gonz\u00e1lez, quien ofrece servicios de transporte a trav\u00e9s de plataformas digitales, le dijo a CNN que ahora trabaja sin miedo y que ya entra en lugares donde antes no iba por temor a ser asesinado.<\/p>\n<p>\u201cLa Campanera misma, me ha tocado ir a recoger usuarios al Pino, que son lugares santuarios a\u00f1os atr\u00e1s\u201d, dice Gonz\u00e1lez sobre esas colonias que eran controlados por las pandillas, pero que tras la implementaci\u00f3n del r\u00e9gimen de excepci\u00f3n el 27 de marzo de 2022 han experimentado un cambio.<\/p>\n<p>El r\u00e9gimen de excepci\u00f3n, que sigue vigente con pr\u00f3rrogas de 30 d\u00edas cada una, fue en respuesta a un repunte de la violencia, que se produjo mientras funcionarios del Gobierno negociaban una tregua con las pandillas, seg\u00fan una acusaci\u00f3n desclasificada y que fue presentada a inicios de 2023 en una corte federal del Distrito Este de Nueva York contra 13 pandilleros de alto rango de la pandilla Mara Salvatrucha.<\/p>\n<p>Las autoridades reportan haber detenido a m\u00e1s de 75.000 personas hasta inicios de enero de 2024 por supuestos v\u00ednculos con las pandillas. \u201cAntes no pod\u00eda uno estar libremente en alg\u00fan lugar, cualquiera\u201d, explica Juan Alvarado, residente de San Salvador, a CNN.<\/p>\n<p>\u201cAhora ya venimos nosotros tranquilamente a sentarnos. Ya no venimos con miedo, pero antes yo ni ven\u00eda al parque\u201d, agrega Mabel Mel\u00e9ndez, otra residente de la capital del pa\u00eds.<\/p>\n<p>AN\u00c1LISIS | Bukele reporta bajas cifras de homicidios en El Salvador tras casi cinco a\u00f1os, pero con denuncias de violaciones de derechos humanos como tel\u00f3n de fondo<\/p>\n<p>Sin embargo, la pol\u00edtica de seguridad tambi\u00e9n ha provocado cr\u00edticas de organismos internacionales como Human Rights Watch y Amnist\u00eda Internacional, que consideran que viola los derechos humanos. Adem\u00e1s, sostienen que mantiene en prisi\u00f3n a personas que no pertenecen a pandillas y han pedido, sin \u00e9xito, la derogatoria del r\u00e9gimen de excepci\u00f3n.<\/p>\n<p>Familiares de detenidos han denunciado en reiteradas ocasiones lo que consideran capturas arbitrarias, porque, seg\u00fan dicen, se realizan sin orden judicial, sin investigaci\u00f3n previa e, incluso, a ra\u00edz de denuncias an\u00f3nimas. El Gobierno responde que es el sistema judicial el que decide si hay pruebas para que contin\u00faen detenidos.<\/p>\n<p>La Fundaci\u00f3n para el Debido Proceso, que tiene su sede en Washington y se dedica a promover los derechos humanos, dice que cada vez son m\u00e1s los gobiernos y candidatos pol\u00edticos que tienen como referente a Bukele, y que buscan implementar medidas de seguridad similares, como Honduras, donde la presidenta Xiomara Castro implement\u00f3 un r\u00e9gimen de excepci\u00f3n parcial en varias regiones.<\/p>\n<p>El presidente Bukele pronuncia un discurso durante la inauguraci\u00f3n de la Central Hidroel\u00e9ctrica en San Luis de la Reina, El Salvador. (Cr\u00e9dito: MARVIN RECINOS\/AFP via Getty Images)<\/p>\n<p>\u201cYa no en uno, dos o tres, sino en muchos pa\u00edses se habla del modelo Bukele, del fen\u00f3meno Bukele, como esta forma de gobernar que permite acabar con la inseguridad en los pa\u00edses. Y esto\u2026 bueno, es un error\u201d, dice a CNN Katya Salazar, directora ejecutiva de la Fundaci\u00f3n para el Debido Proceso.<\/p>\n<p>Bukele, actualmente con licencia aprobada por la Asamblea Legislativa (controlada por su partido, Nuevas Ideas) para realizar la campa\u00f1a para su reelecci\u00f3n, ya ha advertido a sus hom\u00f3logos que no es f\u00e1cil obtener los mismos resultados. Bukele design\u00f3 a su secretaria privada para ejerza las funciones de la Presidencia mientras dura su licencia.<\/p>\n<p>\u00bfCu\u00e1ndo son las elecciones de El Salvador 2024 y que se votar\u00e1?<\/p>\n<p>\u00bfQu\u00e9 deja la megac\u00e1rcel de Nayib Bukele? 4:59<\/p>\n<p>Mayor seguridad, mayores precios de las viviendas<\/p>\n<p>La seguridad ha generado un nuevo problema para El Salvador: un alarmante incremento en el precio de las viviendas, sobre todo en barrios y colonias que antes eran controladas por las pandillas.<\/p>\n<p>Eso ha llevado a muchos salvadore\u00f1os a expresar su preocupaci\u00f3n: \u201cHan recuperado las casas que antes consideraban perdidas, han invertido m\u00e1s para mejorarlas y ahora se quiere el precio de la casa, se quiere la ganancia de la inversi\u00f3n y se quiere una ganancia extra por la vivienda\u201d, dice a CNN Stanley Ar\u00e9valo, una joven que ha visto frustrada sus intenciones de comprar una casa en Soyapango, municipio ubicado a unos 10 kil\u00f3metros de la capital.<\/p>\n<p>El 3 de enero, durante una transmisi\u00f3n en vivo en X (antes Twitter) Bukele admiti\u00f3 que la mejora en los niveles de seguridad ha hecho que aumente el precio de las viviendas, especialmente en lugares que antes eran controlados por las pandillas.<\/p>\n<p>\u201cHab\u00eda literalmente viviendas de US$ 3.000\u2026 claro, vivir ah\u00ed era imposible porque el d\u00eda siguiente iba a amanecer muerto\u201d, dijo durante la transmisi\u00f3n, en respuesta a una de las asistentes al foro virtual que expuso su preocupaci\u00f3n por este fen\u00f3meno.<\/p>\n<p>Bukele reconoci\u00f3 que hay una \u201cburbuja inmobiliaria\u201d y que hay gente que se est\u00e1 aprovechando de la situaci\u00f3n, debido a que en El Salvador no existe el control de precios. Aclar\u00f3 que su gobierno no est\u00e1 pensando en implementar una medida de ese tipo y que, a su juicio, el problema inmobiliario se debe resolver con oferta.<\/p>\n<p>En este momento, de acuerdo con Bukele, hay m\u00e1s demanda que oferta porque, entre otras cosas, hay salvadore\u00f1os que viven en el exterior que est\u00e1n comprando propiedades para preparar su retorno al pa\u00eds. \u201cLo que tenemos que hacer es generar que se construyan m\u00e1s viviendas y entonces, al haber m\u00e1s oferta bajan los precios, porque entonces la gente ya no se puede aprovechar y los precios se vuelven justos\u201d, expres\u00f3 Bukele a inicios de enero.<\/p>\n<p>Debilitada y en desventaja, as\u00ed llega la oposici\u00f3n a las elecciones de El Salvador 2024<\/p>\n<p>El estilo Bukele<\/p>\n<p>El estilo de gobierno de Bukele tiene seguidores, pero tambi\u00e9n detractores, que advierten que las medidas requieren de recursos que el pa\u00eds no tiene y que, por lo tanto, no ser\u00edan sostenibles en el tiempo.<\/p>\n<p>\u201cCreo yo que no van a resolver el fondo del problema, dan un maquillaje. Por este momento est\u00e1n resolviendo el problema, pero en alg\u00fan momento esta caja de Pandora se va a reventar, se va a abrir y va a explotar en la cara de todos los salvadore\u00f1os\u201d, advierte Katya Salazar, directora ejecutiva de la Fundaci\u00f3n para el Debido Proceso.<\/p>\n<p>Bukele ha ignorado recomendaciones de organismos internacionales como el Banco Mundial y el Fondo Monetario Internacional en materia econ\u00f3mica, y de la Comisi\u00f3n Interamericana de Derechos Humanos en materia de seguridad.<\/p>\n<p>A juicio del mandatario, el rumbo del pa\u00eds es el correcto, y para crecer se debe hacer lo que hacen las potencias mundiales, y no lo que dicen que deben hacer los pa\u00edses en v\u00edas de desarrollo.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele, se presenta a las elecciones presidenciales del domingo en busca de un segundo mandato, con el combate a la delincuencia como su principal bandera. En las calles, los salvadore\u00f1os reconocen la mejora en la seguridad. Roberto Gonz\u00e1lez, quien ofrece servicios de transporte a trav\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444800","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele, se presenta a las elecciones presidenciales del domingo en busca de un segundo mandato, con el combate a la delincuencia como su principal bandera. En las calles, los salvadore\u00f1os reconocen la mejora en la seguridad. Roberto Gonz\u00e1lez, quien ofrece servicios de transporte a trav\u00e9s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T19:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador\",\"datePublished\":\"2024-02-02T19:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\"},\"wordCount\":1221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\",\"name\":\"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-02T19:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","og_locale":"es_ES","og_type":"article","og_title":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de El Salvador, Nayib Bukele, se presenta a las elecciones presidenciales del domingo en busca de un segundo mandato, con el combate a la delincuencia como su principal bandera. En las calles, los salvadore\u00f1os reconocen la mejora en la seguridad. Roberto Gonz\u00e1lez, quien ofrece servicios de transporte a trav\u00e9s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","og_site_name":"Noticias","article_published_time":"2024-02-02T19:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/"},"author":{"name":"","@id":""},"headline":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador","datePublished":"2024-02-02T19:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/"},"wordCount":1221,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","name":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-02T19:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-02T19:33:36Z","datePublished":"2024-02-02T19:33:36Z","dateModified":"2024-02-02T19:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/02\\\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/02\\\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-02T19:33:36Z\",\"datePublished\":\"2024-02-02T19:33:36Z\",\"dateModified\":\"2024-02-02T19:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444802,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/logros-y-problemas-durante-la-presidencia-de-nayib-bukele-en-el-salvador-2\/","url_meta":{"origin":1444800,"position":0},"title":"Logros y problemas durante la presidencia de Nayib Bukele en El Salvador","author":"","date":"febrero 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de El Salvador, Nayib Bukele, se presenta a las elecciones presidenciales del domingo en busca de un segundo mandato, con el combate a la delincuencia como su principal bandera.En las calles, los salvadore\u00f1os reconocen la mejora en la seguridad. Roberto Gonz\u00e1lez, quien ofrece servicios de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449894,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/31\/bukele-segundo-mandato-desafios-orix\/","url_meta":{"origin":1444800,"position":1},"title":"Nayib Bukele asumir\u00e1 segundo mandato con el desaf\u00edo de mejorar la econom\u00eda de El Salvador","author":"","date":"mayo 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Nayib Bukele inicia este s\u00e1bado su segundo mandato de cinco a\u00f1os con demandas de impulsar medidas que alivien el alto costo de vida y el fomento del empleo, tras la reducci\u00f3n en los niveles de violencia alcanzada en su primer periodo al frente de El Salvador.\u201cEn estos d\u00edas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451019,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/07\/10\/menores-orfandad-muerte-padres-detenidos-regimen-excepcion-el-salvador-cristosal-orix\/","url_meta":{"origin":1444800,"position":2},"title":"Al menos 176 menores en la orfandad tras muerte de sus padres detenidos durante el r\u00e9gimen de excepci\u00f3n en El Salvador, dice la ONG Cristosal","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Al menos 176 menores quedaron en la orfandad luego de que sus padres murieran bajo custodia del Estado, tras haber sido detenidos durante el r\u00e9gimen de excepci\u00f3n, se\u00f1ala un informe de la organizaci\u00f3n no gubernamental salvadore\u00f1a Cristosal, presentado este mi\u00e9rcoles en San Salvador.De acuerdo con la investigaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459496,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/04\/regimen-excepcion-el-salvador-tres-anios-prorroga-orix\/","url_meta":{"origin":1444800,"position":3},"title":"El r\u00e9gimen de excepci\u00f3n de El Salvador cumplir\u00e1 tres a\u00f1os de vigencia tras nueva pr\u00f3rroga","author":"","date":"marzo 4, 2025","format":false,"excerpt":"El r\u00e9gimen de excepci\u00f3n en El Salvador cumplir\u00e1 tres a\u00f1os en vigor a fines de marzo, tras la m\u00e1s reciente pr\u00f3rroga aprobada este martes por la Asamblea Legislativa, de mayor\u00eda oficialista.La medida de seguridad, aprobada con los votos de 57 de 60 diputados, extiende la suspensi\u00f3n de varias garant\u00edas que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462525,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/19\/arrestan-el-salvador-jefa-ong-critica-bukele-orix\/","url_meta":{"origin":1444800,"position":4},"title":"Arrestan en El Salvador a jefa de Anticorrupci\u00f3n y Justicia de Cristosal, ONG cr\u00edtica de Bukele","author":"","date":"mayo 19, 2025","format":false,"excerpt":"Las autoridades de El Salvador detuvieron este domingo a Ruth Eleonora L\u00f3pez, jefa de la unidad de Anticorrupci\u00f3n y Justicia de la organizaci\u00f3n no gubernamental Cristosal, inform\u00f3 la Fiscal\u00eda General a trav\u00e9s de una publicaci\u00f3n en X.Cristosal promueve la defensa de los derechos humanos y es cr\u00edtica de la gesti\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447836,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/07\/salvador-pasaportes-trabajadores-extranjeros-trax\/","url_meta":{"origin":1444800,"position":5},"title":"El Salvador ofrece 5.000 pasaportes a trabajadores extranjeros calificados","author":"","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- El Salvador ofrece 5.000 \u201cpasaportes gratuitos\u201d a trabajadores altamente calificados del extranjero, anunci\u00f3 este s\u00e1bado el presidente Nayib Bukele en su \u00faltimo intento de impulsar la econom\u00eda del pa\u00eds con inversi\u00f3n extranjera.A los cient\u00edficos, ingenieros, m\u00e9dicos, artistas y fil\u00f3sofos se les otorgar\u00e1 \u201cestatus de ciudadanos plenos\u201d, incluido el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444800"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444800\/revisions"}],"predecessor-version":[{"id":1444816,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444800\/revisions\/1444816"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}