{"id":1444817,"date":"2024-02-02T20:33:28","date_gmt":"2024-02-03T04:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444817"},"modified":"2024-02-02T20:33:28","modified_gmt":"2024-02-03T04:33:28","slug":"muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","title":{"rendered":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os"},"content":{"rendered":"<p>(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y partici\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber.<\/p>\n<p>El actor \u201cfalleci\u00f3 en paz en su casa\u201d este jueves, indic\u00f3 Luber a CNN. No se mencion\u00f3 la causa de muerte.<\/p>\n<p>&#171;Carl era un ser humano excepcional que vivi\u00f3 una vida extraordinaria&#187;, dijo su familia en un comunicado enviado a CNN. \u201cA trav\u00e9s de sus contribuciones al cine, la televisi\u00f3n, las artes y los deportes, ha dejado una huella imborrable y es reconocido en todo el mundo y de generaci\u00f3n en generaci\u00f3n. Era un querido hermano, padre, abuelo, socio y amigo\u201d.<\/p>\n<p>Weathers era en realidad un exjugador de f\u00fatbol que nunca hab\u00eda boxeado cuando hizo su audici\u00f3n para el papel en \u201cRocky\u201d, y luego apareci\u00f3 como Apollo Creed en la pel\u00edcula ganadora del Oscar y en las siguientes tres secuelas.<\/p>\n<p>En una entrevista con The Hollywood Reporter en 2015, Weathers record\u00f3 haber hecho una audici\u00f3n con Stallone, de quien le dijeron que era el escritor de la pel\u00edcula, sin saber que el actor tambi\u00e9n era la estrella. Despu\u00e9s, al sentir que la lectura de prueba no hab\u00eda salido bien, record\u00f3: &#171;Simplemente dije: &#8216;Podr\u00eda hacerlo mucho mejor si me consiguieran un actor real con quien trabajar'&#187;.<\/p>\n<p>El personaje obviamente se inspir\u00f3 en Muhammad Ali, a quien Weathers conoci\u00f3 m\u00e1s posteriormente.<\/p>\n<p>Weathers aprovech\u00f3 su exposici\u00f3n en \u201cRocky\u201d para interpretar otros personajes que capitalizaron su imponente f\u00edsico, incluida la pel\u00edcula de acci\u00f3n y ciencia ficci\u00f3n de 1987 \u201cPredator\u201d, protagonizada por Arnold Schwarzenegger.<\/p>\n<p>Al a\u00f1o siguiente, dio vida a un polic\u00eda de Detroit en la mal recibida &#171;Action Jackson&#187;.<\/p>\n<p>Sus papeles posteriores incluyeron la comedia de Adam Sandler &#171;Happy Gilmore&#187; y las pel\u00edculas para televisi\u00f3n &#171;In the Heat of the Night&#187;, la serie &#171;Arrested Development&#187; y la voz de Combat Carl en la franquicia &#171;Toy Story&#187;.<\/p>\n<p>M\u00e1s recientemente, Weathers interpret\u00f3 un papel secundario clave en la serie de \u201cStar Wars\u201d \u201cThe Mandalorian\u201d, que obtuvo una nominaci\u00f3n al Emmy como actor invitado en un drama, en Disney+, y dirigi\u00f3 uno de los episodios.<\/p>\n<p>Weathers tambi\u00e9n hab\u00eda dirigido episodios de varias series de televisi\u00f3n, incluidas \u201cChicago Med\u201d, \u201cLaw &amp; Order\u201d y \u201cHawaii Five-O\u201d.<\/p>\n<p>Nacido en Nueva Orleans, Weathers jug\u00f3 f\u00fatbol americano universitario en San Diego State y jug\u00f3 brevemente profesionalmente con los Oakland Raiders y en la Canadian Football League.<\/p>\n<p>Dej\u00f3 el f\u00fatbol a mediados de la d\u00e9cada de 1970 y comenz\u00f3 a dedicarse a la actuaci\u00f3n, obteniendo papeles en dos pel\u00edculas antes de su lograr su personaje en \u201cRocky\u201d.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y partici\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber. El actor \u201cfalleci\u00f3 en paz en su casa\u201d este jueves, indic\u00f3 Luber [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444817","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &quot;Rocky&quot;, a los 76 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &quot;Rocky&quot;, a los 76 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y partici\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber. El actor \u201cfalleci\u00f3 en paz en su casa\u201d este jueves, indic\u00f3 Luber [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-03T04:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os\",\"datePublished\":\"2024-02-03T04:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\"},\"wordCount\":499,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\",\"url\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\",\"name\":\"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en \\\"Rocky\\\", a los 76 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-03T04:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en \"Rocky\", a los 76 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en \"Rocky\", a los 76 a\u00f1os - Noticias","og_description":"(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y partici\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber. El actor \u201cfalleci\u00f3 en paz en su casa\u201d este jueves, indic\u00f3 Luber [&hellip;]","og_url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","og_site_name":"Noticias","article_published_time":"2024-02-03T04:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/"},"author":{"name":"","@id":""},"headline":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os","datePublished":"2024-02-03T04:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","url":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","name":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en \"Rocky\", a los 76 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-03T04:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/monterey-salinas\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-03T04:33:28Z","datePublished":"2024-02-03T04:33:28Z","dateModified":"2024-02-03T04:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/02\\\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/02\\\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-03T04:33:28Z\",\"datePublished\":\"2024-02-03T04:33:28Z\",\"dateModified\":\"2024-02-03T04:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444839,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos-2\/","url_meta":{"origin":1444817,"position":0},"title":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y particip\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber.El actor \u201cfalleci\u00f3 en paz en su casa\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444849,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/carl-weathers-mas-alla-de-rocky-las-peliculas-y-series-mas-recordadas-del-actor\/","url_meta":{"origin":1444817,"position":1},"title":"Carl Weathers m\u00e1s all\u00e1 de &#171;Rocky&#187;: las pel\u00edculas y series m\u00e1s recordadas del actor","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El actor Carl Weathers, quien falleci\u00f3 a los 76 a\u00f1os, se hizo mundialmente famoso con la interpretaci\u00f3n de Apollo Creed en la saga de Rocky. Sin embargo, su extensa carrera trascendi\u00f3 con creces el papel del boxeador inspirado en Muhammad Ali. Aqu\u00ed, un repaso a algunas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446013,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/26\/kenneth-mitchell-actor-star-trek-marvel-muere-49-anios-trax\/","url_meta":{"origin":1444817,"position":2},"title":"Kenneth Mitchell, actor de &#171;Star Trek&#187; y &#171;Marvel&#187;, muere a los 49 a\u00f1os","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN) -- Kenneth Mitchell, actor que apareci\u00f3 en las series \"Star Trek: Discovery\" y \"Captain Marvel\" de Marvel, muri\u00f3, anunci\u00f3 su familia en un comunicado compartido en sus redes sociales verificadas este domingo.Ten\u00eda 49 a\u00f1os.\"Con gran pesar anunciamos el fallecimiento de Kenneth Alexander Mitchell, amado padre, esposo, hermano, t\u00edo, hijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464487,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/13\/kentucky-tiroteo-muertos-iglesia-trax\/","url_meta":{"origin":1444817,"position":3},"title":"Dos muertos en iglesia de Kentucky tras tiroteo en el que un atacante dispar\u00f3 a un agente estatal; el sospechoso muri\u00f3","author":"","date":"julio 13, 2025","format":false,"excerpt":"Una mujer de 72 a\u00f1os y otra de 32 murieron en un tiroteo este domingo en la iglesia bautista Richmond Road, en Lexington, Kentucky, informaron las autoridades.El atacante, quien tambi\u00e9n muri\u00f3, ya fue identificado, pero la polic\u00eda no revel\u00f3 su nombre porque su familia a\u00fan no ha sido notificada, indicaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473287,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/17\/empleada-dhs-maraton-madre-murieron-ataques-atlanta-trax\/","url_meta":{"origin":1444817,"position":4},"title":"Qui\u00e9nes eran las tres v\u00edctimas que murieron en ataques en Atlanta presuntamente cometidos por el mismo agresor","author":"","date":"abril 17, 2026","format":false,"excerpt":"Para el p\u00fablico, Lauren Bullis era una empleada dedicada del Departamento de Seguridad Nacional en Georgia: una profesional ejemplar comprometida con el servicio p\u00fablico.Para sus seres queridos, la mujer de 40 a\u00f1os, originaria de Decatur, era una exploradora aventurera que viajaba por el mundo y llevaba alegr\u00eda a amigos cercanos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449244,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","url_meta":{"origin":1444817,"position":5},"title":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- Poco despu\u00e9s de que Sylvester Stallone terminara de filmar \u201cRocky\u201d, la pel\u00edcula que lanz\u00f3 su carrera en Hollywood, vio a Gregg Allman, de Allman Brothers Band, que se hab\u00eda quedado dormido y hab\u00eda dejado el brazo colgando en el pasillo con un distintivo reloj de oro en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444817"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444817\/revisions"}],"predecessor-version":[{"id":1444833,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444817\/revisions\/1444833"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}