{"id":1444847,"date":"2024-02-03T11:33:37","date_gmt":"2024-02-03T19:33:37","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444847"},"modified":"2024-02-03T11:33:37","modified_gmt":"2024-02-03T19:33:37","slug":"chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","title":{"rendered":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Chile, Gabriel Boric, decret\u00f3 el estado de excepci\u00f3n constitucional para las provincias de Marga Marga y Valpara\u00edso debido a los incendios forestales, inform\u00f3 este s\u00e1bado la delegada presidencial de la regi\u00f3n Valpara\u00edso, Sof\u00eda Gonz\u00e1lez Cort\u00e9s.<\/p>\n<p>La funcionaria agreg\u00f3 que se estableci\u00f3 tambi\u00e9n un toque de queda entre las 08:00 a.m. (hora local) y el medidodia en las comunas de Limache, Villa Alemana, Quilpu\u00e9, y Vi\u00f1a del Mar con el prop\u00f3stio de faciltar el despliegue de los medios log\u00edsticos y medios de emergencia.<\/p>\n<p>El viernes, el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (Senapred) inform\u00f3 que\u00a0Valpara\u00edso y Marga Marga fueron declaradas en alerta roja debido a tres incendios forestales que hasta ese momento hab\u00edan afectado en total unas 565 hect\u00e1reas.<\/p>\n<p>El incendio m\u00e1s extenso hasta ahora, seg\u00fan el reporte del viernes, es el que se desarrolla en el complejo Las Tablas y la reserva Lago Pe\u00f1uelas, en Valpara\u00edso, donde 480 hect\u00e1reas se han visto afectadas, indic\u00f3 el Senapred en un bolet\u00edn informativo.<\/p>\n<p>Los otros dos incendios est\u00e1n en Lo Moscoso, en las comunas Quilp\u00e9 y Villa Alemana, donde 80 hect\u00e1reas est\u00e1n siendo afectadas, y en el camino Dos Locas, tambi\u00e9n en Valpara\u00edso, los da\u00f1os son en 5 hect\u00e1reas.<\/p>\n<p>El Senapred inform\u00f3 que por esta situaci\u00f3n se orden\u00f3 la evacuaci\u00f3n de algunos sectores de la comuna Villa Alemana.<\/p>\n<p>CNN no ha podido saber si los incendios han dejado personas heridas o fallecidas.<\/p>\n<p>Boric dijo en su cuenta en la red social X que fuerzas gubernamentales est\u00e1n desplegadas para controlar los incendios. Tambi\u00e9n inform\u00f3 que orden\u00f3 a la ministra del Interior, Carolina Toh\u00e1, realizar este s\u00e1bado, a las 12:30 a.m. (hora local), una reuni\u00f3n del Comit\u00e9 de Gesti\u00f3n de Riesgos y Desastres (Cogrid).<\/p>\n<p>Boric pidi\u00f3 a la ciudadan\u00eda atender las indicaciones de las autoridades y evitar exponerse a riesgos.<\/p>\n<p>Nota del editor: este art\u00edculo fue actualizado con informaci\u00f3n adicional.<\/p>\n<p>Con informaci\u00f3n de Omar Fajardo.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Chile, Gabriel Boric, decret\u00f3 el estado de excepci\u00f3n constitucional para las provincias de Marga Marga y Valpara\u00edso debido a los incendios forestales, inform\u00f3 este s\u00e1bado la delegada presidencial de la regi\u00f3n Valpara\u00edso, Sof\u00eda Gonz\u00e1lez Cort\u00e9s. La funcionaria agreg\u00f3 que se estableci\u00f3 tambi\u00e9n un toque de queda entre las 08:00 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444847","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de Chile, Gabriel Boric, decret\u00f3 el estado de excepci\u00f3n constitucional para las provincias de Marga Marga y Valpara\u00edso debido a los incendios forestales, inform\u00f3 este s\u00e1bado la delegada presidencial de la regi\u00f3n Valpara\u00edso, Sof\u00eda Gonz\u00e1lez Cort\u00e9s. La funcionaria agreg\u00f3 que se estableci\u00f3 tambi\u00e9n un toque de queda entre las 08:00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-03T19:33:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales\",\"datePublished\":\"2024-02-03T19:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\"},\"wordCount\":386,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\",\"name\":\"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-03T19:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","og_locale":"es_ES","og_type":"article","og_title":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de Chile, Gabriel Boric, decret\u00f3 el estado de excepci\u00f3n constitucional para las provincias de Marga Marga y Valpara\u00edso debido a los incendios forestales, inform\u00f3 este s\u00e1bado la delegada presidencial de la regi\u00f3n Valpara\u00edso, Sof\u00eda Gonz\u00e1lez Cort\u00e9s. La funcionaria agreg\u00f3 que se estableci\u00f3 tambi\u00e9n un toque de queda entre las 08:00 [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","og_site_name":"Noticias","article_published_time":"2024-02-03T19:33:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/"},"author":{"name":"","@id":""},"headline":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales","datePublished":"2024-02-03T19:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/"},"wordCount":386,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","name":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-03T19:33:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Chile decreta toque de queda en comunidades de Valpara\u00edso y Marga Marga por incendios forestales","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-03T19:33:37Z","datePublished":"2024-02-03T19:33:37Z","dateModified":"2024-02-03T19:33:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Chile decreta toque de queda en comunidades de Valpara\\u00edso y Marga Marga por incendios forestales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/03\\\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/03\\\/chile-decreta-toque-de-queda-en-comunidades-de-valparaiso-y-marga-marga-por-incendios-forestales\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-03T19:33:37Z\",\"datePublished\":\"2024-02-03T19:33:37Z\",\"dateModified\":\"2024-02-03T19:33:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444834,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-declara-alerta-roja-en-las-provincias-de-valparaiso-y-marga-marga-por-incendios-forestales-2\/","url_meta":{"origin":1444847,"position":0},"title":"Chile declara alerta roja en las provincias de Valpara\u00edso y Marga Marga por incendios forestales","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Las provincias de Valpara\u00edso y Marga Marga fueron declaradas en alerta roja debido a tres incendios forestales que hasta el momento han afectado en total unas 565 hect\u00e1reas, inform\u00f3 este viernes el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (Senapred).El incendio m\u00e1s extenso hasta ahora es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444832,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/chile-declara-alerta-roja-en-las-provincias-de-valparaiso-y-marga-marga-por-incendios-forestales\/","url_meta":{"origin":1444847,"position":1},"title":"Chile declara alerta roja en las provincias de Valpara\u00edso y Marga Marga por incendios forestales","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Las provincias de Valpara\u00edso y Marga Marga fueron declaradas en alerta roja debido a tres incendios forestales que hasta el momento han afectado en total unas 565 hect\u00e1reas, inform\u00f3 este viernes el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (Senapred).El incendio m\u00e1s extenso hasta ahora es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444877,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/al-menos-46-muertos-por-incendios-en-valparaiso-chile-informa-el-presidente\/","url_meta":{"origin":1444847,"position":2},"title":"Al menos 46 muertos por incendios en Valpara\u00edso, Chile, informa el presidente","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN En espa\u00f1ol) --\u00a0El n\u00famero de v\u00edctimas mortales por los incendios de Valpara\u00edso, Chile, subi\u00f3 a 46, inform\u00f3 Gabriel Boric, presidente del pa\u00eds.40 personas fallecieron durante los incendios y 6 m\u00e1s mientras eran atendidas en los hospitales por quemaduras, dijo Boric en comparencia.Anteriormente, la ministra del Interior de Chile, Carolina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444881,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/al-menos-51-muertos-por-incendios-en-chile-informa-gobierno\/","url_meta":{"origin":1444847,"position":3},"title":"Al menos 51 muertos por incendios en Chile, informa Gobierno","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN En espa\u00f1ol) --\u00a0El n\u00famero de v\u00edctimas mortales por los incendios de Valpara\u00edso, Chile, subi\u00f3 a 51, inform\u00f3 el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (Senapred) en conferencia de prensa.Anteriormente, el presidente de Chile, Gabriel Boric, inform\u00f3 que 40 personas fallecieron durante los incendios y 6 m\u00e1s mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444883,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/al-menos-51-muertos-por-incendios-en-chile-informa-gobierno-2\/","url_meta":{"origin":1444847,"position":4},"title":"Al menos 51 muertos por incendios en Chile, informa Gobierno","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN En espa\u00f1ol) --\u00a0El n\u00famero de v\u00edctimas mortales por los incendios de Valpara\u00edso, Chile, subi\u00f3 a 51, inform\u00f3 el Servicio Nacional de Prevenci\u00f3n y Respuesta ante Desastres (Senapred) en conferencia de prensa.Anteriormente, el presidente de Chile, Gabriel Boric, inform\u00f3 que 40 personas fallecieron durante los incendios y 6 m\u00e1s mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444879,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/fotos-los-mortales-incendios-forestales-en-chile\/","url_meta":{"origin":1444847,"position":5},"title":"FOTOS | Los mortales incendios forestales en Chile","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Chile est\u00e1 siendo afectado por incendios forestales en varias regiones del pa\u00eds. Los fuertes incendios han dejado al menos 51 muertos, de acuerdo con el presidente Gabriel Boric, y \"dadas las condiciones de la tragedia, el n\u00famero de v\u00edctimas seguramente aumentar\u00e1 en las pr\u00f3ximas horas\", asegur\u00f3.Casas arden durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444847"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444847\/revisions"}],"predecessor-version":[{"id":1444863,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444847\/revisions\/1444863"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}